{"id":721,"count":49,"description":"","link":"https:\/\/blog.wika.com\/en\/tag\/process-safety\/","name":"Process safety","slug":"process-safety","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Process safety article - WIKA blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Process safety article - WIKA blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/en\/tag\/process-safety\/\" \/>\n<meta property=\"og:site_name\" content=\"WIKA blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/en\/files\/2015\/06\/wika_social_media_standard_en.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"879\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/tag\\\/process-safety\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/tag\\\/process-safety\\\/\",\"name\":\"Process safety article - WIKA blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/tag\\\/process-safety\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/tag\\\/process-safety\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Process safety\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/\",\"name\":\"WIKA blog\",\"description\":\"Our blog offers many interesting articles on pressure, temperature, level, force, flow measurement calibration technology and provides insights into the WIKA Group.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Process safety article - WIKA blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Process safety article - WIKA blog","og_url":"https:\/\/blog.wika.com\/en\/tag\/process-safety\/","og_site_name":"WIKA blog","og_image":[{"width":958,"height":879,"url":"https:\/\/blog.wika.com\/en\/files\/2015\/06\/wika_social_media_standard_en.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.wika.com\/en\/tag\/process-safety\/","url":"https:\/\/blog.wika.com\/en\/tag\/process-safety\/","name":"Process safety article - WIKA blog","isPartOf":{"@id":"https:\/\/blog.wika.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.wika.com\/en\/tag\/process-safety\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/en\/tag\/process-safety\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wika.com\/en\/"},{"@type":"ListItem","position":2,"name":"Process safety"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/en\/#website","url":"https:\/\/blog.wika.com\/en\/","name":"WIKA blog","description":"Our blog offers many interesting articles on pressure, temperature, level, force, flow measurement calibration technology and provides insights into the WIKA Group.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/en\/wp-json\/wp\/v2\/tags\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.wika.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.wika.com\/en\/wp-json\/wp\/v2\/posts?tags=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}