{"id":10049,"date":"2023-05-15T11:30:35","date_gmt":"2023-05-15T09:30:35","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=10049"},"modified":"2023-11-16T07:55:17","modified_gmt":"2023-11-16T06:55:17","slug":"l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/","title":{"rendered":"L&rsquo;importance de la protection des capteurs de pression contre l&rsquo;humidit\u00e9 et l&rsquo;eau"},"content":{"rendered":"<p><strong>La p\u00e9n\u00e9tration d&rsquo;humidit\u00e9 est l&rsquo;une des causes les plus courantes de d\u00e9faillance des capteurs de pression. Pour \u00e9viter cette situation, il faut choisir un transducteur ou un transmetteur de pression dont l&rsquo;indice de protection IP, la r\u00e9f\u00e9rence de mesure et la connexion \u00e9lectrique sont adapt\u00e9s.<\/strong><\/p>\n<p>La sortie de votre transmetteur de pression d\u00e9rive ou l&rsquo;ensemble de l&rsquo;unit\u00e9 est en panne. <br \/>\nQue s&rsquo;est-il pass\u00e9 ? <br \/>\nL&rsquo;humidit\u00e9, qui peut rapidement endommager la carte de circuit imprim\u00e9 ou les connexions \u00e9lectriques internes, est l&rsquo;une des causes possibles. Pour prot\u00e9ger les capteurs de pression, il faut d&rsquo;abord choisir le bon instrument de pression, avec la classe IP, la r\u00e9f\u00e9rence de mesure et les connexions \u00e9lectriques appropri\u00e9es.<\/p>\n<h2>Capteurs de pression et indices IP<\/h2>\n<p>\n<a href=\"https:\/\/www.wika.com\/fr-fr\/capteurs_de_pression.WIKA\" rel=\"external\" target=\"_blank\">Les capteurs de pression<\/a>, \u00e9galement appel\u00e9s transducteurs de pression, sont utilis\u00e9s dans un large \u00e9ventail d&rsquo;applications. Certains capteurs sont plac\u00e9s dans des laboratoires climatis\u00e9s o\u00f9 l&rsquo;humidit\u00e9 est constamment faible. D&rsquo;autres sont soumis \u00e0 un nettoyage r\u00e9gulier et \u00e0 une st\u00e9rilisation \u00e0 la vapeur haute pression, c&rsquo;est le cas dans les industries <a href=\"https:\/\/www.wika.com\/fr-fr\/agroalimentaire.WIKA?tab=1\" rel=\"external\" target=\"_blank\">agro-alimentaires<\/a> et <a href=\"https:\/\/www.wika.com\/fr-fr\/industrie_pharmaceutique_et_biotechnologie.WIKA?tab=1\" rel=\"external\" target=\"_blank\">pharmaceutiques<\/a>.<\/p>\n<p>Pour minimiser les risques de d\u00e9faillance des capteurs de pression, v\u00e9rifiez toujours que la protection contre les agressions (IP) ou la classification NEMA de l&rsquo;instrument r\u00e9pond aux exigences de l&rsquo;endroit o\u00f9 il se trouve. Notez que le type de connexion \u00e9lectrique fait une diff\u00e9rence significative. <br \/>\nPar exemple, le <a href=\"https:\/\/www.wika.com\/fr-fr\/a_10.WIKA\" rel=\"external\" target=\"_blank\">transmetteur de pression A-10<\/a> \u00e9quip\u00e9 d&rsquo;un connecteur angulaire est class\u00e9 IP65, ce qui signifie qu&rsquo;il est prot\u00e9g\u00e9 contre les jets et les pulv\u00e9risations d&rsquo;eau \u00e0 basse pression ; une certaine p\u00e9n\u00e9tration est autoris\u00e9e. Cependant, avec un connecteur circulaire ou une sortie de c\u00e2ble, l&rsquo;indice de protection du transmetteur de pression passe \u00e0 IP67, ce qui permet d&rsquo;immerger compl\u00e8tement l&rsquo;instrument dans l&rsquo;eau pendant une dur\u00e9e limit\u00e9e et jusqu&rsquo;\u00e0 une certaine profondeur.<\/p>\n<h2>R\u00e9f\u00e9rences de pression ambiante ou absolue<\/h2>\n<p>\nLe fait qu&rsquo;un transmetteur de pression soit ventil\u00e9 ou scell\u00e9 fait une grande diff\u00e9rence dans la capacit\u00e9 de l&rsquo;instrument \u00e0 emp\u00eacher l&rsquo;eau et d&rsquo;autres liquides de p\u00e9n\u00e9trer. Il existe trois types principaux de transmetteurs de pression, chacun ayant des exigences diff\u00e9rentes en mati\u00e8re de protection contre l&rsquo;humidit\u00e9 :<\/p>\n<ul>\n<li><strong>Les transmetteurs relatifs<\/strong> sont g\u00e9n\u00e9ralement utilis\u00e9s pour les plages de mesure inf\u00e9rieures, o\u00f9 les variations de la pression atmosph\u00e9rique peuvent \u00eatre plus importantes que la marge d&rsquo;erreur du transmetteur. L&rsquo;instrument est mis \u00e0 l&rsquo;air libre afin que les relev\u00e9s de pression puissent \u00eatre compar\u00e9s \u00e0 la pression ambiante (atmosph\u00e9rique). Les transmetteurs de pression \u00e9tant dot\u00e9s d&rsquo;un orifice de mise \u00e0 l&rsquo;air libre, ils n\u00e9cessitent un connecteur \u00e9lectrique et un syst\u00e8me de mise \u00e0 l&rsquo;air libre interne soigneusement con\u00e7us pour emp\u00eacher l&rsquo;humidit\u00e9 de p\u00e9n\u00e9trer dans l&rsquo;appareil et de l&rsquo;endommager. Par exemple, certains transmetteurs de pression ont un petit trou sous le filetage de la bague de retenue d&rsquo;un connecteur \u00e9lectrique. Ce trou est prot\u00e9g\u00e9 par un mat\u00e9riau de type Gore-Tex ou T\u00e9flon qui laisse passer l&rsquo;air mais pas l&rsquo;humidit\u00e9.<\/li>\n<li><strong>Les transmetteurs relatifs scell\u00e9s<\/strong> mesurent des plages de pression plus \u00e9lev\u00e9es o\u00f9 les variations de la pression barom\u00e9trique sont inf\u00e9rieures \u00e0 la marge d&rsquo;erreur des sp\u00e9cifications de pr\u00e9cision de l&rsquo;instrument ; en d&rsquo;autres termes, les variations de la pression ambiante n&rsquo;affectent pas la lecture de sortie. Ce type de transmetteur de pression n&rsquo;a g\u00e9n\u00e9ralement pas besoin d&rsquo;\u00eatre ventil\u00e9, mais selon la conception, l&rsquo;humidit\u00e9 peut toujours s&rsquo;y infiltrer. Le choix d&rsquo;un transmetteur ayant l&rsquo;indice de protection IP ou NEMA requis permet d&rsquo;\u00e9viter ce probl\u00e8me.<\/li>\n<li><strong>Les transmetteurs absolus<\/strong> mesurent la pression par r\u00e9f\u00e9rence \u00e0 une chambre \u00e0 vide scell\u00e9e situ\u00e9e derri\u00e8re l&rsquo;\u00e9l\u00e9ment du capteur. En tant que syst\u00e8me ferm\u00e9, le circuit de conditionnement est prot\u00e9g\u00e9 des \u00e9l\u00e9ments. Cependant, la connexion \u00e9lectrique reste un point faible potentiel, car les mat\u00e9riaux d&rsquo;\u00e9tanch\u00e9it\u00e9 souples de l&rsquo;assemblage du capteur peuvent se d\u00e9grader au fil du temps, permettant \u00e0 l&rsquo;humidit\u00e9 ou aux fluides de p\u00e9n\u00e9trer. La solution est une cellule de mesure enti\u00e8rement soud\u00e9e, qui \u00e9limine le besoin d&rsquo;un scellement d\u00e9gradable.<\/li>\n<\/ul>\n<p>La gamme compl\u00e8te de capteurs de pression WIKA comprend :<\/p>\n<ul>\n<li><a href=\"https:\/\/www.wika.com\/fr-fr\/a_10.WIKA\" rel=\"external\" target=\"_blank\">Transmetteur de pression A-10<\/a> pour les applications industrielles g\u00e9n\u00e9rales<\/li>\n<li><a href=\"https:\/\/www.wika.com\/fr-fr\/s_20.WIKA\" rel=\"external\" target=\"_blank\">Transmetteur de pression de haute qualit\u00e9 S-20<\/a> pour les applications industrielles g\u00e9n\u00e9rales<\/li>\n<li><a href=\"https:\/\/www.wika.com\/fr-fr\/psd_4.WIKA\" rel=\"external\" target=\"_blank\">Pressostat \u00e9lectronique PSD-4<\/a> avec affichage<\/li>\n<li><a href=\"https:\/\/www.wika.com\/fr-fr\/mh_4.WIKA\" rel=\"external\" target=\"_blank\">Les capteurs de pression OEM, MH-4 et MH-4-CAN<\/a>, pour machines mobiles<\/li>\n<\/ul>\n<h2>La connexion \u00e9lectrique : Un point de vuln\u00e9rabilit\u00e9<\/h2>\n<p>\nLe raccordement \u00e9lectrique est l&rsquo;un des endroits o\u00f9 l&rsquo;humidit\u00e9 p\u00e9n\u00e8tre le plus souvent dans un transmetteur de pression. Le choix de la bonne connexion fait une grande diff\u00e9rence dans la protection des capteurs de pression contre les dommages caus\u00e9s par l&rsquo;humidit\u00e9. Certaines connexions, comme le type \u00ab\u00a0sol\u00e9no\u00efde\u00a0\u00bb DIN 43 650, sont con\u00e7ues pour des environnements relativement secs. D&rsquo;autres peuvent r\u00e9sister \u00e0 des quantit\u00e9s importantes d&rsquo;humidit\u00e9 et d&rsquo;eau.<\/p>\n<p>\n<strong>C\u00e2ble \u00e0 extr\u00e9mit\u00e9s libres<\/strong><br \/>\nUne sortie de c\u00e2ble correctement raccord\u00e9e est une excellente solution pour la protection contre les infiltrations. Ce c\u00e2ble se termine g\u00e9n\u00e9ralement \u00e0 l&rsquo;int\u00e9rieur d&rsquo;une bo\u00eete de jonction s\u00e8che contenant d&rsquo;autres composants \u00e9lectriques. De plus, le c\u00e2blage peut \u00e9galement servir d&rsquo;\u00e9vent, permettant \u00e0 un transmetteur de compenser les variations de pression atmosph\u00e9rique tout en le prot\u00e9geant des dommages caus\u00e9s par l&rsquo;eau.<\/p>\n<h2>Les transmetteurs immergeables cr\u00e9ent des d\u00e9fis uniques<\/h2>\n<p>\nLes<a href=\"https:\/\/www.wika.com\/fr-fr\/transmetteurs_de_pression_immergeables.WIKA\" rel=\"external\" target=\"_blank\"> capteurs de pression immergeables<\/a> sont d&rsquo;excellentes solutions pour mesurer le niveau des puits, des r\u00e9servoirs et des forages. Mais comme ils sont immerg\u00e9s pendant de longues p\u00e9riodes dans des milieux qui peuvent \u00eatre visqueux, corrosifs, riches en particules et\/ou tr\u00e8s chauds, ces capteurs de pression sp\u00e9ciaux sont dot\u00e9s de plusieurs caract\u00e9ristiques qui les aident \u00e0 r\u00e9sister \u00e0 des environnements extr\u00eames et \u00e0 recevoir un classement IP68 ou NEMA 6P :<\/p>\n<ul>\n<li>Bo\u00eetier tr\u00e8s r\u00e9sistant en acier inoxydable 316L, en titane ou en Hastelloy<\/li>\n<li>Joint herm\u00e9tique permanent<\/li>\n<li>Mat\u00e9riau de c\u00e2blage r\u00e9sistant \u00e0 l&rsquo;abrasion<\/li>\n<li>Fibre aramide \u00e0 l&rsquo;int\u00e9rieur du c\u00e2ble pour le supporter ainsi que le poids du transmetteur.<\/li>\n<\/ul>\n<p>Certains fabricants de transmetteurs de pression immergeables installent des soufflets \u00e9tanches ou des poires en caoutchouc \u00e0 l&rsquo;extr\u00e9mit\u00e9 du tube d&rsquo;\u00e9vent, mais WIKA ne le fait pas. <br \/>\nPourquoi ? <br \/>\nBien que ces assemblages prot\u00e8gent l&rsquo;\u00e9lectronique interne du transmetteur de l&rsquo;humidit\u00e9, ils peuvent \u00e9galement introduire une erreur significative dans les lectures de niveau parce que l&rsquo;air dans les soufflets se dilate et se contracte avec les changements de temp\u00e9rature, cr\u00e9ant des changements de pression \u00e0 l&rsquo;int\u00e9rieur du capteur. <br \/>\nUne meilleure solution consiste \u00e0 laisser le tube s&rsquo;\u00e9vacuer directement dans l&rsquo;atmosph\u00e8re. L&rsquo;installation de l&rsquo;extr\u00e9mit\u00e9 du c\u00e2ble dans une bo\u00eete de jonction conforme \u00e0 la norme NEMA 4 prot\u00e9gera le tube de mise \u00e0 l&rsquo;air libre contre les infiltrations d&rsquo;eau. Des produits d\u00e9shydratants rechargeables peuvent \u00e9galement \u00eatre utilis\u00e9s pour emp\u00eacher l&rsquo;accumulation d&rsquo;humidit\u00e9 dans la bo\u00eete de jonction et le tube d&rsquo;a\u00e9ration.<\/p>\n<h2>Choix d&rsquo;un capteur de pression ? Demandez \u00e0 un expert.<\/h2>\n<p>\nAvec tant de facteurs \u00e0 prendre en consid\u00e9ration, il peut \u00eatre difficile de d\u00e9terminer quel transducteur ou transmetteur de pression acheter. <br \/>\nC&rsquo;est pourquoi WIKA encourage ses clients potentiels et actuels \u00e0 contacter nos sp\u00e9cialistes pour toute question concernant la fiabilit\u00e9, la performance, la dur\u00e9e de vie et l&rsquo;ad\u00e9quation des capteurs de pression \u00e0 leur application particuli\u00e8re. Car la pr\u00e9vention des d\u00e9faillances des capteurs de pression commence par le choix des bons produits.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La p\u00e9n\u00e9tration d&rsquo;humidit\u00e9 est l&rsquo;une des causes les plus courantes de d\u00e9faillance des capteurs de pression. Pour \u00e9viter cette situation, il faut choisir un transducteur ou un transmetteur de pression dont l&rsquo;indice de protection IP, la r\u00e9f\u00e9rence de mesure et la connexion \u00e9lectrique sont adapt\u00e9s. La sortie de votre transmetteur de pression d\u00e9rive ou l&rsquo;ensemble [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":10048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,5],"tags":[77,562,428],"class_list":["post-10049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-savoir-faire","tag-capteur-pression","tag-capteur-de-pression-immergeable","tag-machines-mobiles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protection des capteurs de pression contre l&#039;humidit\u00e9 et l&#039;eau - Blog WIKA<\/title>\n<meta name=\"description\" content=\"La p\u00e9n\u00e9tration d&#039;humidit\u00e9 est l&#039;une des causes les plus courantes de d\u00e9faillance des capteurs de pression. Comment \u00e9viter cette situation ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protection des capteurs de pression contre l&#039;humidit\u00e9 et l&#039;eau - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La p\u00e9n\u00e9tration d&#039;humidit\u00e9 est l&#039;une des causes les plus courantes de d\u00e9faillance des capteurs de pression. Comment \u00e9viter cette situation ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2023\/05\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"L&rsquo;importance de la protection des capteurs de pression contre l&rsquo;humidit\u00e9 et l&rsquo;eau\",\"datePublished\":\"2023-05-15T09:30:35+00:00\",\"dateModified\":\"2023-11-16T06:55:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/\"},\"wordCount\":1371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/05\\\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg\",\"keywords\":[\"Capteur de pression\",\"capteur de pression immergeable\",\"machines mobiles\"],\"articleSection\":[\"G\u00e9n\u00e9ral\",\"Savoir-faire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/\",\"name\":\"Protection des capteurs de pression contre l'humidit\u00e9 et l'eau - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/05\\\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg\",\"datePublished\":\"2023-05-15T09:30:35+00:00\",\"dateModified\":\"2023-11-16T06:55:17+00:00\",\"description\":\"La p\u00e9n\u00e9tration d'humidit\u00e9 est l'une des causes les plus courantes de d\u00e9faillance des capteurs de pression. Comment \u00e9viter cette situation ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/05\\\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/05\\\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg\",\"width\":838,\"height\":471,\"caption\":\"pharmaceutical medicine industrial washer cleaning and drying machine for powder drugs glassware bottles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;importance de la protection des capteurs de pression contre l&rsquo;humidit\u00e9 et l&rsquo;eau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protection des capteurs de pression contre l'humidit\u00e9 et l'eau - Blog WIKA","description":"La p\u00e9n\u00e9tration d'humidit\u00e9 est l'une des causes les plus courantes de d\u00e9faillance des capteurs de pression. Comment \u00e9viter cette situation ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/","og_locale":"fr_FR","og_type":"article","og_title":"Protection des capteurs de pression contre l'humidit\u00e9 et l'eau - Blog WIKA","og_description":"La p\u00e9n\u00e9tration d'humidit\u00e9 est l'une des causes les plus courantes de d\u00e9faillance des capteurs de pression. Comment \u00e9viter cette situation ?","og_url":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2023\/05\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"L&rsquo;importance de la protection des capteurs de pression contre l&rsquo;humidit\u00e9 et l&rsquo;eau","datePublished":"2023-05-15T09:30:35+00:00","dateModified":"2023-11-16T06:55:17+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/"},"wordCount":1371,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/05\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg","keywords":["Capteur de pression","capteur de pression immergeable","machines mobiles"],"articleSection":["G\u00e9n\u00e9ral","Savoir-faire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/","url":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/","name":"Protection des capteurs de pression contre l'humidit\u00e9 et l'eau - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/05\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg","datePublished":"2023-05-15T09:30:35+00:00","dateModified":"2023-11-16T06:55:17+00:00","description":"La p\u00e9n\u00e9tration d'humidit\u00e9 est l'une des causes les plus courantes de d\u00e9faillance des capteurs de pression. Comment \u00e9viter cette situation ?","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/05\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/05\/w23-20-protecting-pressure-sensors-from-moisture_shutterstock_314497964.jpg","width":838,"height":471,"caption":"pharmaceutical medicine industrial washer cleaning and drying machine for powder drugs glassware bottles"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/general\/l-importance-de-la-protection-des-capteurs-de-pression-contre-l-humidite-et-l-eau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;importance de la protection des capteurs de pression contre l&rsquo;humidit\u00e9 et l&rsquo;eau"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/10049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=10049"}],"version-history":[{"count":6,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/10049\/revisions"}],"predecessor-version":[{"id":11148,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/10049\/revisions\/11148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/10048"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=10049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=10049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=10049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}