{"id":10112,"date":"2023-07-17T08:00:35","date_gmt":"2023-07-17T06:00:35","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=10112"},"modified":"2023-11-16T10:39:33","modified_gmt":"2023-11-16T09:39:33","slug":"technologies-de-mesure-pour-une-economie-de-l-hydrogene","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/","title":{"rendered":"Technologies de mesure pour une \u00e9conomie de l&rsquo;hydrog\u00e8ne"},"content":{"rendered":"<p><strong>La perm\u00e9ation et la fragilisation sont des probl\u00e8mes qui emp\u00eachent de r\u00e9aliser une infrastructure hydrog\u00e8ne viable et mature. Pour les capteurs de pression et de temp\u00e9rature, l&rsquo;utilisation de mat\u00e9riaux qui prot\u00e8gent contre ces conditions est la cl\u00e9 de la s\u00e9curit\u00e9 et de la rentabilit\u00e9 dans l&rsquo;industrie chimique.<\/strong><\/p>\n<p>\nL&rsquo;hydrog\u00e8ne mol\u00e9culaire (H<sub>2<\/sub>) peut traverser la plupart des mat\u00e9riaux non m\u00e9talliques. Et lorsque le dihydrog\u00e8ne entre en contact avec des surfaces m\u00e9talliques, il faut relativement peu d&rsquo;\u00e9nergie &#8211; m\u00eame dans des conditions ambiantes &#8211; pour dissocier le gaz en sa forme atomique, puis en ions qui peuvent si facilement p\u00e9n\u00e9trer la structure du r\u00e9seau de la plupart des m\u00e9taux.<\/p>\n<p>Plus l&rsquo;\u00e9nergie dans l&rsquo;environnement est \u00e9lev\u00e9e, comme les temp\u00e9ratures et les pressions de process extr\u00eames, plus la perm\u00e9ation et la fragilisation se produiront rapidement dans les cuves de stockage et les pipelines.<\/p>\n<p>Les instruments de mesure sont \u00e9galement confront\u00e9s aux m\u00eames probl\u00e8mes, entra\u00eenant une d\u00e9rive du signal et une d\u00e9faillance m\u00e9canique. Heureusement, il existe des moyens de surmonter ces d\u00e9fis.<\/p>\n<h2>Mat\u00e9riaux qui r\u00e9sistent \u00e0 la perm\u00e9ation et \u00e0 la fragilisation<\/h2>\n<p>\nLes instruments de mesure utilis\u00e9s dans un environnement d&rsquo;hydrog\u00e8ne doivent \u00eatre fabriqu\u00e9s avec des m\u00e9taux qui ont un agencement de cellules tr\u00e8s serr\u00e9es. <br \/>\nIls comprennent le 316L (acier inoxydable 316 \u00e0 faible teneur en carbone), le 316Ti (version stabilis\u00e9e au titane du 316) et d&rsquo;autres aciers aust\u00e9nitiques, id\u00e9aux pour les environnements hautement corrosifs et \u00e0 haute temp\u00e9rature. Les alliages sp\u00e9ciaux tels que l&rsquo;Hastelloy C276, l&rsquo;Inconel 718 ou le 2.4711 (Elgiloy\u00ae) sont \u00e9galement bien adapt\u00e9s aux applications hydrog\u00e8ne.<\/p>\n<h2>Des rev\u00eatements qui r\u00e9sistent \u00e0 la perm\u00e9ation de l&rsquo;hydrog\u00e8ne<\/h2>\n<p>\nPour une meilleure r\u00e9sistance \u00e0 la perm\u00e9ation de l&rsquo;hydrog\u00e8ne, l&rsquo;acier aust\u00e9nitique ou l&rsquo;alliage sp\u00e9cial peut \u00eatre rev\u00eatu d&rsquo;une barri\u00e8re m\u00e9tallique. Le nickel, l&rsquo;aluminium et le cuivre pr\u00e9sentent une faible perm\u00e9abilit\u00e9 \u00e0 l&rsquo;hydrog\u00e8ne, mais l&rsquo;or est de loin le m\u00e9tal qui r\u00e9siste le mieux \u00e0 la perm\u00e9abilit\u00e9, m\u00eame \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es.<\/p>\n<h2>Instruments qui minimisent les fuites de H<sub>2<\/sub><\/h2>\n<p>\nLes joints des manom\u00e8tres sont des zones o\u00f9 l&rsquo;hydrog\u00e8ne peut s&rsquo;\u00e9chapper. Pour cette raison, les manom\u00e8tres utilis\u00e9s dans les applications d&rsquo;hydrog\u00e8ne doivent avoir un joint m\u00e9tallique plut\u00f4t qu&rsquo;un joint en polym\u00e8re ordinaire. Une conception enti\u00e8rement soud\u00e9e emp\u00eache \u00e9galement les fuites. De plus, choisissez des instruments de mesure de pression qui ont subi un test de fuite \u00e0 l&rsquo;h\u00e9lium dans le cadre de leur process d&rsquo;assurance qualit\u00e9.<\/p>\n<h2>Instruments qui r\u00e9sistent aux conditions de process extr\u00eames<\/h2>\n<p>\nDans les stations de ravitaillement en hydrog\u00e8ne, le gaz est stock\u00e9 \u00e0 des pressions pouvant atteindre 1050 bar. Et pour l&rsquo;hydrog\u00e8ne liquide, les solutions de mesure de la temp\u00e9rature doivent maintenir leur pr\u00e9cision \u00e0 ou en dessous de \u2212253 \u00b0C.<\/p>\n<h2>WIKA, Smart in Sensing pour l&rsquo;industrie chimique<\/h2>\n<p>\nPour des raisons de s\u00e9curit\u00e9 et de performance, les applications hydrog\u00e8ne n\u00e9cessitent des instruments de mesure con\u00e7us pour r\u00e9pondre \u00e0 des conditions extr\u00eames, et des sp\u00e9cialistes poss\u00e9dant des ann\u00e9es d&rsquo;expertise chimique et d&rsquo;exp\u00e9rience industrielle.<\/p>\n<p>Leader mondial dans le domaine des solutions de mesure hautes performances, WIKA est un partenaire \u00e9prouv\u00e9 pour les entreprises qui produisent, transportent et utilisent de l&rsquo;hydrog\u00e8ne. <br \/>\nDes stations de compression et de remplissage d&rsquo;hydrog\u00e8ne aux piles \u00e0 combustible mobiles et stationnaires, WIKA propose des instruments de qualit\u00e9 pour l&rsquo;ensemble de la cha\u00eene de valeur de l&rsquo;industrie, que le H<sub>2<\/sub> soit produit de mani\u00e8re conventionnelle ou avec des ressources renouvelables.<\/p>\n<p>Rendez-vous sur notre site internet pour voir l&rsquo;ensemble de notre portefeuille de<a href=\"https:\/\/www.wika.com\/fr-fr\/hydrogene.WIKA\" rel=\"external\" target=\"_blank\"> solutions de mesure optimis\u00e9es pour l&rsquo;hydrog\u00e8ne<\/a>. Nous vous invitons \u00e9galement \u00e0 <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">contacter nos experts<\/a> pour plus d&rsquo;informations et des conseils personnalis\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La perm\u00e9ation et la fragilisation sont des probl\u00e8mes qui emp\u00eachent de r\u00e9aliser une infrastructure hydrog\u00e8ne viable et mature. Pour les capteurs de pression et de temp\u00e9rature, l&rsquo;utilisation de mat\u00e9riaux qui prot\u00e8gent contre ces conditions est la cl\u00e9 de la s\u00e9curit\u00e9 et de la rentabilit\u00e9 dans l&rsquo;industrie chimique. L&rsquo;hydrog\u00e8ne mol\u00e9culaire (H2) peut traverser la plupart des [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":10104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232,1],"tags":[286,416,394,396],"class_list":["post-10112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","category-general","tag-chimie","tag-hydrogne","tag-mesure-de-pression","tag-mesure-de-temprature"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Technologies de mesure pour une \u00e9conomie de l&#039;hydrog\u00e8ne - Blog WIKA<\/title>\n<meta name=\"description\" content=\"La perm\u00e9ation et la fragilisation sont des probl\u00e8mes qui emp\u00eachent de r\u00e9aliser une infrastructure hydrog\u00e8ne viable et mature.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technologies de mesure pour une \u00e9conomie de l&#039;hydrog\u00e8ne - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La perm\u00e9ation et la fragilisation sont des probl\u00e8mes qui emp\u00eachent de r\u00e9aliser une infrastructure hydrog\u00e8ne viable et mature.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2023\/07\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Technologies de mesure pour une \u00e9conomie de l&rsquo;hydrog\u00e8ne\",\"datePublished\":\"2023-07-17T06:00:35+00:00\",\"dateModified\":\"2023-11-16T09:39:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/\"},\"wordCount\":705,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/07\\\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg\",\"keywords\":[\"Chimie\",\"hydrog\u00e8ne\",\"mesure de pression\",\"mesure de temp\u00e9rature\"],\"articleSection\":[\"Applications\",\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/\",\"name\":\"Technologies de mesure pour une \u00e9conomie de l'hydrog\u00e8ne - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/07\\\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg\",\"datePublished\":\"2023-07-17T06:00:35+00:00\",\"dateModified\":\"2023-11-16T09:39:33+00:00\",\"description\":\"La perm\u00e9ation et la fragilisation sont des probl\u00e8mes qui emp\u00eachent de r\u00e9aliser une infrastructure hydrog\u00e8ne viable et mature.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/07\\\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/07\\\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg\",\"width\":838,\"height\":471,\"caption\":\"Abstract transparent hydrogen H2 molecules on blue background, clean energy or chemistry concept, 3D illustration\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technologies de mesure pour une \u00e9conomie de l&rsquo;hydrog\u00e8ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Technologies de mesure pour une \u00e9conomie de l'hydrog\u00e8ne - Blog WIKA","description":"La perm\u00e9ation et la fragilisation sont des probl\u00e8mes qui emp\u00eachent de r\u00e9aliser une infrastructure hydrog\u00e8ne viable et mature.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/","og_locale":"fr_FR","og_type":"article","og_title":"Technologies de mesure pour une \u00e9conomie de l'hydrog\u00e8ne - Blog WIKA","og_description":"La perm\u00e9ation et la fragilisation sont des probl\u00e8mes qui emp\u00eachent de r\u00e9aliser une infrastructure hydrog\u00e8ne viable et mature.","og_url":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2023\/07\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Technologies de mesure pour une \u00e9conomie de l&rsquo;hydrog\u00e8ne","datePublished":"2023-07-17T06:00:35+00:00","dateModified":"2023-11-16T09:39:33+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/"},"wordCount":705,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/07\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg","keywords":["Chimie","hydrog\u00e8ne","mesure de pression","mesure de temp\u00e9rature"],"articleSection":["Applications","G\u00e9n\u00e9ral"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/","url":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/","name":"Technologies de mesure pour une \u00e9conomie de l'hydrog\u00e8ne - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/07\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg","datePublished":"2023-07-17T06:00:35+00:00","dateModified":"2023-11-16T09:39:33+00:00","description":"La perm\u00e9ation et la fragilisation sont des probl\u00e8mes qui emp\u00eachent de r\u00e9aliser une infrastructure hydrog\u00e8ne viable et mature.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/07\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/07\/w23-29-hydrogen-permeation_shutterstock_1983187967.jpg","width":838,"height":471,"caption":"Abstract transparent hydrogen H2 molecules on blue background, clean energy or chemistry concept, 3D illustration"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/general\/technologies-de-mesure-pour-une-economie-de-l-hydrogene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Technologies de mesure pour une \u00e9conomie de l&rsquo;hydrog\u00e8ne"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/10112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=10112"}],"version-history":[{"count":3,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/10112\/revisions"}],"predecessor-version":[{"id":11206,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/10112\/revisions\/11206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/10104"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=10112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=10112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=10112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}