{"id":11040,"date":"2023-08-28T08:00:32","date_gmt":"2023-08-28T06:00:32","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=11040"},"modified":"2023-11-16T11:57:34","modified_gmt":"2023-11-16T10:57:34","slug":"nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/","title":{"rendered":"Nouveau logiciel en ligne de calcul de stress des doigts de gant par WIKA"},"content":{"rendered":"<p><strong>Deux logiciel gratuits pour le calcul de stress &#8211; une version simplifi\u00e9e et une version compl\u00e8te &#8211; ont \u00e9t\u00e9 mis en ligne par WIKA pour faciliter la d\u00e9termination des diam\u00e8tres, longueurs, \u00e9paisseurs et des mat\u00e9riaux des doigts de gant.<\/strong><\/p>\n<p><a href=\"https:\/\/www.wika.com\/fr-fr\/doigts_de_gant_tubes_de_protection.WIKA\" rel=\"external\" target=\"_blank\">Les doigts de gant<\/a> sont des accessoires importants qui prot\u00e8gent les sondes de temp\u00e9rature sensibles des fluides abrasifs ou corrosifs, de la haute pression et d&rsquo;autres conditions d\u00e9favorables qui endommageraient <a href=\"https:\/\/www.wika.com\/fr-fr\/thermocouples.WIKA\" rel=\"external\" target=\"_blank\">les thermocouples<\/a>, <a href=\"https:\/\/www.wika.com\/fr-fr\/thermometres_a_cadran.WIKA\" rel=\"external\" target=\"_blank\">les thermom\u00e8tres \u00e0 cadran<\/a> ou <a href=\"https:\/\/www.wika.com\/fr-fr\/sondes_a_resistance.WIKA\" rel=\"external\" target=\"_blank\">les sondes \u00e0 r\u00e9sistance (RTD)<\/a>.<\/p>\n<p>Comme ces dispositifs de protection sont install\u00e9s dans des tuyauteries, o\u00f9 le fluide peut s&rsquo;\u00e9couler \u00e0 grande vitesse, les plongeurs ou gaines doivent avoir une longueur, un diam\u00e8tre de racine et un diam\u00e8tre d&rsquo;extr\u00e9mit\u00e9 corrects pour \u00e9viter la formation de tourbillons induits par le sillage qui cr\u00e9ent des vibrations et provoquent une fatigue m\u00e9canique.<\/p>\n<h2>L&rsquo;importance du calcul de stress<\/h2>\n<p>\nLes fabricants de capteurs proposent des calculateurs de stress (WFC = Wake Frequency Calculation) pour aider les clients \u00e0 d\u00e9terminer les dimensions id\u00e9ales et les autres exigences des doigts de gant pour des applications sp\u00e9cifiques. <br \/>\nChaque calculateur est l\u00e9g\u00e8rement diff\u00e9rent, mais en g\u00e9n\u00e9ral, cet outil demande \u00e0 l&rsquo;utilisateur de saisir des informations sur le process (pression, densit\u00e9, vitesse, etc.) et sur le doigt de gant (longueur d&rsquo;insertion, mat\u00e9riau, diam\u00e8tres, etc.). <span style=\"font-size: 1rem\">\u00c0 l&rsquo;aide de ces donn\u00e9es, le logiciel d\u00e9termine si le doigt de gant est adapt\u00e9 aux conditions du process.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>L&rsquo;objectif est de concevoir un doigt de gant qui ne subira aucun dommage dans une application particuli\u00e8re. <br \/>\nSi les sp\u00e9cifications ne satisfont pas aux calculs de s\u00e9curit\u00e9, l&rsquo;utilisateur peut affiner les dimensions, le style du plongeur, etc. jusqu&rsquo;\u00e0 ce que les r\u00e9sultats se situent dans des limites acceptables.<\/p>\n<p>&nbsp;<\/p>\n<h2>Logiciel de calcul de stress WIKA<\/h2>\n<p>\nPendant plus de deux d\u00e9cennies, le logiciel WFC de WIKA \u00e9tait bas\u00e9 sur des macros VBA dans Excel. Nos clients dans le monde entier ont utilis\u00e9 cet outil pour concevoir leurs doigts de gant, et chaque nouvelle version de ce programme a ajout\u00e9 des fonctionnalit\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>Les applications bas\u00e9es sur VBA ont bien fonctionn\u00e9 pendant de nombreuses ann\u00e9es. Mais des probl\u00e8mes ont commenc\u00e9 \u00e0 appara\u00eetre, tels que l&rsquo;incompatibilit\u00e9 croissante avec les nouvelles versions de Windows et l&rsquo;inqui\u00e9tude de nombreuses entreprises quant \u00e0 la s\u00e9curit\u00e9 des logiciels tiers.<br \/>\n<span style=\"font-size: 1rem\">En bref, il \u00e9tait temps de proc\u00e9der \u00e0 une mise \u00e0 jour.<\/span><\/p>\n<p>Les ing\u00e9nieurs et programmeurs de WIKA ont cr\u00e9\u00e9 une solution en ligne avec tous les attributs de la version Excel originale, mais avec plusieurs fonctionnalit\u00e9s suppl\u00e9mentaires et la commodit\u00e9 d&rsquo;une application bas\u00e9e sur un navigateur. <br \/>\n<a href=\"https:\/\/www.wika.com\/fr-fr\/logiciels.WIKA\" rel=\"external\" target=\"_blank\">Notre logiciel de calcul de stress des doigts de gant<\/a>, gratuit et bas\u00e9 sur le web pour les ordinateurs portables et de bureau, est facile \u00e0 utiliser mais puissant, et se d\u00e9cline en deux variantes.<\/p>\n<h2>Calcul unique<\/h2>\n<p>\nLa version simplifi\u00e9e mais enti\u00e8rement fonctionnelle calcule l&rsquo;ad\u00e9quation d&rsquo;un seul doigt de gant conform\u00e9ment \u00e0 la norme ASME PTC 19.3 TW-2016. Apr\u00e8s avoir saisi les donn\u00e9es requises pour le process et le doigt de gant, cliquez sur le bouton \u00ab\u00a0Calculer\u00a0\u00bb pour afficher tous les r\u00e9sultats les plus importants (les informations affich\u00e9es sont exactement les m\u00eames que dans l&rsquo;ancienne version Excel). <br \/>\nLes r\u00e9sultats dynamiques comprennent le rapport de fr\u00e9quence ainsi que le facteur de s\u00e9curit\u00e9 pour la contrainte de fatigue par flexion, tandis que les r\u00e9sultats statiques sont les facteurs de s\u00e9curit\u00e9 pour la contrainte de flexion et la charge de pression sur le doigt de gant.<\/p>\n<p>&nbsp;<\/p>\n\n      <div class=\"wp-caption alignnone\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2023\/08\/w23-35-1-wfc_fig-1-388x197-1.png\" \/><p class=\"wp-caption-text\">Logiciel de calcul de stress, calcul unique<\/p><\/div>\n    \n<p>&nbsp;<\/p>\n<p>Le doigt de gant est \u00e9galement repr\u00e9sent\u00e9 en 3D avec toutes les dimensions propos\u00e9es. Pour sauvegarder et partager les r\u00e9sultats, il suffit de cliquer sur le bouton \u00ab\u00a0PDF\u00a0\u00bb pour les t\u00e9l\u00e9charger. Le PDF d&rsquo;une page comprend \u00e9galement des r\u00e9sultats qui ne figurent pas sur la page web, tels que le nombre de Strouhal, les fr\u00e9quences de Strouhal et de r\u00e9sonance, la charge de pression maximale admissible, le nombre de Scruton et le nombre de Reynolds. <br \/>\nNotez que cette version simplifi\u00e9e propose les mat\u00e9riaux et les r\u00e9sultats de calcul les plus courants.<\/p>\n<p>&nbsp;<\/p>\n<h2>Calculs multiples<\/h2>\n<p>\nLa version compl\u00e8te du logiciel poss\u00e8de le m\u00eame algorithme et les m\u00eames fonctionnalit\u00e9s que la version simplifi\u00e9e, mais permet aux utilisateurs de calculer un nombre presque illimit\u00e9 de doigts de gant. Voici les \u00e9tapes \u00e0 suivre :<\/p>\n<ol>\n<li>Enregistrez-vous et v\u00e9rifiez votre compte.<\/li>\n<li>Saisir les donn\u00e9es du doigt de gant directement dans le formulaire de calcul de la page web, ou utiliser une feuille de calcul avec toutes les donn\u00e9es de process et les donn\u00e9es du doigt de gant demand\u00e9es dans le m\u00eame ordre que le logiciel en ligne. Si vous utilisez une feuille de calcul, copiez les donn\u00e9es puis collez-les dans le logiciel.<\/li>\n<li>Les calculs sont effectu\u00e9s automatiquement lors de la saisie et affich\u00e9s dans un tableau avec la mention \u00ab\u00a0r\u00e9ussi\u00a0\u00bb (= \u00ab passed \u00bb) ou \u00ab\u00a0\u00e9chou\u00e9\u00a0\u00bb (= failed) et toutes les donn\u00e9es et calculs.<\/li>\n<li>Les calculs sont stock\u00e9s dans le compte de l&rsquo;utilisateur, avec la possibilit\u00e9 de g\u00e9n\u00e9rer un PDF pour chaque doigt de gant ou d&rsquo;exporter l&rsquo;ensemble du tableau sous forme de fichier Excel.<\/li>\n<\/ol>\n\n      <div class=\"wp-caption alignnone\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2023\/08\/w23-35-2-wfc_fig-3-838x471-1-388x218.png\" \/><p class=\"wp-caption-text\">Logiciel de calcul de stress, calculs multiples<\/p><\/div>\n    \n<p>&nbsp;<\/p>\n<h2>Des fonctionnalit\u00e9s puissantes<\/h2>\n<p>\nLa version compl\u00e8te du logiciel WFC offre de nombreuses options :<\/p>\n<ul>\n<li>Toutes les conceptions de plongeurs\/gaines relevant de la norme ASME PTC 19.3 TW-2016 (conique, droite, \u00e9tag\u00e9e) peuvent \u00eatre calcul\u00e9es en combinaison avec n&rsquo;importe quel type de raccord (\u00e0 bride, filet\u00e9, soud\u00e9, Vanstone).<\/li>\n<li>Les utilisateurs peuvent s\u00e9lectionner les unit\u00e9s m\u00e9triques ou imp\u00e9riales, ou un m\u00e9lange des deux.<\/li>\n<li>La base de donn\u00e9es contient plus de 60 mat\u00e9riaux dont les donn\u00e9es sont stock\u00e9es conform\u00e9ment \u00e0 l&rsquo;ASME BPVC Section II Part D, et nous en ajoutons d&rsquo;autres sur demande. Comme pour la version \u00e0 calcul unique, les utilisateurs peuvent s\u00e9lectionner le mat\u00e9riau en fonction de sa d\u00e9signation ASTM, de son num\u00e9ro UNS, de son num\u00e9ro DIN ou de sa d\u00e9signation internationale standard.<\/li>\n<li>La fonction de survol (mouseover) affiche des informations utiles, telles qu&rsquo;un texte explicatif et une description d\u00e9taill\u00e9e des fonctionnalit\u00e9s du logiciel.<\/li>\n<li>Lorsque des valeurs d&rsquo;entr\u00e9e sont en dehors des sp\u00e9cifications de conception ASME PTC 19.3, elles apparaissent sur un fond ombr\u00e9.<\/li>\n<li>Si le calcul d&rsquo;un doigt de gant ne respecte pas les seuils de s\u00e9curit\u00e9, le programme fournit un code de remarque et recommande une longueur d&rsquo;insertion optimis\u00e9e. L&rsquo;utilisateur peut alors modifier les sp\u00e9cifications de ce doigt de gant et effectuer un nouveau calcul.<\/li>\n<\/ul>\n<h2>WIKA, Smart in sensing<\/h2>\n<p>Avec tant de variables et d&rsquo;options, le choix et la conception des doigts de gant peuvent \u00eatre un process d\u00e9courageant.<a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\"> Contactez les sp\u00e9cialistes de la temp\u00e9rature WIKA<\/a> pour obtenir une assistance dans le choix des capteurs de temp\u00e9rature et des doigts de gant adapt\u00e9s \u00e0 vos applications.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deux logiciel gratuits pour le calcul de stress &#8211; une version simplifi\u00e9e et une version compl\u00e8te &#8211; ont \u00e9t\u00e9 mis en ligne par WIKA pour faciliter la d\u00e9termination des diam\u00e8tres, longueurs, \u00e9paisseurs et des mat\u00e9riaux des doigts de gant. Les doigts de gant sont des accessoires importants qui prot\u00e8gent les sondes de temp\u00e9rature sensibles des [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":11034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232,1],"tags":[303,405],"class_list":["post-11040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","category-general","tag-doigt-de-gant","tag-mesure-de-la-temprature"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logiciel en ligne de calcul de stress des doigts de gant - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Deux logiciel gratuits pour le calcul de stress ont \u00e9t\u00e9 mis en ligne par WIKA pour faciliter la d\u00e9termination des diam\u00e8tres, longueurs, \u00e9paisseurs et des mat\u00e9riaux des doigts de gant.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logiciel en ligne de calcul de stress des doigts de gant - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Deux logiciel gratuits pour le calcul de stress ont \u00e9t\u00e9 mis en ligne par WIKA pour faciliter la d\u00e9termination des diam\u00e8tres, longueurs, \u00e9paisseurs et des mat\u00e9riaux des doigts de gant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2023\/08\/w23-35-wfc_featured-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Nouveau logiciel en ligne de calcul de stress des doigts de gant par WIKA\",\"datePublished\":\"2023-08-28T06:00:32+00:00\",\"dateModified\":\"2023-11-16T10:57:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/\"},\"wordCount\":1249,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/08\\\/w23-35-wfc_featured-image.png\",\"keywords\":[\"Doigt de gant\",\"mesure de la temp\u00e9rature\"],\"articleSection\":[\"Applications\",\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/\",\"name\":\"Logiciel en ligne de calcul de stress des doigts de gant - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/08\\\/w23-35-wfc_featured-image.png\",\"datePublished\":\"2023-08-28T06:00:32+00:00\",\"dateModified\":\"2023-11-16T10:57:34+00:00\",\"description\":\"Deux logiciel gratuits pour le calcul de stress ont \u00e9t\u00e9 mis en ligne par WIKA pour faciliter la d\u00e9termination des diam\u00e8tres, longueurs, \u00e9paisseurs et des mat\u00e9riaux des doigts de gant.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/08\\\/w23-35-wfc_featured-image.png\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/08\\\/w23-35-wfc_featured-image.png\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouveau logiciel en ligne de calcul de stress des doigts de gant par WIKA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logiciel en ligne de calcul de stress des doigts de gant - Blog WIKA","description":"Deux logiciel gratuits pour le calcul de stress ont \u00e9t\u00e9 mis en ligne par WIKA pour faciliter la d\u00e9termination des diam\u00e8tres, longueurs, \u00e9paisseurs et des mat\u00e9riaux des doigts de gant.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/","og_locale":"fr_FR","og_type":"article","og_title":"Logiciel en ligne de calcul de stress des doigts de gant - Blog WIKA","og_description":"Deux logiciel gratuits pour le calcul de stress ont \u00e9t\u00e9 mis en ligne par WIKA pour faciliter la d\u00e9termination des diam\u00e8tres, longueurs, \u00e9paisseurs et des mat\u00e9riaux des doigts de gant.","og_url":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2023\/08\/w23-35-wfc_featured-image.png","type":"image\/png"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Nouveau logiciel en ligne de calcul de stress des doigts de gant par WIKA","datePublished":"2023-08-28T06:00:32+00:00","dateModified":"2023-11-16T10:57:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/"},"wordCount":1249,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/08\/w23-35-wfc_featured-image.png","keywords":["Doigt de gant","mesure de la temp\u00e9rature"],"articleSection":["Applications","G\u00e9n\u00e9ral"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/","url":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/","name":"Logiciel en ligne de calcul de stress des doigts de gant - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/08\/w23-35-wfc_featured-image.png","datePublished":"2023-08-28T06:00:32+00:00","dateModified":"2023-11-16T10:57:34+00:00","description":"Deux logiciel gratuits pour le calcul de stress ont \u00e9t\u00e9 mis en ligne par WIKA pour faciliter la d\u00e9termination des diam\u00e8tres, longueurs, \u00e9paisseurs et des mat\u00e9riaux des doigts de gant.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/08\/w23-35-wfc_featured-image.png","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/08\/w23-35-wfc_featured-image.png","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/nouveau-logiciel-en-ligne-de-calcul-de-stress-des-doigts-de-gant-par-wika\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouveau logiciel en ligne de calcul de stress des doigts de gant par WIKA"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=11040"}],"version-history":[{"count":5,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11040\/revisions"}],"predecessor-version":[{"id":11235,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11040\/revisions\/11235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/11034"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=11040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=11040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=11040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}