{"id":11051,"date":"2023-09-11T17:17:23","date_gmt":"2023-09-11T15:17:23","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=11051"},"modified":"2023-11-16T11:31:38","modified_gmt":"2023-11-16T10:31:38","slug":"securisez-vos-silos-alimentaires-avec-des-pressostats","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/","title":{"rendered":"S\u00e9curisez vos silos alimentaires avec des pressostats"},"content":{"rendered":"<p><strong>Les pressostats utilis\u00e9s dans les silos alimentaires contribuent de mani\u00e8re significative \u00e0 la d\u00e9tection \u00e0 temps des surpressions et \u00e0 leur pr\u00e9vention en toute s\u00e9curit\u00e9. Un fabricant de ces cuves utilise le pressostat m\u00e9canique MA pour cette t\u00e2che. <br \/>\nUne caract\u00e9ristique particuli\u00e8re a fait pencher la balance en faveur de cet instrument antid\u00e9flagrant : il est \u00e9galement homologu\u00e9 pour les applications en milieu poussi\u00e9reux.<\/strong><\/p>\n<h2>Outre la surpression, il existe \u00e9galement un risque d&rsquo;explosion d\u00fb \u00e0 la formation de poussi\u00e8re<\/h2>\n<p>\nLes silos alimentaires du client contiennent des produits en vrac, principalement du lait en poudre, de la farine et du sucre. Une surpression peut se former lors du remplissage pneumatique, ce qui met en p\u00e9ril la s\u00e9curit\u00e9 du silo et donc des personnes et de l&rsquo;environnement. La pr\u00e9sence de poussi\u00e8res hautement inflammables peut aggraver le risque d&rsquo;explosion. Le potentiel de risque est donc important et n\u00e9cessite des mesures appropri\u00e9es.<\/p>\n<p>Le client de WIKA a donc install\u00e9 un syst\u00e8me de s\u00e9curit\u00e9 complexe pour prot\u00e9ger ses silos alimentaires contre les surpressions. Le pressostat mod\u00e8le MA assume une fonction centrale : Il surveille le profil de pression dans les silos et active une vanne lorsque la valeur limite d\u00e9finie est d\u00e9pass\u00e9e, ce qui lib\u00e8re la surpression.<\/p>\n<h2>Pressostat robuste pour les applications critiques en termes de s\u00e9curit\u00e9, notamment dans les silos alimentaires<\/h2>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2023\/09\/w23-37-1-textbild_lebensmittelsilo_ma_2.jpg\" \/><p class=\"wp-caption-text\">Le pressostat mod\u00e8le MA convient \u00e9galement aux environnements poussi\u00e9reux tels que les silos alimentaires.<\/p><\/div>\n    \n<p>Le <a href=\"https:\/\/www.wika.com\/fr-fr\/ma.WIKA?ProductGroup=70899\" rel=\"external\" target=\"_blank\">pressostat mod\u00e8le MA<\/a> est pr\u00e9destin\u00e9 aux applications critiques en mati\u00e8re de s\u00e9curit\u00e9, telles que les silos alimentaires. En tant qu&rsquo;instrument m\u00e9canique, il fonctionne sans alimentation auxiliaire. Il est \u00e9quip\u00e9 d&rsquo;un ou deux microrupteurs actionn\u00e9s par un joint antid\u00e9flagrant.<\/p>\n<p>Le client a \u00e9galement choisi ce pressostat pour sa robustesse. Le bo\u00eetier est en alliage d&rsquo;aluminium et peut r\u00e9sister \u00e0 des pressions jusqu&rsquo;\u00e0 600 bar. Le mod\u00e8le MA est homologu\u00e9 IECEx ou ATEX et est con\u00e7u conform\u00e9ment au type de protection Ex d (bo\u00eetier antid\u00e9flagrant). Il peut \u00eatre utilis\u00e9 dans des environnements gazeux et poussi\u00e9reux. Ce pressostat est \u00e9galement disponible en versions SIL 2 et SIL 3.<\/p>\n<p>\n<strong>Remarque<\/strong><br \/>\nDe plus amples informations techniques sur le pressostat mod\u00e8le MA sont disponibles sur le <a href=\"https:\/\/www.wika.com\/fr-fr\/page_d_accueil.WIKA\" rel=\"external\" target=\"_blank\">site Internet WIKA<\/a>. Nous y pr\u00e9sentons \u00e9galement d&rsquo;autres produits et solutions pour <a href=\"https:\/\/www.wika.com\/fr-fr\/agroalimentaire.WIKA?tab=3\" rel=\"external\" target=\"_blank\">l&rsquo;industrie agro-alimentaire<\/a>.<\/p>\n<p>Si vous avez des questions, <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">votre contact<\/a> se fera un plaisir de vous aider.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les pressostats utilis\u00e9s dans les silos alimentaires contribuent de mani\u00e8re significative \u00e0 la d\u00e9tection \u00e0 temps des surpressions et \u00e0 leur pr\u00e9vention en toute s\u00e9curit\u00e9. Un fabricant de ces cuves utilise le pressostat m\u00e9canique MA pour cette t\u00e2che. Une caract\u00e9ristique particuli\u00e8re a fait pencher la balance en faveur de cet instrument antid\u00e9flagrant : il est [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":11050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232,1],"tags":[542,401,79,565,262],"class_list":["post-11051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","category-general","tag-industrie-agroalimentaire","tag-pression","tag-pressostat","tag-process-de-scurit","tag-securite-fonctionnelle-sil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9curisez vos silos alimentaires avec des pressostats - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Les pressostats utilis\u00e9s dans les silos alimentaires contribuent \u00e0 la d\u00e9tection \u00e0 temps des surpressions et \u00e0 leur pr\u00e9vention en toute s\u00e9curit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9curisez vos silos alimentaires avec des pressostats - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Les pressostats utilis\u00e9s dans les silos alimentaires contribuent \u00e0 la d\u00e9tection \u00e0 temps des surpressions et \u00e0 leur pr\u00e9vention en toute s\u00e9curit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2023\/09\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"S\u00e9curisez vos silos alimentaires avec des pressostats\",\"datePublished\":\"2023-09-11T15:17:23+00:00\",\"dateModified\":\"2023-11-16T10:31:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/\"},\"wordCount\":438,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/09\\\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg\",\"keywords\":[\"Industrie agroalimentaire\",\"pression\",\"Pressostat\",\"process de s\u00e9curit\u00e9\",\"S\u00e9curit\u00e9 fonctionnelle (SIL)\"],\"articleSection\":[\"Applications\",\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/\",\"name\":\"S\u00e9curisez vos silos alimentaires avec des pressostats - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/09\\\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg\",\"datePublished\":\"2023-09-11T15:17:23+00:00\",\"dateModified\":\"2023-11-16T10:31:38+00:00\",\"description\":\"Les pressostats utilis\u00e9s dans les silos alimentaires contribuent \u00e0 la d\u00e9tection \u00e0 temps des surpressions et \u00e0 leur pr\u00e9vention en toute s\u00e9curit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/09\\\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/09\\\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/securisez-vos-silos-alimentaires-avec-des-pressostats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9curisez vos silos alimentaires avec des pressostats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9curisez vos silos alimentaires avec des pressostats - Blog WIKA","description":"Les pressostats utilis\u00e9s dans les silos alimentaires contribuent \u00e0 la d\u00e9tection \u00e0 temps des surpressions et \u00e0 leur pr\u00e9vention en toute s\u00e9curit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9curisez vos silos alimentaires avec des pressostats - Blog WIKA","og_description":"Les pressostats utilis\u00e9s dans les silos alimentaires contribuent \u00e0 la d\u00e9tection \u00e0 temps des surpressions et \u00e0 leur pr\u00e9vention en toute s\u00e9curit\u00e9.","og_url":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2023\/09\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"S\u00e9curisez vos silos alimentaires avec des pressostats","datePublished":"2023-09-11T15:17:23+00:00","dateModified":"2023-11-16T10:31:38+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/"},"wordCount":438,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/09\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg","keywords":["Industrie agroalimentaire","pression","Pressostat","process de s\u00e9curit\u00e9","S\u00e9curit\u00e9 fonctionnelle (SIL)"],"articleSection":["Applications","G\u00e9n\u00e9ral"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/","url":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/","name":"S\u00e9curisez vos silos alimentaires avec des pressostats - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/09\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg","datePublished":"2023-09-11T15:17:23+00:00","dateModified":"2023-11-16T10:31:38+00:00","description":"Les pressostats utilis\u00e9s dans les silos alimentaires contribuent \u00e0 la d\u00e9tection \u00e0 temps des surpressions et \u00e0 leur pr\u00e9vention en toute s\u00e9curit\u00e9.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/09\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/09\/w23-37-beitragsbild_lebensmittelsilo_ma.jpg","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/general\/securisez-vos-silos-alimentaires-avec-des-pressostats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"S\u00e9curisez vos silos alimentaires avec des pressostats"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=11051"}],"version-history":[{"count":5,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11051\/revisions"}],"predecessor-version":[{"id":11223,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11051\/revisions\/11223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/11050"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=11051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=11051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=11051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}