{"id":1162,"date":"2016-03-02T08:27:25","date_gmt":"2016-03-02T07:27:25","guid":{"rendered":"http:\/\/test5.wika-blog-live.mcon.net\/?p=1162"},"modified":"2023-11-27T08:40:18","modified_gmt":"2023-11-27T07:40:18","slug":"mesure-niveau-eaux-eaux-uses-traitement","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/","title":{"rendered":"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es"},"content":{"rendered":"<p><span>La nouvelle brochure<\/span> \u00ab\u00a0<a href=\"https:\/\/www.wika.com\/media\/Brochures-and-flyers\/Industries\/br_waterwastewater_en_co.pdf\" target=\"_blank\" rel=\"noopener external\">Mesure de niveau dans <span>l&rsquo;eau<\/span> potable <span>et le traitement<\/span> <span>des eaux us\u00e9es<\/span><\/a>\u00a0\u00bb <span>offre<\/span> <span>un aper\u00e7u complet des<\/span> <span>applications typiques<\/span> <span>de mesure de niveau<\/span> <span>dans l&rsquo;industrie<\/span> <span>de l&rsquo;eau<\/span> potable <span>et des eaux us\u00e9es<\/span>.<\/p>\n<p><span>De nombreux<\/span> exemples d&rsquo;applications <span>montrent<\/span> <span>les<\/span><a href=\"https:\/\/www.wika.com\/fr-fr\/transmetteurs_de_pression_immergeables.WIKA\" target=\"_blank\" rel=\"noopener external\"> <span>transmetteurs de pression<\/span> <span>submersibles WIKA<\/span><\/a> <span>dans le contr\u00f4le<\/span> <span>et le suivi de<\/span> <span>toutes les \u00e9tapes<\/span> <span>du processus<\/span> <span>de traitement dans les r\u00e9seaux urbains<\/span>. De la mesure de niveau des eaux souterraines ou de surface, en passant par le pompage, le stockage d\u2019eau potable jusqu\u2019au traitement des eaux us\u00e9es, vous trouverez des exemples pour chaque application.<\/p>\n<p><span>Enfin<\/span>, la brochure <span>offre un guide<\/span> de choix <span>simple et<\/span> <span>clair pour les<\/span> <span>transmetteurs de pression<\/span> <span>submersibles<\/span> <span>dans les<\/span> <span>applications dans les eaux douce et potable,<\/span> <span>eaux us\u00e9es<\/span>, huiles et carburants <span>et encore<\/span> <span>fluides agressifs<\/span>. <span>Pour<\/span> <span>obtenir de l&rsquo;aide<\/span> <span>ou<\/span> <span>des conseils avis\u00e9s sur vos applications<\/span>, <span>n\u2019h\u00e9sitez pas \u00e0 utiliser<\/span> <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" target=\"_blank\" rel=\"noopener external\"><span>notre formulaire de contact<\/span><\/a>.<\/p>\n<p>&nbsp;<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2013\/05\/WIKA-level-probes-applications-838x471.jpg\" class=\"alignnone\" \/><\/figure>\n<p>&nbsp;<\/p>\n<p><span>Vous trouverez<\/span> plus d&rsquo;informations <span>sur ce sujet<\/span> <span>sur notre<\/span> <span>plateforme d&rsquo;information<\/span> <span>\u00ab\u00a0<\/span><a href=\"http:\/\/en-co.wika.de\/ms_hl_home_en_co.WIKA?utm_campaign=Hydrostatic-Level-Measurement-Microsite&amp;utm_source=wika.com&amp;utm_medium=vanityurl\" target=\"_blank\" rel=\"noopener external\">mesure <span>de niveau hydrostatique<\/span><\/a>\u00a0\u00bb\u00a0\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nouvelle brochure \u00ab\u00a0Mesure de niveau dans l&rsquo;eau potable et le traitement des eaux us\u00e9es\u00a0\u00bb offre un aper\u00e7u complet des applications typiques de mesure de niveau dans l&rsquo;industrie de l&rsquo;eau potable et des eaux us\u00e9es. De nombreux exemples d&rsquo;applications montrent les transmetteurs de pression submersibles WIKA dans le contr\u00f4le et le suivi de toutes les [&hellip;]<\/p>\n","protected":false},"author":130,"featured_media":6192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232],"tags":[253,287,101],"class_list":["post-1162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","tag-hydrostatique","tag-mesure-niveau-hydrostatique","tag-transmetteur-pression-submersible"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es - Blog WIKA<\/title>\n<meta name=\"description\" content=\"La nouvelle brochure &quot;Mesure de niveau dans l&#039;eau potable et le traitement des eaux us\u00e9es&quot; offre un aper\u00e7u complet des applications typiques de mesure de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La nouvelle brochure &quot;Mesure de niveau dans l&#039;eau potable et le traitement des eaux us\u00e9es&quot; offre un aper\u00e7u complet des applications typiques de mesure de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2013\/05\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guy Deiber\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guy Deiber\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/\"},\"author\":{\"name\":\"Guy Deiber\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/b611d106d000838b6e15567e7b56f91f\"},\"headline\":\"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es\",\"datePublished\":\"2016-03-02T07:27:25+00:00\",\"dateModified\":\"2023-11-27T07:40:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/\"},\"wordCount\":200,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2013\\\/05\\\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg\",\"keywords\":[\"Hydrostatique\",\"Mesure de niveau hydrostatique\",\"Transmetteur de pression submersible\"],\"articleSection\":[\"Applications\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/\",\"name\":\"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2013\\\/05\\\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg\",\"datePublished\":\"2016-03-02T07:27:25+00:00\",\"dateModified\":\"2023-11-27T07:40:18+00:00\",\"description\":\"La nouvelle brochure \\\"Mesure de niveau dans l'eau potable et le traitement des eaux us\u00e9es\\\" offre un aper\u00e7u complet des applications typiques de mesure de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2013\\\/05\\\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2013\\\/05\\\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-niveau-eaux-eaux-uses-traitement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/b611d106d000838b6e15567e7b56f91f\",\"name\":\"Guy Deiber\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/03\\\/g_deiber_outlook-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/03\\\/g_deiber_outlook-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/03\\\/g_deiber_outlook-140x140.jpg\",\"caption\":\"Guy Deiber\"},\"description\":\"Actif dans l\u2019instrumentation de process depuis 28 ans, dans les domaines de la mesure de niveau, pression, d\u00e9bit et ce dans diverses fonctions allant de l\u2019apr\u00e8s-vente jusqu\u2019\u00e0 l\u2019ing\u00e9nierie, j\u2019ai aujourd\u2019hui la responsabilit\u00e9 des activit\u00e9s marketing et support avant-vente chez WIKA France. N\u00e9 avec le g\u00e8ne du partage, je me fais un plaisir de vous servir mon exp\u00e9rience pour la r\u00e9ussite de vos projets.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/deiberg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es - Blog WIKA","description":"La nouvelle brochure \"Mesure de niveau dans l'eau potable et le traitement des eaux us\u00e9es\" offre un aper\u00e7u complet des applications typiques de mesure de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/","og_locale":"fr_FR","og_type":"article","og_title":"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es - Blog WIKA","og_description":"La nouvelle brochure \"Mesure de niveau dans l'eau potable et le traitement des eaux us\u00e9es\" offre un aper\u00e7u complet des applications typiques de mesure de","og_url":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2013\/05\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg","type":"image\/jpeg"}],"author":"Guy Deiber","twitter_misc":{"\u00c9crit par":"Guy Deiber","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/"},"author":{"name":"Guy Deiber","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/b611d106d000838b6e15567e7b56f91f"},"headline":"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es","datePublished":"2016-03-02T07:27:25+00:00","dateModified":"2023-11-27T07:40:18+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/"},"wordCount":200,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2013\/05\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg","keywords":["Hydrostatique","Mesure de niveau hydrostatique","Transmetteur de pression submersible"],"articleSection":["Applications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/","url":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/","name":"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2013\/05\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg","datePublished":"2016-03-02T07:27:25+00:00","dateModified":"2023-11-27T07:40:18+00:00","description":"La nouvelle brochure \"Mesure de niveau dans l'eau potable et le traitement des eaux us\u00e9es\" offre un aper\u00e7u complet des applications typiques de mesure de","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2013\/05\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2013\/05\/Cover_Flyer_Submersible-pressure-transmitter-e1432732540853.jpg","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-niveau-eaux-eaux-uses-traitement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Mesure de niveau dans la production d\u2019eau potable et traitement des eaux us\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/b611d106d000838b6e15567e7b56f91f","name":"Guy Deiber","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2016\/03\/g_deiber_outlook-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/03\/g_deiber_outlook-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/03\/g_deiber_outlook-140x140.jpg","caption":"Guy Deiber"},"description":"Actif dans l\u2019instrumentation de process depuis 28 ans, dans les domaines de la mesure de niveau, pression, d\u00e9bit et ce dans diverses fonctions allant de l\u2019apr\u00e8s-vente jusqu\u2019\u00e0 l\u2019ing\u00e9nierie, j\u2019ai aujourd\u2019hui la responsabilit\u00e9 des activit\u00e9s marketing et support avant-vente chez WIKA France. N\u00e9 avec le g\u00e8ne du partage, je me fais un plaisir de vous servir mon exp\u00e9rience pour la r\u00e9ussite de vos projets.","url":"https:\/\/blog.wika.com\/fr\/author\/deiberg\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/1162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/130"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=1162"}],"version-history":[{"count":23,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/1162\/revisions"}],"predecessor-version":[{"id":11535,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/1162\/revisions\/11535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/6192"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=1162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=1162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=1162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}