{"id":11654,"date":"2024-01-22T08:00:54","date_gmt":"2024-01-22T07:00:54","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=11654"},"modified":"2024-01-05T14:50:49","modified_gmt":"2024-01-05T13:50:49","slug":"sauver-des-lions-de-mer-grace-aux-manometres-wika","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/","title":{"rendered":"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA"},"content":{"rendered":"<p><strong>Les manom\u00e8tres WIKA remplissent une mission importante dans le cadre du sauvetage de lions de mer au Mexique &#8211; un exemple parmi d&rsquo;autres des possibilit\u00e9s d&rsquo;application des produits WIKA.<\/strong><\/p>\n<p>\nLes lions de mer habitent la p\u00e9ninsule de Basse-Californie. Leur population est toutefois menac\u00e9e par les filets de p\u00eache et les lignes de p\u00eache dans lesquels ces cr\u00e9atures peuvent se prendre. <br \/>\nM\u00eame apr\u00e8s avoir \u00e9t\u00e9 lib\u00e9r\u00e9s, ils peuvent mourir des suites des blessures qu&rsquo;ils ont subies. L&rsquo;organisation \u00ab\u00a0Rescate de Lobos Marinos\u00a0\u00bb, fond\u00e9e en 2014, s&rsquo;est donc donn\u00e9 pour objectif de venir en aide \u00e0 ces mammif\u00e8res aquatiques.<\/p>\n<p>\nEn collaboration avec des scientifiques et des b\u00e9n\u00e9voles, l&rsquo;organisation m\u00e8ne \u00e0 intervalles r\u00e9guliers des campagnes d&rsquo;identification des lions de mer et d&rsquo;aide aux animaux en mauvaise condition physique.<\/p>\n<p>Cependant, il n&rsquo;est pas facile d&rsquo;attraper les lions de mer, qui peuvent peser jusqu&rsquo;\u00e0 1 200 kilogrammes, et de les lib\u00e9rer des filets de p\u00eache. Il faut beaucoup d&rsquo;habilet\u00e9 pour les approcher et les tranquilliser. Et c&rsquo;est l\u00e0 que WIKA entre en jeu : Les manom\u00e8tres WIKA sont un \u00e9l\u00e9ment central des pistolets \u00e0 fl\u00e9chettes.<\/p>\n<p>En effet, une mesure pr\u00e9cise de la pression est n\u00e9cessaire pour doser la bonne quantit\u00e9 de dioxyde de carbone, le gaz propulseur, pour un tir efficace, en fonction de la distance par rapport \u00e0 l&rsquo;animal.<\/p>\n<p>\n<strong>Remarque<\/strong><br \/>\nVous trouverez de plus amples informations sur WIKA et les produits de notre soci\u00e9t\u00e9 sur le<a href=\"https:\/\/www.wika.com\/fr-fr\/page_d_accueil.WIKA\" rel=\"external\" target=\"_blank\"> site Internet de WIKA.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les manom\u00e8tres WIKA remplissent une mission importante dans le cadre du sauvetage de lions de mer au Mexique &#8211; un exemple parmi d&rsquo;autres des possibilit\u00e9s d&rsquo;application des produits WIKA. Les lions de mer habitent la p\u00e9ninsule de Basse-Californie. Leur population est toutefois menac\u00e9e par les filets de p\u00eache et les lignes de p\u00eache dans lesquels [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":11653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,215],"tags":[288,544,75],"class_list":["post-11654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-wika","tag-filiale","tag-instrument-de-mesure-de-pression","tag-manometre"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Les manom\u00e8tres WIKA remplissent une mission importante dans le cadre du sauvetage de lions de mer au Mexique\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Les manom\u00e8tres WIKA remplissent une mission importante dans le cadre du sauvetage de lions de mer au Mexique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2024\/01\/24-4-beitragsbild_seeloewen-projekt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Betty Pic\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Betty Pic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/\"},\"author\":{\"name\":\"Betty Pic\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/bed07f29fd632fb2c9cc589b66281151\"},\"headline\":\"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA\",\"datePublished\":\"2024-01-22T07:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/\"},\"wordCount\":276,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2024\\\/01\\\/24-4-beitragsbild_seeloewen-projekt.jpg\",\"keywords\":[\"Filiale\",\"Instrument de mesure de pression\",\"Manom\u00e8tre\"],\"articleSection\":[\"G\u00e9n\u00e9ral\",\"Le monde WIKA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/\",\"name\":\"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2024\\\/01\\\/24-4-beitragsbild_seeloewen-projekt.jpg\",\"datePublished\":\"2024-01-22T07:00:54+00:00\",\"description\":\"Les manom\u00e8tres WIKA remplissent une mission importante dans le cadre du sauvetage de lions de mer au Mexique\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2024\\\/01\\\/24-4-beitragsbild_seeloewen-projekt.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2024\\\/01\\\/24-4-beitragsbild_seeloewen-projekt.jpg\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/sauver-des-lions-de-mer-grace-aux-manometres-wika\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/bed07f29fd632fb2c9cc589b66281151\",\"name\":\"Betty Pic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/03\\\/picbetty-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/03\\\/picbetty-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/03\\\/picbetty-140x140.jpg\",\"caption\":\"Betty Pic\"},\"sameAs\":[\"http:\\\/\\\/www.wika.it\"],\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/bettypic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA - Blog WIKA","description":"Les manom\u00e8tres WIKA remplissent une mission importante dans le cadre du sauvetage de lions de mer au Mexique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/","og_locale":"fr_FR","og_type":"article","og_title":"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA - Blog WIKA","og_description":"Les manom\u00e8tres WIKA remplissent une mission importante dans le cadre du sauvetage de lions de mer au Mexique","og_url":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2024\/01\/24-4-beitragsbild_seeloewen-projekt.jpg","type":"image\/jpeg"}],"author":"Betty Pic","twitter_misc":{"\u00c9crit par":"Betty Pic","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/"},"author":{"name":"Betty Pic","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/bed07f29fd632fb2c9cc589b66281151"},"headline":"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA","datePublished":"2024-01-22T07:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/"},"wordCount":276,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2024\/01\/24-4-beitragsbild_seeloewen-projekt.jpg","keywords":["Filiale","Instrument de mesure de pression","Manom\u00e8tre"],"articleSection":["G\u00e9n\u00e9ral","Le monde WIKA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/","url":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/","name":"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2024\/01\/24-4-beitragsbild_seeloewen-projekt.jpg","datePublished":"2024-01-22T07:00:54+00:00","description":"Les manom\u00e8tres WIKA remplissent une mission importante dans le cadre du sauvetage de lions de mer au Mexique","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2024\/01\/24-4-beitragsbild_seeloewen-projekt.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2024\/01\/24-4-beitragsbild_seeloewen-projekt.jpg","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/wika\/sauver-des-lions-de-mer-grace-aux-manometres-wika\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sauver des lions de mer gr\u00e2ce aux manom\u00e8tres WIKA"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/bed07f29fd632fb2c9cc589b66281151","name":"Betty Pic","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2018\/03\/picbetty-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2018\/03\/picbetty-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/03\/picbetty-140x140.jpg","caption":"Betty Pic"},"sameAs":["http:\/\/www.wika.it"],"url":"https:\/\/blog.wika.com\/fr\/author\/bettypic\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=11654"}],"version-history":[{"count":1,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11654\/revisions"}],"predecessor-version":[{"id":11655,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11654\/revisions\/11655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/11653"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=11654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=11654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=11654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}