{"id":11930,"date":"2024-07-08T11:00:55","date_gmt":"2024-07-08T09:00:55","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=11930"},"modified":"2024-07-15T17:39:05","modified_gmt":"2024-07-15T15:39:05","slug":"sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/","title":{"rendered":"SEP dans les process pharmaceutiques : St\u00e9rilisation \u00e0 la vapeur ultrapure"},"content":{"rendered":"<p><strong>La \u00ab\u00a0st\u00e9rilisation en place\u00a0\u00bb ou \u00ab\u00a0vapeur en place\u00a0\u00bb, en abr\u00e9g\u00e9 SEP, est un process indispensable dans la production pharmaceutique. Il consiste \u00e0 st\u00e9riliser l&rsquo;\u00e9quipement concern\u00e9 directement dans l&rsquo;usine \u00e0 l&rsquo;aide de vapeur de condensation.<\/strong><\/p>\n<p>Apr\u00e8s le process de nettoyage en place (NEP), la tuyauterie, les instruments et les autres composants utilis\u00e9s dans la production pharmaceutique doivent \u00eatre st\u00e9rilis\u00e9s r\u00e9guli\u00e8rement et de mani\u00e8re fiable. L&rsquo;\u00e9limination de tous les micro-organismes, tels que les germes, les bact\u00e9ries et les virus, garantit la qualit\u00e9 souhait\u00e9e du produit et, par cons\u00e9quent, la s\u00e9curit\u00e9 du patient.<\/p>\n<h2>St\u00e9rilisation sans d\u00e9montage<\/h2>\n<p>Dans le process SEP, l&rsquo;\u00e9quipement est st\u00e9rilis\u00e9 directement dans le syst\u00e8me ferm\u00e9 \u00e0 l&rsquo;aide de vapeur, sans d\u00e9montage pr\u00e9alable des diff\u00e9rents composants. Le risque de recontamination est ainsi r\u00e9duit au minimum. Parall\u00e8lement, les fabricants doivent concevoir leurs installations de production de mani\u00e8re \u00e0 ce qu&rsquo;elles soient compatibles avec le process SEP, c&rsquo;est-\u00e0-dire sans espace mort, avec des surfaces lisses, sans crevasses et sans risque de poches d&rsquo;air. Les mat\u00e9riaux utilis\u00e9s doivent pouvoir r\u00e9sister \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es. La norme ASME BPE (\u00ab\u00a0Bioprocessing Equipment\u00a0\u00bb), mondialement reconnue, constitue une ligne directrice \u00e0 cet \u00e9gard. Les appareils de mesure WIKA pour les applications pharmaceutiques r\u00e9pondent \u00e0 ces exigences.<\/p>\n<h2>Vapeur chaude et pression atmosph\u00e9rique<\/h2>\n<p>La SEP est bas\u00e9e sur la vapeur produite \u00e0 partir d&rsquo;eau ultrapure par un g\u00e9n\u00e9rateur. Les temp\u00e9ratures de la vapeur se situent entre 121 \u00b0C et 134 \u00b0C dans des conditions de vapeur satur\u00e9e \u00e0 une surpression de 1 \u00e0 2 bar (15 \u00e0 30 psi). Le temps de st\u00e9rilisation au point le plus froid est d&rsquo;au moins 20 minutes. Cependant, la pression et la temp\u00e9rature avec la SEP peuvent varier en fonction de la conception de l&rsquo;instrument, de la sensibilit\u00e9 du produit et des directives locales. Les sp\u00e9cifications sont fix\u00e9es par les autorit\u00e9s et institutions r\u00e9glementaires comp\u00e9tentes, telles que la Food and Drug Administration (FDA) aux \u00c9tats-Unis et l&rsquo;Agence europ\u00e9enne des m\u00e9dicaments (EMA) en Europe.<\/p>\n<h2>Automatisation et validation des process SEP<\/h2>\n<p>La plupart des process SEP sont automatis\u00e9s afin de garantir la coh\u00e9rence et la fiabilit\u00e9. Des instruments appropri\u00e9s contr\u00f4lent les param\u00e8tres cl\u00e9s que sont la temp\u00e9rature, la pression et la dur\u00e9e de st\u00e9rilisation. Le process SEP exige \u00e9galement une documentation compl\u00e8te des proc\u00e9dures ; la validation est essentielle \u00e0 cet \u00e9gard. Elle sert de preuve que toutes les exigences de st\u00e9rilisation ont \u00e9t\u00e9 satisfaites et que les r\u00e9glementations sous-jacentes ont \u00e9t\u00e9 respect\u00e9es. L&rsquo;inspection et l&rsquo;entretien r\u00e9guliers des syst\u00e8mes SEP sont tout aussi importants que la validation des process. Cela comprend \u00e9galement l&rsquo;\u00e9talonnage de tous les instruments de mesure.<\/p>\n<h2>Large gamme de produits pour les op\u00e9rations de surveillance avec SEP<\/h2>\n<p>Le process de st\u00e9rilisation pose des exigences \u00e9lev\u00e9es \u00e0 l&rsquo;instrumentation utilis\u00e9e pour le surveiller et le contr\u00f4ler. WIKA propose \u00e0 cet effet une large gamme d&rsquo;instruments de mesure. Cela vaut aussi bien pour la surveillance de la production de vapeur que pour les appareils adapt\u00e9s au process SEP.<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:846px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2024\/07\/textbild_quer_5_sip_pharma-838x356.jpg\" alt=\"La st\u00e9rilisation en place (SEP) impose des exigences \u00e9lev\u00e9es \u00e0 l'instrumentation de mesure pour les t\u00e2ches de surveillance.\" \/><p class=\"wp-caption-text\">Instrumentation d&rsquo;un g\u00e9n\u00e9rateur de vapeur pour les mesures de pression (bleu), de temp\u00e9rature (rouge) et de niveau (vert). Les instruments de mesure WIKA suivants ont \u00e9t\u00e9 s\u00e9lectionn\u00e9s pour cet exemple (dans le sens des aiguilles d&rsquo;une montre, en partant du bas \u00e0 gauche) : transmetteur de process en ligne mod\u00e8le DMSU22SA, sonde \u00e0 r\u00e9sistance mod\u00e8le TR22-B (2x), thermom\u00e8tre bim\u00e9tallique mod\u00e8le TG58SA, transmetteur de pression mod\u00e8le DMSU21SA avec syst\u00e8me de contr\u00f4le d&rsquo;\u00e9tanch\u00e9it\u00e9 de membrane, transmetteur de niveau \u00e0 cha\u00eene reed mod\u00e8le FLR-H, manom\u00e8tre mod\u00e8le 232.50 (avec siphon mod\u00e8le 910.15 D) et sonde \u00e0 r\u00e9sistance filet\u00e9e mod\u00e8le TR10-D (2x).<\/p><\/div>\n    \n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Note<\/strong><br \/>\nVous trouverez un aper\u00e7u des instruments de mesure pour la SEP et d&rsquo;autres applications dans l&rsquo;industrie pharmaceutique, <a href=\"https:\/\/www.wika.com\/fr-fr\/industrie_pharmaceutique_et_biotechnologie.WIKA\" rel=\"external\" target=\"_blank\">sur le site WIKA<\/a>. Si vous avez des questions, <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">votre interlocuteur<\/a> se fera un plaisir de vous aider.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00ab\u00a0st\u00e9rilisation en place\u00a0\u00bb ou \u00ab\u00a0vapeur en place\u00a0\u00bb, en abr\u00e9g\u00e9 SEP, est un process indispensable dans la production pharmaceutique. Il consiste \u00e0 st\u00e9riliser l&rsquo;\u00e9quipement concern\u00e9 directement dans l&rsquo;usine \u00e0 l&rsquo;aide de vapeur de condensation. Apr\u00e8s le process de nettoyage en place (NEP), la tuyauterie, les instruments et les autres composants utilis\u00e9s dans la production pharmaceutique [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":11933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,5],"tags":[573,273,533,401,545,323],"class_list":["post-11930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-savoir-faire","tag-automation","tag-nettoyage","tag-pharmaceutique","tag-pression","tag-scurit-du-process","tag-temprature"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>St\u00e9rilisation \u00e0 la vapeur ultrapure- Blog WIKA<\/title>\n<meta name=\"description\" content=\"La &quot;st\u00e9rilisation en place&quot; ou &quot;vapeur en place&quot;, en abr\u00e9g\u00e9 SEP, est un process indispensable dans la production pharmaceutique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"St\u00e9rilisation \u00e0 la vapeur ultrapure- Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La &quot;st\u00e9rilisation en place&quot; ou &quot;vapeur en place&quot;, en abr\u00e9g\u00e9 SEP, est un process indispensable dans la production pharmaceutique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2024\/07\/beitragsbild_sip_pharma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"SEP dans les process pharmaceutiques : St\u00e9rilisation \u00e0 la vapeur ultrapure\",\"datePublished\":\"2024-07-08T09:00:55+00:00\",\"dateModified\":\"2024-07-15T15:39:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/\"},\"wordCount\":725,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2024\\\/07\\\/beitragsbild_sip_pharma.jpg\",\"keywords\":[\"automation\",\"Nettoyage\",\"Pharmaceutique\",\"pression\",\"S\u00e9curit\u00e9 du process\",\"Temp\u00e9rature\"],\"articleSection\":[\"G\u00e9n\u00e9ral\",\"Savoir-faire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/\",\"name\":\"St\u00e9rilisation \u00e0 la vapeur ultrapure- Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2024\\\/07\\\/beitragsbild_sip_pharma.jpg\",\"datePublished\":\"2024-07-08T09:00:55+00:00\",\"dateModified\":\"2024-07-15T15:39:05+00:00\",\"description\":\"La \\\"st\u00e9rilisation en place\\\" ou \\\"vapeur en place\\\", en abr\u00e9g\u00e9 SEP, est un process indispensable dans la production pharmaceutique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2024\\\/07\\\/beitragsbild_sip_pharma.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2024\\\/07\\\/beitragsbild_sip_pharma.jpg\",\"width\":838,\"height\":471,\"caption\":\"With SIP (\\\"Sterilisation in Place\\\"), the equipment in pharmaceutical processes is sterilized with pure steam without prior disassembly.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEP dans les process pharmaceutiques : St\u00e9rilisation \u00e0 la vapeur ultrapure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"St\u00e9rilisation \u00e0 la vapeur ultrapure- Blog WIKA","description":"La \"st\u00e9rilisation en place\" ou \"vapeur en place\", en abr\u00e9g\u00e9 SEP, est un process indispensable dans la production pharmaceutique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/","og_locale":"fr_FR","og_type":"article","og_title":"St\u00e9rilisation \u00e0 la vapeur ultrapure- Blog WIKA","og_description":"La \"st\u00e9rilisation en place\" ou \"vapeur en place\", en abr\u00e9g\u00e9 SEP, est un process indispensable dans la production pharmaceutique.","og_url":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2024\/07\/beitragsbild_sip_pharma.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"SEP dans les process pharmaceutiques : St\u00e9rilisation \u00e0 la vapeur ultrapure","datePublished":"2024-07-08T09:00:55+00:00","dateModified":"2024-07-15T15:39:05+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/"},"wordCount":725,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2024\/07\/beitragsbild_sip_pharma.jpg","keywords":["automation","Nettoyage","Pharmaceutique","pression","S\u00e9curit\u00e9 du process","Temp\u00e9rature"],"articleSection":["G\u00e9n\u00e9ral","Savoir-faire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/","url":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/","name":"St\u00e9rilisation \u00e0 la vapeur ultrapure- Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2024\/07\/beitragsbild_sip_pharma.jpg","datePublished":"2024-07-08T09:00:55+00:00","dateModified":"2024-07-15T15:39:05+00:00","description":"La \"st\u00e9rilisation en place\" ou \"vapeur en place\", en abr\u00e9g\u00e9 SEP, est un process indispensable dans la production pharmaceutique.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2024\/07\/beitragsbild_sip_pharma.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2024\/07\/beitragsbild_sip_pharma.jpg","width":838,"height":471,"caption":"With SIP (\"Sterilisation in Place\"), the equipment in pharmaceutical processes is sterilized with pure steam without prior disassembly."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/general\/sep-dans-les-process-pharmaceutiques-sterilisation-a-la-vapeur-ultrapure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"SEP dans les process pharmaceutiques : St\u00e9rilisation \u00e0 la vapeur ultrapure"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=11930"}],"version-history":[{"count":7,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11930\/revisions"}],"predecessor-version":[{"id":11955,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/11930\/revisions\/11955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/11933"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=11930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=11930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=11930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}