{"id":6737,"date":"2016-10-18T10:45:46","date_gmt":"2016-10-18T08:45:46","guid":{"rendered":"http:\/\/test5.wika-blog-live.mcon.net\/?p=6737"},"modified":"2023-11-17T09:35:55","modified_gmt":"2023-11-17T08:35:55","slug":"manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/","title":{"rendered":"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages"},"content":{"rendered":"<p><strong>Les manom\u00e8tres avec bo\u00eetier rempli de liquide sont utilis\u00e9s pour des applications qui impliquent des chocs dynamiques \u00e9lev\u00e9s et des vibrations. Le liquide de remplissage amortit les vibrations ainsi produites et soulage de la sorte les composants m\u00e9caniques du manom\u00e8tre.<\/strong><strong><br \/>\n<\/strong><\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><a href=\"https:\/\/blog.wika.com\/de\/files\/2015\/07\/213.53_ge\u00e4nderte-Gr\u00f6\u00dfe.jpg\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/de\/files\/2015\/07\/213.53_ge\u00e4nderte-Gr\u00f6\u00dfe-388x471.jpg\" alt=\"Pressure gauge with filling liquid - model 213.53\" \/><\/a><p class=\"wp-caption-text\">Manom\u00e8tre avec liquide de remplissage\u00a0&#8211;\u00a0type 213.53<\/p><\/div>\n    \n<h2>Utilisation des liquides de remplissage<\/h2>\n<p>En fonction des conditions, on utilisera le plus souvent des m\u00e9langes glyc\u00e9rine-eau ou des huiles de silicone. Le m\u00e9lange glyc\u00e9rine-eau convient \u00e0 la plupart des applications et des temp\u00e9ratures ambiantes. Il est d\u2019ailleurs logique de l&rsquo;utiliser en particulier pour les basses pressions en raison de la faible densit\u00e9 du liquide et de la faible r\u00e9sistance sur l&rsquo;\u00e9l\u00e9ment de mesure de pression de l\u2019instrument. L&rsquo;huile de silicone est principalement requise lorsque le manom\u00e8tre est expos\u00e9 \u00e0 des temp\u00e9ratures particuli\u00e8rement \u00e9lev\u00e9es (&gt; +60 \u00b0 C) ou tr\u00e8s faibles (&lt;-20 \u00b0 C).<\/p>\n<p><span>Le bo\u00eetier du manom\u00e8tre n&rsquo;est pas compl\u00e8tement rempli, \u00e9tant donn\u00e9 qu\u2019en fonction de l&rsquo;humidit\u00e9 et de la temp\u00e9rature ambiante, le liquide de remplissage absorbe de l&rsquo;eau suppl\u00e9mentaire et se dilate en cons\u00e9quence. Le bo\u00eetier sera seulement rempli \u00e0 80 &#8211; 90% par d\u00e9faut pour fournir suffisamment d&rsquo;espace pour cette dilatation et pour \u00e9viter les fuites (voir la figure du mod\u00e8le 213.53).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n      <div class=\"wp-caption alignleft\" style=\"max-width:396px;\"><a href=\"https:\/\/blog.wika.com\/de\/files\/2015\/07\/213.53-mit-vibrierendem-Zeiger.jpg\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/de\/files\/2015\/07\/213.53-mit-vibrierendem-Zeiger-388x435.jpg\" alt=\"Pressure gauge without filling liquid - result: vibrating pointer\" \/><\/a><p class=\"wp-caption-text\">Manom\u00e8tre sans liquide de remplissage\u00a0&#8211; r\u00e9sultat : L&rsquo;aiguille vibre<\/p><\/div>\n    \n<h2>Avantages des liquides de remplissage<\/h2>\n<p>Le liquide de remplissage amortit toute pression d\u00fb \u00e0 des pics, des chocs et des vibrations et prot\u00e8ge la m\u00e9canique du manom\u00e8tre. Ainsi, la fatigue des mat\u00e9riaux et les mauvais fonctionnements sont contrecarr\u00e9s.<\/p>\n<p>Un autre facteur &#8211; d\u00e9cisif pour l&rsquo;utilisateur &#8211; est d&rsquo;assurer la lisibilit\u00e9 de la pression. Le liquide de remplissage limite le mouvement de l\u2019aiguille m\u00eame sous des charges de vibrations s\u00e9v\u00e8res. Sans liquide de remplissage, l\u2019aiguille ne montrerait pas la pression appliqu\u00e9e proprement dite, mais oscillerait de fa\u00e7on plus ou moins prononc\u00e9e en fonction de la fr\u00e9quence des vibrations dans l&rsquo;application. En cas de r\u00e9sonance, cette oscillation peut s\u2019effectuer sur un angle de 180\u00b0 et rendre par cons\u00e9quent toute lecture impossible.<\/p>\n<p>&nbsp;<\/p>\n<p>Les manom\u00e8tres remplis de liquide sont adapt\u00e9s pour une grande vari\u00e9t\u00e9 d&rsquo;applications, en particulier les process impliquant des chocs et vibrations.<\/p>\n<p>Note : En cas de besoin d&rsquo;aide ou de conseils pour votre application sp\u00e9cifique, votre interlocuteur se fera un plaisir de vous aider.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les manom\u00e8tres avec bo\u00eetier rempli de liquide sont utilis\u00e9s pour des applications qui impliquent des chocs dynamiques \u00e9lev\u00e9s et des vibrations. Le liquide de remplissage amortit les vibrations ainsi produites et soulage de la sorte les composants m\u00e9caniques du manom\u00e8tre. Utilisation des liquides de remplissage En fonction des conditions, on utilisera le plus souvent des [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":6738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[220,6],"tags":[75,264],"class_list":["post-6737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produits-pression","category-produits","tag-manometre","tag-vibrations-chocs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manom\u00e8tres avec liquide de remplissage : utilisation et avantages - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Les manom\u00e8tres avec liquide de remplissage sont utilis\u00e9s pour des applications qui impliquent des chocs dynamiques \u00e9lev\u00e9s et des vibrations\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Les manom\u00e8tres avec liquide de remplissage sont utilis\u00e9s pour des applications qui impliquent des chocs dynamiques \u00e9lev\u00e9s et des vibrations\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2015\/08\/Filmausschitt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"411\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages\",\"datePublished\":\"2016-10-18T08:45:46+00:00\",\"dateModified\":\"2023-11-17T08:35:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/\"},\"wordCount\":457,\"commentCount\":19,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2015\\\/08\\\/Filmausschitt.jpg\",\"keywords\":[\"Manom\u00e8tre\",\"Vibrations \\\/ chocs\"],\"articleSection\":[\"Pression\",\"Produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/\",\"name\":\"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2015\\\/08\\\/Filmausschitt.jpg\",\"datePublished\":\"2016-10-18T08:45:46+00:00\",\"dateModified\":\"2023-11-17T08:35:55+00:00\",\"description\":\"Les manom\u00e8tres avec liquide de remplissage sont utilis\u00e9s pour des applications qui impliquent des chocs dynamiques \u00e9lev\u00e9s et des vibrations\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2015\\\/08\\\/Filmausschitt.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2015\\\/08\\\/Filmausschitt.jpg\",\"width\":838,\"height\":411,\"caption\":\"Manom\u00e8tre avec ou sans liquide de remplissage\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages - Blog WIKA","description":"Les manom\u00e8tres avec liquide de remplissage sont utilis\u00e9s pour des applications qui impliquent des chocs dynamiques \u00e9lev\u00e9s et des vibrations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/","og_locale":"fr_FR","og_type":"article","og_title":"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages - Blog WIKA","og_description":"Les manom\u00e8tres avec liquide de remplissage sont utilis\u00e9s pour des applications qui impliquent des chocs dynamiques \u00e9lev\u00e9s et des vibrations","og_url":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":411,"url":"https:\/\/blog.wika.com\/fr\/files\/2015\/08\/Filmausschitt.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages","datePublished":"2016-10-18T08:45:46+00:00","dateModified":"2023-11-17T08:35:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/"},"wordCount":457,"commentCount":19,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2015\/08\/Filmausschitt.jpg","keywords":["Manom\u00e8tre","Vibrations \/ chocs"],"articleSection":["Pression","Produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/","url":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/","name":"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2015\/08\/Filmausschitt.jpg","datePublished":"2016-10-18T08:45:46+00:00","dateModified":"2023-11-17T08:35:55+00:00","description":"Les manom\u00e8tres avec liquide de remplissage sont utilis\u00e9s pour des applications qui impliquent des chocs dynamiques \u00e9lev\u00e9s et des vibrations","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2015\/08\/Filmausschitt.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2015\/08\/Filmausschitt.jpg","width":838,"height":411,"caption":"Manom\u00e8tre avec ou sans liquide de remplissage"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/produits\/manometre-avec-boitier-liquide-de-remplissage-utilisation-avantages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Manom\u00e8tres avec liquide de remplissage : utilisation et avantages"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/6737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=6737"}],"version-history":[{"count":15,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/6737\/revisions"}],"predecessor-version":[{"id":8743,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/6737\/revisions\/8743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/6738"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=6737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=6737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=6737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}