{"id":6823,"date":"2016-09-13T11:18:08","date_gmt":"2016-09-13T09:18:08","guid":{"rendered":"http:\/\/test5.wika-blog-live.mcon.net\/?p=6823"},"modified":"2023-11-17T13:33:10","modified_gmt":"2023-11-17T12:33:10","slug":"etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/","title":{"rendered":"Etalonnage comparatif par rapport \u00e0 l&rsquo;\u00e9talonnage en points fixes"},"content":{"rendered":"<p><strong>Il existe aujourd\u2019hui deux m\u00e9thodes d&rsquo;\u00e9talonnage pour les instruments de mesure de temp\u00e9rature &#8211; l&rsquo;\u00e9talonnage comparatif et l&rsquo;\u00e9talonnage <\/strong><strong>en <\/strong><strong>points fixes. La m\u00e9thode d&rsquo;\u00e9talonnage \u00e0 utiliser sera d\u00e9finie selon les exigences de pr\u00e9cision et le type d&rsquo;instrument <\/strong><strong>sous <\/strong><strong>test. Cependant la m\u00e9thode comparative repr\u00e9sente la m\u00e9thode <\/strong><strong>d&rsquo;\u00e9talonnage <\/strong><strong>la plus largement <\/strong><strong>utilis\u00e9e<\/strong><strong>.<\/strong><\/p>\n<p>Mais en quoi diff\u00e8rent ces 2 m\u00e9thodes\u00a0? En prenant l\u2019exemple d\u2019une sonde \u00e0 r\u00e9sistance \u00e0 \u00e9talonner, cet article vous expliquera les 2 m\u00e9thodes et fera en sorte de vous apporter toutes les r\u00e9ponses d\u2019une mani\u00e8re claire et objective.<\/p>\n<p>&nbsp;<\/p>\n<h2>L&rsquo;\u00e9talonnage comparatif<\/h2>\n<p>Comme l\u2019indique son nom, ce type d\u2019\u00e9talonnage s\u2019effectue en comparant la sonde \u00e0 \u00e9talonner \u00e0 une sonde de r\u00e9f\u00e9rence de qualit\u00e9 sup\u00e9rieure. La sonde de r\u00e9f\u00e9rence devrait donc avoir une pr\u00e9cision 3 ou 4 fois sup\u00e9rieure \u00e0 la sonde \u00e0 \u00e9talonner. Pour ce faire, on placera les deux sondes dans une m\u00eame source homog\u00e8ne de temp\u00e9rature, en veillant \u00e0 laisser un petit espace entre elles, et que les \u00e9l\u00e9ments sensibles (c\u2019est-\u00e0-dire les points de mesure) soient \u00e0 la m\u00eame hauteur. On utilisera le plus souvent un bain de liquide ou un four sec comme source de temp\u00e9rature.<\/p>\n<p>&nbsp;<\/p>\n<h2>L&rsquo;\u00e9talonnage en points fixes<\/h2>\n<p>L\u2019\u00e9talonnage en points fixes, contrairement \u00e0 l\u2019\u00e9talonnage comparatif, est r\u00e9alis\u00e9 selon le principe des points triple, de cong\u00e9lation et de fusion selon l\u2019Echelle Internationale de Temp\u00e9rature de 1990 (ITS-90). Les points fixes d\u00e9finissent les temp\u00e9ratures auxquelles l\u2019\u00e9tat physique des substances se modifie. Le point le plus important de l\u2019ITS-90 est le point triple de l&rsquo;eau. A la temp\u00e9rature de 0,01 \u00b0C, l\u2019\u00e9tat physique de l\u2019eau pure varie constamment entre la vapeur, la glace et l\u2019\u00e9tat liquide. Les quantit\u00e9s des \u00e9tats physiques restent toujours en proportion constantes. En r\u00e8gle g\u00e9n\u00e9rale, seuls les laboratoires nationaux et les laboratoires accr\u00e9dit\u00e9s pour de tr\u00e8s faibles incertitudes de mesure travaillent avec ces cellules \u00e0 points fixes, car celles-ci sont ch\u00e8res et sp\u00e9cifiques \u00e0 cette application. Les PRTs ultra stables, qui serviront comme sondes de r\u00e9f\u00e9rence, seront calibr\u00e9es selon cette m\u00e9thode de points fixes. La sonde de r\u00e9f\u00e9rence est ins\u00e9r\u00e9e dans une cellule \u00e0 point fixe ouverte ou ferm\u00e9e, qui permettra \u00e0 la temp\u00e9rature de rester constante pendant une longue p\u00e9riode.<\/p>\n<p>&nbsp;<\/p>\n<h2>Exemple: points fixes\u00a0de -189\u00a0\u00e0 660 \u00b0C\u00a0selon ITS-90 :<\/h2>\n<table>\n<tbody>\n<tr>\n<td><strong>Point fixe<\/strong><\/td>\n<td><strong>Temp\u00e9rature<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Point triple\u00a0de l&rsquo;argon<\/td>\n<td>-189,3442 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Point triple du\u00a0mercure<\/td>\n<td>-38,8344 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Point triple de l&rsquo;eau<\/td>\n<td>0,01 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Point de fusion du gallium<\/td>\n<td>29,7646 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Point de cong\u00e9lation de l&rsquo;indium<\/td>\n<td>156,5985 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Point de cong\u00e9lation de l&rsquo;\u00e9tain<\/td>\n<td>\u00a0231,928 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Point de cong\u00e9lation du zinc<\/td>\n<td>\u00a0419,527 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Point de cong\u00e9lation de l&rsquo;aluminium<\/td>\n<td>\u00a0660,323 \u00b0C<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong><br \/>\nNote<br \/>\n<\/strong>Tous les <a href=\"https:\/\/www.wika.com\/fr-fr\/service_d_etalonnage.WIKA\" rel=\"external\" target=\"_blank\">services en \u00e9talonnage d\u2019instruments de mesure de temp\u00e9rature <\/a>sont disponibles sur le site WIKA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il existe aujourd\u2019hui deux m\u00e9thodes d&rsquo;\u00e9talonnage pour les instruments de mesure de temp\u00e9rature &#8211; l&rsquo;\u00e9talonnage comparatif et l&rsquo;\u00e9talonnage en points fixes. La m\u00e9thode d&rsquo;\u00e9talonnage \u00e0 utiliser sera d\u00e9finie selon les exigences de pr\u00e9cision et le type d&rsquo;instrument sous test. Cependant la m\u00e9thode comparative repr\u00e9sente la m\u00e9thode d&rsquo;\u00e9talonnage la plus largement utilis\u00e9e. Mais en quoi diff\u00e8rent [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":6824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-savoir-faire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>etalonnage comparatif par rapport \u00e0 l&#039;etalonnage en points fixes<\/title>\n<meta name=\"description\" content=\"Il existe aujourd\u2019hui deux m\u00e9thodes d&#039;\u00e9talonnage pour les instruments de mesure de temp\u00e9rature - l&#039;\u00e9talonnage comparatif et l&#039;\u00e9talonnage en points fixes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"etalonnage comparatif par rapport \u00e0 l&#039;etalonnage en points fixes\" \/>\n<meta property=\"og:description\" content=\"Il existe aujourd\u2019hui deux m\u00e9thodes d&#039;\u00e9talonnage pour les instruments de mesure de temp\u00e9rature - l&#039;\u00e9talonnage comparatif et l&#039;\u00e9talonnage en points fixes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2015\/09\/vergleich_fixpunkt_838_471px_v1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"836\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas Chevin\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas Chevin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/\"},\"author\":{\"name\":\"Nicolas Chevin\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/a4d6253f6cb517f7f0fcde44426a5e92\"},\"headline\":\"Etalonnage comparatif par rapport \u00e0 l&rsquo;\u00e9talonnage en points fixes\",\"datePublished\":\"2016-09-13T09:18:08+00:00\",\"dateModified\":\"2023-11-17T12:33:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/\"},\"wordCount\":516,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2015\\\/09\\\/vergleich_fixpunkt_838_471px_v1.jpg\",\"articleSection\":[\"Savoir-faire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/\",\"name\":\"etalonnage comparatif par rapport \u00e0 l'etalonnage en points fixes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2015\\\/09\\\/vergleich_fixpunkt_838_471px_v1.jpg\",\"datePublished\":\"2016-09-13T09:18:08+00:00\",\"dateModified\":\"2023-11-17T12:33:10+00:00\",\"description\":\"Il existe aujourd\u2019hui deux m\u00e9thodes d'\u00e9talonnage pour les instruments de mesure de temp\u00e9rature - l'\u00e9talonnage comparatif et l'\u00e9talonnage en points fixes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2015\\\/09\\\/vergleich_fixpunkt_838_471px_v1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2015\\\/09\\\/vergleich_fixpunkt_838_471px_v1.jpg\",\"width\":836,\"height\":471,\"caption\":\"l'\u00e9talonnage comparatif et l'\u00e9talonnag en points fixes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Etalonnage comparatif par rapport \u00e0 l&rsquo;\u00e9talonnage en points fixes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/a4d6253f6cb517f7f0fcde44426a5e92\",\"name\":\"Nicolas Chevin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"caption\":\"Nicolas Chevin\"},\"description\":\"D\u00e9sormais en charge de la gamme de produits \u00ab Calibration \u00bb, et fort d\u2019une exp\u00e9rience de 15 ans dans le domaine de l\u2019instrumentation de mesure et de la m\u00e9trologie, je serai votre contact privil\u00e9gi\u00e9 pour toute demande d\u2019information sur le mat\u00e9riel d\u2019\u00e9talonnage mais aussi sur les services associ\u00e9s propos\u00e9s par notre Laboratoire COFRAC chez Wika\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/fraisso\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"etalonnage comparatif par rapport \u00e0 l'etalonnage en points fixes","description":"Il existe aujourd\u2019hui deux m\u00e9thodes d'\u00e9talonnage pour les instruments de mesure de temp\u00e9rature - l'\u00e9talonnage comparatif et l'\u00e9talonnage en points fixes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/","og_locale":"fr_FR","og_type":"article","og_title":"etalonnage comparatif par rapport \u00e0 l'etalonnage en points fixes","og_description":"Il existe aujourd\u2019hui deux m\u00e9thodes d'\u00e9talonnage pour les instruments de mesure de temp\u00e9rature - l'\u00e9talonnage comparatif et l'\u00e9talonnage en points fixes.","og_url":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/","og_site_name":"Blog WIKA","og_image":[{"width":836,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2015\/09\/vergleich_fixpunkt_838_471px_v1.jpg","type":"image\/jpeg"}],"author":"Nicolas Chevin","twitter_misc":{"\u00c9crit par":"Nicolas Chevin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/"},"author":{"name":"Nicolas Chevin","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/a4d6253f6cb517f7f0fcde44426a5e92"},"headline":"Etalonnage comparatif par rapport \u00e0 l&rsquo;\u00e9talonnage en points fixes","datePublished":"2016-09-13T09:18:08+00:00","dateModified":"2023-11-17T12:33:10+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/"},"wordCount":516,"commentCount":6,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2015\/09\/vergleich_fixpunkt_838_471px_v1.jpg","articleSection":["Savoir-faire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/","url":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/","name":"etalonnage comparatif par rapport \u00e0 l'etalonnage en points fixes","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2015\/09\/vergleich_fixpunkt_838_471px_v1.jpg","datePublished":"2016-09-13T09:18:08+00:00","dateModified":"2023-11-17T12:33:10+00:00","description":"Il existe aujourd\u2019hui deux m\u00e9thodes d'\u00e9talonnage pour les instruments de mesure de temp\u00e9rature - l'\u00e9talonnage comparatif et l'\u00e9talonnage en points fixes.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2015\/09\/vergleich_fixpunkt_838_471px_v1.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2015\/09\/vergleich_fixpunkt_838_471px_v1.jpg","width":836,"height":471,"caption":"l'\u00e9talonnage comparatif et l'\u00e9talonnag en points fixes"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/etalonnage-comparatif-par-rapport-etalonnage-en-points-fixes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Etalonnage comparatif par rapport \u00e0 l&rsquo;\u00e9talonnage en points fixes"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/a4d6253f6cb517f7f0fcde44426a5e92","name":"Nicolas Chevin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","caption":"Nicolas Chevin"},"description":"D\u00e9sormais en charge de la gamme de produits \u00ab Calibration \u00bb, et fort d\u2019une exp\u00e9rience de 15 ans dans le domaine de l\u2019instrumentation de mesure et de la m\u00e9trologie, je serai votre contact privil\u00e9gi\u00e9 pour toute demande d\u2019information sur le mat\u00e9riel d\u2019\u00e9talonnage mais aussi sur les services associ\u00e9s propos\u00e9s par notre Laboratoire COFRAC chez Wika","url":"https:\/\/blog.wika.com\/fr\/author\/fraisso\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/6823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=6823"}],"version-history":[{"count":10,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/6823\/revisions"}],"predecessor-version":[{"id":11416,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/6823\/revisions\/11416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/6824"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=6823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=6823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=6823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}