{"id":7265,"date":"2017-05-15T16:24:09","date_gmt":"2017-05-15T14:24:09","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=7265"},"modified":"2023-11-17T13:35:30","modified_gmt":"2023-11-17T12:35:30","slug":"fonctionnement-d-un-capteur-de-debit-calorimetrique","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/","title":{"rendered":"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ?"},"content":{"rendered":"<p><strong>Lorsqu\u2019il est n\u00e9cessaire de contr\u00f4ler le d\u00e9bit dans une tuyauterie, on utilise r\u00e9guli\u00e8rement un capteur de d\u00e9bit calorim\u00e9trique (\u00e9galement appel\u00e9 contr\u00f4leur de d\u00e9bit). Mais comment cet appareil fonctionne-t\u2019il\u00a0? c\u2019est l\u2019objet de cet article.<\/strong><\/p>\n<p>Les capteurs de d\u00e9bit calorim\u00e9triques, que l\u2019on peut associer au concept de r\u00e9gulateur thermique de d\u00e9bit, recourent aux lois physiques li\u00e9es aux flux de transfert de chaleur. Une distinction est faite entre deux solutions techniques\u00a0: l\u2019\u00e9chauffement chaleur continue et l\u2019\u00e9chauffement r\u00e9gul\u00e9.<\/p>\n<p>&nbsp;<\/p>\n\n      <div class=\"wp-caption alignnone\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/wp-content\/blogs.dir\/26\/files\/2017\/06\/calorimetric-flow-switch-388x167.jpg\" alt=\"Schematic illustration of a measuring probe for a calorimetric flow switch\" \/><p class=\"wp-caption-text\">Sch\u00e9ma de fonctionnement d\u2019un capteur de d\u00e9bit calorim\u00e9trique<\/p><\/div>\n    \n<p>&nbsp;<\/p>\n<h2>Echauffement continu<\/h2>\n<p>Un capteur de d\u00e9bit fonctionnant selon le principe de mesure calorim\u00e9trique est constitu\u00e9 d\u2019une sonde de mesure \u00e0 l\u2019extr\u00e9mit\u00e9 de laquelle se trouvent deux capteurs de temp\u00e9rature (voir l\u2019illustration). Un des capteurs est chauff\u00e9 de fa\u00e7on continue \u00e0 l\u2019aide d\u2019un \u00e9l\u00e9ment chauffant int\u00e9gr\u00e9 (\u00e9l\u00e9ment bobin\u00e9) avec une puissance de chauffe constante et mesure la temp\u00e9rature au niveau de cet \u00e9l\u00e9ment chauffant. Le second capteur d\u00e9termine la temp\u00e9rature du fluide dans la tuyauterie. De cette fa\u00e7on, on g\u00e9n\u00e8re une diff\u00e9rence de temp\u00e9rature entre les deux capteurs qui est enregistr\u00e9e par l\u2019\u00e9lectronique. Plus\u00a0la vitesse d\u2019\u00e9coulement du fluide dans la tuyauterie sera \u00e9lev\u00e9e, plus faible sera la diff\u00e9rence de temp\u00e9rature. La raison en est l\u2019effet refroidissant du fluide en \u00e9coulement. Les mol\u00e9cules du fluide, en passant \u00e0 proximit\u00e9 de l\u2019extr\u00e9mit\u00e9 de la sonde, captent la chaleur et la dissipent en s\u2019\u00e9coulant. Plus l\u2019\u00e9coulement de ces mol\u00e9cules est \u00e9lev\u00e9, plus l\u2019effet refroidissant est \u00e9lev\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h2>Echauffement r\u00e9gul\u00e9<\/h2>\n<p>La sonde de mesure est \u00e0 la base identique : il y a deux capteurs de temp\u00e9rature dans le fluide, l\u2019un d\u2019entre eux peut \u00eatre r\u00e9chauff\u00e9. Avec cette solution technique, la puissance d\u2019\u00e9chauffement est r\u00e9gul\u00e9e de fa\u00e7on \u00e0 ce que la diff\u00e9rence de temp\u00e9rature entre les deux capteurs de temp\u00e9rature soit maintenue constante en permanence. Lorsque la vitesse d\u2019\u00e9coulement augmente, la puissance d\u2019\u00e9chauffement doit \u00eatre augment\u00e9e de fa\u00e7on \u00e0 conserver la diff\u00e9rence de temp\u00e9rature constante. La puissance d\u2019\u00e9chauffement g\u00e9n\u00e9r\u00e9e correspond donc \u00e0 une mesure directe de la vitesse d\u2019\u00e9coulement du fluide.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Note<br \/>\n<\/strong><\/p>\n<p>Avez-vous des questions sur le principe de mesure des capteurs de d\u00e9bit calorim\u00e9triques\u00a0? Avez-vous besoin d\u2019aide pour le choix d\u2019un tel instrument\u00a0? WIKA poss\u00e8de dans sa gamme un capteur de d\u00e9bit calorim\u00e9trique pour contr\u00f4ler le d\u00e9bit de fluides liquides (mod\u00e8le <a href=\"https:\/\/www.wika.com\/fr-fr\/fsd_4.WIKA\" rel=\"external\" target=\"_blank\">FSD-4<\/a>). Votre <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">contact commercial <\/a>WIKA sera heureux de vous renseigner.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu\u2019il est n\u00e9cessaire de contr\u00f4ler le d\u00e9bit dans une tuyauterie, on utilise r\u00e9guli\u00e8rement un capteur de d\u00e9bit calorim\u00e9trique (\u00e9galement appel\u00e9 contr\u00f4leur de d\u00e9bit). Mais comment cet appareil fonctionne-t\u2019il\u00a0? c\u2019est l\u2019objet de cet article. Les capteurs de d\u00e9bit calorim\u00e9triques, que l\u2019on peut associer au concept de r\u00e9gulateur thermique de d\u00e9bit, recourent aux lois physiques li\u00e9es aux [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":7268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-7265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produits"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ? - Blog WIKA<\/title>\n<meta name=\"description\" content=\"La pr\u00e9sence d&#039;\u00e9coulement dans un syst\u00e8me de tuyauterie implique l&#039;utilisation de capteur de d\u00e9bit calorim\u00e9trique, pour la surveillance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ? - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La pr\u00e9sence d&#039;\u00e9coulement dans un syst\u00e8me de tuyauterie implique l&#039;utilisation de capteur de d\u00e9bit calorim\u00e9trique, pour la surveillance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/kalorimetrischer-str\u00f6mungsschalter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ?\",\"datePublished\":\"2017-05-15T14:24:09+00:00\",\"dateModified\":\"2023-11-17T12:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/\"},\"wordCount\":486,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/06\\\/kalorimetrischer-str\u00f6mungsschalter.jpg\",\"articleSection\":[\"Produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/\",\"name\":\"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ? - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/06\\\/kalorimetrischer-str\u00f6mungsschalter.jpg\",\"datePublished\":\"2017-05-15T14:24:09+00:00\",\"dateModified\":\"2023-11-17T12:35:30+00:00\",\"description\":\"La pr\u00e9sence d'\u00e9coulement dans un syst\u00e8me de tuyauterie implique l'utilisation de capteur de d\u00e9bit calorim\u00e9trique, pour la surveillance.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/06\\\/kalorimetrischer-str\u00f6mungsschalter.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/06\\\/kalorimetrischer-str\u00f6mungsschalter.jpg\",\"width\":838,\"height\":471,\"caption\":\"Capteur de d\u00e9bit calorim\u00e9trique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/fonctionnement-d-un-capteur-de-debit-calorimetrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ? - Blog WIKA","description":"La pr\u00e9sence d'\u00e9coulement dans un syst\u00e8me de tuyauterie implique l'utilisation de capteur de d\u00e9bit calorim\u00e9trique, pour la surveillance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ? - Blog WIKA","og_description":"La pr\u00e9sence d'\u00e9coulement dans un syst\u00e8me de tuyauterie implique l'utilisation de capteur de d\u00e9bit calorim\u00e9trique, pour la surveillance.","og_url":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/kalorimetrischer-str\u00f6mungsschalter.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ?","datePublished":"2017-05-15T14:24:09+00:00","dateModified":"2023-11-17T12:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/"},"wordCount":486,"commentCount":4,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/kalorimetrischer-str\u00f6mungsschalter.jpg","articleSection":["Produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/","url":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/","name":"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ? - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/kalorimetrischer-str\u00f6mungsschalter.jpg","datePublished":"2017-05-15T14:24:09+00:00","dateModified":"2023-11-17T12:35:30+00:00","description":"La pr\u00e9sence d'\u00e9coulement dans un syst\u00e8me de tuyauterie implique l'utilisation de capteur de d\u00e9bit calorim\u00e9trique, pour la surveillance.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/kalorimetrischer-str\u00f6mungsschalter.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/kalorimetrischer-str\u00f6mungsschalter.jpg","width":838,"height":471,"caption":"Capteur de d\u00e9bit calorim\u00e9trique"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/produits\/fonctionnement-d-un-capteur-de-debit-calorimetrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment fonctionne un capteur de d\u00e9bit calorim\u00e9trique ?"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=7265"}],"version-history":[{"count":7,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7265\/revisions"}],"predecessor-version":[{"id":11417,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7265\/revisions\/11417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/7268"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=7265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=7265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=7265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}