{"id":7272,"date":"2017-02-03T16:39:04","date_gmt":"2017-02-03T15:39:04","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=7272"},"modified":"2019-04-17T16:34:24","modified_gmt":"2019-04-17T14:34:24","slug":"plus-despace-pour-s-epanouir","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/","title":{"rendered":"WIKA France a maintenant plus d&rsquo;espace pour s&rsquo;\u00e9panouir"},"content":{"rendered":"<p><strong><span id=\"result_box\" lang=\"fr\"><span>WIKA France\u00a0a d\u00e9m\u00e9nag\u00e9\u00a0dans un nouveau b\u00e2timent \u00e0 1 km du pr\u00e9c\u00e9dent.<\/span> <span>Avec une superficie totale de 3 000 m\u00e8tres carr\u00e9s, l&rsquo;espace disponible pour la filiale a plus que doubl\u00e9.<\/span> <span>Parall\u00e8lement, l&rsquo;organisation a \u00e9t\u00e9 nouvellement structur\u00e9e.<\/span> <span>\u00ab\u00a0Nous sommes maintenant pr\u00eats pour la vision 2025\u00a0\u00bb, souligne le\u00a0directeur de la filiale Claunel Massi\u00e8s.<\/span><\/span><span class=\"trans-verified-button goog-toolbar-button\" id=\"t-served-community-button\" role=\"button\"><span class=\"jfk-button-img\"><\/span><\/span><\/strong><\/p>\n<p>Compte-tenu des conditions de travail dans le b\u00e2timent pr\u00e9c\u00e9dent, le d\u00e9m\u00e9nagement dans des locaux plus adapt\u00e9s devenait imp\u00e9ratif. En effet, en 24 ans, le nombre de salari\u00e9s a plus que doubl\u00e9 et la soci\u00e9t\u00e9 DH Desgranges et Huot et ses 20 collaborateurs ont rejoint l\u2019entit\u00e9 WIKA et ses locaux en 2015.\u00a0Le personnel WIKA et DH commen\u00e7ait donc \u00e0 \u00eatre \u00e0 l\u2019\u00e9troit dans ce b\u00e2timent. C&rsquo;est maintenant 3 \u00e9tages avec 2 ailes par \u00e9tage, pour une surface totale de plus de 3000m\u00b2 qui vont donner des ailes \u00e0 WIKA France pour son d\u00e9veloppement commercial\u00a0!<\/p>\n<p>En effet, en parall\u00e8le de ce d\u00e9m\u00e9nagement, toute l\u2019organisation a \u00e9t\u00e9 re-pens\u00e9e pour permettre un d\u00e9veloppement commercial optimum.<\/p>\n<p>Maintenant une hotline technique a \u00e9t\u00e9 mise en place pour le service calibration afin d\u2019\u00eatre plus rapide dans la prise en charge et les r\u00e9ponses apport\u00e9es \u00e0 nos clients, et les plages horaires de pr\u00e9sence t\u00e9l\u00e9phonique ont \u00e9t\u00e9 agrandies.\u00a0Un num\u00e9ro direct et gratuit a aussi \u00e9t\u00e9 mis en place pour le suivi des commandes, toujours dans l\u2019objectif de satisfaire au mieux les besoins de nos clients.<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/files\/2016\/10\/frankreich_showroom_neu-388x300.jpg\" alt=\"The new premises include an impressive showroom.\" \/><p class=\"wp-caption-text\">Les nouveaux locaux inclus un impressionnant show-room.<\/p><\/div>\n    \n<h2>Des espaces d\u00e9di\u00e9s<\/h2>\n<p><span id=\"result_box\" lang=\"fr\"><span>Dans ce nouveau b\u00e2timent, chaque d\u00e9partement poss\u00e8de son propre\u00a0espace parfaitement adapt\u00e9 \u00e0 ses besoins.<\/span> <span>La direction, l&rsquo;eng\u00e9nierie,\u00a0les services avant-vente et apr\u00e8s-vente\u00a0ont maintenant des\u00a0bureaux s\u00e9par\u00e9s.<\/span> D<span>e nouvelles salles pour les formations internes et clients ont aussi vu le jour, ainsi qu&rsquo;un\u00a0show-room\u00a0et qu&rsquo;un nouvel espace de restauration et de d\u00e9tente.<\/span><\/span><\/p>\n<div id=\"gt-res-dir-ctr\" class=\"trans-verified-button-small\" dir=\"ltr\"><span id=\"gt-res-error\"><\/span><span id=\"result_box\" lang=\"fr\"><span>Les conditions de travail pour DH et le service d&rsquo;\u00e9talonnage se sont \u00e9galement consid\u00e9rablement am\u00e9lior\u00e9es<\/span><\/span>. La surface de laboratoire a doubl\u00e9, afin d\u2019\u00e9largir la port\u00e9e d\u2019accr\u00e9ditation et augmenter l\u2019activit\u00e9.<\/div>\n<p>&nbsp;<\/p>\n<h2>\u00a0<\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WIKA France\u00a0a d\u00e9m\u00e9nag\u00e9\u00a0dans un nouveau b\u00e2timent \u00e0 1 km du pr\u00e9c\u00e9dent. Avec une superficie totale de 3 000 m\u00e8tres carr\u00e9s, l&rsquo;espace disponible pour la filiale a plus que doubl\u00e9. Parall\u00e8lement, l&rsquo;organisation a \u00e9t\u00e9 nouvellement structur\u00e9e. \u00ab\u00a0Nous sommes maintenant pr\u00eats pour la vision 2025\u00a0\u00bb, souligne le\u00a0directeur de la filiale Claunel Massi\u00e8s. Compte-tenu des conditions de travail [&hellip;]<\/p>\n","protected":false},"author":117,"featured_media":7275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[215],"tags":[],"class_list":["post-7272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wika"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WIKA France a maintenant plus d&#039;espace pour s&#039;\u00e9panouir - Blog WIKA<\/title>\n<meta name=\"description\" content=\"WIKA France a d\u00e9m\u00e9nag\u00e9 dans un nouveau b\u00e2timent. Avec une superficie totale de 3 000 m\u00e8tres carr\u00e9s, l&#039;espace disponible pour la filiale a plus que doubl\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WIKA France a maintenant plus d&#039;espace pour s&#039;\u00e9panouir - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"WIKA France a d\u00e9m\u00e9nag\u00e9 dans un nouveau b\u00e2timent. Avec une superficie totale de 3 000 m\u00e8tres carr\u00e9s, l&#039;espace disponible pour la filiale a plus que doubl\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/frankreich_geb\u00e4ude_neu-1024x508.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sandrine Beaufils\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandrine Beaufils\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/\"},\"author\":{\"name\":\"Sandrine Beaufils\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/826de9bb4efe969369c26fee264d0201\"},\"headline\":\"WIKA France a maintenant plus d&rsquo;espace pour s&rsquo;\u00e9panouir\",\"datePublished\":\"2017-02-03T15:39:04+00:00\",\"dateModified\":\"2019-04-17T14:34:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/06\\\/frankreich_geb\u00e4ude_neu.jpg\",\"articleSection\":[\"Le monde WIKA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/\",\"name\":\"WIKA France a maintenant plus d'espace pour s'\u00e9panouir - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/06\\\/frankreich_geb\u00e4ude_neu.jpg\",\"datePublished\":\"2017-02-03T15:39:04+00:00\",\"dateModified\":\"2019-04-17T14:34:24+00:00\",\"description\":\"WIKA France a d\u00e9m\u00e9nag\u00e9 dans un nouveau b\u00e2timent. Avec une superficie totale de 3 000 m\u00e8tres carr\u00e9s, l'espace disponible pour la filiale a plus que doubl\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/06\\\/frankreich_geb\u00e4ude_neu.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/06\\\/frankreich_geb\u00e4ude_neu.jpg\",\"width\":1736,\"height\":861,\"caption\":\"WIKA France\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/wika\\\/plus-despace-pour-s-epanouir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WIKA France a maintenant plus d&rsquo;espace pour s&rsquo;\u00e9panouir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/826de9bb4efe969369c26fee264d0201\",\"name\":\"Sandrine Beaufils\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/03\\\/s_beaufils_outlook-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/03\\\/s_beaufils_outlook-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/03\\\/s_beaufils_outlook-140x140.jpg\",\"caption\":\"Sandrine Beaufils\"},\"description\":\"Je suis tomb\u00e9e dans la marmite de la com depuis maintenant plus de 15 ans. D'un naturel plut\u00f4t communicatif, j'aime profiter des ressources diverses et vari\u00e9es \u00e0 notre disposition pour mettre en avant les produits et la soci\u00e9t\u00e9 WIKA. En charge de la communication de WIKA France depuis 2012, je suis ravie de pouvoir vous montrer au travers de sujets tr\u00e8s h\u00e9t\u00e9roclites que WIKA est une entreprise ou il fait bon travailler. J'attends avec impatience de pouvoir \u00e9changer avec vous autour de sujets sur le monde de WIKA.\",\"sameAs\":[\"http:\\\/\\\/www.wika.fr\"],\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/beaufis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WIKA France a maintenant plus d'espace pour s'\u00e9panouir - Blog WIKA","description":"WIKA France a d\u00e9m\u00e9nag\u00e9 dans un nouveau b\u00e2timent. Avec une superficie totale de 3 000 m\u00e8tres carr\u00e9s, l'espace disponible pour la filiale a plus que doubl\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/","og_locale":"fr_FR","og_type":"article","og_title":"WIKA France a maintenant plus d'espace pour s'\u00e9panouir - Blog WIKA","og_description":"WIKA France a d\u00e9m\u00e9nag\u00e9 dans un nouveau b\u00e2timent. Avec une superficie totale de 3 000 m\u00e8tres carr\u00e9s, l'espace disponible pour la filiale a plus que doubl\u00e9.","og_url":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/","og_site_name":"Blog WIKA","og_image":[{"width":1024,"height":508,"url":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/frankreich_geb\u00e4ude_neu-1024x508.jpg","type":"image\/jpeg"}],"author":"Sandrine Beaufils","twitter_misc":{"\u00c9crit par":"Sandrine Beaufils","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/"},"author":{"name":"Sandrine Beaufils","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/826de9bb4efe969369c26fee264d0201"},"headline":"WIKA France a maintenant plus d&rsquo;espace pour s&rsquo;\u00e9panouir","datePublished":"2017-02-03T15:39:04+00:00","dateModified":"2019-04-17T14:34:24+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/frankreich_geb\u00e4ude_neu.jpg","articleSection":["Le monde WIKA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/","url":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/","name":"WIKA France a maintenant plus d'espace pour s'\u00e9panouir - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/frankreich_geb\u00e4ude_neu.jpg","datePublished":"2017-02-03T15:39:04+00:00","dateModified":"2019-04-17T14:34:24+00:00","description":"WIKA France a d\u00e9m\u00e9nag\u00e9 dans un nouveau b\u00e2timent. Avec une superficie totale de 3 000 m\u00e8tres carr\u00e9s, l'espace disponible pour la filiale a plus que doubl\u00e9.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/frankreich_geb\u00e4ude_neu.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/06\/frankreich_geb\u00e4ude_neu.jpg","width":1736,"height":861,"caption":"WIKA France"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/wika\/plus-despace-pour-s-epanouir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"WIKA France a maintenant plus d&rsquo;espace pour s&rsquo;\u00e9panouir"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/826de9bb4efe969369c26fee264d0201","name":"Sandrine Beaufils","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2016\/03\/s_beaufils_outlook-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/03\/s_beaufils_outlook-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/03\/s_beaufils_outlook-140x140.jpg","caption":"Sandrine Beaufils"},"description":"Je suis tomb\u00e9e dans la marmite de la com depuis maintenant plus de 15 ans. D'un naturel plut\u00f4t communicatif, j'aime profiter des ressources diverses et vari\u00e9es \u00e0 notre disposition pour mettre en avant les produits et la soci\u00e9t\u00e9 WIKA. En charge de la communication de WIKA France depuis 2012, je suis ravie de pouvoir vous montrer au travers de sujets tr\u00e8s h\u00e9t\u00e9roclites que WIKA est une entreprise ou il fait bon travailler. J'attends avec impatience de pouvoir \u00e9changer avec vous autour de sujets sur le monde de WIKA.","sameAs":["http:\/\/www.wika.fr"],"url":"https:\/\/blog.wika.com\/fr\/author\/beaufis\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=7272"}],"version-history":[{"count":2,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7272\/revisions"}],"predecessor-version":[{"id":7276,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7272\/revisions\/7276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/7275"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=7272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=7272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=7272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}