{"id":7396,"date":"2017-12-08T11:15:48","date_gmt":"2017-12-08T10:15:48","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=7396"},"modified":"2025-01-24T08:53:54","modified_gmt":"2025-01-24T07:53:54","slug":"fonctionnement-de-l-io-link","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/","title":{"rendered":"Comment fonctionne l&rsquo;IO-Link ?"},"content":{"rendered":"<p><strong>Comment fonctionne l&rsquo;interface de communication IO-Link de pressostat WIKA <a href=\"https:\/\/www.wika.com\/fr-fr\/psd_4.WIKA\" rel=\"external\" target=\"_blank\">PSD-4<\/a>? L\u2019IO-Link est une connexion point \u00e0 point (c&rsquo;est-\u00e0-dire pas un nouveau bus de terrain) entre le capteur \/ actionneur et un ma\u00eetre de bus de terrain tel qu&rsquo;un automate.<\/strong><\/p>\n<p>L&rsquo;alimentation de l\u2019instrument de mesure type PSD-4 ou PSD-30 (broche 1 et broche 3) et de la transmission du signal (broche 4) utilise une connexion \u00e0 3 conducteurs, qui est typique et normalis\u00e9e au niveau du terrain. La transmission du signal se fait initialement de mani\u00e8re classique, c&rsquo;est-\u00e0-dire sans IO-Link dans le mode dit SIO (mode IO standard). Ce n&rsquo;est qu&rsquo;apr\u00e8s un \u00ab\u00a0r\u00e9veil\u00a0\u00bb effectu\u00e9 via le ma\u00eetre IO-Link en utilisant une commande d\u00e9finie, que la communication IO-Link num\u00e9rique est d\u00e9marr\u00e9e.<\/p>\n<p>Les paquets de donn\u00e9es normalis\u00e9s sont ensuite \u00e9chang\u00e9s de mani\u00e8re bidirectionnelle via un protocole s\u00e9rie. Les param\u00e8tres de configuration peuvent maintenant \u00eatre transmis du syst\u00e8me central au capteur et les valeurs de mesure et les donn\u00e9es de diagnostic du capteur au syst\u00e8me de commande. La fonctionnalit\u00e9 IO-Link du capteur est repr\u00e9sent\u00e9e dans un fichier de description d&rsquo;appareil (IODD &#8211; Description de l&rsquo;appareil IO-Link, fichier xml) et doit \u00eatre enregistr\u00e9e dans l&rsquo;outil d&rsquo;interpr\u00e9tation IO-Link utilis\u00e9.<\/p>\n<h2>Informations techniques pour IO-Link:<\/h2>\n<p>D\u00e9bit : 4.8 \/ 38.4 \/ 230.4 kbaud Max.<\/p>\n<p>Longueur de c\u00e2ble : 20 m, non blind\u00e9<\/p>\n<p>Dur\u00e9e de cycle typique : 2 ms<\/p>\n<p>Type de connexion : point \u00e0 point, s\u00e9rie, bidirectionnelle, semi-duplex<\/p>\n<p>Connecteurs standard : M5, M8, M12<\/p>\n<p>Pour plus de d\u00e9tails sur l&rsquo;IO-Link,\u00a0rendez-vous sur\u00a0la <a href=\"http:\/\/www.io-link.com\/en\/\" rel=\"external\" target=\"_blank\">page du site<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment fonctionne l&rsquo;interface de communication IO-Link de pressostat WIKA PSD-4? L\u2019IO-Link est une connexion point \u00e0 point (c&rsquo;est-\u00e0-dire pas un nouveau bus de terrain) entre le capteur \/ actionneur et un ma\u00eetre de bus de terrain tel qu&rsquo;un automate. L&rsquo;alimentation de l\u2019instrument de mesure type PSD-4 ou PSD-30 (broche 1 et broche 3) et de [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":7397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-7396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-savoir-faire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment fonctionne l&#039;interface de communication IO-Link des pressostats WIKA PSD-4 et PSD-30<\/title>\n<meta name=\"description\" content=\"L&#039;interface de communication IO-Link est une connexion point \u00e0 point entre le capteur \/ actionneur et un ma\u00eetre de bus de terrain tel qu&#039;un automate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment fonctionne l&#039;interface de communication IO-Link des pressostats WIKA PSD-4 et PSD-30\" \/>\n<meta property=\"og:description\" content=\"L&#039;interface de communication IO-Link est une connexion point \u00e0 point entre le capteur \/ actionneur et un ma\u00eetre de bus de terrain tel qu&#039;un automate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2017\/12\/Funktion_IO-Link1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"423\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Comment fonctionne l&rsquo;IO-Link ?\",\"datePublished\":\"2017-12-08T10:15:48+00:00\",\"dateModified\":\"2025-01-24T07:53:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/12\\\/Funktion_IO-Link1.jpg\",\"articleSection\":[\"Savoir-faire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/\",\"name\":\"Comment fonctionne l'interface de communication IO-Link des pressostats WIKA PSD-4 et PSD-30\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/12\\\/Funktion_IO-Link1.jpg\",\"datePublished\":\"2017-12-08T10:15:48+00:00\",\"dateModified\":\"2025-01-24T07:53:54+00:00\",\"description\":\"L'interface de communication IO-Link est une connexion point \u00e0 point entre le capteur \\\/ actionneur et un ma\u00eetre de bus de terrain tel qu'un automate.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/12\\\/Funktion_IO-Link1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/12\\\/Funktion_IO-Link1.jpg\",\"width\":423,\"height\":423,\"caption\":\"Fonctionnement de l'IO-Link\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/fonctionnement-de-l-io-link\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment fonctionne l&rsquo;IO-Link ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment fonctionne l'interface de communication IO-Link des pressostats WIKA PSD-4 et PSD-30","description":"L'interface de communication IO-Link est une connexion point \u00e0 point entre le capteur \/ actionneur et un ma\u00eetre de bus de terrain tel qu'un automate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment fonctionne l'interface de communication IO-Link des pressostats WIKA PSD-4 et PSD-30","og_description":"L'interface de communication IO-Link est une connexion point \u00e0 point entre le capteur \/ actionneur et un ma\u00eetre de bus de terrain tel qu'un automate.","og_url":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/","og_site_name":"Blog WIKA","og_image":[{"width":423,"height":423,"url":"https:\/\/blog.wika.com\/fr\/files\/2017\/12\/Funktion_IO-Link1.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Comment fonctionne l&rsquo;IO-Link ?","datePublished":"2017-12-08T10:15:48+00:00","dateModified":"2025-01-24T07:53:54+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/12\/Funktion_IO-Link1.jpg","articleSection":["Savoir-faire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/","url":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/","name":"Comment fonctionne l'interface de communication IO-Link des pressostats WIKA PSD-4 et PSD-30","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/12\/Funktion_IO-Link1.jpg","datePublished":"2017-12-08T10:15:48+00:00","dateModified":"2025-01-24T07:53:54+00:00","description":"L'interface de communication IO-Link est une connexion point \u00e0 point entre le capteur \/ actionneur et un ma\u00eetre de bus de terrain tel qu'un automate.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2017\/12\/Funktion_IO-Link1.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/12\/Funktion_IO-Link1.jpg","width":423,"height":423,"caption":"Fonctionnement de l'IO-Link"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/fonctionnement-de-l-io-link\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment fonctionne l&rsquo;IO-Link ?"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=7396"}],"version-history":[{"count":8,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7396\/revisions"}],"predecessor-version":[{"id":12247,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7396\/revisions\/12247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/7397"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=7396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=7396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=7396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}