{"id":7867,"date":"2018-08-20T14:09:22","date_gmt":"2018-08-20T12:09:22","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=7867"},"modified":"2023-11-17T13:29:33","modified_gmt":"2023-11-17T12:29:33","slug":"connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/","title":{"rendered":"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature"},"content":{"rendered":"<p><strong><span lang=\"EN-US\" style=\"font-family: 'Arial','sans-serif'\"><span style=\"color: #000000\">L&rsquo;utilisation d&rsquo;un connecteur M12 sur la t\u00eate de raccordement d\u2019une sonde de temp\u00e9rature, plut\u00f4t que d&rsquo;une sortie de c\u00e2ble standard, permet une connexion rapide et s\u00fbre. Dans les industries alimentaires et pharmaceutiques, un tel design est de plus en plus demand\u00e9.<\/span><\/span><\/strong><\/p>\n<p><span lang=\"EN-US\"><span style=\"color: #000000\">Dans la pratique, les OEM pr\u00e9f\u00e8rent faire le pr\u00e9-c\u00e2blage avec des connecteurs mont\u00e9s, car cela simplifie le c\u00e2blage des t\u00eates. Le temps n\u00e9cessaire au montage et au d\u00e9montage pendant l&rsquo;\u00e9talonnage ou lors du remplacement de l&rsquo;instrument peut ainsi \u00eatre consid\u00e9rablement r\u00e9duit. Autre avantage, en cas de remplacement d&rsquo;un instrument, une erreur de c\u00e2blage sera impossible.<\/span><\/span><\/p>\n<p><span lang=\"EN-US\"><span style=\"color: #000000\">En g\u00e9n\u00e9ral, il convient \u00e9galement de noter que, pour assurer la s\u00e9curit\u00e9 de fonctionnement des installations et pour leur entretien, il est imp\u00e9ratif que l&rsquo;\u00e9quipement offre un nettoyage facile et que sa protection contre l&rsquo;humidit\u00e9 soit maximale. Ces exigences s&rsquo;appliquent \u00e0 tous les composants du proc\u00e9d\u00e9 et \u00e9galement hors proc\u00e9d\u00e9 (dans la \u00abzone de d\u00e9marrage\u00bb).<\/span><\/span><\/p>\n<p><span lang=\"EN-US\"><span style=\"color: #000000\"><strong>Remarque<\/strong><br \/>\nWIKA a adapt\u00e9 le connecteur M12 enti\u00e8rement m\u00e9tallique, \u00e0 la sortie de c\u00e2ble pour sondes de temp\u00e9rature avec t\u00eate de raccordement et a ainsi permis une connexion simple et fiable avec un connecteur M12 \u00e0 4 broches. Le concept d&rsquo;\u00e9tanch\u00e9it\u00e9 de haute qualit\u00e9 de ce connecteur a \u00e9galement fait ses preuves pour les exigences extr\u00eames des capteurs autoclavables. En plus de la sonde miniature \u00e0 r\u00e9sistance <a href=\"https:\/\/www.wika.com\/fr-fr\/tr21_a.WIKA\" rel=\"external\" target=\"_blank\">TR21<\/a> d\u00e9j\u00e0 disponible, qui a \u00e9t\u00e9 con\u00e7u pour r\u00e9pondre aux exigences \u00e9lev\u00e9es des applications sanitaires, WIKA propose \u00e9galement des sondes avec t\u00eates de raccordement &#8211; mod\u00e8les <a href=\"https:\/\/www.wika.com\/fr-fr\/tr20.WIKA\" rel=\"external\" target=\"_blank\">TR20<\/a>, <a href=\"https:\/\/www.wika.com\/fr-fr\/tr22_a.WIKA\" rel=\"external\" target=\"_blank\">TR22<\/a>, <a href=\"https:\/\/www.wika.com\/fr-fr\/tr25.WIKA\" rel=\"external\" target=\"_blank\">TR25<\/a> &#8211; avec un raccord M12 pour les industries alimentaires et pharmaceutiques.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;utilisation d&rsquo;un connecteur M12 sur la t\u00eate de raccordement d\u2019une sonde de temp\u00e9rature, plut\u00f4t que d&rsquo;une sortie de c\u00e2ble standard, permet une connexion rapide et s\u00fbre. Dans les industries alimentaires et pharmaceutiques, un tel design est de plus en plus demand\u00e9. Dans la pratique, les OEM pr\u00e9f\u00e8rent faire le pr\u00e9-c\u00e2blage avec des connecteurs mont\u00e9s, car [&hellip;]<\/p>\n","protected":false},"author":176,"featured_media":7868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232,221],"tags":[],"class_list":["post-7867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","category-produits-temperature"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature - Blog WIKA<\/title>\n<meta name=\"description\" content=\"L&#039;utilisation d&#039;un connecteur M12 sur la t\u00eate de raccordement d\u2019une sonde de temp\u00e9rature, plut\u00f4t que d&#039;une sortie de c\u00e2ble standard, permet une connexion rapide et s\u00fbre. Dans les industries alimentaires et pharmaceutiques, un tel design est de plus en plus demand\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"L&#039;utilisation d&#039;un connecteur M12 sur la t\u00eate de raccordement d\u2019une sonde de temp\u00e9rature, plut\u00f4t que d&#039;une sortie de c\u00e2ble standard, permet une connexion rapide et s\u00fbre. Dans les industries alimentaires et pharmaceutiques, un tel design est de plus en plus demand\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2018\/07\/hygienegerechter-m12-anschlussstecker.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dominique Dumont\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dominique Dumont\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/\"},\"author\":{\"name\":\"Dominique Dumont\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/55e5985ae0bbddbbed66e5dca7f48ffd\"},\"headline\":\"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature\",\"datePublished\":\"2018-08-20T12:09:22+00:00\",\"dateModified\":\"2023-11-17T12:29:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/07\\\/hygienegerechter-m12-anschlussstecker.jpg\",\"articleSection\":[\"Applications\",\"Temp\u00e9rature\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/\",\"name\":\"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/07\\\/hygienegerechter-m12-anschlussstecker.jpg\",\"datePublished\":\"2018-08-20T12:09:22+00:00\",\"dateModified\":\"2023-11-17T12:29:33+00:00\",\"description\":\"L'utilisation d'un connecteur M12 sur la t\u00eate de raccordement d\u2019une sonde de temp\u00e9rature, plut\u00f4t que d'une sortie de c\u00e2ble standard, permet une connexion rapide et s\u00fbre. Dans les industries alimentaires et pharmaceutiques, un tel design est de plus en plus demand\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/07\\\/hygienegerechter-m12-anschlussstecker.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/07\\\/hygienegerechter-m12-anschlussstecker.jpg\",\"width\":837,\"height\":471,\"caption\":\"Hygienic M12 coupler connector\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/55e5985ae0bbddbbed66e5dca7f48ffd\",\"name\":\"Dominique Dumont\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/dumontdominique-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/dumontdominique-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/dumontdominique-140x140.jpg\",\"caption\":\"Dominique Dumont\"},\"description\":\"Form\u00e9 sur les chantiers, j\u2019ai acquis une grande connaissance des besoins clients et des complexit\u00e9s des proc\u00e9d\u00e9s industriels, cette exp\u00e9rience terrain associ\u00e9e \u00e0 ma capacit\u00e9 d\u2019\u00e9coute m\u2019ont permis de mieux r\u00e9pondre aux attentes et de trouver des solutions adapt\u00e9es au niveau technique et commercial. Aujourd\u2019hui en charge du d\u00e9veloppement des ventes focus Temp\u00e9rature chez Wika, je mets mon exp\u00e9rience et mes connaissances aux services des clients et aussi aux \u00e9quipes afin de toujours affiner notre compr\u00e9hension des proc\u00e9d\u00e9s et proposer des solutions innovantes.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/dumond\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature - Blog WIKA","description":"L'utilisation d'un connecteur M12 sur la t\u00eate de raccordement d\u2019une sonde de temp\u00e9rature, plut\u00f4t que d'une sortie de c\u00e2ble standard, permet une connexion rapide et s\u00fbre. Dans les industries alimentaires et pharmaceutiques, un tel design est de plus en plus demand\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/","og_locale":"fr_FR","og_type":"article","og_title":"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature - Blog WIKA","og_description":"L'utilisation d'un connecteur M12 sur la t\u00eate de raccordement d\u2019une sonde de temp\u00e9rature, plut\u00f4t que d'une sortie de c\u00e2ble standard, permet une connexion rapide et s\u00fbre. Dans les industries alimentaires et pharmaceutiques, un tel design est de plus en plus demand\u00e9.","og_url":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/","og_site_name":"Blog WIKA","og_image":[{"width":837,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2018\/07\/hygienegerechter-m12-anschlussstecker.jpg","type":"image\/jpeg"}],"author":"Dominique Dumont","twitter_misc":{"\u00c9crit par":"Dominique Dumont","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/"},"author":{"name":"Dominique Dumont","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/55e5985ae0bbddbbed66e5dca7f48ffd"},"headline":"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature","datePublished":"2018-08-20T12:09:22+00:00","dateModified":"2023-11-17T12:29:33+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/07\/hygienegerechter-m12-anschlussstecker.jpg","articleSection":["Applications","Temp\u00e9rature"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/","url":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/","name":"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/07\/hygienegerechter-m12-anschlussstecker.jpg","datePublished":"2018-08-20T12:09:22+00:00","dateModified":"2023-11-17T12:29:33+00:00","description":"L'utilisation d'un connecteur M12 sur la t\u00eate de raccordement d\u2019une sonde de temp\u00e9rature, plut\u00f4t que d'une sortie de c\u00e2ble standard, permet une connexion rapide et s\u00fbre. Dans les industries alimentaires et pharmaceutiques, un tel design est de plus en plus demand\u00e9.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2018\/07\/hygienegerechter-m12-anschlussstecker.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/07\/hygienegerechter-m12-anschlussstecker.jpg","width":837,"height":471,"caption":"Hygienic M12 coupler connector"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/connecteur-hygienique-sur-tete-de-raccordement-de-sonde-de-temperature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Connecteur hygi\u00e9nique sur t\u00eate de raccordement de sonde de temp\u00e9rature"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/55e5985ae0bbddbbed66e5dca7f48ffd","name":"Dominique Dumont","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/dumontdominique-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/dumontdominique-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/dumontdominique-140x140.jpg","caption":"Dominique Dumont"},"description":"Form\u00e9 sur les chantiers, j\u2019ai acquis une grande connaissance des besoins clients et des complexit\u00e9s des proc\u00e9d\u00e9s industriels, cette exp\u00e9rience terrain associ\u00e9e \u00e0 ma capacit\u00e9 d\u2019\u00e9coute m\u2019ont permis de mieux r\u00e9pondre aux attentes et de trouver des solutions adapt\u00e9es au niveau technique et commercial. Aujourd\u2019hui en charge du d\u00e9veloppement des ventes focus Temp\u00e9rature chez Wika, je mets mon exp\u00e9rience et mes connaissances aux services des clients et aussi aux \u00e9quipes afin de toujours affiner notre compr\u00e9hension des proc\u00e9d\u00e9s et proposer des solutions innovantes.","url":"https:\/\/blog.wika.com\/fr\/author\/dumond\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/176"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=7867"}],"version-history":[{"count":5,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7867\/revisions"}],"predecessor-version":[{"id":11413,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/7867\/revisions\/11413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/7868"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=7867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=7867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=7867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}