{"id":8023,"date":"2019-02-04T08:00:41","date_gmt":"2019-02-04T07:00:41","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=8023"},"modified":"2026-05-22T11:06:44","modified_gmt":"2026-05-22T09:06:44","slug":"integration-dun-capteur-de-pression-ceramique","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/","title":{"rendered":"Int\u00e9gration d&rsquo;un capteur de pression c\u00e9ramique"},"content":{"rendered":"<p><strong>Dans les applications critiques en termes d&rsquo;espace et de prix, le capteur de pression c\u00e9ramique offre une solution compacte et \u00e9conomique pour la mise en \u0153uvre d&rsquo;une mesure de pression int\u00e9gr\u00e9e dans l&rsquo;application du client. Cependant, il y a quelques \u00e9l\u00e9ments \u00e0 prendre en compte lors de l&rsquo;int\u00e9gration de la cellule c\u00e9ramique.<\/strong><\/p>\n<p>Par exemple, chaque capteur doit \u00eatre mesur\u00e9 et r\u00e9gl\u00e9. De plus, d\u2019autres points sont \u00e9galement \u00e0 consid\u00e9rer lors de l&rsquo;int\u00e9gration m\u00e9canique d&rsquo;un capteur c\u00e9ramique. Une \u00e9tanch\u00e9it\u00e9 axiale ou radiale doit \u00eatre r\u00e9alis\u00e9e au moyen d&rsquo;un joint torique avec une force de serrage adapt\u00e9e. Dans le cas d\u2019une \u00e9tanch\u00e9it\u00e9 axiale, cette force de serrage doit \u00eatre r\u00e9partie uniform\u00e9ment sur la circonf\u00e9rence du capteur et ne doit pas \u00eatre trop importante, ceci afin d&rsquo;\u00e9viter une d\u00e9formation du capteur et donc une mesure erron\u00e9e. Dans tous les cas, il faut \u00e9viter de serrer le capteur entre des corps solides sans joint d&rsquo;\u00e9tanch\u00e9it\u00e9.<\/p>\n<p><strong>Note<\/strong><\/p>\n<p>WIKA vous assiste volontiers avec des instructions de montage et de r\u00e9glage pour le capteur c\u00e9ramique mod\u00e8le SCT-1. Pour toutes questions et conseils d&rsquo;application d\u00e9taill\u00e9s sur les transmetteurs de pression et capteurs de WIKA,\u00a0<a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">votre interlocuteur WIKA<\/a> se fera un plaisir de vous renseigner.<\/p>\n<p><strong>Autres articles sur le m\u00eame sujet :<br \/>\n<\/strong><a href=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/precision-des-capteurs-de-pression\/\">Pr\u00e9cision des capteurs de pression \u2013 Qu\u2019est-ce que cela signifie exactement?<\/a><br \/>\n<a href=\"https:\/\/blog.wika.com\/products\/pressure-products\/which-are-the-available-configuration-levels-for-pressure-sensors\/\">Quels sont les configurations disponibles pour un capteur de pression ?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans les applications critiques en termes d&rsquo;espace et de prix, le capteur de pression c\u00e9ramique offre une solution compacte et \u00e9conomique pour la mise en \u0153uvre d&rsquo;une mesure de pression int\u00e9gr\u00e9e dans l&rsquo;application du client. Cependant, il y a quelques \u00e9l\u00e9ments \u00e0 prendre en compte lors de l&rsquo;int\u00e9gration de la cellule c\u00e9ramique. Par exemple, chaque [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":8024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232,220],"tags":[325],"class_list":["post-8023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","category-produits-pression","tag-capteur-cramique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Int\u00e9gration d&#039;un capteur de pression c\u00e9ramique - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Le capteur de pression c\u00e9ramique offre une solution compacte et \u00e9conomique pour une mesure de pression int\u00e9gr\u00e9e dans l\u2019application du client.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Int\u00e9gration d&#039;un capteur de pression c\u00e9ramique - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Le capteur de pression c\u00e9ramique offre une solution compacte et \u00e9conomique pour une mesure de pression int\u00e9gr\u00e9e dans l\u2019application du client.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2018\/11\/keramik-drucksensoren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philippe Bertrand\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Philippe Bertrand\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/\"},\"author\":{\"name\":\"Philippe Bertrand\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/dc2e89d85421ef1630df0d0ce555a825\"},\"headline\":\"Int\u00e9gration d&rsquo;un capteur de pression c\u00e9ramique\",\"datePublished\":\"2019-02-04T07:00:41+00:00\",\"dateModified\":\"2026-05-22T09:06:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/11\\\/keramik-drucksensoren.jpg\",\"keywords\":[\"capteur c\u00e9ramique\"],\"articleSection\":[\"Applications\",\"Pression\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/\",\"name\":\"Int\u00e9gration d'un capteur de pression c\u00e9ramique - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/11\\\/keramik-drucksensoren.jpg\",\"datePublished\":\"2019-02-04T07:00:41+00:00\",\"dateModified\":\"2026-05-22T09:06:44+00:00\",\"description\":\"Le capteur de pression c\u00e9ramique offre une solution compacte et \u00e9conomique pour une mesure de pression int\u00e9gr\u00e9e dans l\u2019application du client.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/11\\\/keramik-drucksensoren.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/11\\\/keramik-drucksensoren.jpg\",\"width\":838,\"height\":471,\"caption\":\"Capteurs de pression en c\u00e9ramique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/integration-dun-capteur-de-pression-ceramique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Int\u00e9gration d&#8217;un capteur de pression c\u00e9ramique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/dc2e89d85421ef1630df0d0ce555a825\",\"name\":\"Philippe Bertrand\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/05\\\/p_bertrand_blog-2-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/05\\\/p_bertrand_blog-2-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/05\\\/p_bertrand_blog-2-140x140.jpg\",\"caption\":\"Philippe Bertrand\"},\"description\":\"Depuis plus de 20 ans dans le domaine de l\u2019automatisme industriel, j\u2019ai d\u00e9velopp\u00e9 de r\u00e9elles comp\u00e9tences dans la vente de composants et le d\u00e9veloppement de projets aupr\u00e8s de diff\u00e9rentes typologies de clients tels que les fabricants de machine et les industries du process. Aujourd\u2019hui, en charge du d\u00e9veloppement de la gamme WIKA des produits de mesure de pression \u00e9lectronique, je serais votre interlocuteur privil\u00e9gi\u00e9 pour r\u00e9pondre \u00e0 vos questions et serais heureux de partager mon expertise afin de solutionner vos besoins actuels et futurs.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/bertrandp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Int\u00e9gration d'un capteur de pression c\u00e9ramique - Blog WIKA","description":"Le capteur de pression c\u00e9ramique offre une solution compacte et \u00e9conomique pour une mesure de pression int\u00e9gr\u00e9e dans l\u2019application du client.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/","og_locale":"fr_FR","og_type":"article","og_title":"Int\u00e9gration d'un capteur de pression c\u00e9ramique - Blog WIKA","og_description":"Le capteur de pression c\u00e9ramique offre une solution compacte et \u00e9conomique pour une mesure de pression int\u00e9gr\u00e9e dans l\u2019application du client.","og_url":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2018\/11\/keramik-drucksensoren.jpg","type":"image\/jpeg"}],"author":"Philippe Bertrand","twitter_misc":{"\u00c9crit par":"Philippe Bertrand","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/"},"author":{"name":"Philippe Bertrand","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/dc2e89d85421ef1630df0d0ce555a825"},"headline":"Int\u00e9gration d&rsquo;un capteur de pression c\u00e9ramique","datePublished":"2019-02-04T07:00:41+00:00","dateModified":"2026-05-22T09:06:44+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/11\/keramik-drucksensoren.jpg","keywords":["capteur c\u00e9ramique"],"articleSection":["Applications","Pression"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/","url":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/","name":"Int\u00e9gration d'un capteur de pression c\u00e9ramique - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/11\/keramik-drucksensoren.jpg","datePublished":"2019-02-04T07:00:41+00:00","dateModified":"2026-05-22T09:06:44+00:00","description":"Le capteur de pression c\u00e9ramique offre une solution compacte et \u00e9conomique pour une mesure de pression int\u00e9gr\u00e9e dans l\u2019application du client.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2018\/11\/keramik-drucksensoren.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/11\/keramik-drucksensoren.jpg","width":838,"height":471,"caption":"Capteurs de pression en c\u00e9ramique"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/integration-dun-capteur-de-pression-ceramique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Int\u00e9gration d&#8217;un capteur de pression c\u00e9ramique"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/dc2e89d85421ef1630df0d0ce555a825","name":"Philippe Bertrand","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2018\/05\/p_bertrand_blog-2-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2018\/05\/p_bertrand_blog-2-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/05\/p_bertrand_blog-2-140x140.jpg","caption":"Philippe Bertrand"},"description":"Depuis plus de 20 ans dans le domaine de l\u2019automatisme industriel, j\u2019ai d\u00e9velopp\u00e9 de r\u00e9elles comp\u00e9tences dans la vente de composants et le d\u00e9veloppement de projets aupr\u00e8s de diff\u00e9rentes typologies de clients tels que les fabricants de machine et les industries du process. Aujourd\u2019hui, en charge du d\u00e9veloppement de la gamme WIKA des produits de mesure de pression \u00e9lectronique, je serais votre interlocuteur privil\u00e9gi\u00e9 pour r\u00e9pondre \u00e0 vos questions et serais heureux de partager mon expertise afin de solutionner vos besoins actuels et futurs.","url":"https:\/\/blog.wika.com\/fr\/author\/bertrandp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=8023"}],"version-history":[{"count":7,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8023\/revisions"}],"predecessor-version":[{"id":13005,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8023\/revisions\/13005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/8024"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=8023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=8023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=8023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}