{"id":8172,"date":"2019-06-10T08:38:11","date_gmt":"2019-06-10T06:38:11","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=8172"},"modified":"2023-11-20T10:20:24","modified_gmt":"2023-11-20T09:20:24","slug":"cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/","title":{"rendered":"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage"},"content":{"rendered":"<p><strong>La validation des logiciels d&rsquo;\u00e9talonnage \u2013 tel qu\u2019exig\u00e9e dans la norme ISO 17025, par exemple \u2013 soul\u00e8ve un certain nombre de questions : Quel logiciel doit \u00eatre valid\u00e9 ? Qui doit s&rsquo;en occuper ? Quelles exigences doivent \u00eatre satisfaites par la validation ? Comment le faire efficacement et comment le documenter ? Pour vous aider, nous partageons notre exp\u00e9rience et recommandons la mise en \u0153uvre de cette validation en cinq \u00e9tapes.<\/strong><\/p>\n<p>Dans un laboratoire d&rsquo;\u00e9talonnage, les logiciels sont utilis\u00e9s, entre autres, dans le process d&rsquo;\u00e9valuation jusqu&rsquo;aux \u00e9talonnages totalement automatique. Quel que soit le degr\u00e9 d&rsquo;automatisation du logiciel, la validation fait toujours r\u00e9f\u00e9rence aux process complets dans lesquels le programme est int\u00e9gr\u00e9. Derri\u00e8re la validation se cache donc la question fondamentale de savoir si le process d&rsquo;\u00e9talonnage remplit son r\u00f4le et s&rsquo;il atteint tous les objectifs vis\u00e9s, c&rsquo;est-\u00e0-dire s&rsquo;il fournit la fonctionnalit\u00e9 requise avec une pr\u00e9cision suffisante.<\/p>\n<p>Si vous souhaitez r\u00e9aliser un test de validation, vous devez conna\u00eetre les deux principes de base des tests logiciels :<\/p>\n<ol>\n<li>Un test complet n&rsquo;est pas possible<\/li>\n<li>Les tests d\u00e9pendent toujours de l&rsquo;environnement<\/li>\n<\/ol>\n<p>Le premier indique que le test comprenant toutes les entr\u00e9es et configurations possibles d&rsquo;un programme ne peut pas \u00eatre effectu\u00e9 en raison du trop grand nombre de combinaisons possibles. En fonction de l&rsquo;application, l&rsquo;utilisateur doit toujours d\u00e9cider quelles fonctionnalit\u00e9s, quelles configurations et quelles caract\u00e9ristiques li\u00e9es \u00e0 la qualit\u00e9 doivent \u00eatre prioritaires et celles qui ne le sont pas.<\/p>\n<p>La d\u00e9cision qui est prise d\u00e9pend souvent du deuxi\u00e8me point &#8211; l&rsquo;environnement d&rsquo;exploitation du logiciel. Il y a toujours des exigences et des priorit\u00e9s pour l&rsquo;utilisation du logiciel qui diff\u00e9rent en fonction de l&rsquo;application. Le logiciel est \u00e9galement adapt\u00e9 aux besoins sp\u00e9cifiques du client, par exemple en ce qui concerne le contenu du certificat. Les conditions environnementales du laboratoire, avec sa large gamme d&rsquo;instruments, g\u00e9n\u00e8rent aussi des diff\u00e9rences. La grande vari\u00e9t\u00e9 d&rsquo;exigences et la complexit\u00e9 infinie des configurations logicielles dans les domaines d&rsquo;application client rendent donc impossible pour un fabricant la possibilit\u00e9 de tester tous les pr\u00e9requis sp\u00e9cifiques d&rsquo;un client.<\/p>\n<p>En cons\u00e9quence, compte tenu des points \u00e9nonc\u00e9s ci-dessus, la validation incombe \u00e0 l&rsquo;utilisateur lui-m\u00eame. Afin de rendre ce process aussi efficace que possible, il est recommand\u00e9 de suivre la proc\u00e9dure en cinq points suivante :<\/p>\n<ol>\n<li>Les donn\u00e9es des configurations d&rsquo;\u00e9talonnage typiques doivent \u00eatre d\u00e9finies comme des \u00ab\u00a0ensembles d&rsquo;essai\u00a0\u00bb<\/li>\n<li>A intervalles r\u00e9guliers, g\u00e9n\u00e9ralement une fois par an, mais au moins apr\u00e8s toute mise \u00e0 jour du logiciel, ces ensembles de tests doivent \u00eatre programm\u00e9s dans le logiciel.<\/li>\n<li>Les certificats obtenus doivent pouvoir \u00eatre compar\u00e9s \u00e0 ceux de la version pr\u00e9c\u00e9dente<\/li>\n<li>Dans le cas d&rsquo;une premi\u00e8re validation, un contr\u00f4le crois\u00e9, par exemple via MS Excel, peut avoir lieu<\/li>\n<li>Les preuves de validation doivent \u00eatre consign\u00e9es et archiv\u00e9es<\/li>\n<\/ol>\n<p>WIKA fournit sur demande une documentation PDF des calculs effectu\u00e9s dans ses logiciels.<\/p>\n<h2>Note<\/h2>\n<p>Pour plus d&rsquo;informations sur nos <a href=\"https:\/\/www.wika.com\/fr-fr\/wika_cal.WIKA\" rel=\"external\" target=\"_blank\">logiciels d&rsquo;\u00e9talonnage<\/a> et nos <a href=\"https:\/\/www.wika.com\/fr-fr\/service_d_etalonnage.WIKA\" rel=\"external\" target=\"_blank\">laboratoires d&rsquo;\u00e9talonnage<\/a>, visitez le site web de <a href=\"https:\/\/www.wika.com\/fr-fr\/page_d_accueil.WIKA\" rel=\"external\" target=\"_blank\">WIKA<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La validation des logiciels d&rsquo;\u00e9talonnage \u2013 tel qu\u2019exig\u00e9e dans la norme ISO 17025, par exemple \u2013 soul\u00e8ve un certain nombre de questions : Quel logiciel doit \u00eatre valid\u00e9 ? Qui doit s&rsquo;en occuper ? Quelles exigences doivent \u00eatre satisfaites par la validation ? Comment le faire efficacement et comment le documenter ? Pour vous aider, [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":8173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-8172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-savoir-faire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage - Blog WIKA<\/title>\n<meta name=\"description\" content=\"La validation des logiciels d&#039;\u00e9talonnage soul\u00e8ve un certain nombre de questions. Pour vous aider, voici la mise en \u0153uvre de cette validation en cinq \u00e9tapes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La validation des logiciels d&#039;\u00e9talonnage soul\u00e8ve un certain nombre de questions. Pour vous aider, voici la mise en \u0153uvre de cette validation en cinq \u00e9tapes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2019\/05\/validate_blog-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas Chevin\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas Chevin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/\"},\"author\":{\"name\":\"Nicolas Chevin\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/a4d6253f6cb517f7f0fcde44426a5e92\"},\"headline\":\"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage\",\"datePublished\":\"2019-06-10T06:38:11+00:00\",\"dateModified\":\"2023-11-20T09:20:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/\"},\"wordCount\":562,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/05\\\/validate_blog-1.jpg\",\"articleSection\":[\"Savoir-faire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/\",\"name\":\"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/05\\\/validate_blog-1.jpg\",\"datePublished\":\"2019-06-10T06:38:11+00:00\",\"dateModified\":\"2023-11-20T09:20:24+00:00\",\"description\":\"La validation des logiciels d'\u00e9talonnage soul\u00e8ve un certain nombre de questions. Pour vous aider, voici la mise en \u0153uvre de cette validation en cinq \u00e9tapes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/05\\\/validate_blog-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/05\\\/validate_blog-1.jpg\",\"width\":838,\"height\":471,\"caption\":\"validation des logiciels d\u2019\u00e9talonnage\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/a4d6253f6cb517f7f0fcde44426a5e92\",\"name\":\"Nicolas Chevin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"caption\":\"Nicolas Chevin\"},\"description\":\"D\u00e9sormais en charge de la gamme de produits \u00ab Calibration \u00bb, et fort d\u2019une exp\u00e9rience de 15 ans dans le domaine de l\u2019instrumentation de mesure et de la m\u00e9trologie, je serai votre contact privil\u00e9gi\u00e9 pour toute demande d\u2019information sur le mat\u00e9riel d\u2019\u00e9talonnage mais aussi sur les services associ\u00e9s propos\u00e9s par notre Laboratoire COFRAC chez Wika\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/fraisso\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage - Blog WIKA","description":"La validation des logiciels d'\u00e9talonnage soul\u00e8ve un certain nombre de questions. Pour vous aider, voici la mise en \u0153uvre de cette validation en cinq \u00e9tapes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/","og_locale":"fr_FR","og_type":"article","og_title":"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage - Blog WIKA","og_description":"La validation des logiciels d'\u00e9talonnage soul\u00e8ve un certain nombre de questions. Pour vous aider, voici la mise en \u0153uvre de cette validation en cinq \u00e9tapes.","og_url":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2019\/05\/validate_blog-1.jpg","type":"image\/jpeg"}],"author":"Nicolas Chevin","twitter_misc":{"\u00c9crit par":"Nicolas Chevin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/"},"author":{"name":"Nicolas Chevin","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/a4d6253f6cb517f7f0fcde44426a5e92"},"headline":"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage","datePublished":"2019-06-10T06:38:11+00:00","dateModified":"2023-11-20T09:20:24+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/"},"wordCount":562,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2019\/05\/validate_blog-1.jpg","articleSection":["Savoir-faire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/","url":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/","name":"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2019\/05\/validate_blog-1.jpg","datePublished":"2019-06-10T06:38:11+00:00","dateModified":"2023-11-20T09:20:24+00:00","description":"La validation des logiciels d'\u00e9talonnage soul\u00e8ve un certain nombre de questions. Pour vous aider, voici la mise en \u0153uvre de cette validation en cinq \u00e9tapes.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2019\/05\/validate_blog-1.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2019\/05\/validate_blog-1.jpg","width":838,"height":471,"caption":"validation des logiciels d\u2019\u00e9talonnage"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/cinq-points-connaitre-sur-la-validation-des-logiciels-d-etalonnage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Cinq points \u00e0 conna\u00eetre sur la validation des logiciels d\u2019\u00e9talonnage"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/a4d6253f6cb517f7f0fcde44426a5e92","name":"Nicolas Chevin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","caption":"Nicolas Chevin"},"description":"D\u00e9sormais en charge de la gamme de produits \u00ab Calibration \u00bb, et fort d\u2019une exp\u00e9rience de 15 ans dans le domaine de l\u2019instrumentation de mesure et de la m\u00e9trologie, je serai votre contact privil\u00e9gi\u00e9 pour toute demande d\u2019information sur le mat\u00e9riel d\u2019\u00e9talonnage mais aussi sur les services associ\u00e9s propos\u00e9s par notre Laboratoire COFRAC chez Wika","url":"https:\/\/blog.wika.com\/fr\/author\/fraisso\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=8172"}],"version-history":[{"count":6,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8172\/revisions"}],"predecessor-version":[{"id":11484,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8172\/revisions\/11484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/8173"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=8172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=8172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=8172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}