{"id":8548,"date":"2020-01-13T08:09:28","date_gmt":"2020-01-13T07:09:28","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=8548"},"modified":"2023-11-20T10:29:48","modified_gmt":"2023-11-20T09:29:48","slug":"le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/","title":{"rendered":"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l&rsquo;humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations."},"content":{"rendered":"<p><strong>Le SF<sub>6<\/sub> pur est un excellent isolant dans les appareillages \u00e9lectriques, mais l&rsquo;humidit\u00e9 dans le gaz diminue son pouvoir isolant et peut \u00e9galement entra\u00eener des produits de d\u00e9composition tr\u00e8s nocifs pour l&rsquo;homme, les machines et l&rsquo;environnement. Cr\u00e9\u00e9 en partenariat avec une soci\u00e9t\u00e9 europ\u00e9enne de services publics, le GAD-2000 r\u00e9volutionnaire de WIKA \u00e9limine non seulement l&rsquo;humidit\u00e9 du gaz SF<sub>6<\/sub> et d\u00e9shydrate le compartiment lui-m\u00eame, mais il le fait aussi pendant que tout l&rsquo;\u00e9quipement est encore en ligne.<\/strong><\/p>\n<p>L&rsquo;hexafluorure de soufre (SF<sub>6<\/sub>) est un excellent isolant di\u00e9lectrique que l&rsquo;on trouve couramment dans les appareillages \u00e9lectriques moyenne et haute tension. Ce gaz ininflammable est un puissant agent d&rsquo;extinction d&rsquo;arc : dans l&rsquo;environnement \u00e0 haute temp\u00e9rature d&rsquo;une d\u00e9charge \u00e9lectrique, les six atomes de fluor se s\u00e9parent de l&rsquo;atome de soufre pour capturer un \u00e9lectron. Apr\u00e8s l&rsquo;extinction de la d\u00e9charge, la mol\u00e9cule se reconstitue rapidement. De plus, le gaz SF<sub>6<\/sub> n&rsquo;est pas toxique.<\/p>\n<p>Cependant, l&rsquo;humidit\u00e9 dans le gaz cause de graves probl\u00e8mes de fonctionnement et de s\u00e9curit\u00e9. <a href=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/eau-limpurete-la-plus-puissante-du-sf6\/\">L&rsquo;eau est une impuret\u00e9<\/a> qui, par sa pr\u00e9sence m\u00eame, diminue la rigidit\u00e9 di\u00e9lectrique globale du syst\u00e8me. L\u2019H<sub>2<\/sub>O emp\u00eache \u00e9galement le soufre et le fluorure de se recombiner compl\u00e8tement. Lorsque le SF<sub>6<\/sub> ne \u00ab\u00a0s&rsquo;auto-r\u00e9g\u00e9n\u00e8re\u00a0\u00bb pas compl\u00e8tement apr\u00e8s chaque arc \u00e9lectrique, il y en a de moins en moins. De plus, le soufre et le fluor s\u00e9par\u00e9s peuvent se combiner aux mol\u00e9cules d&rsquo;oxyg\u00e8ne de l&rsquo;eau pour cr\u00e9er des sous-produits toxiques : t\u00e9trafluorure de thionyle (SOF<sub>4<\/sub>), fluorure de thionyle (SOF<sub>2<\/sub>), fluorure de sulfuryle (SO<sub>2<\/sub>F<sub>2<\/sub>) et dioxyde de soufre (SO<sub>2<\/sub>). Cet environnement acide et corrosif endommage les \u00e9quipements, entra\u00eenant des fuites qui peuvent mettre en danger le personnel et l&rsquo;environnement (le SF<sub>6 <\/sub>est un puissant gaz \u00e0 effet de serre).<\/p>\n<p>Afin de maintenir une bonne isolation et d&rsquo;\u00e9viter la corrosion et les conditions critiques, les op\u00e9rateurs enl\u00e8vent r\u00e9guli\u00e8rement l&rsquo;humidit\u00e9 du gaz pour la maintenir sous le point de saturation de l&rsquo;eau. Jusqu&rsquo;\u00e0 r\u00e9cemment, la seule fa\u00e7on de d\u00e9shydrater le SF<sub>6<\/sub> consistait \u00e0 d\u00e9brancher l&rsquo;appareillage de commutation \u00e0 isolation gazeuse (GIS), \u00e0 \u00e9vacuer le gaz, \u00e0 le faire passer dans une <a href=\"https:\/\/www.wika.com\/fr-fr\/gpu_s_3000.WIKA?highlightedText=gpu\" rel=\"external\" target=\"_blank\">unit\u00e9 de traitement des gaz<\/a> avec filtres de d\u00e9shydratation, \u00e0 remplir le GIS avec le gaz s\u00e9ch\u00e9, puis \u00e0 remettre le syst\u00e8me en fonction. Il peut s&rsquo;agir d&rsquo;un processus qui prend beaucoup de temps et qui n\u00e9cessite l&rsquo;arr\u00eat d&rsquo;une centrale \u00e9lectrique.<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2019\/12\/gad_2000-388x388-388x388.png\" alt=\"Le nouveau syst\u00e8me de d\u00e9shydratation de gaz SF6 GAD-2000 de WIKA \u00e9limine l'humidit\u00e9 pendant que les op\u00e9rations se poursuivent comme d'habitude\" \/><p class=\"wp-caption-text\">Le nouveau syst\u00e8me de d\u00e9shydratation de gaz SF<sub>6<\/sub> GAD-2000 de WIKA \u00e9limine l&rsquo;humidit\u00e9 pendant que les op\u00e9rations se poursuivent comme d&rsquo;habitude<\/p><\/div>\n    \n<h2>\u00c9limination en ligne de l&rsquo;humidit\u00e9 du gaz SF<sub>6<\/sub><\/h2>\n<p>Une entreprise de services publics en Europe avait besoin d&rsquo;un appareil capable d&rsquo;ass\u00e9cher le gaz SF<sub>6<\/sub> alors que tout l&rsquo;\u00e9quipement \u00e9tait encore en service. Il avait m\u00eame un brevet pour une telle unit\u00e9. Ce qu&rsquo;il n&rsquo;avait pas, c&rsquo;\u00e9tait les ressources n\u00e9cessaires pour le d\u00e9velopper et le fabriquer.<\/p>\n<p>Sachant que WIKA est un leader dans l&rsquo;industrie du transport et de la distribution d&rsquo;\u00e9nergie, la soci\u00e9t\u00e9 de services publics a demand\u00e9 l&rsquo;aide de nos experts du SF<sub>6<\/sub>. C\u2019est ainsi qu\u2019est n\u00e9 le <a href=\"https:\/\/www.wika.com\/fr-fr\/gad_2000.WIKA?Group=6804&amp;tab=1\" rel=\"external\" target=\"_blank\">GAD-2000<\/a>.<\/p>\n<p>Ce d\u00e9shydrateur de gaz r\u00e9volutionnaire enl\u00e8ve une partie du SF<sub>6<\/sub> du SIG, fait passer le gaz \u00e0 travers une s\u00e9rie de compresseurs sans huile et deux filtres absorbant l&rsquo;eau, puis retourne le gaz s\u00e9ch\u00e9 dans le SIG. Ce processus est r\u00e9p\u00e9t\u00e9 jusqu&rsquo;\u00e0 ce que le niveau d&rsquo;eau dans le gaz soit inf\u00e9rieur au point de saturation ou atteigne une valeur souhait\u00e9e. Comme le GAD-2000 d\u00e9shydrate automatiquement le gaz pendant que le SIG est encore en ligne, il y a peu ou pas de temps d&rsquo;arr\u00eat, ni d&rsquo;intervention humaine. Lorsqu&rsquo;un technicien doit interagir avec le d\u00e9shydrateur de gaz, l&rsquo;\u00e9cran tactile de 7 pouces est facile et intuitif \u00e0 utiliser.<\/p>\n<h2>S\u00e9curit\u00e9 de la centrale : Une priorit\u00e9 dans la manipulation des gaz SF<sub>6<\/sub><\/h2>\n<p>\u00c9tant donn\u00e9 que le SF<sub>6<\/sub> est un gaz potentiellement dangereux et un composant critique du syst\u00e8me, il n\u00e9cessite un syst\u00e8me de s\u00e9curit\u00e9 robuste et une manipulation extr\u00eamement prudente. Le GAD-2000 dispose d&rsquo;un compartiment \u00e0 gaz automatique qui isole le SF<sub>6<\/sub> dans un module de s\u00e9curit\u00e9 pendant l&rsquo;extraction et le remplissage, en cas d&rsquo;erreur. L&rsquo;appareil peut, en option, contr\u00f4ler en continu l&rsquo;instrumentation de surveillance \u00e0 partir du compartiment \u00e0 gaz et dispose en outre d&rsquo;une commande de s\u00e9curit\u00e9 SIL2 impl\u00e9ment\u00e9e.<\/p>\n<p>De plus, le GAD-2000 peut \u00eatre \u00e9quip\u00e9 en option d&rsquo;un module GSM (Global System for Mobile communications) pour transf\u00e9rer les donn\u00e9es directement sur un appareil mobile. Une fois install\u00e9, l&rsquo;op\u00e9rateur peut laisser l&rsquo;appareil fonctionner automatiquement et recevoir \u00e0 distance des informations sur :<\/p>\n<ul>\n<li>Le taux d&rsquo;humidit\u00e9 actuel dans le compartiment \u00e0 gaz<\/li>\n<li>Les conditions de filtrage<\/li>\n<li>Le travail achev\u00e9<\/li>\n<\/ul>\n<p>Le GAD-2000 est une unit\u00e9 de d\u00e9shydratation de gaz tr\u00e8s efficace et efficiente qui permet \u00e0 une centrale \u00e9lectrique de continuer \u00e0 fonctionner normalement tout en maintenant les niveaux d&rsquo;humidit\u00e9 s\u00e9curitaires du gaz SF<sub>6<\/sub> dans les tableaux de distribution. Pour en savoir plus sur le GAD-2000 et les autres \u00e9quipements d&rsquo;\u00e9puration, de manutention et d&rsquo;entretien des gaz SF<sub>6<\/sub> de WIKA, <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">contactez nos sp\u00e9cialistes<\/a> en transmission et distribution de puissance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le SF6 pur est un excellent isolant dans les appareillages \u00e9lectriques, mais l&rsquo;humidit\u00e9 dans le gaz diminue son pouvoir isolant et peut \u00e9galement entra\u00eener des produits de d\u00e9composition tr\u00e8s nocifs pour l&rsquo;homme, les machines et l&rsquo;environnement. Cr\u00e9\u00e9 en partenariat avec une soci\u00e9t\u00e9 europ\u00e9enne de services publics, le GAD-2000 r\u00e9volutionnaire de WIKA \u00e9limine non seulement l&rsquo;humidit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":8550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[333,332],"class_list":["post-8548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produits","tag-dshumidificateur","tag-sf6"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l&#039;humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations. - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Le d\u00e9shumidificateur de gaz type GAD-2000 WIKA \u00e9limine l&#039;humidit\u00e9 du gaz SF6 et d\u00e9shydrate le compartiment lui-m\u00eame pendant que l&#039;\u00e9quipement est en marche\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l&#039;humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations. - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9shumidificateur de gaz type GAD-2000 WIKA \u00e9limine l&#039;humidit\u00e9 du gaz SF6 et d\u00e9shydrate le compartiment lui-m\u00eame pendant que l&#039;\u00e9quipement est en marche\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2019\/12\/sf6_deshumidificateur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l&rsquo;humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations.\",\"datePublished\":\"2020-01-13T07:09:28+00:00\",\"dateModified\":\"2023-11-20T09:29:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/\"},\"wordCount\":970,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/12\\\/sf6_deshumidificateur.jpg\",\"keywords\":[\"d\u00e9shumidificateur\",\"SF6\"],\"articleSection\":[\"Produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/\",\"name\":\"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l'humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations. - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/12\\\/sf6_deshumidificateur.jpg\",\"datePublished\":\"2020-01-13T07:09:28+00:00\",\"dateModified\":\"2023-11-20T09:29:48+00:00\",\"description\":\"Le d\u00e9shumidificateur de gaz type GAD-2000 WIKA \u00e9limine l'humidit\u00e9 du gaz SF6 et d\u00e9shydrate le compartiment lui-m\u00eame pendant que l'\u00e9quipement est en marche\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/12\\\/sf6_deshumidificateur.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/12\\\/sf6_deshumidificateur.jpg\",\"width\":838,\"height\":471,\"caption\":\"SF6_deshumidificateur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l&rsquo;humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l'humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations. - Blog WIKA","description":"Le d\u00e9shumidificateur de gaz type GAD-2000 WIKA \u00e9limine l'humidit\u00e9 du gaz SF6 et d\u00e9shydrate le compartiment lui-m\u00eame pendant que l'\u00e9quipement est en marche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/","og_locale":"fr_FR","og_type":"article","og_title":"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l'humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations. - Blog WIKA","og_description":"Le d\u00e9shumidificateur de gaz type GAD-2000 WIKA \u00e9limine l'humidit\u00e9 du gaz SF6 et d\u00e9shydrate le compartiment lui-m\u00eame pendant que l'\u00e9quipement est en marche","og_url":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2019\/12\/sf6_deshumidificateur.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l&rsquo;humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations.","datePublished":"2020-01-13T07:09:28+00:00","dateModified":"2023-11-20T09:29:48+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/"},"wordCount":970,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2019\/12\/sf6_deshumidificateur.jpg","keywords":["d\u00e9shumidificateur","SF6"],"articleSection":["Produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/","url":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/","name":"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l'humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations. - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2019\/12\/sf6_deshumidificateur.jpg","datePublished":"2020-01-13T07:09:28+00:00","dateModified":"2023-11-20T09:29:48+00:00","description":"Le d\u00e9shumidificateur de gaz type GAD-2000 WIKA \u00e9limine l'humidit\u00e9 du gaz SF6 et d\u00e9shydrate le compartiment lui-m\u00eame pendant que l'\u00e9quipement est en marche","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2019\/12\/sf6_deshumidificateur.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2019\/12\/sf6_deshumidificateur.jpg","width":838,"height":471,"caption":"SF6_deshumidificateur"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/produits\/le-deshydrateur-innovant-gad-2000-wika-elimine-lhumidite-du-gaz-sf6-sans-arreter-les-operations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le d\u00e9shydrateur innovant GAD-2000 WIKA \u00e9limine l&rsquo;humidit\u00e9 du gaz SF6 sans arr\u00eater les op\u00e9rations."}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=8548"}],"version-history":[{"count":5,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8548\/revisions"}],"predecessor-version":[{"id":11489,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8548\/revisions\/11489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/8550"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=8548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=8548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=8548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}