{"id":8587,"date":"2020-02-10T08:17:18","date_gmt":"2020-02-10T07:17:18","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=8587"},"modified":"2023-11-20T08:07:03","modified_gmt":"2023-11-20T07:07:03","slug":"etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/","title":{"rendered":"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client"},"content":{"rendered":"<p><strong>Une entreprise du secteur de l&rsquo;\u00e9nergie et de l&rsquo;eau\/eaux us\u00e9es a contact\u00e9 WIKA pour installer un montage sur s\u00e9parateur sur un pipeline avec un faible d\u00e9gagement, ainsi qu\u2019une exigence sp\u00e9cifique : Le manom\u00e8tre process devait \u00eatre lisible des deux c\u00f4t\u00e9s. La division \u00ab\u00a0S\u00e9parateurs\u00a0\u00bb de WIKA a con\u00e7u une solution sur mesure qui r\u00e9pondait aux besoins pr\u00e9cis du client.<\/strong><\/p>\n<p>Les industries allant de la p\u00e9trochimie \u00e0 la pharmacie utilisent des <a href=\"https:\/\/www.wika.com\/fr-fr\/separateurs.WIKA\" rel=\"external\" target=\"_blank\">s\u00e9parateurs<\/a> pour mesurer la pression. Dot\u00e9 d&rsquo;une membrane m\u00e9tallique \u00e0 la fois solide et flexible, un syst\u00e8me de <a href=\"https:\/\/www.wika.com\/fr-fr\/montages_sur_separateur.WIKA\" rel=\"external\" target=\"_blank\">montage sur s\u00e9parateur<\/a> garantit que les fluides sanitaires restent s\u00e9par\u00e9s des m\u00e9canismes internes d&rsquo;un manom\u00e8tre, afin d&rsquo;\u00e9viter de contaminer le produit. \u00c0 l&rsquo;inverse, la membrane prot\u00e8ge les capteurs de pression sensibles des temp\u00e9ratures extr\u00eames et\/ou des milieux agressifs. Les montages sur s\u00e9parateur sont \u00e9galement utiles lorsqu&rsquo;il est difficile de fixer directement un instrument de pression sur un raccord process.<\/p>\n<p>Un montage sur s\u00e9parateur est constitu\u00e9 de :<\/p>\n<ul>\n<li>Une membrane flexible<\/li>\n<li>Des raccords ou des brides permettant le montage direct sur une conduite<\/li>\n<li>Un manom\u00e8tre ou un capteur reli\u00e9 au corps sup\u00e9rieur de la membrane<\/li>\n<li>Un liquide de remplissage du syst\u00e8me qui occupe l&rsquo;espace interne entre la membrane et l&rsquo;instrument de mesure<\/li>\n<\/ul>\n<p>La pression du fluide passe de la membrane au fluide de remplissage du syst\u00e8me, et la pression r\u00e9sultante est transmise \u00e0 l&rsquo;instrument de mesure.<\/p>\n<h2>Double d\u00e9fi : Contraintes spatiales et lectures bilat\u00e9rales<\/h2>\n<p>Une grande entreprise am\u00e9ricaine du secteur de l&rsquo;\u00e9nergie et des eaux\/eaux us\u00e9es avait des difficult\u00e9s \u00e0 relever les pressions du process dans le pipeline d&rsquo;une application d&rsquo;acide. Le premier d\u00e9fi \u00e9tait d\u2019avoir un espace limit\u00e9. En effet, le r\u00e9seau a\u00e9rien de tuyauteries de faible hauteur ne laissait que peu de place pour un assemblage de grande taille. Le client voulait \u00e9galement pouvoir lire le manom\u00e8tre de chaque c\u00f4t\u00e9 de la conduite.<\/p>\n<h2>La solution : Un montage sur s\u00e9parateur sur mesure<\/h2>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:213px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/232_34_233_34.png\" alt=\"Manom\u00e8tre process XSEL\u00ae type 23X.34\" \/><p class=\"wp-caption-text\">Manom\u00e8tre process XSEL\u00ae type 23X.34<\/p><\/div>\n    \n<p>WIKA dispose d&rsquo;une large gamme de s\u00e9parateurs standards \u00e0 membrane, mais aucun d&rsquo;entre eux ne r\u00e9pondaient aux exigences sp\u00e9cifiques de ce client. La situation exigeait une solution sur mesure .<\/p>\n<p>Pour ce montage sur mesure, l&rsquo;\u00e9quipe d&rsquo;ing\u00e9nieurs de WIKA a utilis\u00e9 deux <a href=\"https:\/\/www.wika.com\/fr-fr\/232_34_233_34.WIKA\" rel=\"external\" target=\"_blank\">manom\u00e8tres de process XSEL\u00ae<\/a> dos \u00e0 dos avec une plage de 300 psi. Comme une seule membrane devait pousser contre deux manom\u00e8tres, l&#8217;embout a \u00e9t\u00e9 con\u00e7u sur mesure pour pouvoir s&rsquo;adapter aux deux instruments, en minimisant le volume. Ce dernier a \u00e9t\u00e9 calcul\u00e9 pour pouvoir utiliser les manom\u00e8tres sur toute leur plage.<\/p>\n\n      <div class=\"wp-caption alignleft\" style=\"max-width:199px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/990_41.png\" alt=\"Membrane d'\u00e9tanch\u00e9it\u00e9 avec raccord \u00e0 bride type 990.41\" \/><p class=\"wp-caption-text\">Membrane d&rsquo;\u00e9tanch\u00e9it\u00e9 avec raccord \u00e0 bride type 990.41<\/p><\/div>\n    \n<p>WIKA a utilis\u00e9 un s\u00e9parateur avec une membrane de 100mm en acier inox 316L. Les ing\u00e9nieurs ont personnalis\u00e9 le mod\u00e8le <a href=\"https:\/\/www.wika.com\/fr-fr\/990_41.WIKA\" rel=\"external\" target=\"_blank\">990.41<\/a> avec une conception boulonn\u00e9 et ont recouvert la face inf\u00e9rieure de PFA pour une protection suppl\u00e9mentaire contre les effets corrosifs de l&rsquo;acide. Une membrane en retrait permet des mesures pr\u00e9cises m\u00eame avec un raccord process de petite dimension &#8211; dans ce cas, une bride ASME DN25mm en classe 150 lbs. L&rsquo;ensemble comprend une membrane soud\u00e9e \u00e0 la bride sup\u00e9rieure, les parties sup\u00e9rieures et inf\u00e9rieures de la bride sont boulonn\u00e9s ensemble. Des trous de fixation usin\u00e9s dans la bride inf\u00e9rieure sont utilis\u00e9s pour le raccordement au process. En ce qui concerne le fluide de remplissage du syst\u00e8me, les ing\u00e9nieurs ont opt\u00e9 pour le KN2 \u00e0 base de silicone, couramment pour les usages g\u00e9n\u00e9raux dans le process. L\u2019ensemble de mesure a \u00e9t\u00e9 mont\u00e9 directement sur la canalisation \u00e0 l&rsquo;aide du raccord process \u00e0 bride.<\/p>\n<p>Trois raisons ont motiv\u00e9 le choix de l&rsquo;assemblage direct plut\u00f4t que des extensions capillaires : les limitations en volume du syst\u00e8me, les contraintes d&rsquo;espace qui ont emp\u00each\u00e9 un syst\u00e8me de grande taille et la r\u00e9ticence du client \u00e0 ajouter des supports sur la canalisation pour maintenir les manom\u00e8tres. L&rsquo;assemblage direct offre \u00e9galement une bonne protection contre les surcharges, car la membrane peut s&rsquo;appuyer sur la bride.<\/p>\n<p>Le client a \u00e9t\u00e9 satisfait de la solution sur mesure qui r\u00e9pondait \u00e0 toutes ses exigences en mati\u00e8re d&rsquo;espace, de lecture bilat\u00e9rale et de fiabilit\u00e9. Il a \u00e9t\u00e9 particuli\u00e8rement content du d\u00e9lai d&rsquo;ex\u00e9cution rapide : seulement cinq semaines entre l&rsquo;appel d&rsquo;offres (demande de devis) et l&rsquo;exp\u00e9dition du produit final.<\/p>\n<h2>WIKA Division s\u00e9parateurs : Engag\u00e9e dans les solutions de pression sur mesure<\/h2>\n<p>WIKA a pr\u00e8s de deux d\u00e9cennies d&rsquo;exp\u00e9rience dans la conception et l&rsquo;installation de montages sur s\u00e9parateur. La division est fi\u00e8re de rechercher les solutions les plus utiles et les plus rentables pour tout d\u00e9fi de pression de process. <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">Contactez nos experts<\/a> pour en savoir plus sur les montages sur s\u00e9parateurs \u00e0 membrane, les services de r\u00e9paration de s\u00e9parateurs \u00e0 membrane ou les solutions personnalis\u00e9es pour vos besoins uniques de mesure de pression.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une entreprise du secteur de l&rsquo;\u00e9nergie et de l&rsquo;eau\/eaux us\u00e9es a contact\u00e9 WIKA pour installer un montage sur s\u00e9parateur sur un pipeline avec un faible d\u00e9gagement, ainsi qu\u2019une exigence sp\u00e9cifique : Le manom\u00e8tre process devait \u00eatre lisible des deux c\u00f4t\u00e9s. La division \u00ab\u00a0S\u00e9parateurs\u00a0\u00bb de WIKA a con\u00e7u une solution sur mesure qui r\u00e9pondait aux besoins [&hellip;]<\/p>\n","protected":false},"author":239,"featured_media":8590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232],"tags":[335,336,337],"class_list":["post-8587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","tag-la-pression-sur-mesure","tag-montage-sur-sparateur","tag-sur-mesure"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client - Blog WIKA<\/title>\n<meta name=\"description\" content=\"WIKA a relev\u00e9 un double d\u00e9fi de contraintes spatiales et lectures bilat\u00e9rales gr\u00e2ce \u00e0 un montage sur s\u00e9parateur fabriqu\u00e9 sur mesure en un temps record\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"WIKA a relev\u00e9 un double d\u00e9fi de contraintes spatiales et lectures bilat\u00e9rales gr\u00e2ce \u00e0 un montage sur s\u00e9parateur fabriqu\u00e9 sur mesure en un temps record\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/dual-gauge-dss_resized.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"St\u00e9phane Peyrache\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"St\u00e9phane Peyrache\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/\"},\"author\":{\"name\":\"St\u00e9phane Peyrache\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/1cd45e596e3bc461c1043dc0f7116e9c\"},\"headline\":\"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client\",\"datePublished\":\"2020-02-10T07:17:18+00:00\",\"dateModified\":\"2023-11-20T07:07:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/\"},\"wordCount\":911,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/02\\\/dual-gauge-dss_resized.jpg\",\"keywords\":[\"la pression sur mesure\",\"montage sur s\u00e9parateur\",\"sur mesure\"],\"articleSection\":[\"Applications\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/\",\"name\":\"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/02\\\/dual-gauge-dss_resized.jpg\",\"datePublished\":\"2020-02-10T07:17:18+00:00\",\"dateModified\":\"2023-11-20T07:07:03+00:00\",\"description\":\"WIKA a relev\u00e9 un double d\u00e9fi de contraintes spatiales et lectures bilat\u00e9rales gr\u00e2ce \u00e0 un montage sur s\u00e9parateur fabriqu\u00e9 sur mesure en un temps record\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/02\\\/dual-gauge-dss_resized.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/02\\\/dual-gauge-dss_resized.jpg\",\"width\":838,\"height\":471,\"caption\":\"Double montage sur s\u00e9parateur de manom\u00e8tres\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/1cd45e596e3bc461c1043dc0f7116e9c\",\"name\":\"St\u00e9phane Peyrache\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/01\\\/peyrachestephane_blog-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/01\\\/peyrachestephane_blog-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/01\\\/peyrachestephane_blog-140x140.jpg\",\"caption\":\"St\u00e9phane Peyrache\"},\"description\":\"Chez WIKA depuis 2000, j\u2019ai b\u00e2ti mon exp\u00e9rience au travers diff\u00e9rentes fonctions et responsabilit\u00e9s en particulier dans la vente, la gestion des projets avec les ing\u00e9nieries pour le march\u00e9 du Oil &amp; gaz et du nucl\u00e9aire, la gestion de production et l\u2019administration des ventes. Ces exp\u00e9riences m\u2019ont permis d\u2019avoir une expertise dans l\u2019instrumentation de pression, temp\u00e9rature et la m\u00e9trologie. Je pourrais r\u00e9pondre \u00e0 vos questions concernant vos recherches de solutions techniques et d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/peyracs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client - Blog WIKA","description":"WIKA a relev\u00e9 un double d\u00e9fi de contraintes spatiales et lectures bilat\u00e9rales gr\u00e2ce \u00e0 un montage sur s\u00e9parateur fabriqu\u00e9 sur mesure en un temps record","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client - Blog WIKA","og_description":"WIKA a relev\u00e9 un double d\u00e9fi de contraintes spatiales et lectures bilat\u00e9rales gr\u00e2ce \u00e0 un montage sur s\u00e9parateur fabriqu\u00e9 sur mesure en un temps record","og_url":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/dual-gauge-dss_resized.jpg","type":"image\/jpeg"}],"author":"St\u00e9phane Peyrache","twitter_misc":{"\u00c9crit par":"St\u00e9phane Peyrache","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/"},"author":{"name":"St\u00e9phane Peyrache","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/1cd45e596e3bc461c1043dc0f7116e9c"},"headline":"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client","datePublished":"2020-02-10T07:17:18+00:00","dateModified":"2023-11-20T07:07:03+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/"},"wordCount":911,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/dual-gauge-dss_resized.jpg","keywords":["la pression sur mesure","montage sur s\u00e9parateur","sur mesure"],"articleSection":["Applications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/","url":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/","name":"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/dual-gauge-dss_resized.jpg","datePublished":"2020-02-10T07:17:18+00:00","dateModified":"2023-11-20T07:07:03+00:00","description":"WIKA a relev\u00e9 un double d\u00e9fi de contraintes spatiales et lectures bilat\u00e9rales gr\u00e2ce \u00e0 un montage sur s\u00e9parateur fabriqu\u00e9 sur mesure en un temps record","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/dual-gauge-dss_resized.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/dual-gauge-dss_resized.jpg","width":838,"height":471,"caption":"Double montage sur s\u00e9parateur de manom\u00e8tres"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/etude-de-cas-une-solution-sur-mesure-de-montages-sur-separateur-repond-aux-exigences-precises-du-client\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9tude de cas : Une solution sur mesure de montages sur s\u00e9parateur r\u00e9pond aux exigences pr\u00e9cises du client"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/1cd45e596e3bc461c1043dc0f7116e9c","name":"St\u00e9phane Peyrache","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2019\/01\/peyrachestephane_blog-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2019\/01\/peyrachestephane_blog-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2019\/01\/peyrachestephane_blog-140x140.jpg","caption":"St\u00e9phane Peyrache"},"description":"Chez WIKA depuis 2000, j\u2019ai b\u00e2ti mon exp\u00e9rience au travers diff\u00e9rentes fonctions et responsabilit\u00e9s en particulier dans la vente, la gestion des projets avec les ing\u00e9nieries pour le march\u00e9 du Oil &amp; gaz et du nucl\u00e9aire, la gestion de production et l\u2019administration des ventes. Ces exp\u00e9riences m\u2019ont permis d\u2019avoir une expertise dans l\u2019instrumentation de pression, temp\u00e9rature et la m\u00e9trologie. Je pourrais r\u00e9pondre \u00e0 vos questions concernant vos recherches de solutions techniques et d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/peyracs\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/239"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=8587"}],"version-history":[{"count":5,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8587\/revisions"}],"predecessor-version":[{"id":11443,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8587\/revisions\/11443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/8590"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=8587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=8587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=8587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}