{"id":8621,"date":"2020-03-16T08:49:31","date_gmt":"2020-03-16T07:49:31","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=8621"},"modified":"2026-05-22T08:57:57","modified_gmt":"2026-05-22T06:57:57","slug":"manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/","title":{"rendered":"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001"},"content":{"rendered":"<p><strong>L&rsquo;institut allemand de normalisation (Deutsches Institut f\u00fcr Normung) a ouvert un nouveau chapitre : Sa norme DIN 16001 est la premi\u00e8re norme au monde qui traite exclusivement des manom\u00e8tres \u00e0 haute pression. Conform\u00e9ment aux crit\u00e8res qui y sont d\u00e9crits, WIKA est \u00e0 l&rsquo;avant-garde des fabricants, en lan\u00e7ant deux nouveaux instruments de mesure de ce type, les mod\u00e8les PG23HP-P et PG23HP-S.<\/strong><\/p>\n<p>La s\u00e9curit\u00e9 est un facteur important dans les process, en particulier dans les plages de haute pression. Les manom\u00e8tres \u00e0 haute pression, en particulier, doivent supporter de lourdes charges afin de r\u00e9sister aux situations critiques. Jusqu&rsquo;\u00e0 pr\u00e9sent, il n&rsquo;existe pas de norme appropri\u00e9e que les fabricants, les acheteurs ou les utilisateurs doivent suivre. En effet, la seule norme pour les instruments de mesure de pression m\u00e9caniques jusqu&rsquo;\u00e0 pr\u00e9sent est la norme EN 837-1 et elle n&rsquo;est valable que pour les pressions jusqu&rsquo;\u00e0 1 600 bars inclus.<\/p>\n<p>&nbsp;<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/pg23hp_din-16001_2.3-388x287.jpg\" alt=\"Manom\u00e8tre haute pression PG23HP-P\" \/><p class=\"wp-caption-text\">Le nouveau manom\u00e8tre haute pression PG23HP-P est d\u00e9j\u00e0 fabriqu\u00e9 et qualifi\u00e9 conform\u00e9ment \u00e0 la norme DIN 16001. La marque de limitation triangulaire dans la section image indique la valeur maximale de la limitation de pression continue.<\/p><\/div>\n    \n<h2>Principales dispositions relatives aux manom\u00e8tres \u00e0 haute pression<\/h2>\n<p>Jusqu&rsquo;\u00e0 la publication de la norme DIN 16001, chaque fabricant pouvait construire ses manom\u00e8tres \u00e0 haute pression comme il le souhaitait et les commercialiser sans marquage. La nouvelle norme, initi\u00e9e par des entreprises telles que WIKA, apporte d\u00e9sormais de la clart\u00e9. Elle s&rsquo;appuie fortement sur la norme EN 837-1, d\u00e9finissant toutefois des crit\u00e8res sp\u00e9cifiques pour les manom\u00e8tres \u00e0 haute pression. Voici un aper\u00e7u des dispositions les plus importantes :<\/p>\n<ul>\n<li>La norme DIN 16001 est valable pour les instruments de mesure dont l&rsquo;\u00e9chelle est comprise entre &gt; 1 600 bar et 10 000 bar (tailles nominales 100 et 160).<\/li>\n<li>Tous les manom\u00e8tres \u00e0 haute pression construits selon la norme DIN 16001 doivent \u00e9galement \u00eatre fabriqu\u00e9s et qualifi\u00e9s, sans exception, pour la cat\u00e9gorie de s\u00e9curit\u00e9 \u00ab\u00a0S3\u00a0\u00bb. Pour ce faire, il faut un bo\u00eetier en verre s\u00e9curit feuillet\u00e9, une cloison de s\u00e9curit\u00e9 entre le syst\u00e8me de mesure et le cadran et un fond arri\u00e8re \u00e9jectable. Ainsi, en cas de panne, le personnel d&rsquo;exploitation est prot\u00e9g\u00e9 sur la face avant, car les fluides ou les composants ne peuvent \u00eatre \u00e9ject\u00e9s que par l&rsquo;arri\u00e8re du bo\u00eetier.<\/li>\n<li>La limitation continue de la pression des manom\u00e8tres haute pression, conform\u00e9ment \u00e0 la norme DIN 16001, se situe \u00e0 75 % de la valeur de la pleine \u00e9chelle. Pendant de courtes p\u00e9riodes, les instruments peuvent \u00eatre charg\u00e9s jusqu&rsquo;\u00e0 la valeur compl\u00e8te de la pleine \u00e9chelle. L&rsquo;instrument ne doit pas \u00eatre expos\u00e9 \u00e0 une pression sup\u00e9rieure \u00e0 la valeur de la pleine \u00e9chelle.<\/li>\n<\/ul>\n<h2>Qualification approfondie des manom\u00e8tres \u00e0 haute pression<\/h2>\n<p>WIKA a construit, qualifi\u00e9 et marqu\u00e9 de fa\u00e7on appropri\u00e9e ses deux nouveaux manom\u00e8tres haute pression conform\u00e9ment \u00e0 la norme DIN 16001. La qualification est tr\u00e8s \u00e9tendue, notamment en raison des essais li\u00e9s \u00e0 la s\u00e9curit\u00e9. Cela n\u00e9cessite un \u00e9quipement sp\u00e9cialis\u00e9, dont WIKA dispose.<\/p>\n<p>Le mod\u00e8le PG23HP-P se caract\u00e9rise par des plages d&rsquo;\u00e9chelle allant jusqu&rsquo;\u00e0 6 000 bar et une grande pr\u00e9cision d&rsquo;indication allant jusqu&rsquo;\u00e0 la classe 0,6 %. Sa stabilit\u00e9 de cycle de charge d\u00e9passe de loin les exigences minimales de la norme (10 000 cycles de charge \u00e0 des pressions allant jusqu&rsquo;\u00e0 5 000 bar, 5 000 cycles de charge \u00e0 des pressions de 5 000 \u00e0 10 000 bar). Le mod\u00e8le PG23HP-S est disponible avec des \u00e9tendues de mesure allant jusqu&rsquo;\u00e0 3 000 bar et une classe de pr\u00e9cision de 1,6 %.<\/p>\n<p><strong>Note<\/strong><\/p>\n<p>De plus amples informations sur les mod\u00e8les <a href=\"https:\/\/www.wika.com\/fr-fr\/pg23hp_p.WIKA\" rel=\"external\" target=\"_blank\">PG23HP-P<\/a> et <a href=\"https:\/\/www.wika.com\/fr-fr\/pg23hp_s.WIKA\" rel=\"external\" target=\"_blank\">PG23HP-S<\/a> sont disponibles sur le site web de WIKA. Des informations suppl\u00e9mentaires sur la norme <a href=\"https:\/\/www.din.de\/en\/getting-involved\/standards-committees\/natg\/publications\/wdc-beuth:din21:395785683\" rel=\"external\" target=\"_blank\">DIN 16001<\/a> sont disponibles sur le site web de l&rsquo;institut allemand de normalisation (Deutsches Institut f\u00fcr Normung &#8211; DIN).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;institut allemand de normalisation (Deutsches Institut f\u00fcr Normung) a ouvert un nouveau chapitre : Sa norme DIN 16001 est la premi\u00e8re norme au monde qui traite exclusivement des manom\u00e8tres \u00e0 haute pression. Conform\u00e9ment aux crit\u00e8res qui y sont d\u00e9crits, WIKA est \u00e0 l&rsquo;avant-garde des fabricants, en lan\u00e7ant deux nouveaux instruments de mesure de ce type, [&hellip;]<\/p>\n","protected":false},"author":239,"featured_media":8624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[220],"tags":[],"class_list":["post-8621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produits-pression"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001 - Blog WIKA<\/title>\n<meta name=\"description\" content=\"WIKA lance deux nouveaux instruments de mesure, PG23HP-P et PG23HP-S, avec la nouvelle norme DIN16001, garantissant la s\u00e9curit\u00e9 dans les process\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001 - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"WIKA lance deux nouveaux instruments de mesure, PG23HP-P et PG23HP-S, avec la nouvelle norme DIN16001, garantissant la s\u00e9curit\u00e9 dans les process\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/beitragsbild_din16001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"St\u00e9phane Peyrache\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"St\u00e9phane Peyrache\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/\"},\"author\":{\"name\":\"St\u00e9phane Peyrache\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/1cd45e596e3bc461c1043dc0f7116e9c\"},\"headline\":\"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001\",\"datePublished\":\"2020-03-16T07:49:31+00:00\",\"dateModified\":\"2026-05-22T06:57:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/\"},\"wordCount\":669,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/02\\\/beitragsbild_din16001.jpg\",\"articleSection\":[\"Pression\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/\",\"name\":\"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001 - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/02\\\/beitragsbild_din16001.jpg\",\"datePublished\":\"2020-03-16T07:49:31+00:00\",\"dateModified\":\"2026-05-22T06:57:57+00:00\",\"description\":\"WIKA lance deux nouveaux instruments de mesure, PG23HP-P et PG23HP-S, avec la nouvelle norme DIN16001, garantissant la s\u00e9curit\u00e9 dans les process\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/02\\\/beitragsbild_din16001.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/02\\\/beitragsbild_din16001.jpg\",\"width\":838,\"height\":471,\"caption\":\"Safety through standard DIN 16001\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-pression\\\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/1cd45e596e3bc461c1043dc0f7116e9c\",\"name\":\"St\u00e9phane Peyrache\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/01\\\/peyrachestephane_blog-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/01\\\/peyrachestephane_blog-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2019\\\/01\\\/peyrachestephane_blog-140x140.jpg\",\"caption\":\"St\u00e9phane Peyrache\"},\"description\":\"Chez WIKA depuis 2000, j\u2019ai b\u00e2ti mon exp\u00e9rience au travers diff\u00e9rentes fonctions et responsabilit\u00e9s en particulier dans la vente, la gestion des projets avec les ing\u00e9nieries pour le march\u00e9 du Oil &amp; gaz et du nucl\u00e9aire, la gestion de production et l\u2019administration des ventes. Ces exp\u00e9riences m\u2019ont permis d\u2019avoir une expertise dans l\u2019instrumentation de pression, temp\u00e9rature et la m\u00e9trologie. Je pourrais r\u00e9pondre \u00e0 vos questions concernant vos recherches de solutions techniques et d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/peyracs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001 - Blog WIKA","description":"WIKA lance deux nouveaux instruments de mesure, PG23HP-P et PG23HP-S, avec la nouvelle norme DIN16001, garantissant la s\u00e9curit\u00e9 dans les process","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/","og_locale":"fr_FR","og_type":"article","og_title":"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001 - Blog WIKA","og_description":"WIKA lance deux nouveaux instruments de mesure, PG23HP-P et PG23HP-S, avec la nouvelle norme DIN16001, garantissant la s\u00e9curit\u00e9 dans les process","og_url":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/beitragsbild_din16001.jpg","type":"image\/jpeg"}],"author":"St\u00e9phane Peyrache","twitter_misc":{"\u00c9crit par":"St\u00e9phane Peyrache","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/"},"author":{"name":"St\u00e9phane Peyrache","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/1cd45e596e3bc461c1043dc0f7116e9c"},"headline":"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001","datePublished":"2020-03-16T07:49:31+00:00","dateModified":"2026-05-22T06:57:57+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/"},"wordCount":669,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/beitragsbild_din16001.jpg","articleSection":["Pression"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/","url":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/","name":"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001 - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/beitragsbild_din16001.jpg","datePublished":"2020-03-16T07:49:31+00:00","dateModified":"2026-05-22T06:57:57+00:00","description":"WIKA lance deux nouveaux instruments de mesure, PG23HP-P et PG23HP-S, avec la nouvelle norme DIN16001, garantissant la s\u00e9curit\u00e9 dans les process","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/beitragsbild_din16001.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/02\/beitragsbild_din16001.jpg","width":838,"height":471,"caption":"Safety through standard DIN 16001"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-pression\/manometres-a-haute-pression-securite-garantie-avec-la-nouvelle-norme-din-16001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Manom\u00e8tres \u00e0 haute pression : S\u00e9curit\u00e9 garantie avec la nouvelle norme DIN 16001"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/1cd45e596e3bc461c1043dc0f7116e9c","name":"St\u00e9phane Peyrache","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2019\/01\/peyrachestephane_blog-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2019\/01\/peyrachestephane_blog-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2019\/01\/peyrachestephane_blog-140x140.jpg","caption":"St\u00e9phane Peyrache"},"description":"Chez WIKA depuis 2000, j\u2019ai b\u00e2ti mon exp\u00e9rience au travers diff\u00e9rentes fonctions et responsabilit\u00e9s en particulier dans la vente, la gestion des projets avec les ing\u00e9nieries pour le march\u00e9 du Oil &amp; gaz et du nucl\u00e9aire, la gestion de production et l\u2019administration des ventes. Ces exp\u00e9riences m\u2019ont permis d\u2019avoir une expertise dans l\u2019instrumentation de pression, temp\u00e9rature et la m\u00e9trologie. Je pourrais r\u00e9pondre \u00e0 vos questions concernant vos recherches de solutions techniques et d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/peyracs\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/239"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=8621"}],"version-history":[{"count":7,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8621\/revisions"}],"predecessor-version":[{"id":12985,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8621\/revisions\/12985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/8624"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=8621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=8621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=8621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}