{"id":8765,"date":"2020-06-22T08:00:06","date_gmt":"2020-06-22T06:00:06","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=8765"},"modified":"2023-11-16T14:12:48","modified_gmt":"2023-11-16T13:12:48","slug":"wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/","title":{"rendered":"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne"},"content":{"rendered":"<p><strong>Dans les v\u00e9hicules \u00e0 hydrog\u00e8ne, le gaz du r\u00e9servoir de stockage d&rsquo;H<sub>2<\/sub> doit \u00eatre r\u00e9gul\u00e9 par une s\u00e9rie de vannes de contr\u00f4le avant d&rsquo;atteindre la pile \u00e0 combustible. Les instruments de pression jouent un r\u00f4le important dans ce process, mais les capteurs de pression standard ne conviennent pas aux applications de l&rsquo;hydrog\u00e8ne car ils ne sont pas fabriqu\u00e9s dans des mat\u00e9riaux appropri\u00e9s. Le MH-3-HY de WIKA est sp\u00e9cialement con\u00e7u pour les v\u00e9hicules qui utilisent des piles \u00e0 combustible hydrog\u00e8ne. De plus, il a re\u00e7u l&rsquo;approbation de la directive CE79\/2009.<\/strong><\/p>\n<p>Les fabricants de machines tout terrain, de camions et d&rsquo;autobus s&rsquo;int\u00e9ressent de plus en plus \u00e0 l&rsquo;hydrog\u00e8ne comme source de carburant. Pourquoi ? La demande des clients pour une rentabilit\u00e9 plus grande en mati\u00e8re de s\u00e9curit\u00e9, d&rsquo;environnement, de performance et d&rsquo;efficacit\u00e9 se fait de plus en plus pressante. Les v\u00e9hicules \u00e0 hydrog\u00e8ne sont beaucoup plus propres que ceux \u00e0 moteur \u00e0 combustion interne, car la vapeur d&rsquo;eau est le seul sous-produit du m\u00e9lange de l&rsquo;hydrog\u00e8ne et de l&rsquo;oxyg\u00e8ne. L&rsquo;absence d&rsquo;\u00e9missions est particuli\u00e8rement d\u00e9terminante pour les v\u00e9hicules utilis\u00e9s \u00e0 l&rsquo;int\u00e9rieur &#8211; chariots \u00e9l\u00e9vateurs, tables \u00e9l\u00e9vatrices \u00e0 ciseaux, tracteurs de remorquage, pr\u00e9parateurs de commandes et v\u00e9hicules de transport &#8211; car les moteurs \u00e0 combustion rejettent dans l&rsquo;air du monoxyde de carbone dangereux, des compos\u00e9s organiques volatils (COV) et d&rsquo;autres sous-produits nocifs, m\u00eame lorsque les v\u00e9hicules sont \u00e9quip\u00e9s des derniers dispositifs de contr\u00f4le de la pollution.<\/p>\n<p>Les v\u00e9hicules \u00e9lectriques \u00e0 batterie sont propres, mais leur principal inconv\u00e9nient est leur autonomie limit\u00e9e et, par cons\u00e9quent, la n\u00e9cessit\u00e9 de les recharger fr\u00e9quemment. De plus, chaque cycle de charge peut prendre plusieurs heures, ce qui signifie que ces machines restent inactives au lieu de produire du travail, ce qui r\u00e9duit le retour sur investissement de l&rsquo;entreprise pour ces actifs. Les v\u00e9hicules \u00e0 hydrog\u00e8ne, en revanche, ne prennent que quelques minutes pour se ravitailler en carburant et sont imm\u00e9diatement remis en service. Les piles \u00e0 combustible sont \u00e9galement plus l\u00e9g\u00e8res que les batteries traditionnelles, ce qui est un avantage lorsque le poids est un facteur important. Les pays d&rsquo;Asie de l&rsquo;Est (en particulier le Japon) et d&rsquo;Europe occidentale sont en t\u00eate en ce qui concerne les v\u00e9hicules \u00e0 pile \u00e0 combustible hydrog\u00e8ne, mais d&rsquo;autres les rattrapent.<\/p>\n<h2>Les applications de l&rsquo;hydrog\u00e8ne n\u00e9cessitent des capteurs de pression sp\u00e9ciaux<\/h2>\n<p>Le gaz comprim\u00e9 dans les r\u00e9servoirs d&rsquo;hydrog\u00e8ne est sous haute pression : environ 360 bar pour la plupart des machines tout-terrain et des v\u00e9hicules municipaux. Avant que l&rsquo;hydrog\u00e8ne n&rsquo;atteigne la pile \u00e0 combustible pour \u00eatre converti en \u00e9nergie, sa pression stock\u00e9e doit \u00eatre r\u00e9duite \u00e0 la pression de fonctionnement de la pile \u00e0 combustion. Pour plus de contr\u00f4le et de s\u00e9curit\u00e9, ce processus se d\u00e9roule g\u00e9n\u00e9ralement en deux \u00e9tapes :<\/p>\n<ol>\n<li>Une soupape de r\u00e9duction de haute pression situ\u00e9e pr\u00e8s du r\u00e9servoir abaisse la pression \u00e0 un peu moins de 20 bar avant d&rsquo;entrer dans le syst\u00e8me.<\/li>\n<li>Un r\u00e9gulateur de pression r\u00e9duit ensuite la pression \u00e0 environ 1 bar avant d&rsquo;entrer dans l&rsquo;injecteur de la pile \u00e0 combustible.<\/li>\n<\/ol>\n<p>Le d\u00e9tendeur haute pression utilise g\u00e9n\u00e9ralement deux capteurs de pression : un \u00e0 l&rsquo;entr\u00e9e de la vanne et un autre \u00e0 sa sortie pour s&rsquo;assurer que la pression du syst\u00e8me est dans les limites de s\u00e9curit\u00e9. Si la pression du syst\u00e8me n&rsquo;est pas correctement r\u00e9gul\u00e9e, une soupape de surpression d\u00e9tectera une condition de surpression et \u00e9vacuera l&rsquo;hydrog\u00e8ne dans l&rsquo;atmosph\u00e8re. Si la pression du syst\u00e8me devient trop faible, la pile \u00e0 combustible n&rsquo;aura pas assez de pression pour fonctionner et finira par arr\u00eater la machine.<\/p>\n<p>Comme tout capteur de pression, il doit \u00eatre suffisamment pr\u00e9cis et robuste pour une application particuli\u00e8re. Cependant, les applications de l&rsquo;H2 posent des probl\u00e8mes pour ces exigences car la mol\u00e9cule se d\u00e9compose en deux ions hydrog\u00e8ne. Ces atomes peuvent facilement entrer dans la structure cristalline de nombreux m\u00e9taux courants, y compris l&rsquo;acier inoxydable, et le processus de diffusion s&rsquo;acc\u00e9l\u00e8re \u00e0 des temp\u00e9ratures et des pressions plus \u00e9lev\u00e9es. C&rsquo;est ce qu&rsquo;on appelle la perm\u00e9ation \u00e0 l&rsquo;hydrog\u00e8ne, et elle a deux impacts dans un capteur de pression :<\/p>\n<ul>\n<li>Elle modifie sa r\u00e9sistance \u00e9lectrique, ce qui entra\u00eene une d\u00e9rive du signal.<\/li>\n<li>Elle rend certains m\u00e9taux plus susceptibles de se fissurer et de se fracturer (fragilisation par l&rsquo;hydrog\u00e8ne).<\/li>\n<\/ul>\n<p>Pour emp\u00eacher la perm\u00e9ation de l&rsquo;hydrog\u00e8ne, un capteur de pression peut \u00eatre dot\u00e9 d&rsquo;une membrane affleurante plaqu\u00e9e or. Cependant, cette option est g\u00e9n\u00e9ralement trop co\u00fbteuse pour la plupart des v\u00e9hicules \u00e0 pile \u00e0 combustible \u00e0 hydrog\u00e8ne. Une solution plus rentable consiste \u00e0 utiliser un alliage sp\u00e9cial moins sensible \u00e0 la perm\u00e9ation de l&rsquo;hydrog\u00e8ne.<\/p>\n<h2>Des capteurs de pression robustes pour les v\u00e9hicules \u00e0 hydrog\u00e8ne<\/h2>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:258px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2020\/06\/mh-3-hy.png\" alt=\"Capteurs de pression pour les applications de l'hydrog\u00e8ne\" \/><p class=\"wp-caption-text\">Capteur de pression MH-3-HY, repr\u00e9sent\u00e9 avec diff\u00e9rents types de connexions \u00e9lectriques<\/p><\/div>\n    \n<p>Le <a href=\"https:\/\/www.wika.com\/fr-fr\/mh_3_hy.WIKA?highlightedText=MH-3\" rel=\"external\" target=\"_blank\">MH-3<\/a> de WIKA est depuis longtemps le capteur de pression \u00e9lectronique OEM de choix pour les conditions de fonctionnement extr\u00eames. Nous avons maintenant cr\u00e9\u00e9 une version sp\u00e9cifique pour les v\u00e9hicules qui utilisent des piles \u00e0 combustible \u00e0 hydrog\u00e8ne comme source principale d&rsquo;\u00e9nergie \u00e9lectrique.<\/p>\n<p>Le <a href=\"https:\/\/www.wika.com\/fr-fr\/mh_3_hy.WIKA?highlightedText=MH-3\" rel=\"external\" target=\"_blank\">MH-3-HY<\/a> pr\u00e9sente la m\u00eame pr\u00e9cision, la m\u00eame fiabilit\u00e9 et la m\u00eame conception robuste que le MH-3, mais avec un capteur \u00e0 couche mince m\u00e9tallique soud\u00e9 en W.Nr 2.4711 (Elgiloy\u00ae), un alliage cobalt-chrome-nickel-molybd\u00e8ne pr\u00e9sentant une grande r\u00e9sistance \u00e0 la fatigue et une excellente r\u00e9sistance \u00e0 la corrosion. Ce capteur de pression n&rsquo;a pas de joints en polym\u00e8re pour le fluide et ne contient pas d&rsquo;huile, ce qui le rend id\u00e9al pour les applications \u00e0 hydrog\u00e8ne avec une plage de pression de 20 \u00e0 550 bar.<\/p>\n<p>Gr\u00e2ce \u00e0 ces mesures, le MH-3-HY a obtenu l&rsquo;homologation CE79\/2009 de l&rsquo;UE pour les v\u00e9hicules fonctionnant \u00e0 l&rsquo;hydrog\u00e8ne, ce qui permet aux constructeurs de certifier beaucoup plus facilement l&rsquo;ensemble de leur syst\u00e8me \u00e0 hydrog\u00e8ne. WIKA est l&rsquo;une des rares entreprises qui fabriquent des capteurs de pression approuv\u00e9s par la directive CE79\/2009. De plus, nous produisons le MH-3-HY sur une ligne hautement automatis\u00e9e, ce qui signifie que nous pouvons fournir aux clients de grandes quantit\u00e9s avec une qualit\u00e9 \u00e9lev\u00e9e et fiable. (D&rsquo;autres fabricants utilisent des lignes semi-automatiques ou manuelles.) Nous v\u00e9rifions \u00e9galement \u00e0 100 % chaque capteur \u00e0 la fin de la ligne, et testons \u00e0 l&rsquo;h\u00e9lium chaque capteur pour d\u00e9tecter les fuites.<\/p>\n<p>De plus en plus de municipalit\u00e9s et d&rsquo;entreprises souhaitent r\u00e9duire leur empreinte carbone sans sacrifier la performance et l&rsquo;efficacit\u00e9, et une fa\u00e7on d&rsquo;y parvenir est d&rsquo;ajouter \u00e0 leur parc de v\u00e9hicules des bus et des machines mobiles fonctionnant \u00e0 l&rsquo;hydrog\u00e8ne. Le vaste portefeuille de produits de mesure de WIKA s&rsquo;inscrit dans cette d\u00e9marche vers un avenir plus propre. En plus du MH-3-HY, nous proposons une vari\u00e9t\u00e9 de capteurs de pression, de temp\u00e9rature, d&rsquo;interrupteurs \u00e0 flotteur et d&rsquo;accessoires connexes pour les applications de l&rsquo;hydrog\u00e8ne allant de la distribution et du stockage \u00e0 l&rsquo;\u00e9nergie des b\u00e2timents. Alors que le march\u00e9 des carburants continue de se d\u00e9placer et d&rsquo;\u00e9voluer, WIKA est l\u00e0. <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">Contactez-nous<\/a> pour plus d&rsquo;informations.<\/p>\n<h2>\u00a0<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Dans les v\u00e9hicules \u00e0 hydrog\u00e8ne, le gaz du r\u00e9servoir de stockage d&rsquo;H2 doit \u00eatre r\u00e9gul\u00e9 par une s\u00e9rie de vannes de contr\u00f4le avant d&rsquo;atteindre la pile \u00e0 combustible. Les instruments de pression jouent un r\u00f4le important dans ce process, mais les capteurs de pression standard ne conviennent pas aux applications de l&rsquo;hydrog\u00e8ne car ils ne [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":8767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232],"tags":[77,358,357],"class_list":["post-8765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","tag-capteur-pression","tag-pile-combustible-hydrogne","tag-vehicule-hydrogne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Le capteur de pression MH-3-HY de WIKA est sp\u00e9cialement con\u00e7uepour les v\u00e9hicules qui utilisent des piles \u00e0 combustible \u00e0 hydrog\u00e8ne\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Le capteur de pression MH-3-HY de WIKA est sp\u00e9cialement con\u00e7uepour les v\u00e9hicules qui utilisent des piles \u00e0 combustible \u00e0 hydrog\u00e8ne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2020\/06\/forklift_shutterstock_776936068.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philippe Bertrand\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Philippe Bertrand\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/\"},\"author\":{\"name\":\"Philippe Bertrand\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/dc2e89d85421ef1630df0d0ce555a825\"},\"headline\":\"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne\",\"datePublished\":\"2020-06-22T06:00:06+00:00\",\"dateModified\":\"2023-11-16T13:12:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/\"},\"wordCount\":1316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/06\\\/forklift_shutterstock_776936068.jpg\",\"keywords\":[\"Capteur de pression\",\"pile \u00e0 combustible hydrog\u00e8ne\",\"vehicule \u00e0 hydrog\u00e8ne\"],\"articleSection\":[\"Applications\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/\",\"name\":\"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/06\\\/forklift_shutterstock_776936068.jpg\",\"datePublished\":\"2020-06-22T06:00:06+00:00\",\"dateModified\":\"2023-11-16T13:12:48+00:00\",\"description\":\"Le capteur de pression MH-3-HY de WIKA est sp\u00e9cialement con\u00e7uepour les v\u00e9hicules qui utilisent des piles \u00e0 combustible \u00e0 hydrog\u00e8ne\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/06\\\/forklift_shutterstock_776936068.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/06\\\/forklift_shutterstock_776936068.jpg\",\"width\":838,\"height\":471,\"caption\":\"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/dc2e89d85421ef1630df0d0ce555a825\",\"name\":\"Philippe Bertrand\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/05\\\/p_bertrand_blog-2-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/05\\\/p_bertrand_blog-2-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2018\\\/05\\\/p_bertrand_blog-2-140x140.jpg\",\"caption\":\"Philippe Bertrand\"},\"description\":\"Depuis plus de 20 ans dans le domaine de l\u2019automatisme industriel, j\u2019ai d\u00e9velopp\u00e9 de r\u00e9elles comp\u00e9tences dans la vente de composants et le d\u00e9veloppement de projets aupr\u00e8s de diff\u00e9rentes typologies de clients tels que les fabricants de machine et les industries du process. Aujourd\u2019hui, en charge du d\u00e9veloppement de la gamme WIKA des produits de mesure de pression \u00e9lectronique, je serais votre interlocuteur privil\u00e9gi\u00e9 pour r\u00e9pondre \u00e0 vos questions et serais heureux de partager mon expertise afin de solutionner vos besoins actuels et futurs.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/bertrandp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne - Blog WIKA","description":"Le capteur de pression MH-3-HY de WIKA est sp\u00e9cialement con\u00e7uepour les v\u00e9hicules qui utilisent des piles \u00e0 combustible \u00e0 hydrog\u00e8ne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/","og_locale":"fr_FR","og_type":"article","og_title":"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne - Blog WIKA","og_description":"Le capteur de pression MH-3-HY de WIKA est sp\u00e9cialement con\u00e7uepour les v\u00e9hicules qui utilisent des piles \u00e0 combustible \u00e0 hydrog\u00e8ne","og_url":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2020\/06\/forklift_shutterstock_776936068.jpg","type":"image\/jpeg"}],"author":"Philippe Bertrand","twitter_misc":{"\u00c9crit par":"Philippe Bertrand","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/"},"author":{"name":"Philippe Bertrand","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/dc2e89d85421ef1630df0d0ce555a825"},"headline":"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne","datePublished":"2020-06-22T06:00:06+00:00","dateModified":"2023-11-16T13:12:48+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/"},"wordCount":1316,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/06\/forklift_shutterstock_776936068.jpg","keywords":["Capteur de pression","pile \u00e0 combustible hydrog\u00e8ne","vehicule \u00e0 hydrog\u00e8ne"],"articleSection":["Applications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/","url":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/","name":"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/06\/forklift_shutterstock_776936068.jpg","datePublished":"2020-06-22T06:00:06+00:00","dateModified":"2023-11-16T13:12:48+00:00","description":"Le capteur de pression MH-3-HY de WIKA est sp\u00e9cialement con\u00e7uepour les v\u00e9hicules qui utilisent des piles \u00e0 combustible \u00e0 hydrog\u00e8ne","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2020\/06\/forklift_shutterstock_776936068.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/06\/forklift_shutterstock_776936068.jpg","width":838,"height":471,"caption":"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/wika-developpe-un-capteur-de-pression-pour-les-vehicules-a-hydrogene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"WIKA d\u00e9veloppe un capteur de pression pour les v\u00e9hicules \u00e0 hydrog\u00e8ne"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/dc2e89d85421ef1630df0d0ce555a825","name":"Philippe Bertrand","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2018\/05\/p_bertrand_blog-2-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2018\/05\/p_bertrand_blog-2-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2018\/05\/p_bertrand_blog-2-140x140.jpg","caption":"Philippe Bertrand"},"description":"Depuis plus de 20 ans dans le domaine de l\u2019automatisme industriel, j\u2019ai d\u00e9velopp\u00e9 de r\u00e9elles comp\u00e9tences dans la vente de composants et le d\u00e9veloppement de projets aupr\u00e8s de diff\u00e9rentes typologies de clients tels que les fabricants de machine et les industries du process. Aujourd\u2019hui, en charge du d\u00e9veloppement de la gamme WIKA des produits de mesure de pression \u00e9lectronique, je serais votre interlocuteur privil\u00e9gi\u00e9 pour r\u00e9pondre \u00e0 vos questions et serais heureux de partager mon expertise afin de solutionner vos besoins actuels et futurs.","url":"https:\/\/blog.wika.com\/fr\/author\/bertrandp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=8765"}],"version-history":[{"count":6,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8765\/revisions"}],"predecessor-version":[{"id":11282,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/8765\/revisions\/11282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/8767"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=8765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=8765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=8765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}