{"id":9013,"date":"2020-12-21T08:20:23","date_gmt":"2020-12-21T07:20:23","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9013"},"modified":"2023-11-20T10:04:44","modified_gmt":"2023-11-20T09:04:44","slug":"quelle-est-la-difference-entre-mttf-et-mttfd","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/","title":{"rendered":"Quelle est la diff\u00e9rence entre MTTF et MTTFD  ?"},"content":{"rendered":"<h2>Qu&rsquo;est-ce qu&rsquo;une valeur MTTF ?<\/h2>\n<p>La valeur MTTF (<strong>m<\/strong>ean <strong>t<\/strong>ime <strong>t<\/strong>o <strong>f<\/strong>ailure) est un terme d\u00e9riv\u00e9 du domaine de l&rsquo;analyse et de l&rsquo;\u00e9valuation des risques. La signification exacte repr\u00e9sente le temps moyen avant une d\u00e9faillance ou simplement la dur\u00e9e de vie moyenne d&rsquo;un composant. Le MTTF a acquis une pertinence particuli\u00e8re gr\u00e2ce \u00e0 la norme EN ISO 13849-1. Conform\u00e9ment \u00e0 cette norme, le niveau de performance peut \u00eatre calcul\u00e9 sur la base du MTTF. Cela signifie que cette valeur est utilis\u00e9e pour l&rsquo;\u00e9valuation des risques des machines et des installations. Cette valeur est donc \u00e9galement importante pour le marquage CE, puisque la s\u00e9curit\u00e9 des machines doit \u00e9galement \u00eatre \u00e9valu\u00e9e dans le cadre de l&rsquo;\u00e9valuation de la conformit\u00e9.<\/p>\n<h2>Qu&rsquo;est-ce qu&rsquo;une valeur MTTF<sub>D<\/sub> ?<\/h2>\n<p>La valeur du MTTFD est importante dans ce contexte. La valeur MTTFD est le \u00ab\u00a0temps moyen avant une d\u00e9faillance dangereuse\u00a0\u00bb (<strong>m<\/strong>ean <strong>t<\/strong>ime <strong>t<\/strong>o <strong>d<\/strong>angerous <strong>f<\/strong>ailure).<\/p>\n<h2>Diff\u00e9rence entre MTTF et MTTF<sub>D<\/sub><\/h2>\n<p>La diff\u00e9rence entre MTTF et MTTF<sub>D<\/sub> est que la valeur MTTF ne fournit qu&rsquo;une indication neutre de la dur\u00e9e de vie moyenne en service d&rsquo;un composant. La valeur MTTF<sub>D<\/sub>, en revanche, indique le temps de fonctionnement jusqu&rsquo;\u00e0 ce qu&rsquo;une d\u00e9faillance dangereuse se produise. Cela signifie que, dans ce cas, seules les d\u00e9faillances affectant la fonction de s\u00e9curit\u00e9 sont prises en compte et incluses dans le niveau de performance. Exemple de d\u00e9faillance non dangereuse : la d\u00e9faillance d&rsquo;un certain capteur peut causer des dommages au moteur, mais n&rsquo;est pas pertinente pour les consid\u00e9rations de s\u00e9curit\u00e9 dans l&rsquo;\u00e9valuation des risques et des dangers.<\/p>\n<h2>Pourquoi les fabricants de composants ne fournissent-ils pas une valeur MTTF<sub>D<\/sub> ?<\/h2>\n<p>Les fabricants de composants (tels que WIKA) ne peuvent pas fournir la valeur MTTF<sub>D<\/sub> puisqu&rsquo;ils savent seulement quand leur composant peut en moyenne \u00eatre d\u00e9faillant, mais pas quels d\u00e9fauts, s&rsquo;il y en a, sont des d\u00e9fauts dangereux. Cela d\u00e9pend enti\u00e8rement de la fonction concern\u00e9e. De plus, la combinaison de plusieurs \u00e9l\u00e9ments peut \u00e9galement affecter le temps total avant une d\u00e9faillance dangereuse\u00a0(MTTF<sub>D<\/sub>). Cela signifie que le MTTF<sub>D<\/sub> ne peut \u00eatre d\u00e9termin\u00e9 que par la personne qui con\u00e7oit la machine ou le syst\u00e8me avec le composant correspondant et qui planifie les fonctions de s\u00e9curit\u00e9 qu&rsquo;elle pr\u00e9voit. En g\u00e9n\u00e9ral, ce sont les d\u00e9veloppeurs ou les concepteurs qui peuvent calculer la valeur MTTF<sub>D<\/sub>.<\/p>\n<p>Pour plus d&rsquo;informations sur la valeur du MTTF ou du MTTF<sub>D<\/sub>, n&rsquo;h\u00e9sitez pas \u00e0<a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\"> nous contacter<\/a>.<\/p>\n<p>A lire \u00e9galement sur le m\u00eame th\u00e8me : MTTF et MTBF : d\u00e9finition et utilisation<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;est-ce qu&rsquo;une valeur MTTF ? La valeur MTTF (mean time to failure) est un terme d\u00e9riv\u00e9 du domaine de l&rsquo;analyse et de l&rsquo;\u00e9valuation des risques. La signification exacte repr\u00e9sente le temps moyen avant une d\u00e9faillance ou simplement la dur\u00e9e de vie moyenne d&rsquo;un composant. Le MTTF a acquis une pertinence particuli\u00e8re gr\u00e2ce \u00e0 la norme [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":9019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-9013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-savoir-faire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quelle est la diff\u00e9rence entre MTTF et MTTFD ? - Blog WIKA<\/title>\n<meta name=\"description\" content=\"La valeur MTTF indique la dur\u00e9e de vie moyenne en service d&#039;un composant tandis que la valeur MTTFD va jusqu&#039;\u00e0 la d\u00e9faillance dangereuse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelle est la diff\u00e9rence entre MTTF et MTTFD ? - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La valeur MTTF indique la dur\u00e9e de vie moyenne en service d&#039;un composant tandis que la valeur MTTFD va jusqu&#039;\u00e0 la d\u00e9faillance dangereuse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2020\/11\/mttf-vs-mttfd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Quelle est la diff\u00e9rence entre MTTF et MTTFD ?\",\"datePublished\":\"2020-12-21T07:20:23+00:00\",\"dateModified\":\"2023-11-20T09:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/11\\\/mttf-vs-mttfd.jpg\",\"articleSection\":[\"Savoir-faire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/\",\"name\":\"Quelle est la diff\u00e9rence entre MTTF et MTTFD ? - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/11\\\/mttf-vs-mttfd.jpg\",\"datePublished\":\"2020-12-21T07:20:23+00:00\",\"dateModified\":\"2023-11-20T09:04:44+00:00\",\"description\":\"La valeur MTTF indique la dur\u00e9e de vie moyenne en service d'un composant tandis que la valeur MTTFD va jusqu'\u00e0 la d\u00e9faillance dangereuse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/11\\\/mttf-vs-mttfd.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2020\\\/11\\\/mttf-vs-mttfd.jpg\",\"width\":800,\"height\":400,\"caption\":\"Diff\u00e9rence entre MTTF et MTTFD\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/savoir-faire\\\/quelle-est-la-difference-entre-mttf-et-mttfd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelle est la diff\u00e9rence entre MTTF et MTTFD ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelle est la diff\u00e9rence entre MTTF et MTTFD ? - Blog WIKA","description":"La valeur MTTF indique la dur\u00e9e de vie moyenne en service d'un composant tandis que la valeur MTTFD va jusqu'\u00e0 la d\u00e9faillance dangereuse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelle est la diff\u00e9rence entre MTTF et MTTFD ? - Blog WIKA","og_description":"La valeur MTTF indique la dur\u00e9e de vie moyenne en service d'un composant tandis que la valeur MTTFD va jusqu'\u00e0 la d\u00e9faillance dangereuse.","og_url":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/","og_site_name":"Blog WIKA","og_image":[{"width":800,"height":400,"url":"https:\/\/blog.wika.com\/fr\/files\/2020\/11\/mttf-vs-mttfd.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Quelle est la diff\u00e9rence entre MTTF et MTTFD ?","datePublished":"2020-12-21T07:20:23+00:00","dateModified":"2023-11-20T09:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/11\/mttf-vs-mttfd.jpg","articleSection":["Savoir-faire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/","url":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/","name":"Quelle est la diff\u00e9rence entre MTTF et MTTFD ? - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/11\/mttf-vs-mttfd.jpg","datePublished":"2020-12-21T07:20:23+00:00","dateModified":"2023-11-20T09:04:44+00:00","description":"La valeur MTTF indique la dur\u00e9e de vie moyenne en service d'un composant tandis que la valeur MTTFD va jusqu'\u00e0 la d\u00e9faillance dangereuse.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2020\/11\/mttf-vs-mttfd.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2020\/11\/mttf-vs-mttfd.jpg","width":800,"height":400,"caption":"Diff\u00e9rence entre MTTF et MTTFD"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/savoir-faire\/quelle-est-la-difference-entre-mttf-et-mttfd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Quelle est la diff\u00e9rence entre MTTF et MTTFD ?"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9013"}],"version-history":[{"count":3,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9013\/revisions"}],"predecessor-version":[{"id":11477,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9013\/revisions\/11477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9019"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}