{"id":9126,"date":"2021-03-15T08:53:54","date_gmt":"2021-03-15T07:53:54","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9126"},"modified":"2023-11-17T11:58:20","modified_gmt":"2023-11-17T10:58:20","slug":"des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/","title":{"rendered":"Des thermom\u00e8tres industriels et des capteurs de temp\u00e9rature d\u00e9di\u00e9s aux syst\u00e8mes HVAC"},"content":{"rendered":"<p><strong>La temp\u00e9rature est le param\u00e8tre le plus mesur\u00e9 et le plus surveill\u00e9 dans les applications HVAC (= Heating Ventilation &amp; Air Conditioning = chauffage, ventilation, climatisation) domestiques, commerciales et industrielles. C&rsquo;est pourquoi il est indispensable de disposer d&rsquo;une instrumentation fiable. WIKA fabrique une gamme compl\u00e8te de thermom\u00e8tres \u00e0 cadran de haute qualit\u00e9 pour la mesure de temp\u00e9rature dans les syst\u00e8mes HVAC industriels.<\/strong><\/p>\n<p>Les <a href=\"https:\/\/www.wika.com\/fr-fr\/technique_de_chauffage_ventilation_et_conditionnement_d_air.WIKA\" rel=\"external\" target=\"_blank\">syst\u00e8mes de chauffage, de ventilation et de climatisation<\/a> assurent par exemple le confort des personnes \u00e0 leur domicile et le fonctionnement des ordinateurs dans des conditions optimales. Les syst\u00e8mes HVAC maintiennent \u00e9galement les mat\u00e9riaux et les produits &#8211; dans des environnements allant des supermarch\u00e9s et des silos aux mus\u00e9es et aux serres &#8211; dans les plages de temp\u00e9rature ambiante recommand\u00e9es pour \u00e9viter leur d\u00e9gradation.<\/p>\n<p>Les capteurs de temp\u00e9rature sont essentiels dans les appareils HVAC tels que :<\/p>\n<ul>\n<li><span style=\"font-size: 1rem\">Chauffages d&rsquo;ambiance<\/span><\/li>\n<li>Chauffe-eau<\/li>\n<li>Syst\u00e8mes thermiques solaires<\/li>\n<li>Centrales de production combin\u00e9e de chaleur et d&rsquo;\u00e9lectricit\u00e9<\/li>\n<li>Refroidisseurs<\/li>\n<li>Chaudi\u00e8res<\/li>\n<\/ul>\n<p>Les capteurs de temp\u00e9rature HVAC industriels doivent fonctionner dans des conditions difficiles, notamment d&rsquo;humidit\u00e9 voire de forte humidit\u00e9 et de temp\u00e9ratures plus ou moins extr\u00eames. Parall\u00e8lement, les pr\u00e9occupations environnementales exigent <a href=\"https:\/\/blog.wika.com\/fr\/applications\/les-instruments-de-mesure-sont-la-cle-de-lefficacite-energetique-des-centrales-de-traitement-dair\/\">l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique des unit\u00e9s de traitement de l&rsquo;air<\/a>.<\/p>\n<p>WIKA est fournisseur d\u2019une gamme compl\u00e8te d&rsquo;instruments de mesure de temp\u00e9rature, y compris de solutions personnalis\u00e9es. Forts de nombreuses ann\u00e9es d&rsquo;exp\u00e9rience dans le secteur HVAC, nos sp\u00e9cialistes offrent \u00e9galement des conseils d&rsquo;experts sur les meilleures pratiques, la conformit\u00e9 r\u00e9glementaire et le choix <a href=\"https:\/\/www.wika.com\/fr-fr\/thermometres_a_cadran.WIKA\" rel=\"external\" target=\"_blank\">des thermom\u00e8tres \u00e0 cadran<\/a> analogique ou num\u00e9rique les mieux adapt\u00e9s \u00e0 votre application, votre secteur et votre budget.<\/p>\n<h2>En verre, solaire, bim\u00e9tallique : quelles options pour les thermom\u00e8tres HVAC industriels<\/h2>\n<p>WIKA innove et fabrique des technologies de capteurs de temp\u00e9rature industriels depuis plus de 70 ans. Robustes, fiables et abordables, nos instruments sont id\u00e9aux pour les applications HVAC industrielles. Voici un aper\u00e7u de quelques-uns de nos thermom\u00e8tres \u00e0 cadran les plus populaires :<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:186px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/model-32.jpg\" \/><p class=\"wp-caption-text\">Type 32<\/p><\/div>\n    \n<p><strong>Thermom\u00e8tres en verre remplis de liquide<\/strong><br \/>\nLes thermom\u00e8tres en verre remplis de liquide, \u00e9galement appel\u00e9s thermom\u00e8tres \u00e0 dilatation, sont de loin les capteurs de temp\u00e9rature les plus utilis\u00e9s dans le domaine du HVAC industriel car ils sont r\u00e9sistants aux intemp\u00e9ries, faciles \u00e0 lire et \u00e9conomiques. Les thermom\u00e8tres WIKA bas\u00e9s sur le principe de mesure de l&rsquo;expansion de liquide sont exempts de mercure et ont un bo\u00eetier moul\u00e9 qui les rend r\u00e9sistants aux chocs et aux vibrations. Et comme les thermom\u00e8tres en verre ne sont pas soumis \u00e0 une usure m\u00e9canique, ils ont une longue dur\u00e9e de vie.<\/p>\n<p>Le thermom\u00e8tre <a href=\"https:\/\/www.wika.com\/fr-fr\/32.WIKA\" rel=\"external\" target=\"_blank\">type 32<\/a> est l&rsquo;un des nombreux exemples de thermom\u00e8tre en verre avec un liquide thermom\u00e9trique non toxique. Avec des plages de mesure de -30 \u00e0 200 \u00b0C et trois versions de montage (droit, coud\u00e9 \u00e0 90\u00b0 ou \u00e0 135\u00b0), ce thermom\u00e8tre \u00e0 double \u00e9chelle est une excellente solution pour les mesures de temp\u00e9rature dans les syst\u00e8mes de chauffage central et autres grosses installations de chauffage.<\/p>\n<p><strong>Thermom\u00e8tres \u00e0 \u00e9nergie solaire<\/strong> <br \/>\nLes changements de temp\u00e9rature dans la plupart des unit\u00e9s de chauffage et de refroidissement sont graduels, ce qui est id\u00e9al pour les thermom\u00e8tres de verre. Toutefois, lorsqu&rsquo;une application exige un temps de r\u00e9ponse rapide sans les tracas des piles, il convient d\u2019utiliser un thermom\u00e8tre solaire. Les thermom\u00e8tres solaires \u00e0 LED sont dot\u00e9s d&rsquo;une r\u00e9sistance pour une lecture num\u00e9rique rapide et pr\u00e9cise, et pr\u00e9sentent une large gamme de temp\u00e9ratures : de -45 \u00e0 150 \u00b0C.<\/p>\n<p>WIKA propose plusieurs thermom\u00e8tres industriels \u00e0 \u00e9nergie solaire sp\u00e9cialement con\u00e7us pour les applications HVAC, de plomberie et de r\u00e9frig\u00e9ration. Un exemple :<\/p>\n<ul>\n<li>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:260px;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-9129\" src=\"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/digital-solar-thermometer.jpg\" alt=\"\" width=\"252\" height=\"125\" \/><p class=\"wp-caption-text\">Type TF-LCD<\/p><\/div>\n    <br \/>\nLe thermom\u00e8tre <a href=\"https:\/\/www.wika.com\/fr-fr\/tf_lcd.WIKA\" rel=\"external\" target=\"_blank\">type TF-LCD<\/a> est un thermom\u00e8tre num\u00e9rique de longue dur\u00e9e qui existe en deux versions : solaire ou \u00e0 piles (dur\u00e9e de vie de 7 ans). Cet instrument dispose d&rsquo;un capillaire optionnel (jusqu&rsquo;\u00e0 3m) avec une prise jack pour une lecture facile de la temp\u00e9rature dans les espaces difficiles d&rsquo;acc\u00e8s.<\/li>\n<\/ul>\n<p><strong>Thermom\u00e8tres bim\u00e9talliques<\/strong><br \/>\nLes <a href=\"https:\/\/www.wika.com\/fr-fr\/thermometres_a_cadran.WIKA?Node=70907&amp;235=998\" rel=\"external\" target=\"_blank\">thermom\u00e8tres bim\u00e9talliques<\/a> sont petits, un avantage lorsque l&rsquo;espace est un facteur limitant. Ces instruments abordables ne sont pas aussi robustes que les thermom\u00e8tres en verre, mais ont une plage de mesure de la temp\u00e9rature beaucoup plus large : de -70 \u00e0 600 \u00b0C.<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:223px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/tg54.jpg\" \/><p class=\"wp-caption-text\">Type TG54<\/p><\/div>\n    \n<p>Le thermom\u00e8tre <a href=\"https:\/\/www.wika.com\/fr-fr\/tg54.WIKA?ProductGroup=70907&amp;235=998\" rel=\"external\" target=\"_blank\">type TG54<\/a> est un bon exemple de thermom\u00e8tre bim\u00e9tallique de qualit\u00e9 industrielle r\u00e9sistant aux intemp\u00e9ries. Ce thermom\u00e8tre \u00e0 cadran herm\u00e9tique existe en 4 diam\u00e8tres de bo\u00eetier diff\u00e9rents (63, 80, 100 et 160mm) avec un plongeur de longueur variable de 63 \u00e0 1000 mm. Il est enti\u00e8rement construit en acier inox et poss\u00e8de une plage de temp\u00e9rature sup\u00e9rieure continue jusqu\u2019\u00e0 600 \u00b0C, ce qui en fait une excellente option pour surveiller la temp\u00e9rature dans les chaudi\u00e8res.<\/p>\n<h2>L&rsquo;expertise WIKA en terme de temp\u00e9rature HVAC<\/h2>\n<p>Les clients doivent tenir compte de nombreuses variables &#8211; pr\u00e9cision, plage de mesure, taille, montage, mat\u00e9riaux, protection contre les infiltrations, etc. &#8211; lors du choix d&rsquo;un capteur de temp\u00e9rature HVAC industriel. En plus de la vari\u00e9t\u00e9 de thermom\u00e8tres \u00e0 cadran disponibles, il est possible d&rsquo;utiliser des sondes \u00e0 r\u00e9sistance dans les applications HVAC pour mesurer la temp\u00e9rature le long d&rsquo;un conduit ou sur une section.<\/p>\n<p>Pour vous assurer d&rsquo;obtenir le bon capteur de temp\u00e9rature pour votre application et vos conditions sp\u00e9cifiques, <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">contactez WIKA<\/a>. Notre personnel de vente qualifi\u00e9 peut vous aider \u00e0 gagner du temps et de l&rsquo;argent d\u00e8s maintenant, et \u00e0 \u00e9viter les maux de t\u00eate \u00e0 l&rsquo;avenir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La temp\u00e9rature est le param\u00e8tre le plus mesur\u00e9 et le plus surveill\u00e9 dans les applications HVAC (= Heating Ventilation &amp; Air Conditioning = chauffage, ventilation, climatisation) domestiques, commerciales et industrielles. C&rsquo;est pourquoi il est indispensable de disposer d&rsquo;une instrumentation fiable. WIKA fabrique une gamme compl\u00e8te de thermom\u00e8tres \u00e0 cadran de haute qualit\u00e9 pour la mesure [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":9128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[221],"tags":[],"class_list":["post-9126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produits-temperature"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thermom\u00e8tres et capteurs pour l&#039;HVAC - Blog WIKA<\/title>\n<meta name=\"description\" content=\"La temp\u00e9rature est le param\u00e8tre le plus mesur\u00e9 et le plus surveill\u00e9 dans les applications HVACdomestiques, commerciales et industrielles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thermom\u00e8tres et capteurs pour l&#039;HVAC - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La temp\u00e9rature est le param\u00e8tre le plus mesur\u00e9 et le plus surveill\u00e9 dans les applications HVACdomestiques, commerciales et industrielles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/hvac-thermometer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Des thermom\u00e8tres industriels et des capteurs de temp\u00e9rature d\u00e9di\u00e9s aux syst\u00e8mes HVAC\",\"datePublished\":\"2021-03-15T07:53:54+00:00\",\"dateModified\":\"2023-11-17T10:58:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/\"},\"wordCount\":1005,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/02\\\/hvac-thermometer.jpg\",\"articleSection\":[\"Temp\u00e9rature\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/\",\"name\":\"Thermom\u00e8tres et capteurs pour l'HVAC - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/02\\\/hvac-thermometer.jpg\",\"datePublished\":\"2021-03-15T07:53:54+00:00\",\"dateModified\":\"2023-11-17T10:58:20+00:00\",\"description\":\"La temp\u00e9rature est le param\u00e8tre le plus mesur\u00e9 et le plus surveill\u00e9 dans les applications HVACdomestiques, commerciales et industrielles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/02\\\/hvac-thermometer.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/02\\\/hvac-thermometer.jpg\",\"width\":838,\"height\":471,\"caption\":\"\u00c9quipement de climatisation au sommet d'un b\u00e2timent moderne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/produits\\\/produits-temperature\\\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des thermom\u00e8tres industriels et des capteurs de temp\u00e9rature d\u00e9di\u00e9s aux syst\u00e8mes HVAC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thermom\u00e8tres et capteurs pour l'HVAC - Blog WIKA","description":"La temp\u00e9rature est le param\u00e8tre le plus mesur\u00e9 et le plus surveill\u00e9 dans les applications HVACdomestiques, commerciales et industrielles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/","og_locale":"fr_FR","og_type":"article","og_title":"Thermom\u00e8tres et capteurs pour l'HVAC - Blog WIKA","og_description":"La temp\u00e9rature est le param\u00e8tre le plus mesur\u00e9 et le plus surveill\u00e9 dans les applications HVACdomestiques, commerciales et industrielles.","og_url":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/hvac-thermometer.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Des thermom\u00e8tres industriels et des capteurs de temp\u00e9rature d\u00e9di\u00e9s aux syst\u00e8mes HVAC","datePublished":"2021-03-15T07:53:54+00:00","dateModified":"2023-11-17T10:58:20+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/"},"wordCount":1005,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/hvac-thermometer.jpg","articleSection":["Temp\u00e9rature"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/","url":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/","name":"Thermom\u00e8tres et capteurs pour l'HVAC - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/hvac-thermometer.jpg","datePublished":"2021-03-15T07:53:54+00:00","dateModified":"2023-11-17T10:58:20+00:00","description":"La temp\u00e9rature est le param\u00e8tre le plus mesur\u00e9 et le plus surveill\u00e9 dans les applications HVACdomestiques, commerciales et industrielles.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/hvac-thermometer.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/02\/hvac-thermometer.jpg","width":838,"height":471,"caption":"\u00c9quipement de climatisation au sommet d'un b\u00e2timent moderne"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/produits\/produits-temperature\/des-thermometres-industriels-et-des-capteurs-de-temperature-dedies-aux-systemes-hvac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Des thermom\u00e8tres industriels et des capteurs de temp\u00e9rature d\u00e9di\u00e9s aux syst\u00e8mes HVAC"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9126"}],"version-history":[{"count":3,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9126\/revisions"}],"predecessor-version":[{"id":11401,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9126\/revisions\/11401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9128"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}