{"id":9213,"date":"2021-04-12T08:35:29","date_gmt":"2021-04-12T06:35:29","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9213"},"modified":"2023-11-16T08:18:10","modified_gmt":"2023-11-16T07:18:10","slug":"mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/","title":{"rendered":"Mesure de la pression dans les process pharmaceutiques pour \u00e9viter la contamination"},"content":{"rendered":"<p><strong>Dans les process pharmaceutiques, les instruments de mesure de pression doivent remplir les t\u00e2ches les plus diverses. Ils contr\u00f4lent la pression du process, servent \u00e0 la d\u00e9tection des fuites, sont utilis\u00e9s pour le contr\u00f4le des pompes, des filtres et des processus de nettoyage, ainsi que pour la surveillance des niveaux de remplissage.<\/strong><\/p>\n<p>Ces instruments de mesure de pression utilis\u00e9s dans les <a href=\"https:\/\/www.wika.com\/fr-fr\/industrie_pharmaceutique_et_biotechnologie.WIKA?tab=5\" rel=\"external\" target=\"_blank\">process pharmaceutiques<\/a> sont soumis aux crit\u00e8res de s\u00e9curit\u00e9 les plus stricts : Pour la protection des consommateurs, il ne doit y avoir aucun risque de contamination du produit fini par les instruments de mesure et les assemblages. Par cons\u00e9quent, la barri\u00e8re st\u00e9rile doit \u00eatre maintenue dans chaque phase du processus. Dans les process sensibles de l&rsquo;industrie pharmaceutique, le facteur de risque humain doit \u00eatre r\u00e9duit au minimum. Les usines fonctionnent de mani\u00e8re presque enti\u00e8rement automatique, le contr\u00f4le des process \u00e9tant bas\u00e9 sur des instruments et des syst\u00e8mes \u00e9lectroniques. \u00a0Dans le cas de la mesure de pression, il s&rsquo;agit de <a href=\"https:\/\/www.wika.com\/fr-fr\/capteurs_de_pression.WIKA\" rel=\"external\" target=\"_blank\">capteurs<\/a>, de <a href=\"https:\/\/www.wika.com\/fr-fr\/transmetteurs_de_process.WIKA\" rel=\"external\" target=\"_blank\">transmetteurs<\/a> programmables et de <a href=\"https:\/\/www.wika.com\/fr-fr\/pressostats.WIKA\" rel=\"external\" target=\"_blank\">pressostats<\/a>.<\/p>\n<p>Outre la fiabilit\u00e9 de l&rsquo;enregistrement et du traitement des valeurs mesur\u00e9es, les instruments de mesure utilis\u00e9s doivent \u00eatre robustes, faciles \u00e0 entretenir et \u00e0 utiliser &#8211; et ce, pas seulement pour des raisons \u00e9conomiques. Ces caract\u00e9ristiques favorisent \u00e9galement la s\u00e9curit\u00e9 du process au niveau du produit final. Des \u00e9tudes ont montr\u00e9 que la majorit\u00e9 des dommages subis par les instruments et susceptibles d&rsquo;entra\u00eener une contamination du produit sont dus \u00e0 une mauvaise manipulation. Il peut aussi y avoir des dommages caus\u00e9s par la corrosion ou des \u00e9v\u00e9nements impr\u00e9visibles tels qu&rsquo;une surpression excessive.<\/p>\n<h2>S\u00e9parateurs ou capteurs en c\u00e9ramique<\/h2>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/pic1_wika_achema_frankfurt_170615_3009-652_b-388x259.jpg\" \/><p class=\"wp-caption-text\">Transmetteur de process programmable avec contr\u00f4le de la membrane<\/p><\/div>\n    \n<p>Les solutions avec des <a href=\"https:\/\/www.wika.com\/fr-fr\/separateurs.WIKA\" rel=\"external\" target=\"_blank\">s\u00e9parateurs<\/a> sont utilis\u00e9es pour de nombreuses applications dans l&rsquo;industrie pharmaceutique. Il se compose d&rsquo;un s\u00e9parateur en acier inox ou autre mat\u00e9riau sp\u00e9cifique, de l&rsquo;instrument de mesure lui-m\u00eame et du liquide de transmission &#8211; glyc\u00e9rine ou huile de paraffine &#8211; conforme aux directives GMP. La membrane re\u00e7oit la pression et la transmet hydrauliquement au transmetteur ou pressostat programmable. L&rsquo;instrument de mesure est ainsi s\u00e9par\u00e9 en permanence du process et fournit un r\u00e9sultat de mesure pr\u00e9cis, prot\u00e9g\u00e9 des influences. Les s\u00e9parateurs \u00e0 membrane offrent une grande flexibilit\u00e9 op\u00e9rationnelle. Gr\u00e2ce \u00e0 eux, presque tous les instruments peuvent \u00eatre connect\u00e9s de mani\u00e8re hygi\u00e9nique \u00e0 un process. C&rsquo;est un avantage par rapport aux instruments de mesure \u00e9quip\u00e9s de capteurs en c\u00e9ramique.<\/p>\n\n      <div class=\"wp-caption alignleft\" style=\"max-width:208px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/pic9_utp-20-mit-990.60-g50-388x805.jpg\" \/><p class=\"wp-caption-text\">Transmetteur de processus programmable avec s\u00e9parateur.<\/p><\/div>\n    \n<p>La raison principale de l&rsquo;utilisation de capteurs c\u00e9ramiques dans les applications sanitaires est leur grande pr\u00e9cision. La mesure de la pression est effectu\u00e9e directement par un capteur capacitif affleurant, sans liquide de remplissage du syst\u00e8me qui pourrait, en cas de dommage, se retrouver dans le process. Par rapport aux membranes m\u00e9talliques des s\u00e9parateurs, les capteurs en c\u00e9ramique sont consid\u00e9r\u00e9s comme ayant une meilleure r\u00e9sistance aux forces de cisaillement ou \u00e0 la corrosion sur le long terme. La d\u00e9faillance d&rsquo;un capteur en c\u00e9ramique serait imm\u00e9diatement reconnue par l&rsquo;op\u00e9rateur gr\u00e2ce \u00e0 une perte du signal. Avec un montage sur s\u00e9parateur dont la membrane est endommag\u00e9e, le process de mesure fonctionne toujours. La membrane endommag\u00e9e passe inaper\u00e7ue jusqu&rsquo;\u00e0 ce qu&rsquo;une inspection visuelle soit effectu\u00e9e.<\/p>\n<p>Mais un capteur en c\u00e9ramique n&rsquo;est pas non plus \u00e0 l&rsquo;abri des dommages. Cela peut \u00eatre d\u00fb \u00e0 la pr\u00e9sence d&rsquo;eau charg\u00e9e et de vapeur dans le process ou \u00e0 un cycle thermique brutal. Si la c\u00e9ramique se brise, l&rsquo;air et les mati\u00e8res \u00e9trang\u00e8res provenant de l&rsquo;ext\u00e9rieur peuvent p\u00e9n\u00e9trer dans le process par la ventilation et contaminer le capteur. En utilisant des s\u00e9parateurs, le process reste toujours \u00e9tanche, m\u00eame si une membrane est compromise, et la barri\u00e8re st\u00e9rile est ainsi maintenue.<\/p>\n<p>Cependant, il peut arriver que les produits soient contamin\u00e9s m\u00eame avec un process \u00e9tanche. En raison de la pr\u00e9cision des mesures, l&rsquo;\u00e9paisseur de la membrane est r\u00e9duite.\u00a0 Par cons\u00e9quent, une surcharge \u00e0 long terme dans le process peut entra\u00eener des d\u00e9formations.\u00a0 Et les particules de produit peuvent se d\u00e9poser et former des microbes. Un effet similaire n&rsquo;est pas non plus \u00e0 exclure avec les capteurs en c\u00e9ramique.\u00a0 Le point faible est ici l&rsquo;\u00e9tanch\u00e9it\u00e9 entre le capteur et le raccord m\u00e9tallique du process :\u00a0 En premier lieu, des substances peuvent se diffuser dans le joint et \u00eatre \u00e0 nouveau lib\u00e9r\u00e9es lors de l&rsquo;\u00e9tape suivante du process. D&rsquo;autre part, la membrane peut \u00eatre affect\u00e9e par des variations dynamiques de temp\u00e9ratures \u00e9lev\u00e9es, ce qui peut entra\u00eener la formation d&rsquo;un espace au niveau du raccord process &#8211; un point de d\u00e9p\u00f4t potentiel. Si ceux-ci ne sont pas d\u00e9tect\u00e9s, ils peuvent \u00eatre transf\u00e9r\u00e9s aux process suivants.\u00a0 Cette contamination crois\u00e9e non d\u00e9tect\u00e9e a g\u00e9n\u00e9ralement de graves cons\u00e9quences r\u00e9glementaires et \u00e9conomiques dont les co\u00fbts peuvent se chiffrer en millions. C&rsquo;est pourquoi les entreprises pharmaceutiques s&rsquo;efforcent de pr\u00e9venir de tels dommages. Dans les process hautement sensibles, par exemple, les instruments de mesure de pression sont retir\u00e9s apr\u00e8s chaque lot et v\u00e9rifi\u00e9s pour voir s&rsquo;ils sont endommag\u00e9s.\u00a0 Cela ajoute des co\u00fbts au process de fabrication.<\/p>\n<h2>Le syst\u00e8me de contr\u00f4le d\u2019\u00e9tanch\u00e9it\u00e9 \u00e0 double membrane<\/h2>\n<p>Wika a d\u00e9velopp\u00e9 une solution sp\u00e9ciale qui r\u00e9pond \u00e0 ces probl\u00e8mes : Un syst\u00e8me de s\u00e9parateur avec syst\u00e8me de contr\u00f4le d\u2019\u00e9tanch\u00e9it\u00e9 \u00e0 double membrane avec surveillance de la membrane qui supprime les risques et les dommages cons\u00e9cutifs d\u00e9crits ci-dessus. Gr\u00e2ce \u00e0 ce syst\u00e8me brevet\u00e9, l&rsquo;espace entre les deux membranes est tir\u00e9 au vide et le vide peut \u00eatre contr\u00f4l\u00e9 \u00e0 l&rsquo;aide d&rsquo;un instrument de mesure.<\/p>\n<p>Le type de surveillance mis en oeuvre peut \u00eatre d\u00e9fini sp\u00e9cifiquement, en fonction de la sensibilit\u00e9 du process. Dans le cas d&rsquo;un contr\u00f4le visuel r\u00e9gulier sur site, il suffit par exemple d\u2019utiliser un manom\u00e8tre avec des zones de lecture du cadran de couleurs verte (= situation ok) et rouge (= probl\u00e8me au niveau de la membrane)\u00a0; dans d&rsquo;autres cas, une alarme optique ou acoustique dans la salle de contr\u00f4le peut \u00eatre n\u00e9cessaire. Si la membrane en contact avec le fluide est endommag\u00e9e, la seconde membrane forme une barri\u00e8re fiable avec le process et maintient la surveillance de la pression jusqu&rsquo;\u00e0 ce que le dommage ait \u00e9t\u00e9 r\u00e9par\u00e9. Comme une rupture dans le syst\u00e8me est d\u00e9tect\u00e9e et signal\u00e9e imm\u00e9diatement, aucun microbe ne peut franchir la membrane sans \u00eatre d\u00e9tect\u00e9.<\/p>\n<h2>Manom\u00e8tres \u00e0 membrane<\/h2>\n<p>Malgr\u00e9 le niveau d&rsquo;automatisation extr\u00eamement \u00e9lev\u00e9 des process pharmaceutiques, tous les points de mesure ne doivent pas n\u00e9cessairement \u00eatre g\u00e9r\u00e9s \u00e9lectroniquement. Dans ce cas, les <a href=\"https:\/\/www.wika.com\/fr-fr\/montages_sur_separateur.WIKA?Node=70902&amp;326=1356\" rel=\"external\" target=\"_blank\">manom\u00e8tres \u00e0 membrane affleurante<\/a> sont particuli\u00e8rement int\u00e9ressants. Ils permettent de mesurer de faibles pressions et sont, de par leur conception, particuli\u00e8rement s\u00fbrs en cas de surpression, maintenant l&rsquo;\u00e9tanch\u00e9it\u00e9 m\u00eame dans ces conditions.\u00a0 Pour ces manom\u00e8tres, WIKA propose \u00e9galement un syst\u00e8me de contr\u00f4le d\u2019\u00e9tanch\u00e9it\u00e9 de membranes qui signale imm\u00e9diatement toute rupture de l&rsquo;\u00e9l\u00e9ment de pression.<\/p>\n<p>L&rsquo;industrie pharmaceutique se tournant de plus en plus vers le d\u00e9veloppement et la fabrication de m\u00e9dicaments individuels, les dimensions des r\u00e9servoirs sont de plus en plus r\u00e9duites. Il en r\u00e9sulte des process avec des unit\u00e9s et des lots de petite taille.\u00a0 Les instruments de mesure des r\u00e9servoirs correspondants ont donc un espace disponible limit\u00e9. Cela peut vite devenir \u00e9troit pour les manom\u00e8tres \u00e0 membrane : Plus la pression \u00e0 mesurer est faible, plus le diam\u00e8tre de la membrane doit \u00eatre important et, par cons\u00e9quent, le raccordement au process aussi.<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:208px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/pic5_pg43sa_2_wio0610_6536-388x418.jpg\" \/><p class=\"wp-caption-text\">Manom\u00e8tre \u00e0 membrane affleurante pour applications sanitaires type PG43SA-C<\/p><\/div>\n    \n<p>Pour rem\u00e9dier \u00e0 ce probl\u00e8me, WIKA a mis au point un nouveau manom\u00e8tre pour les petites surfaces ext\u00e9rieures : Le mod\u00e8le <a href=\"https:\/\/www.wika.com\/fr-fr\/pg43sa_c.WIKA\" rel=\"external\" target=\"_blank\">PG43SA-C<\/a> mesure dans les plages de basse pression avec une membrane proportionnellement beaucoup plus petite. Cet instrument combine la taille r\u00e9duite du raccord avec une autre caract\u00e9ristique sp\u00e9cifique qui est particuli\u00e8rement importante pour de telles mesures sur les r\u00e9servoirs : Il est autoclavable. Le manom\u00e8tre peut \u00eatre st\u00e9rilis\u00e9 avec le r\u00e9servoir dans des conditions de vapeur satur\u00e9e \u00e0 des temp\u00e9ratures allant jusqu&rsquo;\u00e0 +134 \u00b0C, sans qu&rsquo;il soit n\u00e9cessaire de le d\u00e9monter. Le process reste ainsi \u00e9tanche, y compris dans la phase mobile, et l&rsquo;assurance qualit\u00e9 est pr\u00e9serv\u00e9e.<\/p>\n<h2>Conclusion<\/h2>\n<p>Plus le process pharmaceutique est critique, plus le maintien constant de la barri\u00e8re st\u00e9rile dans le processus de fabrication est important. Outre la technologie de mesure, la pr\u00e9vention des risques a \u00e9galement des exigences \u00e9lev\u00e9es en mati\u00e8re de pr\u00e9cision et de fiabilit\u00e9.<\/p>\n<p>SI vous souhaitez connaitre les solutions disponibles pour votre application en particulier, nos <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">experts en mesure de pression<\/a> sont \u00e0 votre disposition pour tous renseignements compl\u00e9mentaires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans les process pharmaceutiques, les instruments de mesure de pression doivent remplir les t\u00e2ches les plus diverses. Ils contr\u00f4lent la pression du process, servent \u00e0 la d\u00e9tection des fuites, sont utilis\u00e9s pour le contr\u00f4le des pompes, des filtres et des processus de nettoyage, ainsi que pour la surveillance des niveaux de remplissage. Ces instruments de [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":9214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232],"tags":[387,394],"class_list":["post-9213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","tag-manomtre-membrane","tag-mesure-de-pression"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesure de la pression dans les process pharmaceutiques - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Dans les process pharmaceutiques, les instruments de mesure de pression doivent contr\u00f4ler la pression,d\u00e9tecter les fuites ou encore surveiller des niveaux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesure de la pression dans les process pharmaceutiques - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Dans les process pharmaceutiques, les instruments de mesure de pression doivent contr\u00f4ler la pression,d\u00e9tecter les fuites ou encore surveiller des niveaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/hameln-group_24_\u00a9ulfsalzmann-1024x681.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Mesure de la pression dans les process pharmaceutiques pour \u00e9viter la contamination\",\"datePublished\":\"2021-04-12T06:35:29+00:00\",\"dateModified\":\"2023-11-16T07:18:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/\"},\"wordCount\":1624,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/03\\\/hameln-group_24_\u00a9ulfsalzmann.jpg\",\"keywords\":[\"manom\u00e8tre \u00e0 membrane\",\"mesure de pression\"],\"articleSection\":[\"Applications\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/\",\"name\":\"Mesure de la pression dans les process pharmaceutiques - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/03\\\/hameln-group_24_\u00a9ulfsalzmann.jpg\",\"datePublished\":\"2021-04-12T06:35:29+00:00\",\"dateModified\":\"2023-11-16T07:18:10+00:00\",\"description\":\"Dans les process pharmaceutiques, les instruments de mesure de pression doivent contr\u00f4ler la pression,d\u00e9tecter les fuites ou encore surveiller des niveaux.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/03\\\/hameln-group_24_\u00a9ulfsalzmann.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/03\\\/hameln-group_24_\u00a9ulfsalzmann.jpg\",\"width\":4662,\"height\":3102},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mesure de la pression dans les process pharmaceutiques pour \u00e9viter la contamination\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesure de la pression dans les process pharmaceutiques - Blog WIKA","description":"Dans les process pharmaceutiques, les instruments de mesure de pression doivent contr\u00f4ler la pression,d\u00e9tecter les fuites ou encore surveiller des niveaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/","og_locale":"fr_FR","og_type":"article","og_title":"Mesure de la pression dans les process pharmaceutiques - Blog WIKA","og_description":"Dans les process pharmaceutiques, les instruments de mesure de pression doivent contr\u00f4ler la pression,d\u00e9tecter les fuites ou encore surveiller des niveaux.","og_url":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/","og_site_name":"Blog WIKA","og_image":[{"width":1024,"height":681,"url":"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/hameln-group_24_\u00a9ulfsalzmann-1024x681.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Mesure de la pression dans les process pharmaceutiques pour \u00e9viter la contamination","datePublished":"2021-04-12T06:35:29+00:00","dateModified":"2023-11-16T07:18:10+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/"},"wordCount":1624,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/hameln-group_24_\u00a9ulfsalzmann.jpg","keywords":["manom\u00e8tre \u00e0 membrane","mesure de pression"],"articleSection":["Applications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/","url":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/","name":"Mesure de la pression dans les process pharmaceutiques - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/hameln-group_24_\u00a9ulfsalzmann.jpg","datePublished":"2021-04-12T06:35:29+00:00","dateModified":"2023-11-16T07:18:10+00:00","description":"Dans les process pharmaceutiques, les instruments de mesure de pression doivent contr\u00f4ler la pression,d\u00e9tecter les fuites ou encore surveiller des niveaux.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/hameln-group_24_\u00a9ulfsalzmann.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/03\/hameln-group_24_\u00a9ulfsalzmann.jpg","width":4662,"height":3102},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/mesure-de-la-pression-dans-les-process-pharmaceutiques-pour-eviter-la-contamination\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Mesure de la pression dans les process pharmaceutiques pour \u00e9viter la contamination"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9213"}],"version-history":[{"count":4,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9213\/revisions"}],"predecessor-version":[{"id":11160,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9213\/revisions\/11160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9214"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}