{"id":9555,"date":"2022-01-10T08:00:54","date_gmt":"2022-01-10T07:00:54","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9555"},"modified":"2023-12-11T09:02:55","modified_gmt":"2023-12-11T08:02:55","slug":"surveillance-fiable-des-filtres-avec-des-manometres-differentiels","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/","title":{"rendered":"Surveillance fiable des filtres avec des manom\u00e8tres diff\u00e9rentiels."},"content":{"rendered":"<h2>La surveillance des filtres est une t\u00e2che essentielle des manom\u00e8tres diff\u00e9rentiels : la pression diff\u00e9rentielle augmente d\u00e8s que le filtre se colmate. C\u2019est ainsi que les instruments de mesure signalent quand le filtre doit \u00eatre nettoy\u00e9 ou remplac\u00e9. L&rsquo;efficacit\u00e9 d&rsquo;une telle solution peut \u00eatre illustr\u00e9e par l&rsquo;exemple des manom\u00e8tres WIKA de la s\u00e9rie DELTA-line dans le traitement de l&rsquo;eau.<\/h2>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2021\/12\/w22-02-2-textbild_dpg.jpg\" \/><p class=\"wp-caption-text\">Avec son microrupteur et son affichage, le manom\u00e8tre diff\u00e9rentiel WIKA mod\u00e8le DPGS40 permet de surveiller les filtres en toute s\u00e9curit\u00e9.<\/p><\/div>\n    \n<p>&nbsp;<\/p>\n<p>Dans l&rsquo;industrie de l&rsquo;eau, l&rsquo;osmose inverse est un proc\u00e9d\u00e9 largement utilis\u00e9 pour s\u00e9parer l&rsquo;eau des substances ind\u00e9sirables. Les syst\u00e8mes de filtration correspondants fonctionnent avec des membranes semi-perm\u00e9ables.<\/p>\n<p>Pour la surveillance des filtres, un fournisseur international de solutions pour le traitement des eaux potables, industrielles et us\u00e9es utilise des manom\u00e8tres diff\u00e9rentiels WIKA mod\u00e8le DPGS40 de la famille DELTA-line dans ses usines en Allemagne. L&rsquo;instrument mesure la pression des deux c\u00f4t\u00e9s de la membrane.<\/p>\n<h2>Une intervention au bon moment sur le filtre<\/h2>\n<p>En plus de l\u2019affichage de la pression diff\u00e9rentielle, le manom\u00e8tre est \u00e9quip\u00e9 d&rsquo;un microrupteur int\u00e9gr\u00e9. Celui-ci envoie un signal d&rsquo;avertissement au centre de contr\u00f4le lorsqu&rsquo;une valeur limite d\u00e9finie est atteinte. L&rsquo;op\u00e9rateur peut ainsi prendre des dispositions pour nettoyer ou remplacer le filtre en temps voulu. Gr\u00e2ce \u00e0 son principe de mesure m\u00e9canique, la surveillance du filtre fonctionne \u00e9galement de mani\u00e8re fiable en cas de panne de courant.<\/p>\n<h2>Une surveillance continue<\/h2>\n<p>Une intervention rapide sur le filtre est n\u00e9cessaire pour deux raisons. Premi\u00e8rement : elle permet d&rsquo;\u00e9viter une \u00e9ventuelle contamination de l&rsquo;eau. Deuxi\u00e8mement, l&rsquo;op\u00e9rateur \u00e9conomise de l&rsquo;\u00e9nergie gr\u00e2ce \u00e0 la surveillance continue du filtre. Plus un filtre est encrass\u00e9, plus la pompe doit travailler pour obtenir le d\u00e9bit souhait\u00e9.<\/p>\n<h2>Une indication int\u00e9gr\u00e9e de la pression de travail<\/h2>\n<p>Notre client a choisi le manom\u00e8tre DELTA-line pour la surveillance du filtre pour une autre raison encore : l&rsquo;indication int\u00e9gr\u00e9e de la pression de service. Cette information est importante pour l&rsquo;usine, car elle permet d\u2019analyser les performances respectives de la pompe. Pour obtenir une telle information sans le DELTA-line, un point de mesure suppl\u00e9mentaire aurait d\u00fb \u00eatre install\u00e9.<\/p>\n<h2>Autres exigences de mesure<\/h2>\n<p>En plus de la surveillance des filtres, les manom\u00e8tres diff\u00e9rentiels de la s\u00e9rie DELTA-line sont adapt\u00e9s aux t\u00e2ches de mesure de niveau et de d\u00e9bit. Avec diff\u00e9rentes versions, ils couvrent une large gamme d&rsquo;applications. Les instruments DPGx sont disponibles avec une sortie de signal analogique et jusqu&rsquo;\u00e0 deux microcontacts. Tous sont homologu\u00e9s ATEX. Il existe \u00e9galement une variante avec certification SIL et approbation DNV-GL pour les applications marines.<\/p>\n<p>&nbsp;<\/p>\n<h2>Note<\/h2>\n<p>Vous trouverez une vue d&rsquo;ensemble de tous les instruments de la <a href=\"https:\/\/www.wika.com\/media\/Brochures-and-flyers\/Products_Services\/fl_deltaline_en_co.pdf\" rel=\"external\" target=\"_blank\">s\u00e9rie DELTA-line<\/a> sur notre flyer. Si vous avez des questions, votre interlocuteur se fera un plaisir de vous aider.<\/p>\n<p><strong>WIKA, la pression et la temp\u00e9rature sur-mesure<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La surveillance des filtres est une t\u00e2che essentielle des manom\u00e8tres diff\u00e9rentiels : la pression diff\u00e9rentielle augmente d\u00e8s que le filtre se colmate. C\u2019est ainsi que les instruments de mesure signalent quand le filtre doit \u00eatre nettoy\u00e9 ou remplac\u00e9. L&rsquo;efficacit\u00e9 d&rsquo;une telle solution peut \u00eatre illustr\u00e9e par l&rsquo;exemple des manom\u00e8tres WIKA de la s\u00e9rie DELTA-line dans [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":9547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232],"tags":[75,394,284,401,254,262],"class_list":["post-9555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","tag-manometre","tag-mesure-de-pression","tag-point-de-mesure","tag-pression","tag-protection-ex","tag-securite-fonctionnelle-sil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Surveillance des filtres avec des manom\u00e8tres diff\u00e9rentiels.- Blog WIKA<\/title>\n<meta name=\"description\" content=\"La surveillance des filtres est une t\u00e2che essentielle des manom\u00e8tres diff\u00e9rentiels : la pression diff\u00e9rentielle augmente d\u00e8s que le filtre se colmate. C\u2019est ainsi que les instruments de mesure signalent quand le filtre doit \u00eatre nettoy\u00e9 ou remplac\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Surveillance des filtres avec des manom\u00e8tres diff\u00e9rentiels.- Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"La surveillance des filtres est une t\u00e2che essentielle des manom\u00e8tres diff\u00e9rentiels : la pression diff\u00e9rentielle augmente d\u00e8s que le filtre se colmate. C\u2019est ainsi que les instruments de mesure signalent quand le filtre doit \u00eatre nettoy\u00e9 ou remplac\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2021\/12\/w22-02-1-beitragsbild_deltaline.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Surveillance fiable des filtres avec des manom\u00e8tres diff\u00e9rentiels.\",\"datePublished\":\"2022-01-10T07:00:54+00:00\",\"dateModified\":\"2023-12-11T08:02:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/\"},\"wordCount\":545,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/12\\\/w22-02-1-beitragsbild_deltaline.jpg\",\"keywords\":[\"Manom\u00e8tre\",\"mesure de pression\",\"Point de mesure\",\"pression\",\"Protection Ex\",\"S\u00e9curit\u00e9 fonctionnelle (SIL)\"],\"articleSection\":[\"Applications\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/\",\"name\":\"Surveillance des filtres avec des manom\u00e8tres diff\u00e9rentiels.- Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/12\\\/w22-02-1-beitragsbild_deltaline.jpg\",\"datePublished\":\"2022-01-10T07:00:54+00:00\",\"dateModified\":\"2023-12-11T08:02:55+00:00\",\"description\":\"La surveillance des filtres est une t\u00e2che essentielle des manom\u00e8tres diff\u00e9rentiels : la pression diff\u00e9rentielle augmente d\u00e8s que le filtre se colmate. C\u2019est ainsi que les instruments de mesure signalent quand le filtre doit \u00eatre nettoy\u00e9 ou remplac\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/12\\\/w22-02-1-beitragsbild_deltaline.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2021\\\/12\\\/w22-02-1-beitragsbild_deltaline.jpg\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Surveillance fiable des filtres avec des manom\u00e8tres diff\u00e9rentiels.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Surveillance des filtres avec des manom\u00e8tres diff\u00e9rentiels.- Blog WIKA","description":"La surveillance des filtres est une t\u00e2che essentielle des manom\u00e8tres diff\u00e9rentiels : la pression diff\u00e9rentielle augmente d\u00e8s que le filtre se colmate. C\u2019est ainsi que les instruments de mesure signalent quand le filtre doit \u00eatre nettoy\u00e9 ou remplac\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/","og_locale":"fr_FR","og_type":"article","og_title":"Surveillance des filtres avec des manom\u00e8tres diff\u00e9rentiels.- Blog WIKA","og_description":"La surveillance des filtres est une t\u00e2che essentielle des manom\u00e8tres diff\u00e9rentiels : la pression diff\u00e9rentielle augmente d\u00e8s que le filtre se colmate. C\u2019est ainsi que les instruments de mesure signalent quand le filtre doit \u00eatre nettoy\u00e9 ou remplac\u00e9.","og_url":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2021\/12\/w22-02-1-beitragsbild_deltaline.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Surveillance fiable des filtres avec des manom\u00e8tres diff\u00e9rentiels.","datePublished":"2022-01-10T07:00:54+00:00","dateModified":"2023-12-11T08:02:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/"},"wordCount":545,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/12\/w22-02-1-beitragsbild_deltaline.jpg","keywords":["Manom\u00e8tre","mesure de pression","Point de mesure","pression","Protection Ex","S\u00e9curit\u00e9 fonctionnelle (SIL)"],"articleSection":["Applications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/","url":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/","name":"Surveillance des filtres avec des manom\u00e8tres diff\u00e9rentiels.- Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/12\/w22-02-1-beitragsbild_deltaline.jpg","datePublished":"2022-01-10T07:00:54+00:00","dateModified":"2023-12-11T08:02:55+00:00","description":"La surveillance des filtres est une t\u00e2che essentielle des manom\u00e8tres diff\u00e9rentiels : la pression diff\u00e9rentielle augmente d\u00e8s que le filtre se colmate. C\u2019est ainsi que les instruments de mesure signalent quand le filtre doit \u00eatre nettoy\u00e9 ou remplac\u00e9.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2021\/12\/w22-02-1-beitragsbild_deltaline.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2021\/12\/w22-02-1-beitragsbild_deltaline.jpg","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/surveillance-fiable-des-filtres-avec-des-manometres-differentiels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Surveillance fiable des filtres avec des manom\u00e8tres diff\u00e9rentiels."}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9555"}],"version-history":[{"count":4,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9555\/revisions"}],"predecessor-version":[{"id":11587,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9555\/revisions\/11587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9547"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}