{"id":9608,"date":"2022-03-28T08:00:11","date_gmt":"2022-03-28T06:00:11","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9608"},"modified":"2023-11-16T09:57:31","modified_gmt":"2023-11-16T08:57:31","slug":"l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/","title":{"rendered":"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi !"},"content":{"rendered":"<p><strong>Les instruments d\u2019\u00e9talonnage conventionnels sont g\u00e9n\u00e9ralement con\u00e7us pour des pressions allant jusqu&rsquo;\u00e0 1 000 bars. Or, dans de nombreuses applications, les capteurs travaillent \u00e0 cette valeur, par exemple dans l&rsquo;industrie automobile. Si vous souhaitez \u00e9talonner de tels appareils sur l&rsquo;ensemble de la plage de mesure, WIKA a la solution : <a href=\"https:\/\/www.wika.com\/fr-fr\/cph7000.WIKA?ProductGroup=70935\" rel=\"external\" target=\"_blank\">le calibrateur de process portable CPH7000<\/a> associ\u00e9 au capteur de r\u00e9f\u00e9rence CPT7000 pour des pressions allant jusqu&rsquo;\u00e0 10 000 bars.<\/strong><\/p>\n<p>Notre client, qui d\u00e9veloppe et construit des pompes d&rsquo;injection pour moteurs diesel dans l&rsquo;industrie automobile, a opt\u00e9 pour cette combinaison. La pression exacte inject\u00e9e est d&rsquo;une importance capitale pour le groupe moteur. C&rsquo;est pourquoi l&rsquo;entreprise utilise des bancs d&rsquo;essai moteur pour une analyse pointue du process de combustion. Les transmetteurs de pression qui y sont int\u00e9gr\u00e9s, dont le mod\u00e8le HP-2 de WIKA, doivent mesurer avec pr\u00e9cision des pressions d&rsquo;injection de 3 000 bar, 5 000 bar et 7 000 bar.<\/p>\n<h2><strong>Solution compl\u00e8te, comprenant la pompe de g\u00e9n\u00e9ration de pression hydraulique et le logiciel<\/strong><\/h2>\n<p>&nbsp;<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2022\/02\/w22-13-2-textbild_cph7_hochdruck.jpg\" \/><p class=\"wp-caption-text\">L\u2019ensemble pour l&rsquo;\u00e9talonnage haute pression jusqu&rsquo;\u00e0 10 000 bar : le calibrateur de process mod\u00e8le CPH7000 associ\u00e9 au capteur de r\u00e9f\u00e9rence externe mod\u00e8le CPT7000.<\/p><\/div>\n    \n<p>Pour maintenir la qualit\u00e9 des mesures, un contr\u00f4le r\u00e9gulier des capteurs de pression est indispensable. Pour ce faire, WIKA a mis au point une solution compl\u00e8te pour l&rsquo;\u00e9talonnage des instruments de mesure tr\u00e8s hautes pressions. Outre le calibrateur et le capteur de r\u00e9f\u00e9rence, cette solution comprend une pompe \u00e0 pression hydraulique mod\u00e8le CPP7000-X pour g\u00e9n\u00e9rer la pression n\u00e9cessaire. L\u2019ensemble est compl\u00e9t\u00e9 par le logiciel WIKA-Cal pour la lecture et le traitement des donn\u00e9es. Ainsi, la soci\u00e9t\u00e9 est \u00e9galement en mesure de d\u00e9livrer des certificats d&rsquo;\u00e9talonnage.<\/p>\n<h2><strong>Un capteur de r\u00e9f\u00e9rence avec une conception sp\u00e9ciale<\/strong><\/h2>\n<p>Le client a int\u00e9gr\u00e9 l&rsquo;ensemble pour l&rsquo;\u00e9talonnage de ses capteurs \u00e0 haute pression dans son laboratoire d&rsquo;\u00e9talonnage. Afin de pouvoir \u00e9talonner les instruments de mesure, tels que les capteurs du banc d&rsquo;essai moteur, le capteur de r\u00e9f\u00e9rence a une conception sp\u00e9ciale : La cellule \u00e0 couche mince incassable du mod\u00e8le CPT7000 n&rsquo;est pas soud\u00e9e. Au lieu de cela, elle est solidement fix\u00e9e dans un orifice de pression conique. L&rsquo;\u00e9l\u00e9ment de pression est donc insensible aux profils de pression dynamiques.<\/p>\n<p>La r\u00e9f\u00e9rence de pression ne peut \u00eatre utilis\u00e9e qu&rsquo;en association avec le calibrateur portable CPH7000. Celui-ci pr\u00e9sente un avantage suppl\u00e9mentaire pour l&rsquo;entreprise : la possibilit\u00e9 de r\u00e9aliser des \u00e9talonnage et tests sur site. En plus de l\u2019\u00e9talonnage en laboratoire, le client peut ainsi d\u00e9terminer, directement sur le banc d&rsquo;essai du moteur, comment les capteurs se comportent une fois install\u00e9s.<\/p>\n<h2><strong>Cartographie d\u00e9taill\u00e9e de toutes les s\u00e9quences d\u2019\u00e9talonnage<\/strong><\/h2>\n<p>De plus, le CPH7000 ouvre d&rsquo;autres possibilit\u00e9s. Il s&rsquo;agit d&rsquo;un instrument multifonctions, avec module \u00e9lectrique et pompe manuelle int\u00e9gr\u00e9s, qui est \u00e9galement disponible avec une homologation ATEX. Outre l&rsquo;\u00e9talonnage des instruments de mesure de la pression, le calibrateur remplit \u00e9galement des fonctions de test pour la temp\u00e9rature, la tension et le courant. Son enregistreur de donn\u00e9es affiche chaque s\u00e9quence en d\u00e9tail. L&rsquo;affichage en direct des process d&rsquo;enregistrement sous forme de s\u00e9ries num\u00e9riques ou de graphiques permet d&rsquo;identifier imm\u00e9diatement les d\u00e9viations.<\/p>\n<h2><strong>Note<\/strong><\/h2>\n<p>Vous trouverez de plus amples informations sur le calibrateur de pression portable CPH7000 et le capteur de r\u00e9f\u00e9rence CPT7000 pour les pressions les plus \u00e9lev\u00e9es sur le<a href=\"https:\/\/www.wika.com\/fr-fr\/page_d_accueil.WIKA\" rel=\"external\" target=\"_blank\"> site Web de WIKA<\/a>. Vous y trouverez \u00e9galement des informations sur le <a href=\"https:\/\/www.wika.com\/fr-fr\/cpg1500.WIKA\" rel=\"external\" target=\"_blank\">manom\u00e8tre num\u00e9rique de pr\u00e9cision CPG1500<\/a>, qui peut mesurer des pressions allant jusqu&rsquo;\u00e0 10 000 bars. Si vous avez des questions, votre interlocuteur se fera un plaisir de vous aider.<\/p>\n<h2><strong>WIKA, la pression et la temp\u00e9rature sur-mesure<\/strong><\/h2>\n<p><strong><br \/>\nVous pouvez \u00e9galement en savoir plus sur le mat\u00e9riel d&rsquo;\u00e9talonnage dans la vid\u00e9o suivante :<\/strong><\/p>\n<div data-fullscreen=\"disabled\" data-mode=\"normal\" data-oembed=\"1\" data-provider=\"youtube\" data-reset-after-played id=\"arve-youtube-zukak-qb300\" style=\"max-width:900px;\" class=\"arve\">\n<div class=\"arve-inner\">\n<div style=\"aspect-ratio:500\/281\" class=\"arve-embed arve-embed--has-aspect-ratio\">\n<div class=\"arve-ar\" style=\"padding-top:56.200000%\"><\/div>\n<p>\t\t\t<iframe allow=\"accelerometer &apos;none&apos;;autoplay &apos;none&apos;;bluetooth &apos;none&apos;;browsing-topics &apos;none&apos;;camera &apos;none&apos;;clipboard-read &apos;none&apos;;clipboard-write;display-capture &apos;none&apos;;encrypted-media &apos;none&apos;;gamepad &apos;none&apos;;geolocation &apos;none&apos;;gyroscope &apos;none&apos;;hid &apos;none&apos;;identity-credentials-get &apos;none&apos;;idle-detection &apos;none&apos;;keyboard-map &apos;none&apos;;local-fonts;magnetometer &apos;none&apos;;microphone &apos;none&apos;;midi &apos;none&apos;;otp-credentials &apos;none&apos;;payment &apos;none&apos;;picture-in-picture;publickey-credentials-create &apos;none&apos;;publickey-credentials-get &apos;none&apos;;screen-wake-lock &apos;none&apos;;serial &apos;none&apos;;summarizer &apos;none&apos;;sync-xhr;usb &apos;none&apos;;web-share;window-management &apos;none&apos;;xr-spatial-tracking &apos;none&apos;;\" allowfullscreen=\"\" class=\"arve-iframe fitvidsignore\" credentialless data-arve=\"arve-youtube-zukak-qb300\" data-lenis-prevent=\"\" data-src-no-ap=\"https:\/\/www.youtube-nocookie.com\/embed\/zukAK-QB300?feature=oembed&amp;iv_load_policy=3&amp;modestbranding=1&amp;rel=0&amp;autohide=1&amp;playsinline=0&amp;autoplay=0&amp;enablejsapi=1\" frameborder=\"0\" height=\"505.8\" loading=\"lazy\" name=\"\" referrerpolicy=\"strict-origin-when-cross-origin\" sandbox=\"allow-scripts allow-same-origin allow-presentation allow-popups allow-popups-to-escape-sandbox\" scrolling=\"no\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/zukAK-QB300?feature=oembed&#038;iv_load_policy=3&#038;modestbranding=1&#038;rel=0&#038;autohide=1&#038;playsinline=0&#038;autoplay=0&#038;enablejsapi=1\" title=\"\u00c9talonner un transmetteur de pression dans un environnement explosif avec un calibrateur de pression\" width=\"900\"><\/iframe><\/p><\/div>\n<\/p><\/div>\n<p>\t<script type=\"application\/ld+json\">{\"@context\":\"http:\\\/\\\/schema.org\\\/\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#arve-youtube-zukak-qb300\",\"@type\":\"VideoObject\",\"author\":{\"@type\":\"Organization\",\"name\":\"WIKA Group\"},\"embedURL\":\"https:\\\/\\\/www.youtube-nocookie.com\\\/embed\\\/zukAK-QB300?feature=oembed&iv_load_policy=3&modestbranding=1&rel=0&autohide=1&playsinline=0&autoplay=0&enablejsapi=1\",\"name\":\"\\u00c9talonner un transmetteur de pression dans un environnement explosif avec un calibrateur de pression\",\"thumbnailUrl\":\"https:\\\/\\\/i.ytimg.com\\\/vi\\\/zukAK-QB300\\\/hqdefault.jpg\",\"uploadDate\":\"2021-04-06T07:34:51Z\",\"description\":\"Dans cette vid\\u00e9o, le calibrateur de process CPH7000 Ex est utilis\\u00e9 pour expliquer l'\\u00e9talonnage d'un transmetteur  4\\\/20 mA en environnement explosif.\\n \\n\\u2705 Tout d'abord, nous expliquerons comment pr\\u00e9-programmer une s\\u00e9quence d'\\u00e9talonnage \\u00e0 l'aide des param\\u00e8tres du CPH7000 Ex\\n\\u2705 Ensuite, nous montrerons, \\u00e9tape par \\u00e9tape, comment connecter en toute s\\u00e9curit\\u00e9 le calibrateur CPH7000 Ex \\u00e0 l'instrument \\u00e0 tester et comment ex\\u00e9cuter une s\\u00e9quence d'\\u00e9talonnage.\\n\\u2705 Enfin, nous verrons comment r\\u00e9gler le z\\u00e9ro et la gamme du transmetteur en cas d'\\u00e9chec de l'\\u00e9talonnage. Une fois l'\\u00e9talonnage termin\\u00e9, nous fournirons les \\u00e9tapes successives pour d\\u00e9connecter en toute s\\u00e9curit\\u00e9 le CPH7000 Ex de l'instrument. \\n \\nLe CPH7000 Ex \\u00e0 s\\u00e9curit\\u00e9 intrins\\u00e8que est un calibrateur multifonction portable pr\\u00e9cis. Le syst\\u00e8me de navigation convivial permet une utilisation fluide et simple. Il peut \\u00eatre utilis\\u00e9 dans des environnements dangereux pour \\u00e9talonner et mesurer une large gamme d'instruments de pression et de temp\\u00e9rature\\n\\n\\ud83d\\udccd Caract\\u00e9ristiques sp\\u00e9cifiques comprennant:\\nG\\u00e9n\\u00e9ration de pression manuelle de -0.85 jusqu'\\u00e0 +25 bar (12.3 \\u00e0 360 psi)\\nIncertitude de 0.025% EM\\nEnregistreur de donn\\u00e9es avec fr\\u00e9quence de mesure \\u00e9lev\\u00e9e et grande capacit\\u00e9 de m\\u00e9moire\\n \\n\\ud83c\\udf10 En savoir plus sur notre site Web:  \\n \\nEn savoir plus sur le logiciel WIKA-Cal ici :   \\n\\n\\u25b6 Regarder une vid\\u00e9o concernant l'\\u00e9talonnage d'instruments de mesure :   \\n \\n_ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _\\n \\nSuivez-nous sur les r\\u00e9seaux sociaux:\\n\\ud83d\\udcfa YouTube : \\n\\ud83c\\udfaf LinkedIn :\"}<\/script><\/p>\n<\/div>\n<h2>\u00a0<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Les instruments d\u2019\u00e9talonnage conventionnels sont g\u00e9n\u00e9ralement con\u00e7us pour des pressions allant jusqu&rsquo;\u00e0 1 000 bars. Or, dans de nombreuses applications, les capteurs travaillent \u00e0 cette valeur, par exemple dans l&rsquo;industrie automobile. Si vous souhaitez \u00e9talonner de tels appareils sur l&rsquo;ensemble de la plage de mesure, WIKA a la solution : le calibrateur de process portable [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":9606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232],"tags":[426,378,254],"class_list":["post-9608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","tag-talonnage","tag-talonnage-sur-site","tag-protection-ex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi ! - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Les instruments d\u2019\u00e9talonnage sont g\u00e9n\u00e9ralement con\u00e7us pour des pressions jusqu&#039;\u00e0 1000 bars. Or, dans de nombreuses applications, les capteurs travaillent au dessus de cette valeur. Si vous souhaitez \u00e9talonner de tels appareils, le calibrateur de process portable CPH7000 \u00e9talonne des pressions jusqu&#039;\u00e0 10 000 bars.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi ! - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Les instruments d\u2019\u00e9talonnage sont g\u00e9n\u00e9ralement con\u00e7us pour des pressions jusqu&#039;\u00e0 1000 bars. Or, dans de nombreuses applications, les capteurs travaillent au dessus de cette valeur. Si vous souhaitez \u00e9talonner de tels appareils, le calibrateur de process portable CPH7000 \u00e9talonne des pressions jusqu&#039;\u00e0 10 000 bars.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2022\/02\/w22-13-1-beitragsbild_cph7_hochdruck.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas Chevin\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas Chevin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/\"},\"author\":{\"name\":\"Nicolas Chevin\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/a4d6253f6cb517f7f0fcde44426a5e92\"},\"headline\":\"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi !\",\"datePublished\":\"2022-03-28T06:00:11+00:00\",\"dateModified\":\"2023-11-16T08:57:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/\"},\"wordCount\":707,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/02\\\/w22-13-1-beitragsbild_cph7_hochdruck.jpg\",\"keywords\":[\"\u00e9talonnage\",\"\u00e9talonnage sur site\",\"Protection Ex\"],\"articleSection\":[\"Applications\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/\",\"name\":\"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi ! - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/02\\\/w22-13-1-beitragsbild_cph7_hochdruck.jpg\",\"datePublished\":\"2022-03-28T06:00:11+00:00\",\"dateModified\":\"2023-11-16T08:57:31+00:00\",\"description\":\"Les instruments d\u2019\u00e9talonnage sont g\u00e9n\u00e9ralement con\u00e7us pour des pressions jusqu'\u00e0 1000 bars. Or, dans de nombreuses applications, les capteurs travaillent au dessus de cette valeur. Si vous souhaitez \u00e9talonner de tels appareils, le calibrateur de process portable CPH7000 \u00e9talonne des pressions jusqu'\u00e0 10 000 bars.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/02\\\/w22-13-1-beitragsbild_cph7_hochdruck.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/02\\\/w22-13-1-beitragsbild_cph7_hochdruck.jpg\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/applications\\\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/a4d6253f6cb517f7f0fcde44426a5e92\",\"name\":\"Nicolas Chevin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2017\\\/11\\\/chevinnicolas-1_fr-fr-140x140.jpg\",\"caption\":\"Nicolas Chevin\"},\"description\":\"D\u00e9sormais en charge de la gamme de produits \u00ab Calibration \u00bb, et fort d\u2019une exp\u00e9rience de 15 ans dans le domaine de l\u2019instrumentation de mesure et de la m\u00e9trologie, je serai votre contact privil\u00e9gi\u00e9 pour toute demande d\u2019information sur le mat\u00e9riel d\u2019\u00e9talonnage mais aussi sur les services associ\u00e9s propos\u00e9s par notre Laboratoire COFRAC chez Wika\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/fraisso\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi ! - Blog WIKA","description":"Les instruments d\u2019\u00e9talonnage sont g\u00e9n\u00e9ralement con\u00e7us pour des pressions jusqu'\u00e0 1000 bars. Or, dans de nombreuses applications, les capteurs travaillent au dessus de cette valeur. Si vous souhaitez \u00e9talonner de tels appareils, le calibrateur de process portable CPH7000 \u00e9talonne des pressions jusqu'\u00e0 10 000 bars.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi ! - Blog WIKA","og_description":"Les instruments d\u2019\u00e9talonnage sont g\u00e9n\u00e9ralement con\u00e7us pour des pressions jusqu'\u00e0 1000 bars. Or, dans de nombreuses applications, les capteurs travaillent au dessus de cette valeur. Si vous souhaitez \u00e9talonner de tels appareils, le calibrateur de process portable CPH7000 \u00e9talonne des pressions jusqu'\u00e0 10 000 bars.","og_url":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2022\/02\/w22-13-1-beitragsbild_cph7_hochdruck.jpg","type":"image\/jpeg"}],"author":"Nicolas Chevin","twitter_misc":{"\u00c9crit par":"Nicolas Chevin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/"},"author":{"name":"Nicolas Chevin","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/a4d6253f6cb517f7f0fcde44426a5e92"},"headline":"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi !","datePublished":"2022-03-28T06:00:11+00:00","dateModified":"2023-11-16T08:57:31+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/"},"wordCount":707,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/02\/w22-13-1-beitragsbild_cph7_hochdruck.jpg","keywords":["\u00e9talonnage","\u00e9talonnage sur site","Protection Ex"],"articleSection":["Applications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/","url":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/","name":"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi ! - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/02\/w22-13-1-beitragsbild_cph7_hochdruck.jpg","datePublished":"2022-03-28T06:00:11+00:00","dateModified":"2023-11-16T08:57:31+00:00","description":"Les instruments d\u2019\u00e9talonnage sont g\u00e9n\u00e9ralement con\u00e7us pour des pressions jusqu'\u00e0 1000 bars. Or, dans de nombreuses applications, les capteurs travaillent au dessus de cette valeur. Si vous souhaitez \u00e9talonner de tels appareils, le calibrateur de process portable CPH7000 \u00e9talonne des pressions jusqu'\u00e0 10 000 bars.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2022\/02\/w22-13-1-beitragsbild_cph7_hochdruck.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/02\/w22-13-1-beitragsbild_cph7_hochdruck.jpg","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/applications\/l-etalonnage-jusqu-a-10000-bar-n-est-plus-un-defi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019\u00e9talonnage jusqu\u2019\u00e0 10 000 bar n\u2019est plus un d\u00e9fi !"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/a4d6253f6cb517f7f0fcde44426a5e92","name":"Nicolas Chevin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2017\/11\/chevinnicolas-1_fr-fr-140x140.jpg","caption":"Nicolas Chevin"},"description":"D\u00e9sormais en charge de la gamme de produits \u00ab Calibration \u00bb, et fort d\u2019une exp\u00e9rience de 15 ans dans le domaine de l\u2019instrumentation de mesure et de la m\u00e9trologie, je serai votre contact privil\u00e9gi\u00e9 pour toute demande d\u2019information sur le mat\u00e9riel d\u2019\u00e9talonnage mais aussi sur les services associ\u00e9s propos\u00e9s par notre Laboratoire COFRAC chez Wika","url":"https:\/\/blog.wika.com\/fr\/author\/fraisso\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9608"}],"version-history":[{"count":5,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9608\/revisions"}],"predecessor-version":[{"id":11185,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9608\/revisions\/11185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9606"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}