{"id":9710,"date":"2022-05-25T10:33:22","date_gmt":"2022-05-25T08:33:22","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9710"},"modified":"2023-11-16T10:14:57","modified_gmt":"2023-11-16T09:14:57","slug":"une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/","title":{"rendered":"UNE soudure unique : gain de temps assur\u00e9 avec notre sonde de peau Tefracto-Pad"},"content":{"rendered":"<h2>WIKA est fier de pr\u00e9senter le dernier produit de la famille Gayesco des assemblages thermocouples de sondes de peau : <a href=\"https:\/\/www.wika.com\/fr-fr\/tc59_t.WIKA?ProductGroup=94545\" rel=\"external\" target=\"_blank\">le TC59-T Tefracto-Pad\u00ae<\/a>, en cours de d\u00e9p\u00f4t de brevet. Ce thermocouple de peau tubulaire facile \u00e0 installer r\u00e9duit de moiti\u00e9 les \u00e9tapes de soudage et d&rsquo;inspection et permet une installation infaillible.<\/h2>\n<p>Les experts en mesure de temp\u00e9rature WIKA recherchent continuellement des moyens d&rsquo;am\u00e9liorer nos produits et de faire gagner du temps et de l&rsquo;argent \u00e0 nos clients. L&rsquo;une des informations qu&rsquo;ils nous remont\u00e9 tient au fait que le soudage des <a href=\"https:\/\/www.wika.com\/fr-fr\/thermocouples_tubeskin.WIKA\" rel=\"external\" target=\"_blank\">thermocouples sur les tubes<\/a> de four est difficile et prend du temps. Il n&rsquo;est pas facile d&rsquo;aligner correctement le bouclier thermique sur le \u00ab weld-pad \u00bb et il serait appr\u00e9ciable d\u2019avoir des sondes de peaux plus faciles \u00e0 installer.<\/p>\n<h2>La sonde TC59-T, une sonde de peau pour tuyauterie facile \u00e0 installer<\/h2>\n<p>\nWIKA a des dizaines d&rsquo;ann\u00e9es d&rsquo;exp\u00e9rience dans la conception, la fabrication et l&rsquo;installation de sondes de peaux pour les grandes entreprises des secteurs du p\u00e9trole et du gaz, de la chimie et de la p\u00e9trochimie. Chaque nouvelle g\u00e9n\u00e9ration de nos produits apporte des am\u00e9liorations par rapport \u00e0 la pr\u00e9c\u00e9dente, et notre dernier produit combine des performances maximales avec un temps d&rsquo;installation minimal.<\/p>\n<p>La TC59-T, appel\u00e9e le Tefracto-Pad\u00ae, permet aux clients d&rsquo;\u00e9conomiser du temps et des efforts en rendant possible une installation en une seule \u00e9tape. Dans cet assemblage innovant, le \u00ab weld-pad \u00bb contenant l&rsquo;extr\u00e9mit\u00e9 chaude du thermocouple s&rsquo;ins\u00e8re pr\u00e9cis\u00e9ment dans l&rsquo;encoche de notre bouclier thermique exclusif. Ainsi, les clients n&rsquo;ont plus \u00e0 consacrer du temps \u00e0 la soudure de deux composants distincts et \u00e0 la r\u00e9alisation de deux tests LPI (contr\u00f4le par ressuage) distincts. Il ne faut qu&rsquo;une heure environ pour souder un Tefracto-Pad\u00ae \u00e0 la surface de la tuyauterie du four et r\u00e9aliser le LPI.<\/p>\n<table style=\"width: 98.9103%;height: 710px\">\n<tbody>\n<tr style=\"height: 108px\">\n<td style=\"height: 108px\" width=\"150\">\n<p><strong>Installation conventionnelle capteur avec protection<\/strong><\/p>\n<\/td>\n<td style=\"height: 108px\" width=\"150\">\n<p><strong>Temps requis<\/strong><\/p>\n<\/td>\n<td style=\"height: 108px\" width=\"150\">\n<p><strong>Installation en UNE \u00e9tape du Tefracto-Pad<\/strong><\/p>\n<\/td>\n<td style=\"height: 108px\" width=\"150\">\n<p><strong>Temps requis<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 112px\">\n<td style=\"height: 112px\" width=\"150\">\n<p>Souder le \u00ab\u00a0pad\u00a0\u00bb sur le tube<\/p>\n<\/td>\n<td style=\"height: 112px\" width=\"150\">\n<p>5 mns<\/p>\n<\/td>\n<td style=\"height: 112px\" width=\"150\">\n<p>Souder l\u2019assemblage sur le tube<\/p>\n<\/td>\n<td style=\"height: 112px\" width=\"150\">\n<p>5 minutes<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 88px\">\n<td style=\"height: 88px\" width=\"150\">\n<p>Attendre pour le LPI<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>\u00bb 45 mns<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>Attendre pour le LPI<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>\u00bb 45 mns<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 88px\">\n<td style=\"height: 88px\" width=\"150\">\n<p>V\u00e9rifier le LPI<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>15 mns<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>V\u00e9rifier le LPI<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>15 mns<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 112px\">\n<td style=\"height: 112px\" width=\"150\">\n<p>Souder la protection sur le tube<\/p>\n<\/td>\n<td style=\"height: 112px\" width=\"150\">\n<p>5 mns<\/p>\n<\/td>\n<td style=\"height: 112px\" width=\"150\">\n<p>&nbsp;<\/p>\n<\/td>\n<td style=\"height: 112px\" width=\"150\">\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 88px\">\n<td style=\"height: 88px\" width=\"150\">\n<p>Attendre pour le LPI<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>\u00bb 45 mns<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>&nbsp;<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 88px\">\n<td style=\"height: 88px\" width=\"150\">\n<p>V\u00e9rifier le LPI<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>15 mns<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>&nbsp;<\/p>\n<\/td>\n<td style=\"height: 88px\" width=\"150\">\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 26px\">\n<td style=\"height: 26px\" width=\"150\">\n<p><strong>Temps total<\/strong><\/p>\n<\/td>\n<td style=\"height: 26px\" width=\"150\">\n<p><strong>\u00bb<\/strong><strong> 2 heures<\/strong><\/p>\n<\/td>\n<td style=\"height: 26px\" width=\"150\">\n<p><strong>Temps total<\/strong><\/p>\n<\/td>\n<td style=\"height: 26px\" width=\"150\">\n<p><strong>\u00bb<\/strong><strong> 1 heure<\/strong><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2>Comment installer la sonde Tefracto-Pad\u00ae ?<\/h2>\n<p>\n<img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2022\/05\/w22-21-1-tefracto-pad_fig.-1-388x261-1.png\" \/>Notre conception innovante rend l&rsquo;alignement et l&rsquo;installation infaillibles. Voici les \u00e9tapes simples \u00e0 suivre :<\/p>\n<p>1. Localisez une zone sur la tuyauterie du four pour installer le capteur.<br \/>\n2. Enlevez le tartre et la rouille de l&rsquo;endroit choisi.<br \/>\n3. Placez le \u00ab pad \u00bb sur la surface d\u00e9gag\u00e9e, en v\u00e9rifiant l&rsquo;ajustement et en alignant le \u00ab pad \u00bb avec la ligne centrale de la tuyauterie face aux flammes (figure 1).<br \/>\n4. Placez le bouclier thermique sur le \u00ab pad \u00bb, en vous assurant que le \u00ab pad \u00bb s&rsquo;ins\u00e8re bien dans l&rsquo;encoche du bouclier (figure 2). <br \/>\n5. Utilisez un collier de serrage autour de l&rsquo;ensemble pour assurer un montage affleurant.<br \/>\n6. Soudez l&rsquo;assemblage sur tous les c\u00f4t\u00e9s, sauf \u00e0 l&rsquo;endroit o\u00f9 le c\u00e2ble chemis\u00e9 sort de la coque.<\/p>\n<p>&nbsp;<\/p>\n<h2><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2022\/05\/w22-21-2-tefracto-pad_fig.-2-388x261-1.png\" \/>Assemblages de thermocouples personnalis\u00e9s pour chaque application<\/h2>\n<p>\nNous concevons chaque Tefracto-Pad\u00ae pour r\u00e9pondre aux exigences sp\u00e9cifiques d&rsquo;un four, en tenant compte du diam\u00e8tre ext\u00e9rieur (OD) des tuyauteries, du type et de la taille optimale du thermocouple, de la t\u00eate de raccordement requise, de la longueur du c\u00e2ble chemis\u00e9, des mat\u00e9riaux de la gaine, et plus encore. Cet ensemble de thermocouples est id\u00e9al pour les applications dont la plage de temp\u00e9rature va de 0\u00b0C \u00e0 1 260\u00b0C.<\/p>\n<p>Pour plus d&rsquo;informations sur cette de temp\u00e9rature de peau facile \u00e0 installer, contactez WIKA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WIKA est fier de pr\u00e9senter le dernier produit de la famille Gayesco des assemblages thermocouples de sondes de peau : le TC59-T Tefracto-Pad\u00ae, en cours de d\u00e9p\u00f4t de brevet. Ce thermocouple de peau tubulaire facile \u00e0 installer r\u00e9duit de moiti\u00e9 les \u00e9tapes de soudage et d&rsquo;inspection et permet une installation infaillible. Les experts en mesure [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":9711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232,1],"tags":[399,405,402],"class_list":["post-9710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","category-general","tag-industrie-chimique-et-ptrochimique","tag-mesure-de-la-temprature","tag-thermocouple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une soudure unique pour notre sonde de peau Tefracto-Pad - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Assemblages thermocouples de sondes de peau : le TC59-T Tefracto-Pad\u00ae facile \u00e0 installer r\u00e9duit de moiti\u00e9 les \u00e9tapes de soudage et d&#039;inspection et permet une installation infaillible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une soudure unique pour notre sonde de peau Tefracto-Pad - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Assemblages thermocouples de sondes de peau : le TC59-T Tefracto-Pad\u00ae facile \u00e0 installer r\u00e9duit de moiti\u00e9 les \u00e9tapes de soudage et d&#039;inspection et permet une installation infaillible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2022\/05\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"UNE soudure unique : gain de temps assur\u00e9 avec notre sonde de peau Tefracto-Pad\",\"datePublished\":\"2022-05-25T08:33:22+00:00\",\"dateModified\":\"2023-11-16T09:14:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/05\\\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg\",\"keywords\":[\"industrie chimique et p\u00e9trochimique\",\"mesure de la temp\u00e9rature\",\"thermocouple\"],\"articleSection\":[\"Applications\",\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/\",\"name\":\"Une soudure unique pour notre sonde de peau Tefracto-Pad - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/05\\\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg\",\"datePublished\":\"2022-05-25T08:33:22+00:00\",\"dateModified\":\"2023-11-16T09:14:57+00:00\",\"description\":\"Assemblages thermocouples de sondes de peau : le TC59-T Tefracto-Pad\u00ae facile \u00e0 installer r\u00e9duit de moiti\u00e9 les \u00e9tapes de soudage et d'inspection et permet une installation infaillible.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/05\\\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/05\\\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNE soudure unique : gain de temps assur\u00e9 avec notre sonde de peau Tefracto-Pad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une soudure unique pour notre sonde de peau Tefracto-Pad - Blog WIKA","description":"Assemblages thermocouples de sondes de peau : le TC59-T Tefracto-Pad\u00ae facile \u00e0 installer r\u00e9duit de moiti\u00e9 les \u00e9tapes de soudage et d'inspection et permet une installation infaillible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/","og_locale":"fr_FR","og_type":"article","og_title":"Une soudure unique pour notre sonde de peau Tefracto-Pad - Blog WIKA","og_description":"Assemblages thermocouples de sondes de peau : le TC59-T Tefracto-Pad\u00ae facile \u00e0 installer r\u00e9duit de moiti\u00e9 les \u00e9tapes de soudage et d'inspection et permet une installation infaillible.","og_url":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/","og_site_name":"Blog WIKA","og_image":[{"width":1280,"height":720,"url":"https:\/\/blog.wika.com\/fr\/files\/2022\/05\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"UNE soudure unique : gain de temps assur\u00e9 avec notre sonde de peau Tefracto-Pad","datePublished":"2022-05-25T08:33:22+00:00","dateModified":"2023-11-16T09:14:57+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/05\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg","keywords":["industrie chimique et p\u00e9trochimique","mesure de la temp\u00e9rature","thermocouple"],"articleSection":["Applications","G\u00e9n\u00e9ral"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/","url":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/","name":"Une soudure unique pour notre sonde de peau Tefracto-Pad - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/05\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg","datePublished":"2022-05-25T08:33:22+00:00","dateModified":"2023-11-16T09:14:57+00:00","description":"Assemblages thermocouples de sondes de peau : le TC59-T Tefracto-Pad\u00ae facile \u00e0 installer r\u00e9duit de moiti\u00e9 les \u00e9tapes de soudage et d'inspection et permet une installation infaillible.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2022\/05\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/05\/tefracto-pad\u00ae-offers-performance-cuts-installation-time.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/general\/une-soudure-unique-gain-de-temps-assure-avec-notre-sonde-de-peau-tefracto-pad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"UNE soudure unique : gain de temps assur\u00e9 avec notre sonde de peau Tefracto-Pad"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9710"}],"version-history":[{"count":4,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9710\/revisions"}],"predecessor-version":[{"id":11196,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9710\/revisions\/11196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9711"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}