{"id":9747,"date":"2022-06-27T08:00:37","date_gmt":"2022-06-27T06:00:37","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9747"},"modified":"2025-01-18T17:00:06","modified_gmt":"2025-01-18T16:00:06","slug":"equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/","title":{"rendered":"Equipement de transmission avec du SF6 : la solution pour la mesure d\u2019humidit\u00e9 de pr\u00e9cision !"},"content":{"rendered":"<p><strong>La mesure de l&rsquo;humidit\u00e9 dans les \u00e9quipements de transmission isol\u00e9s au gaz SF6 est essentielle. C&rsquo;est pourquoi WIKA a am\u00e9lior\u00e9 les performances du capteur GDHT-20 pour cette industrie. Le transmetteur, qui fournit \u00e9galement des valeurs pour la densit\u00e9, la pression et la temp\u00e9rature du gaz, mesure d\u00e9sormais le point de ros\u00e9e\/de gel avec une pr\u00e9cision de \u00b12 K.<\/strong><\/p>\n<p>L&rsquo;humidit\u00e9, avec la densit\u00e9, est le param\u00e8tre crucial pour \u00e9valuer l&rsquo;\u00e9tat du gaz SF6 utilis\u00e9. Le GDHT-20 surveille en permanence sa teneur dans le gaz. Les informations issues de la surveillance en ligne constituent les donn\u00e9es d&rsquo;entr\u00e9e d&rsquo;une analyse de tendance en aval. Plus la mesure de la densit\u00e9 et de l&rsquo;humidit\u00e9 sont pr\u00e9cises, plus cette analyse sera pr\u00e9cise.<\/p>\n<h2>Maintenance pr\u00e9dictive en remplacement d&rsquo;intervalles de maintenance r\u00e9guli\u00e8res<\/h2>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2022\/06\/w22-26-2-textbild_gdht.jpg\" \/><p class=\"wp-caption-text\">Le capteur mod\u00e8le GDHT-20 est un instrument tout-en-un pour la surveillance en ligne des installations de transmissions isol\u00e9es au SF6. Il fonctionne avec trois capteurs de temp\u00e9rature (en rouge), un capteur de pression (en bleu) et un capteur d&rsquo;humidit\u00e9 (en jaune).<\/p><\/div>\n    \n<p>L&rsquo;analyse montre \u00e0 l&rsquo;op\u00e9rateur quand le SF6 atteindra un \u00e9tat critique et quand des mesures correctives doivent \u00eatre prises. Par cons\u00e9quent, les travaux de maintenance ou le traitement du gaz ne sont entrepris que lorsqu&rsquo;une action est r\u00e9ellement n\u00e9cessaire. La maintenance pr\u00e9dictive remplace ainsi la s\u00e9quence d&rsquo;intervalles de maintenance r\u00e9guliers qui \u00e9tait auparavant n\u00e9cessaire pour \u00e9viter les risques \u00e9cologiques et de s\u00e9curit\u00e9.<\/p>\n<p>Un exc\u00e8s d&rsquo;humidit\u00e9 dans le compartiment gaz est l&rsquo;un de ces risques. Dans les anciennes installations, l&rsquo;humidit\u00e9 augmente principalement en raison de la perm\u00e9abilit\u00e9 \u00e0 travers les mat\u00e9riaux d&rsquo;\u00e9tanch\u00e9it\u00e9. Dans les installations plus r\u00e9centes, il s&rsquo;agit g\u00e9n\u00e9ralement d&rsquo;une cons\u00e9quence de l&rsquo;humidit\u00e9 restant sur les surfaces m\u00e9talliques ou dans les mat\u00e9riaux d&rsquo;isolation lors de l&rsquo;assemblage du r\u00e9servoir, en raison d&rsquo;une \u00e9vacuation incompl\u00e8te avant le remplissage initial avec du SF6.<\/p>\n<p>Une teneur en humidit\u00e9 excessive entra\u00eene des produits de r\u00e9action corrosifs qui peuvent endommager les composants internes et r\u00e9duire la dur\u00e9e de vie de l\u2019\u00e9quipement. Si de telles substances s&rsquo;\u00e9chappent, cela g\u00e9n\u00e8re des risques suppl\u00e9mentaires pour la sant\u00e9 des personnes.<\/p>\n<p>&nbsp;<\/p>\n<h2>Param\u00e8tres de mesure de l&rsquo;humidit\u00e9 du SF6<\/h2>\n<p>La mesure de l&rsquo;humidit\u00e9 du SF6 est donc indispensable. Dans la plupart des cas, le point de ros\u00e9e ou de gel est utilis\u00e9 comme param\u00e8tre. Il s&rsquo;agit de la temp\u00e9rature \u00e0 laquelle l&rsquo;humidit\u00e9 de l&rsquo;air commence \u00e0 se condenser. Dans le cas du SF6, le point de ros\u00e9e atmosph\u00e9rique sp\u00e9cifi\u00e9 par la norme IEC 60376 est de -36 \u00b0C.<\/p>\n<p>La pr\u00e9cision du GDHT-20 de \u00b12 K pour la mesure de l&rsquo;humidit\u00e9 est valid\u00e9e au point de gel avec un standard de r\u00e9f\u00e9rence valide au niveau international. Toutefois, l&rsquo;instrument de mesure peut \u00e9galement \u00eatre configur\u00e9 pour d&rsquo;autres param\u00e8tres (point de ros\u00e9e, ppmv, ppmw et humidit\u00e9 relative). La nouvelle version du capteur se caract\u00e9rise \u00e9galement par une plus grande flexibilit\u00e9 d&rsquo;application. Le GDHT-20 est d\u00e9sormais adapt\u00e9 \u00e0 la surveillance de la densit\u00e9 des gaz isolants alternatifs N2, CF4, O2, CO2 et 3MTM NovecTM 4710.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Note<br \/>\n<\/strong>Vous trouverez de plus amples informations sur<a href=\"https:\/\/www.wika.com\/fr-fr\/gdht_20.WIKA\" rel=\"external\" target=\"_blank\"> le capteur GDHT-20<\/a> sur le site Web de WIKA. Si vous avez des questions, votre interlocuteur se fera un plaisir de vous aider.<\/p>\n<p>Vous pouvez \u00e9galement en savoir plus sur l&rsquo;expertise de WIKA en mati\u00e8re de SF6 dans la vid\u00e9o suivante :<\/p>\n<div data-fullscreen=\"disabled\" data-mode=\"normal\" data-oembed=\"1\" data-provider=\"youtube\" data-reset-after-played id=\"arve-youtube-tfzhit9op4y\" style=\"max-width:900px;\" class=\"arve\">\n<div class=\"arve-inner\">\n<div style=\"aspect-ratio:500\/281\" class=\"arve-embed arve-embed--has-aspect-ratio\">\n<div class=\"arve-ar\" style=\"padding-top:56.200000%\"><\/div>\n<p>\t\t\t<iframe allow=\"accelerometer &apos;none&apos;;autoplay &apos;none&apos;;bluetooth &apos;none&apos;;browsing-topics &apos;none&apos;;camera &apos;none&apos;;clipboard-read &apos;none&apos;;clipboard-write;display-capture &apos;none&apos;;encrypted-media &apos;none&apos;;gamepad &apos;none&apos;;geolocation &apos;none&apos;;gyroscope &apos;none&apos;;hid &apos;none&apos;;identity-credentials-get &apos;none&apos;;idle-detection &apos;none&apos;;keyboard-map &apos;none&apos;;local-fonts;magnetometer &apos;none&apos;;microphone &apos;none&apos;;midi &apos;none&apos;;otp-credentials &apos;none&apos;;payment &apos;none&apos;;picture-in-picture;publickey-credentials-create &apos;none&apos;;publickey-credentials-get &apos;none&apos;;screen-wake-lock &apos;none&apos;;serial &apos;none&apos;;summarizer &apos;none&apos;;sync-xhr;usb &apos;none&apos;;web-share;window-management &apos;none&apos;;xr-spatial-tracking &apos;none&apos;;\" allowfullscreen=\"\" class=\"arve-iframe fitvidsignore\" credentialless data-arve=\"arve-youtube-tfzhit9op4y\" data-lenis-prevent=\"\" data-src-no-ap=\"https:\/\/www.youtube-nocookie.com\/embed\/tfzhit9op4Y?feature=oembed&amp;iv_load_policy=3&amp;modestbranding=1&amp;rel=0&amp;autohide=1&amp;playsinline=0&amp;autoplay=0&amp;enablejsapi=1\" frameborder=\"0\" height=\"505.8\" loading=\"lazy\" name=\"\" referrerpolicy=\"strict-origin-when-cross-origin\" sandbox=\"allow-scripts allow-same-origin allow-presentation allow-popups allow-popups-to-escape-sandbox\" scrolling=\"no\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/tfzhit9op4Y?feature=oembed&#038;iv_load_policy=3&#038;modestbranding=1&#038;rel=0&#038;autohide=1&#038;playsinline=0&#038;autoplay=0&#038;enablejsapi=1\" title=\"WEgrid Solutions | Your partner for SF\u2086 gas monitoring, analysis and handling\" width=\"900\"><\/iframe><\/p><\/div>\n<\/p><\/div>\n<p>\t<script type=\"application\/ld+json\">{\"@context\":\"http:\\\/\\\/schema.org\\\/\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#arve-youtube-tfzhit9op4y\",\"@type\":\"VideoObject\",\"author\":{\"@type\":\"Organization\",\"name\":\"WIKA Group\"},\"embedURL\":\"https:\\\/\\\/www.youtube-nocookie.com\\\/embed\\\/tfzhit9op4Y?feature=oembed&iv_load_policy=3&modestbranding=1&rel=0&autohide=1&playsinline=0&autoplay=0&enablejsapi=1\",\"name\":\"WEgrid Solutions | Your partner for SF\\u2086 gas monitoring, analysis and handling\",\"thumbnailUrl\":\"https:\\\/\\\/i.ytimg.com\\\/vi\\\/tfzhit9op4Y\\\/hqdefault.jpg\",\"uploadDate\":\"2020-02-27T10:50:34Z\",\"description\":\"La mesure de l'humidit\\u00e9 dans les \\u00e9quipements de transmission isol\\u00e9s au gaz SF6 est essentielle. C'est pourquoi WIKA a am\\u00e9lior\\u00e9 les performances du capteur GDHT-20 pour cette industrie. Le transmetteur, qui fournit \\u00e9galement des valeurs pour la densit\\u00e9, la pression et la temp\\u00e9rature du gaz, mesure d\\u00e9\"}<\/script><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La mesure de l&rsquo;humidit\u00e9 dans les \u00e9quipements de transmission isol\u00e9s au gaz SF6 est essentielle. C&rsquo;est pourquoi WIKA a am\u00e9lior\u00e9 les performances du capteur GDHT-20 pour cette industrie. Le transmetteur, qui fournit \u00e9galement des valeurs pour la densit\u00e9, la pression et la temp\u00e9rature du gaz, mesure d\u00e9sormais le point de ros\u00e9e\/de gel avec une pr\u00e9cision [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":9740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6,414],"tags":[77,420,15,332],"class_list":["post-9747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-produits","category-sf6","tag-capteur-pression","tag-gaz-industriel","tag-precision","tag-sf6"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Equipement de transmission avec du SF6 : mesure d\u2019humidit\u00e9- Blog WIKA<\/title>\n<meta name=\"description\" content=\"Am\u00e9liorez la surveillance du gaz SF6 avec le capteur GDHT-20 de WIKA. Pr\u00e9cision exceptionnelle pour mesurer humidit\u00e9, densit\u00e9, pression et temp\u00e9rature, et maintenance pr\u00e9dictive optimis\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equipement de transmission avec du SF6 : mesure d\u2019humidit\u00e9- Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Am\u00e9liorez la surveillance du gaz SF6 avec le capteur GDHT-20 de WIKA. Pr\u00e9cision exceptionnelle pour mesurer humidit\u00e9, densit\u00e9, pression et temp\u00e9rature, et maintenance pr\u00e9dictive optimis\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2022\/06\/w22-26-beitragsbild_gdht.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Equipement de transmission avec du SF6 : la solution pour la mesure d\u2019humidit\u00e9 de pr\u00e9cision !\",\"datePublished\":\"2022-06-27T06:00:37+00:00\",\"dateModified\":\"2025-01-18T16:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/\"},\"wordCount\":657,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/06\\\/w22-26-beitragsbild_gdht.jpg\",\"keywords\":[\"Capteur de pression\",\"gaz industriel\",\"Pr\u00e9cision\",\"SF6\"],\"articleSection\":[\"G\u00e9n\u00e9ral\",\"Produits\",\"SF6\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/\",\"name\":\"Equipement de transmission avec du SF6 : mesure d\u2019humidit\u00e9- Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/06\\\/w22-26-beitragsbild_gdht.jpg\",\"datePublished\":\"2022-06-27T06:00:37+00:00\",\"dateModified\":\"2025-01-18T16:00:06+00:00\",\"description\":\"Am\u00e9liorez la surveillance du gaz SF6 avec le capteur GDHT-20 de WIKA. Pr\u00e9cision exceptionnelle pour mesurer humidit\u00e9, densit\u00e9, pression et temp\u00e9rature, et maintenance pr\u00e9dictive optimis\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/06\\\/w22-26-beitragsbild_gdht.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/06\\\/w22-26-beitragsbild_gdht.jpg\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipement de transmission avec du SF6 : la solution pour la mesure d\u2019humidit\u00e9 de pr\u00e9cision !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equipement de transmission avec du SF6 : mesure d\u2019humidit\u00e9- Blog WIKA","description":"Am\u00e9liorez la surveillance du gaz SF6 avec le capteur GDHT-20 de WIKA. Pr\u00e9cision exceptionnelle pour mesurer humidit\u00e9, densit\u00e9, pression et temp\u00e9rature, et maintenance pr\u00e9dictive optimis\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/","og_locale":"fr_FR","og_type":"article","og_title":"Equipement de transmission avec du SF6 : mesure d\u2019humidit\u00e9- Blog WIKA","og_description":"Am\u00e9liorez la surveillance du gaz SF6 avec le capteur GDHT-20 de WIKA. Pr\u00e9cision exceptionnelle pour mesurer humidit\u00e9, densit\u00e9, pression et temp\u00e9rature, et maintenance pr\u00e9dictive optimis\u00e9e.","og_url":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2022\/06\/w22-26-beitragsbild_gdht.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Equipement de transmission avec du SF6 : la solution pour la mesure d\u2019humidit\u00e9 de pr\u00e9cision !","datePublished":"2022-06-27T06:00:37+00:00","dateModified":"2025-01-18T16:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/"},"wordCount":657,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/06\/w22-26-beitragsbild_gdht.jpg","keywords":["Capteur de pression","gaz industriel","Pr\u00e9cision","SF6"],"articleSection":["G\u00e9n\u00e9ral","Produits","SF6"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/","url":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/","name":"Equipement de transmission avec du SF6 : mesure d\u2019humidit\u00e9- Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/06\/w22-26-beitragsbild_gdht.jpg","datePublished":"2022-06-27T06:00:37+00:00","dateModified":"2025-01-18T16:00:06+00:00","description":"Am\u00e9liorez la surveillance du gaz SF6 avec le capteur GDHT-20 de WIKA. Pr\u00e9cision exceptionnelle pour mesurer humidit\u00e9, densit\u00e9, pression et temp\u00e9rature, et maintenance pr\u00e9dictive optimis\u00e9e.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2022\/06\/w22-26-beitragsbild_gdht.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/06\/w22-26-beitragsbild_gdht.jpg","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/general\/equipement-de-transmission-avec-du-sf6-la-solution-pour-la-mesure-d-humidite-de-precision\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Equipement de transmission avec du SF6 : la solution pour la mesure d\u2019humidit\u00e9 de pr\u00e9cision !"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9747"}],"version-history":[{"count":3,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9747\/revisions"}],"predecessor-version":[{"id":12235,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9747\/revisions\/12235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9740"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}