{"id":9864,"date":"2022-11-07T14:48:19","date_gmt":"2022-11-07T13:48:19","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9864"},"modified":"2023-11-16T08:03:45","modified_gmt":"2023-11-16T07:03:45","slug":"production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/","title":{"rendered":"Production de pesticides : haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression."},"content":{"rendered":"<p><strong>Les exigences \u00e9lev\u00e9es impos\u00e9es aux pesticides et \u00e0 leur production se refl\u00e8tent \u00e9galement dans la mesure de la pression dans le process. Un client de WIKA a donc compl\u00e9t\u00e9 l&rsquo;instrumentation \u00e9lectronique pour la surveillance de la pression par une deuxi\u00e8me mesure de pression m\u00e9canique. Pour cette redondance, l&rsquo;entreprise utilise les manom\u00e8tres \u00e0 membrane WIKA mod\u00e8le 433.50 &#8211; son principe de mesure offre \u00e9galement un avantage de conception.<\/strong><\/p>\n<p>Les normes de s\u00e9curit\u00e9 compl\u00e8tes refl\u00e8tent le potentiel de danger qui d\u00e9coule de la transformation des produits de base et interm\u00e9diaires. Par exemple, les vapeurs produites sont toxiques et r\u00e9agissent avec l&rsquo;air. Une surveillance sans faille des param\u00e8tres du process est donc indispensable. C&rsquo;est pourquoi le client de WIKA a int\u00e9gr\u00e9 une mesure de pression m\u00e9canique, en plus de sa mesure de pression \u00e9lectronique, dans sa production de pesticides. Ainsi, m\u00eame en cas de panne de courant, ils re\u00e7oivent de mani\u00e8re fiable une valeur mesur\u00e9e, qui est ensuite affich\u00e9e localement.<\/p>\n<h2>Les raisons d&rsquo;utiliser un manom\u00e8tre \u00e0 membrane comme redondance dans la mesure de la pression<\/h2>\n<p>Pour sa mesure de pression de secours, le client a opt\u00e9 pour le mod\u00e8le 433.50, un manom\u00e8tre \u00e0 membrane. Voici les raisons de ce choix :<\/p>\n<ol>\n<li>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9863\" src=\"https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-1-textbild_typ-4.jpg\" alt=\"\" width=\"388\" height=\"265\" srcset=\"https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-1-textbild_typ-4.jpg 388w, https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-1-textbild_typ-4-220x150.jpg 220w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/><p class=\"wp-caption-text\">Optimal pour la mesure de pression redondante dans la production de pesticides : le manom\u00e8tre \u00e0 membrane mod\u00e8le 433.50 de WIKA.<\/p><\/div>\n    <br \/>\n<strong>La flexibilit\u00e9 d&rsquo;utilisation<\/strong><br \/>\nLe manom\u00e8tre peut \u00eatre install\u00e9 \u00e0 diff\u00e9rents endroits de mesure, gr\u00e2ce \u00e0 un large choix de plages de mesure entre 0 &#8230; 16 mbar et 0 &#8230; 25 bar. Il r\u00e9duit ainsi la variance de l&rsquo;instrument.<\/p>\n<\/li>\n<li><strong>La conception robuste<\/strong><br \/>\nLe mod\u00e8le 433.50, de conception robuste, offre une s\u00e9curit\u00e9 \u00e9lev\u00e9e en cas de surpression : jusqu&rsquo;\u00e0 dix fois la valeur de la pleine \u00e9chelle. <\/p>\n<p>Le remplissage du bo\u00eetier &#8211; de la glyc\u00e9rine dans le cas de la production de pesticides &#8211; garantit une mesure de pression fiable en cas de vibrations et de charges de pression dynamiques \u00e9lev\u00e9es. Le design avec un raccord \u00e0 bride permet \u00e9galement un raccordement s\u00fbr au process.<\/p>\n<\/li>\n<li><strong>La r\u00e9sistance au milieu<\/strong><br \/>\nLors de la production de pesticides, des vapeurs avec des temp\u00e9ratures de +120 \u00b0C sont produites. Le manom\u00e8tre peut r\u00e9sister \u00e0 des temp\u00e9ratures moyennes allant jusqu&rsquo;\u00e0 +200 \u00b0C. <\/p>\n<p>Il est \u00e9galement r\u00e9sistant aux substances agressives. Cette r\u00e9sistance peut \u00eatre augment\u00e9e en utilisant des versions avec des mat\u00e9riaux sp\u00e9ciaux. Dans le cas de cette application, une variante avec un rev\u00eatement en PTFE de la bride de mesure inf\u00e9rieure \u00e9tait n\u00e9cessaire (le fait que cela r\u00e9duise la r\u00e9sistance \u00e0 la temp\u00e9rature \u00e0 160 \u00b0C n&rsquo;a pas eu d&rsquo;importance pour la mesure concern\u00e9e). <\/p>\n<p>En outre, pour le process de fabrication, WIKA a \u00e9galement fourni une version d&rsquo;instrument avec une approbation ATEX.<\/p>\n<\/li>\n<li><strong> Le process reste ferm\u00e9 en cas de dommage sur le bo\u00eetier.<\/strong><br \/>\nLes manom\u00e8tres \u00e0 membrane d\u00e9finis pour cette application ont un bo\u00eetier de diam\u00e8tre 100, de sorte que la valeur mesur\u00e9e peut \u00eatre lue sans difficult\u00e9, m\u00eame lors d&rsquo;un simple passage. Par cons\u00e9quent, l&rsquo;instrument de mesure fait saillie dans l&rsquo;environnement. <\/p>\n<p>Si des \u00e9chafaudages sont utilis\u00e9s pour les travaux de maintenance sur les installations de production, il n&rsquo;est pas exclu que le bo\u00eetier soit endommag\u00e9. Avec un manom\u00e8tre \u00e0 tube manom\u00e9trique, le syst\u00e8me de mesure fuirait \u00e9galement dans ce cas, et des fluides dangereux pourraient s&rsquo;\u00e9chapper. <\/p>\n<p>Le manom\u00e8tre \u00e0 membrane, en revanche, transmet la pression au mouvement par l&rsquo;interm\u00e9diaire d&rsquo;une membrane et d&rsquo;une liaison. Cela signifie que la membrane continue \u00e0 maintenir le process ferm\u00e9 m\u00eame si le bo\u00eetier est endommag\u00e9.<\/li>\n<\/ol>\n<h2>Conclusion<\/h2>\n<p>\nLes manom\u00e8tres fournissent un r\u00e9sultat de mesure fiable, sans \u00e9nergie ext\u00e9rieure, en toute situation. C&rsquo;est pourquoi la mesure redondante de la pression \u00e0 l&rsquo;aide d&rsquo;instruments m\u00e9caniques augmente consid\u00e9rablement la s\u00e9curit\u00e9 des installations. Les manom\u00e8tres \u00e0 membrane sont le premier choix pour les process \u00e0 faible pression et les milieux critiques.<\/p>\n<h2>Note<\/h2>\n<p>\nVous trouverez d&rsquo;autres d\u00e9tails techniques sur le <a href=\"https:\/\/www.wika.com\/fr-fr\/432_50_433_50.WIKA\" rel=\"external\" target=\"_blank\">manom\u00e8tre \u00e0 membrane mod\u00e8le 433.50<\/a> sur le site Web WIKA. Vous y trouverez \u00e9galement un aper\u00e7u de nos solutions de mesure pour le secteur chimique, ainsi qu&rsquo;une brochure correspondante. <\/p>\n<p>Vous souhaitez acheter des manom\u00e8tres \u00e0 membrane ? <br \/>\nDans notre <a href=\"https:\/\/shop.wika.com\/fr-fr\/page_d_accueil.WIKA\" rel=\"external\" target=\"_blank\">boutique en ligne WIKA<\/a>, vous trouverez certains de nos mod\u00e8les standards. Si vous avez des questions, <a href=\"https:\/\/www.wika.com\/fr-fr\/contact.WIKA\" rel=\"external\" target=\"_blank\">votre interlocuteur<\/a> se fera un plaisir de vous aider.<\/p>\n<p>Regardez la vid\u00e9o suivante pour conna\u00eetre les diff\u00e9rences entre les principes de mesure des manom\u00e8tres manom\u00e9triques et des manom\u00e8tres \u00e0 membrane.<\/p>\n<div data-fullscreen=\"disabled\" data-mode=\"normal\" data-oembed=\"1\" data-provider=\"youtube\" data-reset-after-played id=\"arve-youtube-4rafqbjparw\" style=\"max-width:900px;\" class=\"arve\">\n<div class=\"arve-inner\">\n<div style=\"aspect-ratio:500\/281\" class=\"arve-embed arve-embed--has-aspect-ratio\">\n<div class=\"arve-ar\" style=\"padding-top:56.200000%\"><\/div>\n<p>\t\t\t<iframe allow=\"accelerometer &apos;none&apos;;autoplay &apos;none&apos;;bluetooth &apos;none&apos;;browsing-topics &apos;none&apos;;camera &apos;none&apos;;clipboard-read &apos;none&apos;;clipboard-write;display-capture &apos;none&apos;;encrypted-media &apos;none&apos;;gamepad &apos;none&apos;;geolocation &apos;none&apos;;gyroscope &apos;none&apos;;hid &apos;none&apos;;identity-credentials-get &apos;none&apos;;idle-detection &apos;none&apos;;keyboard-map &apos;none&apos;;local-fonts;magnetometer &apos;none&apos;;microphone &apos;none&apos;;midi &apos;none&apos;;otp-credentials &apos;none&apos;;payment &apos;none&apos;;picture-in-picture;publickey-credentials-create &apos;none&apos;;publickey-credentials-get &apos;none&apos;;screen-wake-lock &apos;none&apos;;serial &apos;none&apos;;summarizer &apos;none&apos;;sync-xhr;usb &apos;none&apos;;web-share;window-management &apos;none&apos;;xr-spatial-tracking &apos;none&apos;;\" allowfullscreen=\"\" class=\"arve-iframe fitvidsignore\" credentialless data-arve=\"arve-youtube-4rafqbjparw\" data-lenis-prevent=\"\" data-src-no-ap=\"https:\/\/www.youtube-nocookie.com\/embed\/4RaFqBJpARw?feature=oembed&amp;iv_load_policy=3&amp;modestbranding=1&amp;rel=0&amp;autohide=1&amp;playsinline=0&amp;autoplay=0&amp;enablejsapi=1\" frameborder=\"0\" height=\"505.8\" loading=\"lazy\" name=\"\" referrerpolicy=\"strict-origin-when-cross-origin\" sandbox=\"allow-scripts allow-same-origin allow-presentation allow-popups allow-popups-to-escape-sandbox\" scrolling=\"no\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/4RaFqBJpARw?feature=oembed&#038;iv_load_policy=3&#038;modestbranding=1&#038;rel=0&#038;autohide=1&#038;playsinline=0&#038;autoplay=0&#038;enablejsapi=1\" title=\"Comment fonctionne un manom\u00e8tre ? Tube manom\u00e9trique ou \u00e0 membrane ?\" width=\"900\"><\/iframe><\/p><\/div>\n<\/p><\/div>\n<p>\t<script type=\"application\/ld+json\">{\"@context\":\"http:\\\/\\\/schema.org\\\/\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#arve-youtube-4rafqbjparw\",\"@type\":\"VideoObject\",\"author\":{\"@type\":\"Organization\",\"name\":\"WIKA Group\"},\"embedURL\":\"https:\\\/\\\/www.youtube-nocookie.com\\\/embed\\\/4RaFqBJpARw?feature=oembed&iv_load_policy=3&modestbranding=1&rel=0&autohide=1&playsinline=0&autoplay=0&enablejsapi=1\",\"name\":\"Comment fonctionne un manom\\u00e8tre ? Tube manom\\u00e9trique ou \\u00e0 membrane ?\",\"thumbnailUrl\":\"https:\\\/\\\/i.ytimg.com\\\/vi\\\/4RaFqBJpARw\\\/hqdefault.jpg\",\"uploadDate\":\"2020-03-30T07:15:01Z\",\"description\":\"Les manom\\u00e8tres sont des instruments de mesure de pression avec des \\u00e9l\\u00e9ments de mesure r\\u00e9silients qui sont utilis\\u00e9s des millions de fois dans de multiples applications industrielles. En fonction du domaine d'application du manom\\u00e8tre, on utilise des tubes manom\\u00e9triques ou des \\u00e9l\\u00e9ments \\u00e0 membrane comme \\u00e9l\\u00e9ments de mesure de pression.\\u00a0\\n\\u00a0\\nAvec un manom\\u00e8tre \\u00e0 tube manom\\u00e9trique ( la pression est mesur\\u00e9e directement \\u00e0 l'int\\u00e9rieur du manom\\u00e8tre au moyen du tube manom\\u00e9trique, un tube courb\\u00e9 en forme de C avec une section transversale non-circulaire. En cons\\u00e9quence de la d\\u00e9formation du tube, donc du mouvement du tube manom\\u00e9trique, la pression est transmise \\u00e0 l'aiguille par le mouvement pour indiquer la pression. Les manom\\u00e8tres \\u00e0 tube manom\\u00e9trique sont tr\\u00e8s versatiles et peuvent \\u00eatre utilis\\u00e9s pour la plupart des applications.\\u00a0\\nLes tubes manom\\u00e9triques poss\\u00e8dent les avantages suivants par rapport aux \\u00e9l\\u00e9ments \\u00e0 membrane :\\u00a0\\n- Ils couvrent des \\u00e9tendues de mesure faibles de 0 \\u00e0 0,6 bar jusqu'\\u00e0 des \\u00e9tendues de mesure \\u00e9lev\\u00e9es de 0 \\u00e0 10.000 bar.\\u00a0\\n- Ils permettent d'obtenir des incertitudes jusqu'\\u00e0 la classe 0,1 des r\\u00e9gulations d'\\u00e9talonnage.\\u00a0\\n- Ils sont plus faciles \\u00e0 fabriquer.\\u00a0\\n- Ils peuvent facilement \\u00eatre mont\\u00e9 ou scell\\u00e9s avec les composants sous pression. Suivant le mat\\u00e9riau et la charge de pression, ils sont soit bras\\u00e9s, soud\\u00e9s, ou viss\\u00e9s.\\u00a0\\n\\u00a0\\nLes manom\\u00e8tres \\u00e0 membrane ( sont utilis\\u00e9s lorsqu'un manom\\u00e8tre \\u00e0 tube manom\\u00e9trique atteint ses limites.\\u00a0\\n\\u00a0\\nSur les \\u00e9l\\u00e9ments \\u00e0 membrane, la d\\u00e9formation \\u00e9lastique de membranes, subissant la pression sur une des faces et fix\\u00e9es sur leur pourtour, est d\\u00e9termin\\u00e9e comme valeur de r\\u00e9f\\u00e9rence. Cette d\\u00e9formation est convertie, par un mouvement, en une rotation de l'aiguille. Les \\u00e9l\\u00e9ments \\u00e0 membrane ont une haute stabilit\\u00e9 m\\u00e9canique due \\u00e0 leur forme et \\u00e0 leur fixation et sont donc moins sensibles aux vibrations.\\u00a0\\n\\u00a0\\nOn utilise des manom\\u00e8tres \\u00e0 membrane en particulier lorsque l'on mesure des faibles pressions. Gr\\u00e2ce \\u00e0 la grande surface de la membrane, il est possible de mesurer des pression de 0 \\u00e0 16 mbar (de 0 \\u00e0 2,5 mbar avec des manom\\u00e8tres \\u00e0 capsule comme type sp\\u00e9cial de manom\\u00e8tre \\u00e0 membrane).\\u00a0\\n\\u00a0\\nA la diff\\u00e9rence des tubes manom\\u00e9triques, les \\u00e9l\\u00e9ments \\u00e0 membrane peuvent \\u00eatre facilement prot\\u00e9g\\u00e9s contre la surpression. La s\\u00e9curit\\u00e9 contre la surpression est garantie, par exemple, au moyen d'un lit de membrane d'une forme sp\\u00e9ciale contre laquelle l'\\u00e9l\\u00e9ment \\u00e0 membrane peut s'appuyer.\\u00a0\\n\\u00a0\\nEn outre, les manom\\u00e8tres \\u00e0 membrane peuvent \\u00eatre utilis\\u00e9s avec des fluides hautement visqueux, contamin\\u00e9s ou cristallisants, car l'\\u00e9l\\u00e9ment \\u00e0 membrane peut \\u00eatre confectionn\\u00e9 avec diff\\u00e9rents rev\\u00eatements, tels quel le PTFE, l'or et l'Hastelloy. Un manom\\u00e8tre \\u00e0 membrane avec une bride de raccordement ouverte emp\\u00eache \\u00e9galement que le port de pression se bouche, car le diam\\u00e8tre est plus grand.\\u00a0\\n\\u00a0\\n\\ud83d\\udcd6\\u00a0Vous trouverez des t\\u00e9moignages int\\u00e9ressants sur les sujets suivants dans le blog WIKA :\\u00a0\\n- Manom\\u00e8tre \\u00e0 tube manom\\u00e9trique \\u2013 principe de fonctionnement :\\u00a0\\n- S\\u00e9curit\\u00e9 contre la surpression des manom\\u00e8tres \\u00e0 tube manom\\u00e9trique :\\u00a0\\n- Avantages des manom\\u00e8tres \\u00e0 membrane | Mesure de faibles pressions :\\u00a0\\n- Avantages des manom\\u00e8tres \\u00e0 membrane | protection \\u00e9lev\\u00e9e contre les surcharges : \\n\\n\\ud83d\\uded2\\u00a0Procurez-vous des manom\\u00e8tres directement aupr\\u00e8s de notre boutique en ligne WIKA :\\u00a0\\n- Manom\\u00e8tres \\u00e0 tube manom\\u00e9trique :\\u00a0\\n- Manom\\u00e8tres \\u00e0 membrane :\\u00a0\\n- Manom\\u00e8tres \\u00e0 capsule :\\u00a0\\n\\n_ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _ _\\u00a0\\u00a0\\n\\u00a0\\nSuivez-nous sur les r\\u00e9seaux sociaux:\\u00a0\\n\\ud83d\\udcfa\\u00a0YouTube :\\u00a0\\n\\ud83c\\udfaf\\u00a0LinkedIn :\\u00a0\\n\\n\\u25ac Contenu de cette vid\\u00e9o \\u25ac\\u25ac\\u25ac\\u25ac\\u25ac\\u25ac\\u25ac\\u25ac\\u25ac\\u25ac\\u25ac\\u25ac \\n00:00 - Introduction \\n00:04 - S\\u00e9lection de manom\\u00e8tres \\n00:22 - Comment fonctionne un manom\\u00e8tre \\u00e0 tube manom\\u00e9trique ? \\n00:44 - Comment fonctionne un manom\\u00e8tre \\u00e0 membrane ? \\n00:54 - Manom\\u00e8tres \\u00e0 membrane vs manom\\u00e8tres \\u00e0 tube manom\\u00e9trique \\n01:20 - Avantages des manom\\u00e8tres \\u00e0 membrane \\n02:08 \\u2013 Choisir entre les manom\\u00e8tres \\u00e0 tube manom\\u00e9trique ou \\u00e0 membrane\"}<\/script><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les exigences \u00e9lev\u00e9es impos\u00e9es aux pesticides et \u00e0 leur production se refl\u00e8tent \u00e9galement dans la mesure de la pression dans le process. Un client de WIKA a donc compl\u00e9t\u00e9 l&rsquo;instrumentation \u00e9lectronique pour la surveillance de la pression par une deuxi\u00e8me mesure de pression m\u00e9canique. Pour cette redondance, l&rsquo;entreprise utilise les manom\u00e8tres \u00e0 membrane WIKA mod\u00e8le [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":9862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232,1],"tags":[286,274,75,387,398,284,401],"class_list":["post-9864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","category-general","tag-chimie","tag-conditions-utilisation","tag-manometre","tag-manomtre-membrane","tag-manomtre-process","tag-point-de-mesure","tag-pression"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Production de pesticides, haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression. - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Les exigences \u00e9lev\u00e9es impos\u00e9es aux pesticides et \u00e0 leur production se refl\u00e8tent \u00e9galement dans la mesure de la pression dans le process. Deux mesures de pression pour augmenter la s\u00e9curit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Production de pesticides, haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression. - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Les exigences \u00e9lev\u00e9es impos\u00e9es aux pesticides et \u00e0 leur production se refl\u00e8tent \u00e9galement dans la mesure de la pression dans le process. Deux mesures de pression pour augmenter la s\u00e9curit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-beitragsbild_typ-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"Production de pesticides : haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression.\",\"datePublished\":\"2022-11-07T13:48:19+00:00\",\"dateModified\":\"2023-11-16T07:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/\"},\"wordCount\":821,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/11\\\/w22-45-beitragsbild_typ-4.jpg\",\"keywords\":[\"Chimie\",\"Conditions d'utilisation\",\"Manom\u00e8tre\",\"manom\u00e8tre \u00e0 membrane\",\"manom\u00e8tre process\",\"Point de mesure\",\"pression\"],\"articleSection\":[\"Applications\",\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/\",\"name\":\"Production de pesticides, haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression. - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/11\\\/w22-45-beitragsbild_typ-4.jpg\",\"datePublished\":\"2022-11-07T13:48:19+00:00\",\"dateModified\":\"2023-11-16T07:03:45+00:00\",\"description\":\"Les exigences \u00e9lev\u00e9es impos\u00e9es aux pesticides et \u00e0 leur production se refl\u00e8tent \u00e9galement dans la mesure de la pression dans le process. Deux mesures de pression pour augmenter la s\u00e9curit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/11\\\/w22-45-beitragsbild_typ-4.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2022\\\/11\\\/w22-45-beitragsbild_typ-4.jpg\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Production de pesticides : haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Production de pesticides, haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression. - Blog WIKA","description":"Les exigences \u00e9lev\u00e9es impos\u00e9es aux pesticides et \u00e0 leur production se refl\u00e8tent \u00e9galement dans la mesure de la pression dans le process. Deux mesures de pression pour augmenter la s\u00e9curit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/","og_locale":"fr_FR","og_type":"article","og_title":"Production de pesticides, haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression. - Blog WIKA","og_description":"Les exigences \u00e9lev\u00e9es impos\u00e9es aux pesticides et \u00e0 leur production se refl\u00e8tent \u00e9galement dans la mesure de la pression dans le process. Deux mesures de pression pour augmenter la s\u00e9curit\u00e9.","og_url":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-beitragsbild_typ-4.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"Production de pesticides : haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression.","datePublished":"2022-11-07T13:48:19+00:00","dateModified":"2023-11-16T07:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/"},"wordCount":821,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-beitragsbild_typ-4.jpg","keywords":["Chimie","Conditions d'utilisation","Manom\u00e8tre","manom\u00e8tre \u00e0 membrane","manom\u00e8tre process","Point de mesure","pression"],"articleSection":["Applications","G\u00e9n\u00e9ral"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/","url":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/","name":"Production de pesticides, haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression. - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-beitragsbild_typ-4.jpg","datePublished":"2022-11-07T13:48:19+00:00","dateModified":"2023-11-16T07:03:45+00:00","description":"Les exigences \u00e9lev\u00e9es impos\u00e9es aux pesticides et \u00e0 leur production se refl\u00e8tent \u00e9galement dans la mesure de la pression dans le process. Deux mesures de pression pour augmenter la s\u00e9curit\u00e9.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-beitragsbild_typ-4.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2022\/11\/w22-45-beitragsbild_typ-4.jpg","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/general\/production-de-pesticides-haute-securite-avec-2-systemes-de-mesure-de-pression\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Production de pesticides : haute s\u00e9curit\u00e9 avec 2 syst\u00e8mes de mesure de pression."}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9864"}],"version-history":[{"count":6,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9864\/revisions"}],"predecessor-version":[{"id":11154,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9864\/revisions\/11154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9862"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}