{"id":9949,"date":"2023-02-13T14:32:48","date_gmt":"2023-02-13T13:32:48","guid":{"rendered":"https:\/\/blog.wika.com\/fr\/?p=9949"},"modified":"2023-11-16T08:24:25","modified_gmt":"2023-11-16T07:24:25","slug":"etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/","title":{"rendered":"\u00c9tude de cas : Test et validation pour am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin"},"content":{"rendered":"<p><strong>Une soci\u00e9t\u00e9 d&rsquo;\u00e9nergie soup\u00e7onnait que certains thermocouples de peau dans ses unit\u00e9s de traitement n&rsquo;\u00e9taient pas pr\u00e9cis, mais elle ne savait pas lesquels. Le centre de test R&amp;D de WIKA \u00e0 Houston a identifi\u00e9 les sondes en question et a conseill\u00e9 le client sur le capteur et le mod\u00e8le \u00e0 installer lors de son prochain cycle de r\u00e9vision.<\/strong><\/p>\n<p>\nLe centre R&amp;D de WIKA \u00e0 Houston dispose d&rsquo;un four de cuisson grandeur nature qui reproduit fid\u00e8lement les conditions du process, ce qui le rend id\u00e9al pour tester diff\u00e9rents capteurs de temp\u00e9rature dans diverses configurations sans devoir interrompre les op\u00e9rations dans une raffinerie en activit\u00e9. Un client a r\u00e9cemment d\u00e9couvert les avantages de telles capacit\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<h2>Probl\u00e8me : quels capteurs et quelles installations sont les plus pr\u00e9cis ?<\/h2>\n<p>\nUne entreprise du secteur de l&rsquo;\u00e9nergie s&rsquo;inqui\u00e9tait de ses capteurs de temp\u00e9rature, dont chacun donnait une lecture diff\u00e9rente de la temp\u00e9rature. Quelle \u00e9tait la cause de ces diff\u00e9rences de pr\u00e9cision ? Etait-ce l&rsquo;installation des capteurs, les capteurs eux-m\u00eames, ou une combinaison des deux ?<\/p>\n<p>Les ing\u00e9nieurs et les responsables de l&rsquo;entreprise voulaient valider les performances de divers capteurs dans des conceptions particuli\u00e8res afin de pouvoir installer la configuration la plus optimale lors de la prochaine r\u00e9vision (TAR). Cependant, ils ne voulaient pas effectuer les tests dans leurs propres installations, car cela aurait entra\u00een\u00e9 un arr\u00eat co\u00fbteux des op\u00e9rations de la raffinerie. Ce qu&rsquo;il leur fallait, c&rsquo;\u00e9tait un four de taille normale pour effectuer ces tests.<\/p>\n<h2>La solution : Le centre d&rsquo;essai \u00e0 service complet de WIKA<\/h2>\n<p>&nbsp;<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:396px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/fr\/files\/2023\/02\/w23-7-1-process-unit-1_resized-388x218-1.png\" \/><p class=\"wp-caption-text\">L&rsquo;unit\u00e9 de traitement grandeur nature et enti\u00e8rement fonctionnelle de WIKA est consacr\u00e9e aux essais d&rsquo;instruments et \u00e0 la recherche et au d\u00e9veloppement.<\/p><\/div>\n    \n<p>Apr\u00e8s avoir entendu parler de l&rsquo;unit\u00e9 de WIKA qui peut simuler les conditions de process des fours \u00e0 grande \u00e9chelle, la soci\u00e9t\u00e9 \u00e9nerg\u00e9tique nous a contact\u00e9s et nous a fait part de ses besoins.<\/p>\n<p>Depuis que le centre de R&amp;D de Houston a \u00e9t\u00e9 mis en service en 2019, WIKA a test\u00e9 et valid\u00e9 la pr\u00e9cision d&rsquo;une vari\u00e9t\u00e9 de capteurs de temp\u00e9rature, tels que le <a href=\"https:\/\/www.wika.com\/fr-fr\/tc59_t.WIKA?ProductGroup=94545\" rel=\"external\" target=\"_blank\">thermocouple Tefracto-Pad\u00ae tubeskin<\/a>. Notre \u00e9quipe \u00e9tait impatiente de relever un autre d\u00e9fi et a travaill\u00e9 en \u00e9troite collaboration avec l&rsquo;entreprise pour d\u00e9cider lesquels des capteurs et des assemblages \u00e0 tester, ainsi que tous les diff\u00e9rents param\u00e8tres et conditions qui donneraient les r\u00e9sultats les plus pr\u00e9cis.<\/p>\n<p>&nbsp;<\/p>\n<h2>R\u00e9sultat : Une rotation efficace et productive<\/h2>\n<p>\nApr\u00e8s des mois de planification, les essais en direct ont \u00e9t\u00e9 r\u00e9alis\u00e9s en moins d&rsquo;une semaine au centre de R&amp;D de Houston. Ensuite, WIKA a publi\u00e9 un rapport d\u00e9taill\u00e9 contenant des donn\u00e9es, des images de l&rsquo;installation, des r\u00e9sultats du balayage IR et des mesures \u00e0 prendre. La soci\u00e9t\u00e9 d&rsquo;\u00e9nergie a \u00e9t\u00e9 ravie de nos r\u00e9sultats, car elle dispose d\u00e9sormais de donn\u00e9es concluantes pour \u00e9tayer ses soup\u00e7ons. Nous continuons \u00e0 travailler avec le client et des installations sont pr\u00e9vues pour le prochain TAR.<\/p>\n<p>&nbsp;<\/p>\n<h2>WIKA, votre partenaire pour des tests complets de capteurs<\/h2>\n<p>\nPour les entreprises de l&rsquo;industrie p\u00e9troli\u00e8re et gazi\u00e8re, WIKA ne se contente pas de concevoir et de fabriquer une <a href=\"https:\/\/www.wika.com\/fr-fr\/thermocouples.WIKA\" rel=\"external\" target=\"_blank\">gamme compl\u00e8te de thermocouples<\/a> \u00e0 tube, de thermocouples multipoints, de thermom\u00e8tres \u00e0 r\u00e9sistance et de doigts de gant. <br \/>\nNous pouvons \u00e9galement tester et valider une grande vari\u00e9t\u00e9 de capteurs de temp\u00e9rature, quelle qu&rsquo;en soit la source. Contactez-nous pour plus d&rsquo;informations sur les capacit\u00e9s du centre de R&amp;D, sur notre programme innovant de surveillance compl\u00e8te des fours (FCMP) pour une s\u00e9curit\u00e9 et une efficacit\u00e9 accrues, et sur les autres moyens par lesquels WIKA peut vous aider \u00e0 tirer le meilleur parti de votre prochaine r\u00e9vision de r\u00e9acteur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une soci\u00e9t\u00e9 d&rsquo;\u00e9nergie soup\u00e7onnait que certains thermocouples de peau dans ses unit\u00e9s de traitement n&rsquo;\u00e9taient pas pr\u00e9cis, mais elle ne savait pas lesquels. Le centre de test R&amp;D de WIKA \u00e0 Houston a identifi\u00e9 les sondes en question et a conseill\u00e9 le client sur le capteur et le mod\u00e8le \u00e0 installer lors de son prochain [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":9943,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[232,1],"tags":[554,550,15,543,534,402],"class_list":["post-9949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applications","category-general","tag-tude-de-cas","tag-oil-and-gaz","tag-precision","tag-raffinerie","tag-sonde-de-peau","tag-thermocouple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin - Blog WIKA<\/title>\n<meta name=\"description\" content=\"D\u00e9terminer quels thermocouples de peau dans des unit\u00e9s de traitement ne sont pas pr\u00e9cis gr\u00e2ce au centre de test R&amp;D de WIKA \u00e0 Houston.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"D\u00e9terminer quels thermocouples de peau dans des unit\u00e9s de traitement ne sont pas pr\u00e9cis gr\u00e2ce au centre de test R&amp;D de WIKA \u00e0 Houston.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/fr\/files\/2023\/02\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Forestier\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Forestier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/\"},\"author\":{\"name\":\"Pierre Forestier\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\"},\"headline\":\"\u00c9tude de cas : Test et validation pour am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin\",\"datePublished\":\"2023-02-13T13:32:48+00:00\",\"dateModified\":\"2023-11-16T07:24:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/\"},\"wordCount\":696,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/02\\\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg\",\"keywords\":[\"\u00e9tude de cas\",\"Oil and Gaz\",\"Pr\u00e9cision\",\"raffinerie\",\"sonde de peau\",\"thermocouple\"],\"articleSection\":[\"Applications\",\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/\",\"name\":\"Comment am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/02\\\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg\",\"datePublished\":\"2023-02-13T13:32:48+00:00\",\"dateModified\":\"2023-11-16T07:24:25+00:00\",\"description\":\"D\u00e9terminer quels thermocouples de peau dans des unit\u00e9s de traitement ne sont pas pr\u00e9cis gr\u00e2ce au centre de test R&D de WIKA \u00e0 Houston.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/02\\\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/02\\\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg\",\"width\":837,\"height\":471,\"caption\":\"Aerial Panorama Landscape view of Canadian Oil Refinery build along the Athabasca river close to the Oilsands Industrial surface mining area travel Alberta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/general\\\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9tude de cas : Test et validation pour am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#organization\",\"name\":\"WIKA Instruments\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2016\\\/02\\\/logo_wika_cmyk.jpg\",\"width\":758,\"height\":263,\"caption\":\"WIKA Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/#\\\/schema\\\/person\\\/83d7f96b03a20739e9c8e3e5dd254501\",\"name\":\"Pierre Forestier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/files\\\/2023\\\/06\\\/pierre-blog-120x120.jpg\",\"caption\":\"Pierre Forestier\"},\"description\":\"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/fr\\\/author\\\/forestp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin - Blog WIKA","description":"D\u00e9terminer quels thermocouples de peau dans des unit\u00e9s de traitement ne sont pas pr\u00e9cis gr\u00e2ce au centre de test R&D de WIKA \u00e0 Houston.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin - Blog WIKA","og_description":"D\u00e9terminer quels thermocouples de peau dans des unit\u00e9s de traitement ne sont pas pr\u00e9cis gr\u00e2ce au centre de test R&D de WIKA \u00e0 Houston.","og_url":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/","og_site_name":"Blog WIKA","og_image":[{"width":837,"height":471,"url":"https:\/\/blog.wika.com\/fr\/files\/2023\/02\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg","type":"image\/jpeg"}],"author":"Pierre Forestier","twitter_misc":{"\u00c9crit par":"Pierre Forestier","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/"},"author":{"name":"Pierre Forestier","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501"},"headline":"\u00c9tude de cas : Test et validation pour am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin","datePublished":"2023-02-13T13:32:48+00:00","dateModified":"2023-11-16T07:24:25+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/"},"wordCount":696,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/02\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg","keywords":["\u00e9tude de cas","Oil and Gaz","Pr\u00e9cision","raffinerie","sonde de peau","thermocouple"],"articleSection":["Applications","G\u00e9n\u00e9ral"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/","url":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/","name":"Comment am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/02\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg","datePublished":"2023-02-13T13:32:48+00:00","dateModified":"2023-11-16T07:24:25+00:00","description":"D\u00e9terminer quels thermocouples de peau dans des unit\u00e9s de traitement ne sont pas pr\u00e9cis gr\u00e2ce au centre de test R&D de WIKA \u00e0 Houston.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/#primaryimage","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/02\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/02\/w23-7-tubeskin-thermocouple-accuracy_shutterstock_2209344521.jpg","width":837,"height":471,"caption":"Aerial Panorama Landscape view of Canadian Oil Refinery build along the Athabasca river close to the Oilsands Industrial surface mining area travel Alberta"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/fr\/general\/etude-de-cas-test-et-validation-pour-ameliorer-la-precision-des-thermocouples-tubeskin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.wika.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9tude de cas : Test et validation pour am\u00e9liorer la pr\u00e9cision des thermocouples Tubeskin"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/fr\/#website","url":"https:\/\/blog.wika.com\/fr\/","name":"Blog WIKA","description":"Notre blog vous propose de nombreux articles int\u00e9ressants sur la mesure de pression, temp\u00e9rature, niveau, d\u00e9bit et calibration et donne un aper\u00e7u du Groupe WIKA","publisher":{"@id":"https:\/\/blog.wika.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.wika.com\/fr\/#organization","name":"WIKA Instruments","url":"https:\/\/blog.wika.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2016\/02\/logo_wika_cmyk.jpg","width":758,"height":263,"caption":"WIKA Instruments"},"image":{"@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.wika.com\/fr\/#\/schema\/person\/83d7f96b03a20739e9c8e3e5dd254501","name":"Pierre Forestier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","url":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/fr\/files\/2023\/06\/pierre-blog-120x120.jpg","caption":"Pierre Forestier"},"description":"Chez WIKA France depuis 1998, j\u2019ai entre autres la responsabilit\u00e9 des instruments de mesure de pression et de temp\u00e9rature m\u00e9caniques. Cette longue exp\u00e9rience m\u2019a permis de cotoyer de tr\u00e8s nombreuses applications et probl\u00e9matiques d\u2019instrumentation. Je pourrais ainsi r\u00e9pondre \u00e0 vos questions sur des cas concrets d\u2019utilisation de nos instruments.","url":"https:\/\/blog.wika.com\/fr\/author\/forestp\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/comments?post=9949"}],"version-history":[{"count":3,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9949\/revisions"}],"predecessor-version":[{"id":11165,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/posts\/9949\/revisions\/11165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media\/9943"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/media?parent=9949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/categories?post=9949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/fr\/wp-json\/wp\/v2\/tags?post=9949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}