{"id":7573,"date":"2018-10-16T09:08:41","date_gmt":"2018-10-16T07:08:41","guid":{"rendered":"https:\/\/blog.wika.com\/it\/?p=7573"},"modified":"2023-09-01T09:25:30","modified_gmt":"2023-09-01T07:25:30","slug":"la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/","title":{"rendered":"La compensazione dell\u2019errore del segnale per il punto zero e lo span di un trasduttore di pressione"},"content":{"rendered":"<p><strong>Il vantaggio dell\u2019installazione di un trasduttore di pressione o di un corrispondente assieme \u00e8 di poter utilizzare dimensioni molto compatte. Tuttavia, occorre considerare alcuni punti che, se confrontati con l\u2019utilizzo di un trasduttore completamente regolato con un segnale di uscita amplificato, rappresentano per il cliente uno sforzo aggiuntivo.<\/strong><\/p>\n<p>Per ogni trasduttore, ad esempio, \u00e8 possibile misurare e compensare il punto zero e l\u2019errore di span tramite le elettroniche del cliente. A questo scopo, occorre una misura del segnale del trasduttore sia in condizioni di nessuna pressione ad esso applicata sia in condizioni di pressione nominale\/pressione di lavoro.<\/p>\n<p>In entrambi i casi si verificher\u00e0 una deviazione rispetto al valore atteso (= offset). Questi errori di misura, tuttavia, possono essere eliminati tramite le elettroniche di elaborazione del segnale. Occorre fare attenzione, soprattutto quando si imposta la pressione di esercizio, che venga utilizzato un riferimento sufficientemente accurato (valore standard: il riferimento, in accordo alla normativa EN 837 deve avere un errore di misura almeno 4 volte inferiore a quello del trasduttore da regolare).<\/p>\n<p>A scopo illustrativo vediamo un esempio numerico riferito a un trasduttore a film sottile metallico (come ad esempio il modello WIKA TTF-1): l\u2019offset del punto zero pu\u00f2 essere fino al 25 %; l\u2019errore di span, in funzione del campo di pressione, del 15-25 %. Nel peggiore dei casi con lo stesso segno, il che rende il valore misurato privo di significato se non \u00e8 stata eseguita la regolazione descritta in precedenza.<\/p>\n<p>A seguito della regolazione del punto zero e degli errori di span, occorre prestare attenzione alle caratteristiche tecniche riportate nella scheda tecnica dei trasduttori e dei loro componenti in modo da determinarne l\u2019accuratezza alla temperatura ambiente (non linearit\u00e0, isteresi, non ripetibilit\u00e0).<\/p>\n<p>Per ulteriori informazioni trasduttori a film sottile metallici <a href=\"https:\/\/www.wika.com\/it-it\/ttf_1.WIKA\" rel=\"external\" target=\"_blank\">TTF-1<\/a> consultare il sito internet WIKA.<\/p>\n<p><strong>Leggi anche i nostro articoli:<\/strong><br \/>\n<a href=\"https:\/\/blog.wika.com\/it\/knowhow\/precisione-dei-sensori-di-pressione-cosa-sintende-precisamente\/\">Precisione dei sensori di pressione: cosa s\u2019intende \u201cprecisamente\u201d?<\/a><br \/>\n<a href=\"https:\/\/blog.wika.com\/it\/knowhow\/quali-sono-le-versioni-disponibili-dei-sensori-di-pressione\/\">Quali sono le versioni disponibili dei sensori di pressione?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il vantaggio dell\u2019installazione di un trasduttore di pressione o di un corrispondente assieme \u00e8 di poter utilizzare dimensioni molto compatte. Tuttavia, occorre considerare alcuni punti che, se confrontati con l\u2019utilizzo di un trasduttore completamente regolato con un segnale di uscita amplificato, rappresentano per il cliente uno sforzo aggiuntivo. Per ogni trasduttore, ad esempio, \u00e8 possibile [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":7577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[78,30],"class_list":["post-7573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowhow","tag-en-837","tag-sensore-di-pressione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La compensazione dell\u2019errore di segnale - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Il vantaggio dell\u2019installazione di un trasduttore di pressione o di un corrispondente assieme \u00e8 di poter utilizzare dimensioni molto compatte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La compensazione dell\u2019errore di segnale - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Il vantaggio dell\u2019installazione di un trasduttore di pressione o di un corrispondente assieme \u00e8 di poter utilizzare dimensioni molto compatte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/it\/files\/2018\/10\/pressure-sensor-element_it.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michele Moreo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michele Moreo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/\"},\"author\":{\"name\":\"Michele Moreo\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/ca71cf459111ad9cc2f6a99000f7c0a1\"},\"headline\":\"La compensazione dell\u2019errore del segnale per il punto zero e lo span di un trasduttore di pressione\",\"datePublished\":\"2018-10-16T07:08:41+00:00\",\"dateModified\":\"2023-09-01T07:25:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/\"},\"wordCount\":335,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2018\\\/10\\\/pressure-sensor-element_it.jpg\",\"keywords\":[\"EN 837\",\"sensore di pressione\"],\"articleSection\":[\"Know-How\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/\",\"name\":\"La compensazione dell\u2019errore di segnale - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2018\\\/10\\\/pressure-sensor-element_it.jpg\",\"datePublished\":\"2018-10-16T07:08:41+00:00\",\"dateModified\":\"2023-09-01T07:25:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/ca71cf459111ad9cc2f6a99000f7c0a1\"},\"description\":\"Il vantaggio dell\u2019installazione di un trasduttore di pressione o di un corrispondente assieme \u00e8 di poter utilizzare dimensioni molto compatte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2018\\\/10\\\/pressure-sensor-element_it.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2018\\\/10\\\/pressure-sensor-element_it.jpg\",\"width\":838,\"height\":471,\"caption\":\"Compensazione dell'errore di segnale per il punto zero e lo span\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La compensazione dell\u2019errore del segnale per il punto zero e lo span di un trasduttore di pressione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Nel nostro blog in Italiano puoi trovare interessanti articoli sulle misure di pressione, temperatura, livello e portata, oltre che sui prodotti e servizi di taratura.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/ca71cf459111ad9cc2f6a99000f7c0a1\",\"name\":\"Michele Moreo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2015\\\/03\\\/default_avatar-e1434609919901-140x140.png\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2015\\\/03\\\/default_avatar-e1434609919901-140x140.png\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2015\\\/03\\\/default_avatar-e1434609919901-140x140.png\",\"caption\":\"Michele Moreo\"},\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/author\\\/mmoreo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La compensazione dell\u2019errore di segnale - Blog WIKA","description":"Il vantaggio dell\u2019installazione di un trasduttore di pressione o di un corrispondente assieme \u00e8 di poter utilizzare dimensioni molto compatte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/","og_locale":"it_IT","og_type":"article","og_title":"La compensazione dell\u2019errore di segnale - Blog WIKA","og_description":"Il vantaggio dell\u2019installazione di un trasduttore di pressione o di un corrispondente assieme \u00e8 di poter utilizzare dimensioni molto compatte.","og_url":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/it\/files\/2018\/10\/pressure-sensor-element_it.jpg","type":"image\/jpeg"}],"author":"Michele Moreo","twitter_misc":{"Scritto da":"Michele Moreo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/"},"author":{"name":"Michele Moreo","@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/ca71cf459111ad9cc2f6a99000f7c0a1"},"headline":"La compensazione dell\u2019errore del segnale per il punto zero e lo span di un trasduttore di pressione","datePublished":"2018-10-16T07:08:41+00:00","dateModified":"2023-09-01T07:25:30+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/"},"wordCount":335,"commentCount":0,"image":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/it\/files\/2018\/10\/pressure-sensor-element_it.jpg","keywords":["EN 837","sensore di pressione"],"articleSection":["Know-How"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/","url":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/","name":"La compensazione dell\u2019errore di segnale - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/it\/files\/2018\/10\/pressure-sensor-element_it.jpg","datePublished":"2018-10-16T07:08:41+00:00","dateModified":"2023-09-01T07:25:30+00:00","author":{"@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/ca71cf459111ad9cc2f6a99000f7c0a1"},"description":"Il vantaggio dell\u2019installazione di un trasduttore di pressione o di un corrispondente assieme \u00e8 di poter utilizzare dimensioni molto compatte.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/#primaryimage","url":"https:\/\/blog.wika.com\/it\/files\/2018\/10\/pressure-sensor-element_it.jpg","contentUrl":"https:\/\/blog.wika.com\/it\/files\/2018\/10\/pressure-sensor-element_it.jpg","width":838,"height":471,"caption":"Compensazione dell'errore di segnale per il punto zero e lo span"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/it\/knowhow\/la-compensazione-dellerrore-del-segnale-per-il-punto-zero-e-lo-span-di-un-trasduttore-di-pressione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wika.com\/it\/"},{"@type":"ListItem","position":2,"name":"La compensazione dell\u2019errore del segnale per il punto zero e lo span di un trasduttore di pressione"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/it\/#website","url":"https:\/\/blog.wika.com\/it\/","name":"Blog WIKA","description":"Nel nostro blog in Italiano puoi trovare interessanti articoli sulle misure di pressione, temperatura, livello e portata, oltre che sui prodotti e servizi di taratura.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/ca71cf459111ad9cc2f6a99000f7c0a1","name":"Michele Moreo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wika.com\/it\/files\/2015\/03\/default_avatar-e1434609919901-140x140.png","url":"https:\/\/blog.wika.com\/it\/files\/2015\/03\/default_avatar-e1434609919901-140x140.png","contentUrl":"https:\/\/blog.wika.com\/it\/files\/2015\/03\/default_avatar-e1434609919901-140x140.png","caption":"Michele Moreo"},"url":"https:\/\/blog.wika.com\/it\/author\/mmoreo\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/7573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/comments?post=7573"}],"version-history":[{"count":5,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/7573\/revisions"}],"predecessor-version":[{"id":11781,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/7573\/revisions\/11781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/media\/7577"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/media?parent=7573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/categories?post=7573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/tags?post=7573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}