{"id":8549,"date":"2020-10-26T10:27:35","date_gmt":"2020-10-26T09:27:35","guid":{"rendered":"https:\/\/blog.wika.com\/it\/?p=8549"},"modified":"2023-09-12T13:59:41","modified_gmt":"2023-09-12T11:59:41","slug":"soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/","title":{"rendered":"Soluzioni di misura per gli impianti di trattamento delle acque reflue"},"content":{"rendered":"<p><strong>Per garantire che i processi funzionino in modo efficiente e sicuro, gli impianti di trattamento delle acque reflue richiedono una serie di strumenti di misura. WIKA \u00e8 un partner completo per la tecnologia di monitoraggio di cui questo settore ha bisogno.<\/strong><\/p>\n<p>L&#8217;acqua dolce \u00e8 uno dei beni pi\u00f9 importanti del pianeta. Un modo fondamentale per essere sicuri di non sprecare questo prezioso bene \u00e8 quello di pulire e purificare le acque reflue in modo che possano essere restituite alla natura o alla rete idrica pubblica.<\/p>\n<h2>Attrezzature per il trattamento delle acque reflue<\/h2>\n<p>WIKA offre una selezione completa di strumenti per tutte le fasi di un impianto di trattamento. Ecco una panoramica delle tecnologie WIKA per il <a href=\"https:\/\/www.wika.com\/it-it\/acque_e_acque_reflue.WIKA\" rel=\"external\" target=\"_blank\">trattamento delle acque e delle acque reflue<\/a>:<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:308px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/it\/files\/2020\/10\/1_trattamento_preliminare.png\" alt=\"Fase preliminare del trattamento\" \/><p class=\"wp-caption-text\">Fase preliminare del trattamento<\/p><\/div>\n    \n<h2>Fase preliminare del trattamento: rimozione dei detriti e dei galleggianti<\/h2>\n<p>I liquami e i fanghi sono fluidi difficili, che richiedono <strong><a href=\"https:\/\/www.wika.com\/it-it\/manometri.WIKA\" rel=\"external\" target=\"_blank\">manometri<\/a> <\/strong>estremamente robusti e <strong><a href=\"https:\/\/www.wika.com\/it-it\/trasmettitori_da_processo.WIKA\" rel=\"external\" target=\"_blank\">trasmettitori da processo<\/a> <\/strong>per tracciare le condizioni delle linee di influenza. Le <strong><a href=\"https:\/\/www.wika.com\/it-it\/termoresistenze.WIKA\" rel=\"external\" target=\"_blank\">termoresistenze (RTD)<\/a> <\/strong>monitorano le prestazioni di pompe e motori che lavorano praticamente ininterrottamente. Gli <strong><a href=\"https:\/\/www.wika.com\/it-it\/elementi_primari_di_portata.WIKA\" rel=\"external\" target=\"_blank\">elementi primari di portata<\/a> <\/strong>rilevano piccoli problemi nelle tubazioni prima che diventino pi\u00f9 grandi e pi\u00f9 costosi.<\/p>\n<h2>Prima fase del trattamento: chiarificazione delle acque reflue<\/h2>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:308px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/it\/files\/2020\/10\/2_trattamento_primario.png\" \/><p class=\"wp-caption-text\">Prima fase del trattamento<\/p><\/div>\n    \n<p>Gli schiumatoi meccanici rimuovono solidi e grassi, mentre i prodotti chimici aiutano la coagulazione, la flocculazione e il condizionamento dei fanghi. I <strong><a href=\"https:\/\/www.wika.com\/it-it\/pressostati.WIKA\" rel=\"external\" target=\"_blank\">pressostati<\/a> <\/strong>compatti nei sistemi di iniezione montati sugli skid assicurano che le acque reflue ricevano la giusta quantit\u00e0 di sostanze chimiche. Le<strong><a href=\"https:\/\/www.wika.com\/it-it\/sensori_di_livello_immergibili.WIKA\" rel=\"external\" target=\"_blank\"> sonde di pressione immergibili per la misura di livello<\/a> <\/strong>aiutano a prevenire il trabocco in bacini e canali.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u00a0<\/h2>\n<h2>Seconda fase del trattamento: favorire la decomposizione<\/h2>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:308px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/it\/files\/2020\/10\/3_trattamento_secondario.png\" \/><p class=\"wp-caption-text\">Seconda fase del trattamento<\/p><\/div>\n    \n<p>Un modo efficiente per ridurre la biomassa \u00e8 quello di incoraggiare i batteri esistenti ad abbatterla. Per i processi che infondono ossigeno nelle acque reflue (trattamento aerobico), i <strong><a href=\"https:\/\/www.wika.it\/732_31_732_51_it_it.WIKA\" rel=\"external\" target=\"_blank\">manometri differenziali<\/a> <\/strong>rilevano se i dischi di aerazione sono liberi o bloccati. I <strong><a href=\"https:\/\/www.wika.com\/it-it\/trasmettitori_di_temperatura.WIKA\" rel=\"external\" target=\"_blank\">trasmettitori di temperatura<\/a> <\/strong>fanno in modo che i digestori siano ottimizzati per l&#8217;attivit\u00e0 anaerobica.<\/p>\n<h2>\u00a0<\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n      <div class=\"wp-caption alignright\" style=\"max-width:308px;\"><img decoding=\"async\" src=\"https:\/\/blog.wika.com\/it\/files\/2020\/10\/4_trattemento_terziario.png\" \/><p class=\"wp-caption-text\">Terza fase del trattamento<\/p><\/div>\n    \n<h2>Terza fase del trattamento: eliminazione del limo e dei microbi<\/h2>\n<p>Dopo le tre fasi precedenti, le acque di scarico contengono ora solo TSS (solidi sospesi totali). Membrane ad osmosi inversa (RO) setacciano grandi agenti patogeni e limo; i manometri con <strong><a href=\"https:\/\/www.wika.com\/it-it\/separatori_a_membrana.WIKA\" rel=\"external\" target=\"_blank\">separatore<\/a> <\/strong>monitorano questo processo. Gli agenti chimici e\/o la luce UV uccidono i microrganismi rimanenti.<\/p>\n<h2>Competenza nel trattamento delle acque reflue<\/h2>\n<p>Gli specialisti della strumentazione di WIKA hanno contribuito a costruire alcuni dei pi\u00f9 grandi impianti di trattamento delle acque reflue urbane del mondo. Questo bagaglio di conoscenze ed esperienza ci permette di offrire ai nostri clienti un servizio e una consulenza eccezionale su tutti gli aspetti del trattamento delle acque reflue, dalla progettazione iniziale alla manutenzione e alla <strong><a href=\"https:\/\/www.wika.com\/it-it\/prodotti.WIKA?Subnav=6\" rel=\"external\" target=\"_blank\">taratura<\/a><\/strong>.<\/p>\n<p>Scarica la nostra <a href=\"https:\/\/www.wika.com\/media\/Brochures-and-flyers\/Industries\/br_waterwastewater_en_co.pdf\" rel=\"external\" target=\"_blank\">brochure dedicata<\/a> o <a href=\"https:\/\/www.wika.com\/it-it\/contatti.WIKA\" rel=\"external\" target=\"_blank\">contattateci<\/a> per ulteriori informazioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per garantire che i processi funzionino in modo efficiente e sicuro, gli impianti di trattamento delle acque reflue richiedono una serie di strumenti di misura. WIKA \u00e8 un partner completo per la tecnologia di monitoraggio di cui questo settore ha bisogno. L&#8217;acqua dolce \u00e8 uno dei beni pi\u00f9 importanti del pianeta. Un modo fondamentale per [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":8548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[181],"tags":[310],"class_list":["post-8549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-applicazioni","tag-trattamento-acque"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soluzioni di misura per il trattamento di acque reflue - Blog WIKA<\/title>\n<meta name=\"description\" content=\"Per garantire che i processi funzionino in modo efficiente e sicuro, gli impianti di trattamento delle acque reflue richiedono diversi striumenti di misura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soluzioni di misura per il trattamento di acque reflue - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"Per garantire che i processi funzionino in modo efficiente e sicuro, gli impianti di trattamento delle acque reflue richiedono diversi striumenti di misura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/it\/files\/2020\/10\/acque_reflue.png\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Massimo Beatrice\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Massimo Beatrice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/\"},\"author\":{\"name\":\"Massimo Beatrice\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/a631e840f336b80535242401d264402c\"},\"headline\":\"Soluzioni di misura per gli impianti di trattamento delle acque reflue\",\"datePublished\":\"2020-10-26T09:27:35+00:00\",\"dateModified\":\"2023-09-12T11:59:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/\"},\"wordCount\":509,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2020\\\/10\\\/acque_reflue.png\",\"keywords\":[\"Trattamento acque\"],\"articleSection\":[\"Applicazioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/\",\"name\":\"Soluzioni di misura per il trattamento di acque reflue - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2020\\\/10\\\/acque_reflue.png\",\"datePublished\":\"2020-10-26T09:27:35+00:00\",\"dateModified\":\"2023-09-12T11:59:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/a631e840f336b80535242401d264402c\"},\"description\":\"Per garantire che i processi funzionino in modo efficiente e sicuro, gli impianti di trattamento delle acque reflue richiedono diversi striumenti di misura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2020\\\/10\\\/acque_reflue.png\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2020\\\/10\\\/acque_reflue.png\",\"width\":838,\"height\":471},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/applicazioni\\\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluzioni di misura per gli impianti di trattamento delle acque reflue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Nel nostro blog in Italiano puoi trovare interessanti articoli sulle misure di pressione, temperatura, livello e portata, oltre che sui prodotti e servizi di taratura.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/a631e840f336b80535242401d264402c\",\"name\":\"Massimo Beatrice\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2024\\\/06\\\/beatricemassimo-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2024\\\/06\\\/beatricemassimo-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2024\\\/06\\\/beatricemassimo-120x120.jpg\",\"caption\":\"Massimo Beatrice\"},\"description\":\"Pluriennale esperienza nella gestione dei contenuti per il web per aziende leader nella strumentazione industriale. In questo blog contribuir\u00f2 ad alimentare la presenza di contenuti che meglio possano venire incontro alle richieste di informazioni generali o di carattere tecnico che normalmente riceviamo in WIKA Italia.\",\"sameAs\":[\"http:\\\/\\\/www.wika.it\"],\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/author\\\/mbeatrice\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soluzioni di misura per il trattamento di acque reflue - Blog WIKA","description":"Per garantire che i processi funzionino in modo efficiente e sicuro, gli impianti di trattamento delle acque reflue richiedono diversi striumenti di misura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/","og_locale":"it_IT","og_type":"article","og_title":"Soluzioni di misura per il trattamento di acque reflue - Blog WIKA","og_description":"Per garantire che i processi funzionino in modo efficiente e sicuro, gli impianti di trattamento delle acque reflue richiedono diversi striumenti di misura.","og_url":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/it\/files\/2020\/10\/acque_reflue.png","type":"image\/png"}],"author":"Massimo Beatrice","twitter_misc":{"Scritto da":"Massimo Beatrice","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/"},"author":{"name":"Massimo Beatrice","@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/a631e840f336b80535242401d264402c"},"headline":"Soluzioni di misura per gli impianti di trattamento delle acque reflue","datePublished":"2020-10-26T09:27:35+00:00","dateModified":"2023-09-12T11:59:41+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/"},"wordCount":509,"commentCount":0,"image":{"@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/it\/files\/2020\/10\/acque_reflue.png","keywords":["Trattamento acque"],"articleSection":["Applicazioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/","url":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/","name":"Soluzioni di misura per il trattamento di acque reflue - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/it\/files\/2020\/10\/acque_reflue.png","datePublished":"2020-10-26T09:27:35+00:00","dateModified":"2023-09-12T11:59:41+00:00","author":{"@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/a631e840f336b80535242401d264402c"},"description":"Per garantire che i processi funzionino in modo efficiente e sicuro, gli impianti di trattamento delle acque reflue richiedono diversi striumenti di misura.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/#primaryimage","url":"https:\/\/blog.wika.com\/it\/files\/2020\/10\/acque_reflue.png","contentUrl":"https:\/\/blog.wika.com\/it\/files\/2020\/10\/acque_reflue.png","width":838,"height":471},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/it\/applicazioni\/soluzioni-di-misura-per-gli-impianti-di-trattamento-delle-acque-reflue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wika.com\/it\/"},{"@type":"ListItem","position":2,"name":"Soluzioni di misura per gli impianti di trattamento delle acque reflue"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/it\/#website","url":"https:\/\/blog.wika.com\/it\/","name":"Blog WIKA","description":"Nel nostro blog in Italiano puoi trovare interessanti articoli sulle misure di pressione, temperatura, livello e portata, oltre che sui prodotti e servizi di taratura.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/a631e840f336b80535242401d264402c","name":"Massimo Beatrice","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wika.com\/it\/files\/2024\/06\/beatricemassimo-120x120.jpg","url":"https:\/\/blog.wika.com\/it\/files\/2024\/06\/beatricemassimo-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/it\/files\/2024\/06\/beatricemassimo-120x120.jpg","caption":"Massimo Beatrice"},"description":"Pluriennale esperienza nella gestione dei contenuti per il web per aziende leader nella strumentazione industriale. In questo blog contribuir\u00f2 ad alimentare la presenza di contenuti che meglio possano venire incontro alle richieste di informazioni generali o di carattere tecnico che normalmente riceviamo in WIKA Italia.","sameAs":["http:\/\/www.wika.it"],"url":"https:\/\/blog.wika.com\/it\/author\/mbeatrice\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/8549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/comments?post=8549"}],"version-history":[{"count":12,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/8549\/revisions"}],"predecessor-version":[{"id":11949,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/8549\/revisions\/11949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/media\/8548"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/media?parent=8549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/categories?post=8549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/tags?post=8549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}