{"id":861,"date":"2014-12-09T09:08:44","date_gmt":"2014-12-09T08:08:44","guid":{"rendered":"http:\/\/blog.wika.com\/it\/?p=861"},"modified":"2023-09-07T07:05:13","modified_gmt":"2023-09-07T05:05:13","slug":"sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/","title":{"rendered":"Sensori di pressione a sicurezza intrinseca e barriere Ex \u2013 una coppia inseparabile"},"content":{"rendered":"<p>All&#8217;interno della Comunit\u00e0 Europea, i sensori di pressione a sicurezza intrinseca possono essere utilizzati in aree pericolose solo se installati in combinazione con una barriera Ex. La combinazione di sensore di pressione e Ex barriera deve soddisfare la &#8220;<a title=\"Prova sicurezza intrinseca di un sensore ATEX\" href=\"http:\/\/blog.wika.com\/it\/2014\/07\/21\/prova-della-sicurezza-intrinseca-di-sensore-di-pressione-atex\/\" target=\"_blank\" rel=\"noopener noreferrer\">Prova di sicurezza intrinseca<\/a>&#8221; in conformit\u00e0 con la direttiva 94\/9\/CE ATEX.<\/p>\n<p>Non tutte le combinazioni di sensore e barriera dei diversi produttori soddisfano per\u00f2 questa condizione. Da un lato \u00e8 possibile che i valori caratteristici Ex o di sicurezza non siano compatibili tra sensore e barriera e dall\u2019altro lato, le caratteristiche funzionali di questi prodotti devono essere adeguati alla specifica applicazione.<\/p>\n<p>Quindi, anche se i valori di sicurezza corrispondono, la coppia sensore di pressione e barriera Ex potrebbe non funzionare perch\u00e9, ad esempio, entrambi i componenti operano in modo &#8220;passivo&#8221; (ulteriori informazioni sull\u2019argomento &#8220;attivo \/ passivo&#8221; sono disponibili nel precedente post &#8220;<a title=\"Il circuito elettrico dei sensori di pressione\" href=\"http:\/\/blog.wika.com\/it\/2013\/05\/06\/il-circuito-elettrico-dei-sensori-di-pressione-quando-sensore-attivo-quando-passivo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Il circuito elettrico dei sensori di pressione: quando un sensore \u00e8 attivo e quando \u00e8 passivo?<\/a>&#8220;)<\/p>\n<p>E\u2019 necessario pertanto assicurarsi di abbinare solo i sensori di pressione e le barriere i cui dati di sicurezza e funzionali siano corrispondenti. Per questo motivo noi raccomandiamo un modello di barriera Ex compatibile direttamente nelle schede tecniche dei sensori di pressione a sicurezza intrinseca.<\/p>\n<p>Se hai domande o curiosit\u00e0, non esitare a <a title=\"Modulo di contatto WIKA\" href=\"https:\/\/www.wika.com\/it-it\/contatti.WIKA\" target=\"_blank\" rel=\"noopener noreferrer external\">contattarci<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>All&#8217;interno della Comunit\u00e0 Europea, i sensori di pressione a sicurezza intrinseca possono essere utilizzati in aree pericolose solo se installati in combinazione con una barriera Ex. La combinazione di sensore di pressione e Ex barriera deve soddisfare la &#8220;Prova di sicurezza intrinseca&#8221; in conformit\u00e0 con la direttiva 94\/9\/CE ATEX. Non tutte le combinazioni di sensore [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":6505,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[206],"class_list":["post-861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowhow","tag-protezione-ex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sensori di pressione a sicurezza intrinseca ed Ex - Blog WIKA<\/title>\n<meta name=\"description\" content=\"All&#039;interno della Comunit\u00e0 Europea, i sensori di pressione a sicurezza intrinseca possono essere utilizzati in aree pericolose solo se installati in\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sensori di pressione a sicurezza intrinseca ed Ex - Blog WIKA\" \/>\n<meta property=\"og:description\" content=\"All&#039;interno della Comunit\u00e0 Europea, i sensori di pressione a sicurezza intrinseca possono essere utilizzati in aree pericolose solo se installati in\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog WIKA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/it\/files\/2015\/07\/is-20_barriere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ferdinando Miccoli\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ferdinando Miccoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/\"},\"author\":{\"name\":\"Ferdinando Miccoli\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/b849e3c0d96e6814687fc2e8407c4a9c\"},\"headline\":\"Sensori di pressione a sicurezza intrinseca e barriere Ex \u2013 una coppia inseparabile\",\"datePublished\":\"2014-12-09T08:08:44+00:00\",\"dateModified\":\"2023-09-07T05:05:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/\"},\"wordCount\":220,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2015\\\/07\\\/is-20_barriere.jpg\",\"keywords\":[\"protezione Ex\"],\"articleSection\":[\"Know-How\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/\",\"name\":\"Sensori di pressione a sicurezza intrinseca ed Ex - Blog WIKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2015\\\/07\\\/is-20_barriere.jpg\",\"datePublished\":\"2014-12-09T08:08:44+00:00\",\"dateModified\":\"2023-09-07T05:05:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/b849e3c0d96e6814687fc2e8407c4a9c\"},\"description\":\"All'interno della Comunit\u00e0 Europea, i sensori di pressione a sicurezza intrinseca possono essere utilizzati in aree pericolose solo se installati in\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2015\\\/07\\\/is-20_barriere.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2015\\\/07\\\/is-20_barriere.jpg\",\"width\":838,\"height\":471,\"caption\":\"Barriera sicurezza intrinseca IS-20\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/knowhow\\\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sensori di pressione a sicurezza intrinseca e barriere Ex \u2013 una coppia inseparabile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/\",\"name\":\"Blog WIKA\",\"description\":\"Nel nostro blog in Italiano puoi trovare interessanti articoli sulle misure di pressione, temperatura, livello e portata, oltre che sui prodotti e servizi di taratura.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/#\\\/schema\\\/person\\\/b849e3c0d96e6814687fc2e8407c4a9c\",\"name\":\"Ferdinando Miccoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2020\\\/09\\\/pic_author_miccoli-ferdinando_it-it-140x140.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2020\\\/09\\\/pic_author_miccoli-ferdinando_it-it-140x140.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/files\\\/2020\\\/09\\\/pic_author_miccoli-ferdinando_it-it-140x140.jpg\",\"caption\":\"Ferdinando Miccoli\"},\"description\":\"Ho fortemente voluto realizzare questo blog, il cui principale obiettivo \u00e8 fornire un contributo alla diffusione della cultura tecnica relativa alla strumentazione di misura. Vogliamo assistere i visitatori interessati nella loro ricerca di informazioni, rispondendo in modo chiaro e conciso alle loro richieste e curiosit\u00e0.\",\"sameAs\":[\"http:\\\/\\\/www.wika.it\"],\"url\":\"https:\\\/\\\/blog.wika.com\\\/it\\\/author\\\/fmiccoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sensori di pressione a sicurezza intrinseca ed Ex - Blog WIKA","description":"All'interno della Comunit\u00e0 Europea, i sensori di pressione a sicurezza intrinseca possono essere utilizzati in aree pericolose solo se installati in","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/","og_locale":"it_IT","og_type":"article","og_title":"Sensori di pressione a sicurezza intrinseca ed Ex - Blog WIKA","og_description":"All'interno della Comunit\u00e0 Europea, i sensori di pressione a sicurezza intrinseca possono essere utilizzati in aree pericolose solo se installati in","og_url":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/","og_site_name":"Blog WIKA","og_image":[{"width":838,"height":471,"url":"https:\/\/blog.wika.com\/it\/files\/2015\/07\/is-20_barriere.jpg","type":"image\/jpeg"}],"author":"Ferdinando Miccoli","twitter_misc":{"Scritto da":"Ferdinando Miccoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/"},"author":{"name":"Ferdinando Miccoli","@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/b849e3c0d96e6814687fc2e8407c4a9c"},"headline":"Sensori di pressione a sicurezza intrinseca e barriere Ex \u2013 una coppia inseparabile","datePublished":"2014-12-09T08:08:44+00:00","dateModified":"2023-09-07T05:05:13+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/"},"wordCount":220,"commentCount":0,"image":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/it\/files\/2015\/07\/is-20_barriere.jpg","keywords":["protezione Ex"],"articleSection":["Know-How"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/","url":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/","name":"Sensori di pressione a sicurezza intrinseca ed Ex - Blog WIKA","isPartOf":{"@id":"https:\/\/blog.wika.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/it\/files\/2015\/07\/is-20_barriere.jpg","datePublished":"2014-12-09T08:08:44+00:00","dateModified":"2023-09-07T05:05:13+00:00","author":{"@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/b849e3c0d96e6814687fc2e8407c4a9c"},"description":"All'interno della Comunit\u00e0 Europea, i sensori di pressione a sicurezza intrinseca possono essere utilizzati in aree pericolose solo se installati in","breadcrumb":{"@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/#primaryimage","url":"https:\/\/blog.wika.com\/it\/files\/2015\/07\/is-20_barriere.jpg","contentUrl":"https:\/\/blog.wika.com\/it\/files\/2015\/07\/is-20_barriere.jpg","width":838,"height":471,"caption":"Barriera sicurezza intrinseca IS-20"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/it\/knowhow\/sensori-di-pressione-sicurezza-intrinseca-barriere-una-coppia-inseparabile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wika.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sensori di pressione a sicurezza intrinseca e barriere Ex \u2013 una coppia inseparabile"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/it\/#website","url":"https:\/\/blog.wika.com\/it\/","name":"Blog WIKA","description":"Nel nostro blog in Italiano puoi trovare interessanti articoli sulle misure di pressione, temperatura, livello e portata, oltre che sui prodotti e servizi di taratura.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.wika.com\/it\/#\/schema\/person\/b849e3c0d96e6814687fc2e8407c4a9c","name":"Ferdinando Miccoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wika.com\/it\/files\/2020\/09\/pic_author_miccoli-ferdinando_it-it-140x140.jpg","url":"https:\/\/blog.wika.com\/it\/files\/2020\/09\/pic_author_miccoli-ferdinando_it-it-140x140.jpg","contentUrl":"https:\/\/blog.wika.com\/it\/files\/2020\/09\/pic_author_miccoli-ferdinando_it-it-140x140.jpg","caption":"Ferdinando Miccoli"},"description":"Ho fortemente voluto realizzare questo blog, il cui principale obiettivo \u00e8 fornire un contributo alla diffusione della cultura tecnica relativa alla strumentazione di misura. Vogliamo assistere i visitatori interessati nella loro ricerca di informazioni, rispondendo in modo chiaro e conciso alle loro richieste e curiosit\u00e0.","sameAs":["http:\/\/www.wika.it"],"url":"https:\/\/blog.wika.com\/it\/author\/fmiccoli\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/comments?post=861"}],"version-history":[{"count":13,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/861\/revisions"}],"predecessor-version":[{"id":11897,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/posts\/861\/revisions\/11897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/media\/6505"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/media?parent=861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/categories?post=861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/it\/wp-json\/wp\/v2\/tags?post=861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}