{"id":17,"count":59,"description":"","link":"https:\/\/blog.wika.com\/pt\/aplicacoes\/","name":"Aplica\u00e7\u00f5es","slug":"aplicacoes","taxonomy":"category","parent":0,"meta":[],"acf":[],"z_taxonomy_image_url":"http:\/\/blog.wika.com\/pt\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aplica\u00e7\u00f5es: Solu\u00e7\u00f5es WIKA no detalhe - WIKA blog<\/title>\n<meta name=\"description\" content=\"Informa\u00e7\u00f5es \u00fateis e dicas pr\u00e1ticas para usu\u00e1rios e projetistas sobre o uso de nossos instrumentos de medi\u00e7\u00e3o explicado por nossos gerentes de produto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/pt\/aplicacoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aplica\u00e7\u00f5es: Solu\u00e7\u00f5es WIKA no detalhe - WIKA blog\" \/>\n<meta property=\"og:description\" content=\"Informa\u00e7\u00f5es \u00fateis e dicas pr\u00e1ticas para usu\u00e1rios e projetistas sobre o uso de nossos instrumentos de medi\u00e7\u00e3o explicado por nossos gerentes de produto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/pt\/aplicacoes\/\" \/>\n<meta property=\"og:site_name\" content=\"WIKA blog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/aplicacoes\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/aplicacoes\\\/\",\"name\":\"Aplica\u00e7\u00f5es: Solu\u00e7\u00f5es WIKA no detalhe - WIKA blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/#website\"},\"description\":\"Informa\u00e7\u00f5es \u00fateis e dicas pr\u00e1ticas para usu\u00e1rios e projetistas sobre o uso de nossos instrumentos de medi\u00e7\u00e3o explicado por nossos gerentes de produto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/aplicacoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/aplicacoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aplica\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/\",\"name\":\"WIKA blog\",\"description\":\"Artigos interessantes sobre medi\u00e7\u00e3o de press\u00e3o, temperatura, n\u00edvel, for\u00e7a, vaz\u00e3o, SF6 e sobre tecnologia de calibra\u00e7\u00e3o.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aplica\u00e7\u00f5es: Solu\u00e7\u00f5es WIKA no detalhe - WIKA blog","description":"Informa\u00e7\u00f5es \u00fateis e dicas pr\u00e1ticas para usu\u00e1rios e projetistas sobre o uso de nossos instrumentos de medi\u00e7\u00e3o explicado por nossos gerentes de produto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/pt\/aplicacoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Aplica\u00e7\u00f5es: Solu\u00e7\u00f5es WIKA no detalhe - WIKA blog","og_description":"Informa\u00e7\u00f5es \u00fateis e dicas pr\u00e1ticas para usu\u00e1rios e projetistas sobre o uso de nossos instrumentos de medi\u00e7\u00e3o explicado por nossos gerentes de produto.","og_url":"https:\/\/blog.wika.com\/pt\/aplicacoes\/","og_site_name":"WIKA blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.wika.com\/pt\/aplicacoes\/","url":"https:\/\/blog.wika.com\/pt\/aplicacoes\/","name":"Aplica\u00e7\u00f5es: Solu\u00e7\u00f5es WIKA no detalhe - WIKA blog","isPartOf":{"@id":"https:\/\/blog.wika.com\/pt\/#website"},"description":"Informa\u00e7\u00f5es \u00fateis e dicas pr\u00e1ticas para usu\u00e1rios e projetistas sobre o uso de nossos instrumentos de medi\u00e7\u00e3o explicado por nossos gerentes de produto.","breadcrumb":{"@id":"https:\/\/blog.wika.com\/pt\/aplicacoes\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/pt\/aplicacoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog.wika.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Aplica\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/pt\/#website","url":"https:\/\/blog.wika.com\/pt\/","name":"WIKA blog","description":"Artigos interessantes sobre medi\u00e7\u00e3o de press\u00e3o, temperatura, n\u00edvel, for\u00e7a, vaz\u00e3o, SF6 e sobre tecnologia de calibra\u00e7\u00e3o.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}