{"id":9714,"date":"2021-05-21T14:59:18","date_gmt":"2021-05-21T17:59:18","guid":{"rendered":"https:\/\/blog.wika.com\/pt\/\/?p=9714"},"modified":"2021-05-21T15:35:43","modified_gmt":"2021-05-21T18:35:43","slug":"nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto","status":"publish","type":"post","link":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/","title":{"rendered":"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto"},"content":{"rendered":"<p>A medi\u00e7\u00e3o utilizando <strong>elementos prim\u00e1rios como medidores de vaz\u00e3o<\/strong> tem algumas peculiaridades. E uma delas \u00e9 a necessidade de um flu\u00eddo em um perfil de escoamento desej\u00e1vel, que se mova de forma uniforme e com seu ponto de maior velocidade pr\u00f3ximo ao centro da tubula\u00e7\u00e3o. Para tanto, deve-se evitar perturba\u00e7\u00f5es no flu\u00eddo, pois estas podem comprometer significativamente a exatid\u00e3o na medi\u00e7\u00e3o.<\/p>\n<p>Os principais tipos de perturba\u00e7\u00f5es no escoamento do fluido s\u00e3o distor\u00e7\u00f5es e turbilhonamentos (movimento rotacional do fluido dentro da tubula\u00e7\u00e3o) no perfil do fluido. Distor\u00e7\u00f5es s\u00e3o provocadas quando existe uma obstru\u00e7\u00e3o, por exemplo uma v\u00e1lvula parcialmente aberta. J\u00e1 os turbilhonamentos ocorrem quando o fluido passa pelas curvas nos diferentes planos da tubula\u00e7\u00e3o, e esse tipo de perturba\u00e7\u00e3o \u00e9 bem mais dif\u00edcil de se corrigir.<\/p>\n<p>Longos trechos e retificadores de fluxo s\u00e3o requisitados para que se possa ter um flu\u00eddo livre de perturba\u00e7\u00f5es e em um perfil adequado para medi\u00e7\u00e3o, mas ser\u00e1 mesmo que toda aplica\u00e7\u00e3o com elemento prim\u00e1rio tem essa necessidade de trechos retos?<\/p>\n<p>Saiba mais a seguir sobre <strong>medi\u00e7\u00e3o de vaz\u00e3o com elementos prim\u00e1rios<\/strong> e quais as <strong>verdadeiras necessidades envolvidas nesse tipo de instala\u00e7\u00e3o<\/strong>. Al\u00e9m de se inteirar sobre quais verdades j\u00e1 n\u00e3o s\u00e3o mais absolutas devido aos avan\u00e7os tecnol\u00f3gicos na \u00e1rea.<\/p>\n<h2>Medi\u00e7\u00e3o de Vaz\u00e3o com Elemento Prim\u00e1rio<\/h2>\n<p>Basicamente, o princ\u00edpio de funcionamento de todos os medidores de vaz\u00e3o por press\u00e3o diferencial \u00e9 o princ\u00edpio de Bernoulli. Os elementos prim\u00e1rios ou deprimog\u00eanios t\u00eam a fun\u00e7\u00e3o de <strong>causar um afunilamento ou restri\u00e7\u00e3o na tubula\u00e7\u00e3o atrav\u00e9s de um orif\u00edcio previamente calculado<\/strong>, causando um diferencial de press\u00e3o medido antes e posteriormente \u00e0 restri\u00e7\u00e3o. Por esse motivo tamb\u00e9m s\u00e3o conhecidos como geradores de press\u00e3o diferencial.<\/p>\n<p>Os elementos prim\u00e1rios s\u00e3o <strong>largamente utilizados<\/strong>, principalmente pelos avan\u00e7os tecnol\u00f3gicos na \u00e1rea dos medidores de press\u00e3o diferencial que s\u00e3o uma tecnologia extremamente difundida nas instala\u00e7\u00f5es industriais.<\/p>\n<p>Os elementos prim\u00e1rios ainda apresentam vantagens como a sua robustez. Ou seja, um elemento prim\u00e1rio pode <strong>trabalhar durante muitos anos<\/strong>, dependendo do processo, sem que haja a necessidade de manuten\u00e7\u00e3o. E ainda possibilita a separa\u00e7\u00e3o entre o processo e o medidor, <strong>facilitando processos de calibra\u00e7\u00e3o e ajustes<\/strong>\u00a0que possam vir a acontecer.<\/p>\n<h2>Defini\u00e7\u00e3o de trecho reto<\/h2>\n<p>Como o pr\u00f3prio nome diz, o trecho reto \u00e9 uma <strong>se\u00e7\u00e3o tubular retil\u00ednea<\/strong>, utilizada para <strong>estabilizar o fluxo antes mesmo da medi\u00e7\u00e3o da vaz\u00e3o<\/strong>. Ele garante que o escoamento esteja em n\u00edveis ideais para a realiza\u00e7\u00e3o das an\u00e1lises. <strong>Garantindo efici\u00eancia e exatid\u00e3o<\/strong>\u00a0nos procedimentos respons\u00e1veis por mensurar o volume dos fluidos que perpassam pelo sistema.<\/p>\n<p>Os trechos retos s\u00e3o projetados com se\u00e7\u00f5es \u00e0 montante e \u00e0 jusante do ponto de an\u00e1lise. Isso quer dizer que, tanto antes quanto depois da instala\u00e7\u00e3o de elementos prim\u00e1rios que ir\u00e3o gerar a press\u00e3o diferencial para a medi\u00e7\u00e3o, \u00e9 preciso haver certo comprimento de trecho reto.<\/p>\n<p>Toda e qualquer se\u00e7\u00e3o de trecho reto precisa <strong>seguir par\u00e2metros<\/strong> estabelecidos pelas normas vigentes. Tanto em rela\u00e7\u00e3o ao comprimento quanto \u00e0 rugosidade permitida e recomendada para a se\u00e7\u00e3o transversal das tubula\u00e7\u00f5es. Com isso, \u00e9 preciso olhar com aten\u00e7\u00e3o para os materiais que s\u00e3o utilizados na produ\u00e7\u00e3o dessas aplica\u00e7\u00f5es e suas condi\u00e7\u00f5es de instala\u00e7\u00e3o. Pois os <strong>\u00edndices de corros\u00e3o e compatibilidade com o fluido precisam sempre ser levados em considera\u00e7\u00e3o<\/strong>.<\/p>\n<h2>Avan\u00e7os tecnol\u00f3gicos na produ\u00e7\u00e3o de medidores de vaz\u00e3o<\/h2>\n<p>\nNo mercado, j\u00e1 existem equipamentos desenvolvidos exatamente para dar fim \u00e0 essa necessidade de trechos retos. Afinal, qualquer cent\u00edmetro em um projeto entrar\u00e1 na folha de gastos. E por isso que, ao avaliar produtos ou ferramentas, \u00e9 preciso pensar antes no <strong>custo-benef\u00edcio<\/strong> dessa aquisi\u00e7\u00e3o. Porque al\u00e9m do investimento em equipamentos propriamente ditos, existe a preocupa\u00e7\u00e3o com o espa\u00e7o e com as condi\u00e7\u00f5es de instala\u00e7\u00e3o.<\/p>\n<p>Ent\u00e3o, respondendo \u00e0 quest\u00e3o proposta por este artigo: nem toda aplica\u00e7\u00e3o com elemento prim\u00e1rio tem essa necessidade de trechos retos. J\u00e1 \u00e9 poss\u00edvel encontrar no mercado, tanto internacional quanto nacional, <strong>elementos prim\u00e1rios de medi\u00e7\u00e3o que n\u00e3o perdem a efici\u00eancia mesmo na aus\u00eancia do trecho reto<\/strong>. As medi\u00e7\u00f5es s\u00e3o feitas com a mesma efici\u00eancia e exatid\u00e3o mesmo em sistemas que n\u00e3o possuem trechos retos.<\/p>\n<p>J\u00e1 que os medidores de vaz\u00e3o s\u00e3o indispens\u00e1veis para alguns neg\u00f3cios, agora \u00e9 poss\u00edvel tamb\u00e9m poupar espa\u00e7o e alguns metros de tubula\u00e7\u00e3o. Com isso, cada vez mais, estes equipamentos viabilizam a praticidade na instala\u00e7\u00e3o e otimiza\u00e7\u00e3o de sistemas complexos. N\u00e3o podendo esquecer do maior objetivo de constru\u00e7\u00f5es como essa: <strong>viabiliza\u00e7\u00e3o da praticidade, efici\u00eancia e exatid\u00e3o nas medi\u00e7\u00f5es realizadas<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medi\u00e7\u00e3o utilizando elementos prim\u00e1rios como medidores de vaz\u00e3o tem algumas peculiaridades. E uma delas \u00e9 a necessidade de um flu\u00eddo em um perfil de escoamento desej\u00e1vel, que se mova de forma uniforme e com seu ponto de maior velocidade pr\u00f3ximo ao centro da tubula\u00e7\u00e3o. Para tanto, deve-se evitar perturba\u00e7\u00f5es no flu\u00eddo, pois estas podem [&hellip;]<\/p>\n","protected":false},"author":277,"featured_media":9715,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16,7],"tags":[],"class_list":["post-9714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produtos","category-produtos-vazao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto - WIKA blog<\/title>\n<meta name=\"description\" content=\"A medi\u00e7\u00e3o utilizando elementos prim\u00e1rios como medidores de vaz\u00e3o tem algumas peculiaridades. E uma delas \u00e9 a necessidade de um flu\u00eddo em um perfil de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto - WIKA blog\" \/>\n<meta property=\"og:description\" content=\"A medi\u00e7\u00e3o utilizando elementos prim\u00e1rios como medidores de vaz\u00e3o tem algumas peculiaridades. E uma delas \u00e9 a necessidade de um flu\u00eddo em um perfil de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/\" \/>\n<meta property=\"og:site_name\" content=\"WIKA blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WIKA.BR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wika.com\/pt\/files\/2021\/05\/hhr.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriel Rodrigues\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/\"},\"author\":{\"name\":\"Gabriel Rodrigues\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/#\\\/schema\\\/person\\\/0d23c6bf3d62e00b769a5e15e7d6526b\"},\"headline\":\"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto\",\"datePublished\":\"2021-05-21T17:59:18+00:00\",\"dateModified\":\"2021-05-21T18:35:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/\"},\"wordCount\":862,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/files\\\/2021\\\/05\\\/hhr.png\",\"articleSection\":[\"Produtos\",\"Vaz\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/\",\"name\":\"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto - WIKA blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/files\\\/2021\\\/05\\\/hhr.png\",\"datePublished\":\"2021-05-21T17:59:18+00:00\",\"dateModified\":\"2021-05-21T18:35:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/#\\\/schema\\\/person\\\/0d23c6bf3d62e00b769a5e15e7d6526b\"},\"description\":\"A medi\u00e7\u00e3o utilizando elementos prim\u00e1rios como medidores de vaz\u00e3o tem algumas peculiaridades. E uma delas \u00e9 a necessidade de um flu\u00eddo em um perfil de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/files\\\/2021\\\/05\\\/hhr.png\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/files\\\/2021\\\/05\\\/hhr.png\",\"width\":850,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/produtos\\\/produtos-vazao\\\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/\",\"name\":\"WIKA blog\",\"description\":\"Artigos interessantes sobre medi\u00e7\u00e3o de press\u00e3o, temperatura, n\u00edvel, for\u00e7a, vaz\u00e3o, SF6 e sobre tecnologia de calibra\u00e7\u00e3o.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/#\\\/schema\\\/person\\\/0d23c6bf3d62e00b769a5e15e7d6526b\",\"name\":\"Gabriel Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/files\\\/2021\\\/09\\\/rodriguesgabriel-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/files\\\/2021\\\/09\\\/rodriguesgabriel-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/files\\\/2021\\\/09\\\/rodriguesgabriel-120x120.jpg\",\"caption\":\"Gabriel Rodrigues\"},\"description\":\"I am a mechanical engineer with primary experience in production management and manufacturing processes for instrumentation used in measuring pressure, temperature, level, and flow. Working at WIKA Brazil since 2008, I have been involved in various departments such as Quality, Production, and Engineering. Currently, I am part of the Marketing\\\/Sales team as a Product Specialist for the Flow Line, responsible for product promotion, business analysis, and development.\",\"sameAs\":[\"http:\\\/\\\/www.wika.com.br\"],\"url\":\"https:\\\/\\\/blog.wika.com\\\/pt\\\/author\\\/grodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto - WIKA blog","description":"A medi\u00e7\u00e3o utilizando elementos prim\u00e1rios como medidores de vaz\u00e3o tem algumas peculiaridades. E uma delas \u00e9 a necessidade de um flu\u00eddo em um perfil de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/","og_locale":"pt_BR","og_type":"article","og_title":"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto - WIKA blog","og_description":"A medi\u00e7\u00e3o utilizando elementos prim\u00e1rios como medidores de vaz\u00e3o tem algumas peculiaridades. E uma delas \u00e9 a necessidade de um flu\u00eddo em um perfil de","og_url":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/","og_site_name":"WIKA blog","article_publisher":"https:\/\/www.facebook.com\/WIKA.BR","og_image":[{"width":850,"height":370,"url":"https:\/\/blog.wika.com\/pt\/files\/2021\/05\/hhr.png","type":"image\/png"}],"author":"Gabriel Rodrigues","twitter_misc":{"Escrito por":"Gabriel Rodrigues","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/#article","isPartOf":{"@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/"},"author":{"name":"Gabriel Rodrigues","@id":"https:\/\/blog.wika.com\/pt\/#\/schema\/person\/0d23c6bf3d62e00b769a5e15e7d6526b"},"headline":"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto","datePublished":"2021-05-21T17:59:18+00:00","dateModified":"2021-05-21T18:35:43+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/"},"wordCount":862,"commentCount":1,"image":{"@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/pt\/files\/2021\/05\/hhr.png","articleSection":["Produtos","Vaz\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/","url":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/","name":"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto - WIKA blog","isPartOf":{"@id":"https:\/\/blog.wika.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/#primaryimage"},"image":{"@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wika.com\/pt\/files\/2021\/05\/hhr.png","datePublished":"2021-05-21T17:59:18+00:00","dateModified":"2021-05-21T18:35:43+00:00","author":{"@id":"https:\/\/blog.wika.com\/pt\/#\/schema\/person\/0d23c6bf3d62e00b769a5e15e7d6526b"},"description":"A medi\u00e7\u00e3o utilizando elementos prim\u00e1rios como medidores de vaz\u00e3o tem algumas peculiaridades. E uma delas \u00e9 a necessidade de um flu\u00eddo em um perfil de","breadcrumb":{"@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/#primaryimage","url":"https:\/\/blog.wika.com\/pt\/files\/2021\/05\/hhr.png","contentUrl":"https:\/\/blog.wika.com\/pt\/files\/2021\/05\/hhr.png","width":850,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/pt\/produtos\/produtos-vazao\/nem-todos-os-medidores-de-vazo-precisam-da-existncia-do-trecho-reto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog.wika.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Nem todos os medidores de vaz\u00e3o precisam da exist\u00eancia do trecho reto"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/pt\/#website","url":"https:\/\/blog.wika.com\/pt\/","name":"WIKA blog","description":"Artigos interessantes sobre medi\u00e7\u00e3o de press\u00e3o, temperatura, n\u00edvel, for\u00e7a, vaz\u00e3o, SF6 e sobre tecnologia de calibra\u00e7\u00e3o.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/blog.wika.com\/pt\/#\/schema\/person\/0d23c6bf3d62e00b769a5e15e7d6526b","name":"Gabriel Rodrigues","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.wika.com\/pt\/files\/2021\/09\/rodriguesgabriel-120x120.jpg","url":"https:\/\/blog.wika.com\/pt\/files\/2021\/09\/rodriguesgabriel-120x120.jpg","contentUrl":"https:\/\/blog.wika.com\/pt\/files\/2021\/09\/rodriguesgabriel-120x120.jpg","caption":"Gabriel Rodrigues"},"description":"I am a mechanical engineer with primary experience in production management and manufacturing processes for instrumentation used in measuring pressure, temperature, level, and flow. Working at WIKA Brazil since 2008, I have been involved in various departments such as Quality, Production, and Engineering. Currently, I am part of the Marketing\/Sales team as a Product Specialist for the Flow Line, responsible for product promotion, business analysis, and development.","sameAs":["http:\/\/www.wika.com.br"],"url":"https:\/\/blog.wika.com\/pt\/author\/grodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/posts\/9714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/users\/277"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/comments?post=9714"}],"version-history":[{"count":6,"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/posts\/9714\/revisions"}],"predecessor-version":[{"id":9726,"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/posts\/9714\/revisions\/9726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/media\/9715"}],"wp:attachment":[{"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/media?parent=9714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/categories?post=9714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wika.com\/pt\/wp-json\/wp\/v2\/tags?post=9714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}