{"id":223,"count":36,"description":"","link":"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/","name":"Level","slug":"level-products","taxonomy":"category","parent":6,"meta":[],"acf":[],"z_taxonomy_image_url":"http:\/\/blog.wika.com\/us\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Level measurement products: Discover WIKA&#039;s diversity - WIKA blog<\/title>\n<meta name=\"description\" content=\"Find out more about our float switches and other products from the WIKA portfolio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Level measurement products: Discover WIKA&#039;s diversity - WIKA blog\" \/>\n<meta property=\"og:description\" content=\"Find out more about our float switches and other products from the WIKA portfolio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/\" \/>\n<meta property=\"og:site_name\" content=\"WIKA blog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/category\\\/products\\\/level-products\\\/\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/category\\\/products\\\/level-products\\\/\",\"name\":\"Level measurement products: Discover WIKA's diversity - WIKA blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/#website\"},\"description\":\"Find out more about our float switches and other products from the WIKA portfolio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/category\\\/products\\\/level-products\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/category\\\/products\\\/level-products\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/category\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Level\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/#website\",\"url\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/\",\"name\":\"WIKA blog\",\"description\":\"Our blog offers many interesting articles on pressure, temperature, level, flow measurement calibration technology and provides insights into the WIKA Group.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wika.com\\\/us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Level measurement products: Discover WIKA's diversity - WIKA blog","description":"Find out more about our float switches and other products from the WIKA portfolio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/","og_locale":"en_US","og_type":"article","og_title":"Level measurement products: Discover WIKA's diversity - WIKA blog","og_description":"Find out more about our float switches and other products from the WIKA portfolio","og_url":"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/","og_site_name":"WIKA blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/","url":"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/","name":"Level measurement products: Discover WIKA's diversity - WIKA blog","isPartOf":{"@id":"https:\/\/blog.wika.com\/us\/#website"},"description":"Find out more about our float switches and other products from the WIKA portfolio","breadcrumb":{"@id":"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wika.com\/us\/category\/products\/level-products\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wika.com\/us\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/blog.wika.com\/us\/category\/products\/"},{"@type":"ListItem","position":3,"name":"Level"}]},{"@type":"WebSite","@id":"https:\/\/blog.wika.com\/us\/#website","url":"https:\/\/blog.wika.com\/us\/","name":"WIKA blog","description":"Our blog offers many interesting articles on pressure, temperature, level, flow measurement calibration technology and provides insights into the WIKA Group.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wika.com\/us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/blog.wika.com\/us\/wp-json\/wp\/v2\/categories\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wika.com\/us\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.wika.com\/us\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blog.wika.com\/us\/wp-json\/wp\/v2\/categories\/6"}],"wp:post_type":[{"href":"https:\/\/blog.wika.com\/us\/wp-json\/wp\/v2\/posts?categories=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}